{"id":1465179,"date":"2025-08-06T09:03:42","date_gmt":"2025-08-06T16:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/"},"modified":"2025-08-06T09:03:42","modified_gmt":"2025-08-06T16:03:42","slug":"pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/","title":{"rendered":"&#171;Estamos en contra de la pena de muerte, no importa el delito&#187;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero"},"content":{"rendered":"<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este mi\u00e9rcoles que el posicionamiento de su Gobierno es en contra de la pena de muerte, luego de las recientes decisiones de Estados Unidos de no pedir esta medida contra los presuntos narcotraficantes mexicanos Ismael \u201cel Mayo\u201d Zambada y Rafael Caro Quintero, quienes se encuentran detenidos en EE.UU.<\/p>\n<p>\u201cNosotros estamos en contra de la pena de muerte. No importa el delito. No es algo con lo que coincidimos. Entonces, en cualquier sentido, cuando no hay pena de muerte, pues es parte de la pol\u00edtica mexicana, no es un asunto personal\u201d, coment\u00f3 Sheinbaum en su conferencia matutina.<\/p>\n<p>El martes, el Gobierno estadounidense inform\u00f3 a la Corte del Distrito Este de Nueva York que <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/05\/eeuu\/no-buscara-pena-muerte-ismael-mayo-zambada-orix\">no pedir\u00e1<\/a> la pena de muerte contra el Mayo Zambada ni contra Caro Quintero, seg\u00fan documentos judiciales.<\/p>\n<p>El fiscal Joseph Nocella Jr. fue quien envi\u00f3 ambos documentos judiciales a la Corte. El correspondiente al caso contra Zambada fue enviado al juez Brian Cogan. El del caso contra Caro Quintero, al juez Frederic Block.<\/p>\n<p>En los dos documentos, Nocella Jr. dice que informa al juez y a la defensa de los acusados que \u201cla Fiscal\u00eda General ha autorizado y ordenado a esta oficina que no busque la pena de muerte\u201d, un tema que hasta unas semanas <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/25\/eeuu\/caro-quintero-fiscalia-analiza-pena-de-muerte-orix\">se segu\u00eda analizando<\/a>.<\/p>\n<p>Adem\u00e1s del posicionamiento del Gobierno, Sheinbaum record\u00f3 que, en casos de extradici\u00f3n entre M\u00e9xico y los pa\u00edses con los que tiene un tratado en la materia, tiene que haber reciprocidad. \u201cEs decir, no puede haber pena de muerte\u201d de un mexicano extraditado a otro pa\u00eds. ya que la ley en M\u00e9xico proh\u00edbe esta medida.<\/p>\n<p>Sin embargo, tanto en el caso del Mayo Zambada como en el de Caro Quintero, no hubo proceso de extradici\u00f3n, por lo que a\u00fan estaba en duda una posible pena de muerte hasta antes del martes.<\/p>\n<p>Zambada, presunto fundador del C\u00e1rtel de Sinaloa, <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/07\/26\/detienen-ismael-el-mayo-zambada-cartel-de-sinaloa-trax\/\">fue detenido el 25 de julio del a\u00f1o pasado en Texas<\/a>. El presunto narcotraficante dice que fue enga\u00f1ado por Joaqu\u00edn Guzm\u00e1n L\u00f3pez, uno de los hijos de Joaqu\u00edn \u201cel Chapo\u201d Guzm\u00e1n, para ser llevado en avi\u00f3n a territorio estadounidense, donde en septiembre <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/09\/13\/ismael-el-mayo-zambada-se-declara-inocente-nueva-york-orix\/\">se declar\u00f3 inocente de 17 cargos<\/a> relacionados con narcotr\u00e1fico, lavado de dinero y uso de armas.<\/p>\n<p>Caro Quintero, apodado \u201cDon Rafa\u201d y considerado fundador del C\u00e1rtel de Guadalajara, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/27\/eeuu\/quienes-son-29-narcotraficantes-mexico-extradito-estados-unidos-orix\">fue enviado<\/a> por M\u00e9xico a Estados Unidos en febrero de este a\u00f1o. Dicho env\u00edo incluy\u00f3 a otros 28 presuntos delincuentes. El juez Robert M. Levy <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/28\/eeuu\/motivos-extradicion-caro-quintero-criminales-mexico-orix#:~:text=El%20juez%20Robert%20M.%20Levy%20aclar%C3%B3%20este%20viernes%20en%20la%20corte%20que%20Caro%20Quintero%20fue%20expulsado%20de%20M%C3%A9xico%20bajo%20una%20disposici%C3%B3n%20de%20la%20ley%20de%20seguridad%20nacional%2C%20que%20permite%20al%20Gobierno%20mexicano%20expulsar%20a%20un%20individuo%20sin%20pasar%20por%20el%20proceso%20formal%20de%20extradici%C3%B3n.\">explic\u00f3<\/a> en ese entonces que Caro Quintero fue expulsado de M\u00e9xico bajo una disposici\u00f3n de la ley de seguridad nacional, que permite al Gobierno mexicano expulsar a un individuo sin pasar por el proceso formal de extradici\u00f3n.<\/p>\n<p>D\u00edas despu\u00e9s de su llegada a Estados Unidos, Caro Quintero <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/28\/mexico\/rafael-caro-quintero-declara-inocente-corte-orix\">se declar\u00f3<\/a> inocente de cargos por el homicidio del agente de la DEA Enrique \u201cKiki\u201d Camarena, ocurrido en 1985, as\u00ed como por cargos de narcotr\u00e1fico.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este mi\u00e9rcoles que el posicionamiento de su Gobierno es en contra de la pena de muerte, luego de las recientes decisiones de Estados Unidos de no pedir esta medida contra los presuntos narcotraficantes mexicanos Ismael \u201cel Mayo\u201d Zambada y Rafael Caro Quintero, quienes se encuentran detenidos en EE.UU. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1465179","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Estamos en contra de la pena de muerte, no importa el delito&quot;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Estamos en contra de la pena de muerte, no importa el delito&quot;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero - Noticias\" \/>\n<meta property=\"og:description\" content=\"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este mi\u00e9rcoles que el posicionamiento de su Gobierno es en contra de la pena de muerte, luego de las recientes decisiones de Estados Unidos de no pedir esta medida contra los presuntos narcotraficantes mexicanos Ismael \u201cel Mayo\u201d Zambada y Rafael Caro Quintero, quienes se encuentran detenidos en EE.UU. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-06T16:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Estamos en contra de la pena de muerte, no importa el delito&#187;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero\",\"datePublished\":\"2025-08-06T16:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/\"},\"wordCount\":551,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/\",\"name\":\"\\\"Estamos en contra de la pena de muerte, no importa el delito\\\", dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-08-06T16:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Estamos en contra de la pena de muerte, no importa el delito&#187;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Estamos en contra de la pena de muerte, no importa el delito\", dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\"Estamos en contra de la pena de muerte, no importa el delito\", dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero - Noticias","og_description":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este mi\u00e9rcoles que el posicionamiento de su Gobierno es en contra de la pena de muerte, luego de las recientes decisiones de Estados Unidos de no pedir esta medida contra los presuntos narcotraficantes mexicanos Ismael \u201cel Mayo\u201d Zambada y Rafael Caro Quintero, quienes se encuentran detenidos en EE.UU. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/","og_site_name":"Noticias","article_published_time":"2025-08-06T16:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/"},"author":{"name":"","@id":""},"headline":"&#171;Estamos en contra de la pena de muerte, no importa el delito&#187;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero","datePublished":"2025-08-06T16:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/"},"wordCount":551,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/","url":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/","name":"\"Estamos en contra de la pena de muerte, no importa el delito\", dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-08-06T16:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Estamos en contra de la pena de muerte, no importa el delito&#187;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Estamos en contra de la pena de muerte, no importa el delito&#187;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero","url":"http:\/\/noticiasya.com\/los-angeles\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2025\/08\/06\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-08-06T16:03:42Z","datePublished":"2025-08-06T16:03:42Z","dateModified":"2025-08-06T16:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Estamos en contra de la pena de muerte, no importa el delito&#187;, dice Sheinbaum sobre casos del Mayo Zambada y Caro Quintero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2025\\\/08\\\/06\\\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2025\\\/08\\\/06\\\/pena-muerte-delito-sheinbaum-casos-mayo-zambada-caro-quintero-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-08-06T16:03:42Z\",\"datePublished\":\"2025-08-06T16:03:42Z\",\"dateModified\":\"2025-08-06T16:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465262,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/08\/08\/ismael-mayo-zambada-rafael-caro-quintero-que-sigue-ee-uu-orix\/","url_meta":{"origin":1465179,"position":0},"title":"\u00bfQu\u00e9 le espera a Ismael &#171;el Mayo&#187; Zambada y Rafael Caro Quintero ahora que no se considerar\u00e1 la pena de muerte en su juicio?","author":"","date":"agosto 8, 2025","format":false,"excerpt":"Los presuntos narcotraficantes mexicanos Ismael \u201cel Mayo\u201d Zambada y Rafael Caro Quintero, considerados figuras hist\u00f3ricas del crimen organizado en Am\u00e9rica del Norte, tienen la posibilidad de negociar con la Justicia de Estados Unidos luego de que el Gobierno de ese pa\u00eds informara el martes que no pedir\u00e1 la pena de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465662,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/08\/19\/como-explican-negocian-terroristas-sheinbaum-gobierno-ee-uu-mayo-zambada-orix\/","url_meta":{"origin":1465179,"position":1},"title":"&#171;\u00bfC\u00f3mo explican que no negocian con terroristas?&#187;: Sheinbaum cuestiona al Gobierno de EE.UU. por caso del Mayo Zambada","author":"","date":"agosto 19, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, cuestion\u00f3 este martes los procesos del Gobierno de Estados Unidos en el caso de Ismael \u201cMayo\u201d Zambada, presunto fundador del C\u00e1rtel de Sinaloa que se declarar\u00e1 culpable en audiencia ante la Corte Federal de Brooklyn.Sheinbaum critic\u00f3 que EE.UU. llega a \u201cacuerdos\u201d con miembros de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465603,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/08\/18\/ismael-mayo-zambada-cambiara-declaracion-inocencia-orix\/","url_meta":{"origin":1465179,"position":2},"title":"Ismael &#171;El Mayo&#187; Zambada cambiar\u00e1 su declaraci\u00f3n de inocencia ante la Corte Federal de Brooklyn, seg\u00fan documentos judiciales","author":"","date":"agosto 18, 2025","format":false,"excerpt":"Ismael \u201cEl Mayo\u201d Zambada, presunto fundador del C\u00e1rtel de Sinaloa detenido en Estados Unidos, cambiar\u00e1 su declaraci\u00f3n de inocencia en una audiencia que se llevar\u00e1 a cabo el 25 de agosto, seg\u00fan informaci\u00f3n de la Corte Federal de Brooklyn, del distrito Este de Nueva York, revisada por CNN este lunes.Seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465635,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/08\/19\/mayo-zambada-declarara-culpabe-estados-unidos-orix\/","url_meta":{"origin":1465179,"position":3},"title":"El Mayo Zambada se declarar\u00e1 culpable en audiencia ante la Corte Federal de Brooklyn","author":"","date":"agosto 19, 2025","format":false,"excerpt":"Ismael \u201cEl Mayo\u201d Zambada, presunto fundador del C\u00e1rtel de Sinaloa, detenido en Estados Unidos, se declarar\u00e1 culpable en una audiencia que se llevar\u00e1 a cabo el 25 de agosto, seg\u00fan consta en documentos judiciales.CNN pidi\u00f3 comentarios a su abogado y al Departamento de Estado de EE.UU. y espera respuesta.En septiembre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460470,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/03\/26\/juez-90-dias-fiscales-pena-muerte-rafael-caro-quintero-orix\/","url_meta":{"origin":1465179,"position":4},"title":"Juez da 90 d\u00edas a fiscales de EE.UU. para definir si piden pena de muerte para Rafael Caro Quintero","author":"","date":"marzo 26, 2025","format":false,"excerpt":"El narcotraficante mexicano Rafael Caro Quintero se present\u00f3 este mi\u00e9rcoles a una audiencia judicial en Nueva York, en la que el juez otorg\u00f3 90 d\u00edas a los fiscales para definir si pedir\u00e1n la pena de muerte contra el acusado conocido como \u201cnarco de narcos\u201d.Las autoridades mexicanas enviaron a fines de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459155,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/02\/24\/ismael-mayo-zambada-acuerdo-evitar-pena-de-muerte-orix\/","url_meta":{"origin":1465179,"position":5},"title":"Ismael &#171;el Mayo&#187; Zambada busca acuerdo para evitar la pena de muerte","author":"","date":"febrero 24, 2025","format":false,"excerpt":"La defensa legal de Ismael \u201cel Mayo\u201d Zambada busca llegar a un acuerdo con la Fiscal\u00eda del Distrito Este de Nueva York para evitar ser condenado a muerte.Frank P\u00e9rez, representante legal de Zambada en Estados Unidos, dijo a CNN que su cliente acepta declararse culpable de delitos cuyo castigo no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1465179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1465179"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1465179\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1465179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1465179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1465179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}