{"id":1469821,"date":"2026-01-06T03:03:53","date_gmt":"2026-01-06T11:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/"},"modified":"2026-01-06T03:03:53","modified_gmt":"2026-01-06T11:03:53","slug":"agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","title":{"rendered":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo"},"content":{"rendered":"<p>La administraci\u00f3n Trump ha comenzado a desplegar a alrededor de <a href=\"https:\/\/www.cnn.com\/2026\/01\/05\/us\/ice-minnesota-immigration-federal-agents-somali\">2.000 agentes federales<\/a> en Minneapolis como parte del \u00faltimo esfuerzo del presidente de acabar con la inmigraci\u00f3n irregular, afirmaron a CNN dos funcionarios policiales.<\/p>\n<p>Mientras, la ciudad y sus autoridades lidian con un <a href=\"https:\/\/www.cnn.com\/2026\/01\/05\/us\/minnesota-child-care-fraud-investigation\">esc\u00e1ndalo de fraude de asistencia social<\/a> que ha alcanzado un punto \u00e1lgido esta semana.<\/p>\n<p>En los d\u00edas transcurridos desde que un creador de contenido conservador plante\u00f3 acusaciones de fraude en un video de YouTube, con poca evidencia, sobre guarder\u00edas dirigidas por somal\u00edes en Minneapolis, la administraci\u00f3n Trump ha <a href=\"https:\/\/www.cnn.com\/2025\/12\/29\/us\/minnesota-day-care-fraud-what-we-know\">congelado los fondos federales para el cuidado infantil<\/a> y ha desatado una ret\u00f3rica m\u00e1s <a href=\"https:\/\/truthsocial.com\/@realDonaldTrump\/posts\/115814993074933464\">mordaz<\/a> contra esa comunidad, a la que ha llamado anteriormente \u201cbasura\u201d.<\/p>\n<p>Ahora, el presidente est\u00e1 <a href=\"https:\/\/www.cnn.com\/us\/live-news\/minnesota-tim-walz-reelection-scandal-01-05-2026?post-id=cmk1gzbav001a3b6pelbkzywh\">intensificando la aplicaci\u00f3n de las leyes migratorias<\/a>. Agentes federales ya han estado presentes en Minneapolis, y tanto funcionarios del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) como de la Patrulla Fronteriza de EE.UU. se est\u00e1n desplegando en Minnesota.<\/p>\n<p>Se espera que el comandante de la Oficina de Aduanas y Protecci\u00f3n Fronteriza de EE.UU., <a href=\"https:\/\/www.cnn.com\/2025\/10\/08\/politics\/gregory-bovino-border-patrol-chicago-immigration\">Gregory Bovino<\/a>, cuyas controvertidas t\u00e1cticas han sido objeto de <a href=\"https:\/\/www.cnn.com\/2025\/11\/06\/us\/gregory-bovino-deposition-chicago-immigration\">un mayor escrutinio<\/a> en varias ciudades, tambi\u00e9n se despliegue all\u00ed.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/01\/03\/us\/child-care-fraud-minnesota\">La incertidumbre<\/a> se extiende por la ciudad m\u00e1s grande de Minnesota a medida que las acusaciones de fraude provocan cambios en el liderazgo local, y ha surgido una nueva y ambigua medida de control migratorio <a href=\"https:\/\/www.cnn.com\/2026\/01\/04\/us\/minneapolis-somali-community-fraud-allegations\">que intimida a los residentes somal\u00edes<\/a>. Esto es lo que sabemos.<\/p>\n<p>La movilizaci\u00f3n de m\u00e1s agentes a Minneapolis se produce luego de que el gobernador de Minnesota, Tim Walz, quien se ha <a href=\"https:\/\/www.cnn.com\/2025\/06\/12\/politics\/democratic-governors-immigration-hearing\">opuesto firmemente al<\/a> despliegue de tropas de Trump en ciudades estadounidenses, anunci\u00f3 su retir\u00f3 de la disputa por la reelecci\u00f3n el lunes.<\/p>\n<p>El esc\u00e1ndalo de fraude a la asistencia social en su estado se ha intensificado hasta convertirse en un punto de conflicto pol\u00edtico aprovechado por Trump, y la <a href=\"https:\/\/www.cnn.com\/2025\/12\/29\/us\/video\/minnesota-somalia-immigrants-fraud-fbikash-patel-jd-vance-lead\">profundizaci\u00f3n de la investigaci\u00f3n federal<\/a> ha complicado la candidatura de Walz a un tercer mandato sin precedentes.<\/p>\n<p>El gobernador no ha sido acusado de ninguna irregularidad, pero los republicanos han intentado culpar a Walz y a los dem\u00f3cratas por el abuso masivo del dinero de los contribuyentes.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/01\/05\/politics\/tim-walz-minnesota-reelection\">Seg\u00fan<\/a> Walz, las recientes cr\u00edticas de la administraci\u00f3n Trump y sus aliados de derecha contribuyeron a su decisi\u00f3n de no buscar la reelecci\u00f3n.<\/p>\n<p>\u201cDurante los \u00faltimos a\u00f1os, un grupo organizado de delincuentes ha buscado aprovecharse de la generosidad de este estado\u201d, dijo Walz. \u201cY aunque avanzamos en la lucha contra los defraudadores, ahora vemos a un grupo organizado de actores pol\u00edticos que buscan aprovecharse de la crisis\u201d.<\/p>\n<p>Walz hab\u00eda sido criticado por la supervisi\u00f3n de los programas de asistencia social por parte de su administraci\u00f3n. Varios dem\u00f3cratas del estado le advirtieron en privado que no buscara la reelecci\u00f3n, ante la creciente indignaci\u00f3n en Minnesota y otros lugares por el mal uso de fondos.<\/p>\n<p>En su breve comparecencia del lunes, Walz expres\u00f3 su satisfacci\u00f3n por la investigaci\u00f3n federal. A\u00f1adi\u00f3 que era imperativo que los habitantes de Minnesota confiaran en los programas de seguridad social del estado.<\/p>\n<p>El aumento de 2.000 agentes no representa la primera vez que las autoridades federales de inmigraci\u00f3n se centran en las Ciudades Gemelas.<\/p>\n<p>En diciembre, tras los comentarios despectivos de Trump sobre los somal\u00edes y sus llamados a abandonar el pa\u00eds, <a href=\"https:\/\/www.cnn.com\/2025\/12\/17\/us\/minneapolis-police-chief-ice-tactics\" rel=\"noopener noreferrer\" target=\"_blank\">agentes federales<\/a> llegaron a Minneapolis y St. Paul como parte de la amplia campa\u00f1a de deportaci\u00f3n del presidente.<\/p>\n<p>La operaci\u00f3n gener\u00f3 temor y ansiedad en la comunidad somal\u00ed de la zona, cuya gran mayor\u00eda son ciudadanos estadounidenses.<\/p>\n<p>Casi el 58 % de los somal\u00edes en Minnesota nacieron en Estados Unidos, seg\u00fan la Oficina del Censo de Estados Unidos. De los somal\u00edes nacidos en el extranjero en Minnesota, una abrumadora mayor\u00eda (87 %) son ciudadanos estadounidenses naturalizados.<\/p>\n<p>El operativo anterior de ICE provoc\u00f3 protestas y tensos enfrentamientos con los agentes. En un incidente que gener\u00f3 cr\u00edticas del <a href=\"https:\/\/www.cnn.com\/2025\/12\/17\/us\/minneapolis-police-chief-ice-tactics\">jefe de polic\u00eda<\/a> de Minneapolis, un agente puso la rodilla sobre la espalda de una mujer que yac\u00eda sobre un banco de nieve y luego intent\u00f3 arrastrarla hasta un coche.<\/p>\n<p>El incidente tuvo lugar a pocos kil\u00f3metros de donde <a href=\"https:\/\/apnews.com\/hub\/death-of-george-floyd\" rel=\"noopener noreferrer\" target=\"_blank\">George Floyd<\/a> fue asesinado por un polic\u00eda municipal que se arrodill\u00f3 sobre su cuello en 2020.<\/p>\n<p>Los estadounidenses de ascendencia somal\u00ed <a href=\"https:\/\/www.cnn.com\/2025\/12\/04\/us\/minneapolis-somali-community-ice-immigration\">dijeron a CNN<\/a> que han comenzado a llevar consigo sus pasaportes y documentos de identidad, por miedo a que los agentes federales los detengan.<\/p>\n<p>En esta ocasi\u00f3n, el DHS afirm\u00f3 haber tenido dificultades para reservar habitaciones de hotel en Minneapolis para los agentes reci\u00e9n movilizados.<\/p>\n<p>Aleg\u00f3 <a href=\"https:\/\/x.com\/DHSgov\/status\/2008228888795861244?s=20\" rel=\"noopener noreferrer\" target=\"_blank\">que<\/a> la cadena hotelera internacional Hilton lanz\u00f3 una \u201ccampa\u00f1a coordinada\u201d para negar el servicio a los agentes cancelando sus reservas de habitaciones en Minneapolis, mientras la agencia se prepara para intensificar las medidas de control migratorio en esa ciudad.<\/p>\n<p>Las capturas de pantalla que el DHS <a href=\"https:\/\/x.com\/DHSgov\/status\/2008228888795861244?s=20\">public\u00f3 en X<\/a> el lunes por la tarde parecen mostrar correos electr\u00f3nicos de una direcci\u00f3n de Hilton que indica que los agentes de inmigraci\u00f3n no pueden quedarse en la propiedad Hampton Inn Lakeville, ubicada en un suburbio al sur de Minneapolis.<\/p>\n<p>\u201cTras investigar m\u00e1s a fondo en l\u00ednea, hemos encontrado informaci\u00f3n sobre inmigraci\u00f3n relacionada con su nombre y cancelaremos su pr\u00f3xima reserva. En breve, recibir\u00e1 un correo electr\u00f3nico de cancelaci\u00f3n de Hilton en su bandeja de entrada\u201d, se lee en un correo.<\/p>\n<p>La propiedad de Lakeville Hilton es de propiedad y operaci\u00f3n independiente de Everpeak Hospitality, que declar\u00f3 en un <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.everpeakhotels.com%2F&#038;data=05%7C02%7Cdanya.gainor%40cnn.com%7C6c68887d25b7471aa0a508de4cb7558d%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639032547702578770%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=LD37hJ6U%2BUfkK6u0WQ%2FAxVDdFYPrGkGzZI8nu9VatG4%3D&#038;reserved=0\">comunicado<\/a> en su sitio web que el incidente \u201cfue incompatible con nuestra pol\u00edtica de ser un lugar acogedor para todos\u201d y que est\u00e1 \u201cen contacto con los hu\u00e9spedes afectados para garantizar que sean alojados\u201d.<\/p>\n<p>La secretaria adjunta del DHS, Tricia McLaughlin, rechaz\u00f3 esa declaraci\u00f3n y <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fx.com%2FTriciaOhio%2Fstatus%2F2008316557118616025%3Fs%3D20&#038;data=05%7C02%7Cdanya.gainor%40cnn.com%7C6c68887d25b7471aa0a508de4cb7558d%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639032547702603897%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=XOlmaGpL2pjUY7QxDTM82V9Q9lOnCdOEELH3qefl15A%3D&#038;reserved=0\">escribi\u00f3 el<\/a> lunes por la noche que el DHS y el ICE no hab\u00edan tenido noticias de Everpeak Hospitality.<\/p>\n<p>Ni Hilton ni Everpeak Hospitality han confirmado la legitimidad de las capturas de pantalla de correos electr\u00f3nicos publicadas por el DHS.<\/p>\n<p>El 30 de diciembre, el subsecretario del Departamento de Salud y Servicios Humanos, Jim O\u2019Neill, anunci\u00f3 que la agencia <a href=\"https:\/\/x.com\/HHS_Jim\/status\/2006136004294664464?s=20\">congelar\u00eda todos los pagos de cuidado infantil<\/a> a Minnesota en medio de las acusaciones de fraude.<\/p>\n<p>El estado suele recibir alrededor de <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fx.com%2FHHS_Jim%2Fstatus%2F2006136004294664464&#038;data=05%7C02%7Czoe.sottile%40cnn.com%7Cead54b0ec3c94bd7137008de4ab762c6%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639030348907578619%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=ncqlU%2BV7olQgE3%2BaPPx5wyQsCJmQTLfDFizaR6dorD4%3D&#038;reserved=0\">US$ 185 millones<\/a> anuales en fondos federales para el cuidado infantil, lo que apoya la atenci\u00f3n de 19.000 ni\u00f1os.<\/p>\n<p>La semana pasada, los investigadores visitaron todos los centros de cuidado infantil acusados \u200b\u200bde fraude en el video, y todos funcionaban como se esperaba, seg\u00fan las autoridades estatales. Aun as\u00ed, las investigaciones sobre las presuntas irregularidades contin\u00faan.<\/p>\n<p>El Departamento de Ni\u00f1os, J\u00f3venes y Familias del estado anunci\u00f3 este lunes que realizar\u00e1 controles de cumplimiento adicionales en los centros de cuidado infantil de todo el estado.<\/p>\n<p>\u201cLos fondos se liberar\u00e1n solo cuando los estados demuestren que se est\u00e1n gastando leg\u00edtimamente\u201d, declar\u00f3 O\u2019Neill. A\u00f1adi\u00f3 que hab\u00eda exigido a Walz una auditor\u00eda exhaustiva de los centros que aparecen en el video.<\/p>\n<p>La prueba debe entregarse al Gobierno antes del viernes, seg\u00fan un correo electr\u00f3nico enviado por funcionarios estatales a los proveedores de cuidado infantil.<\/p>\n<p>El correo electr\u00f3nico indica que el HHS ha solicitado detalles espec\u00edficos, incluyendo el monto total de los pagos <a href=\"https:\/\/dcyf.mn.gov\/child-care-and-development-fund\" rel=\"noopener noreferrer\" target=\"_blank\">del Fondo de Cuidado y Desarrollo Infantil<\/a> recibidos por cinco centros de cuidado infantil, as\u00ed como datos administrativos, como nombres y n\u00fameros de seguro social, de todos los beneficiarios de fondos federales.<\/p>\n<p>El fondo es la principal fuente de apoyo federal para este tipo de servicio e incluye <a href=\"https:\/\/dcyf.mn.gov\/programs-directory\/child-care-assistance-program\">el Programa de Asistencia para el Cuidado Infantil del estado<\/a>, que <a href=\"https:\/\/www.cnn.com\/2025\/12\/30\/media\/nick-shirley-minnesota-somali-video\">Nick Shirley<\/a>, el creador del video viral, aleg\u00f3 que estaba siendo explotado en Minnesota.<\/p>\n<p>Mientras tanto, miles de familias de Minnesota que dependen de la financiaci\u00f3n federal para el cuidado infantil se encuentran <a href=\"https:\/\/www.cnn.com\/2026\/01\/03\/us\/child-care-fraud-minnesota\">en una situaci\u00f3n inestable<\/a>. No est\u00e1 claro con qu\u00e9 rapidez se podr\u00eda restablecer la financiaci\u00f3n si el estado cumple con el plazo del viernes.<\/p>\n<p>El esc\u00e1ndalo de fraude en el cuidado infantil ha reavivado la persistente hostilidad del presidente hacia los somal\u00edes.<\/p>\n<p>Durante a\u00f1os, Trump ha atacado a los somal\u00edes residentes en Estados Unidos, a la propia Somalia y a l\u00edderes somal\u00edes como <a href=\"https:\/\/www.cnn.com\/2025\/12\/10\/us\/video\/ilhan-omar-reacts-donald-trump-vrt-digvid\">la representante Ilhan Omar<\/a>, a quien, seg\u00fan \u00e9l, no deber\u00eda permit\u00edrsele servir en el Congreso.<\/p>\n<p>Somalia tambi\u00e9n estuvo en la <a href=\"https:\/\/www.cnn.com\/2017\/01\/29\/politics\/how-the-trump-administration-chose-the-7-countries\/index.html\">lista de pa\u00edses con prohibici\u00f3n de viaje<\/a> durante el primer mandato presidencial de Trump.<\/p>\n<p>Bajo la administraci\u00f3n de Obama, varios pa\u00edses de mayor\u00eda musulmana, incluyendo Somalia, fueron identificados como \u201cpa\u00edses de preocupaci\u00f3n\u201d y sujetos a restricciones de viaje.<\/p>\n<p>Somalia hab\u00eda sido a\u00f1adida para abordar \u201cla creciente amenaza de combatientes terroristas extranjeros\u201d, seg\u00fan un <a href=\"https:\/\/www.dhs.gov\/archive\/news\/2016\/02\/18\/dhs-announces-further-travel-restrictions-visa-waiver-program\">comunicado del Departamento de Seguridad Nacional<\/a>. Cuando Trump asumi\u00f3 el cargo, las restricciones se convirtieron en una prohibici\u00f3n de viaje.<\/p>\n<p>El presidente continu\u00f3 con sus ataques el domingo cuando se le pregunt\u00f3 sobre el esc\u00e1ndalo de fraude de Minnesota. Entonces insult\u00f3 a Omar y expres\u00f3 una serie de cosas sin sentido sobre los piratas somal\u00edes, mientras criticaba el robo \u201castron\u00f3mico\u201d de fondos gubernamentales.<\/p>\n<p>Los somal\u00edes y sus defensores se\u00f1alan que el peque\u00f1o grupo de personas acusadas de fraude no refleja su comunidad de miles de personas.<\/p>\n<p>Jaylani Hussein, directora ejecutiva de la secci\u00f3n de Minnesota del Consejo de Relaciones Estadounidenses-Isl\u00e1micas, apunta que existe un motivo claro cuando se utilizan casos aislados de irregularidades para convertir a toda una poblaci\u00f3n en chivo expiatorio.<\/p>\n<p>\u201cCada vez, surge el mismo patr\u00f3n: aislar un caso, generalizarlo a todo un grupo y utilizar el miedo para legitimar la discriminaci\u00f3n\u201d, denunci\u00f3 Hussein.<\/p>\n<p>\u201cLa comunidad somal\u00ed en las Ciudades Gemelas est\u00e1 compuesta abrumadoramente por familias trabajadoras, propietarios de peque\u00f1as empresas, trabajadores de la salud, estudiantes y contribuyentes que aportan todos los d\u00edas a la econom\u00eda y la vida c\u00edvica de Minnesota\u201d, afirm\u00f3.<\/p>\n<p>Las acusaciones de fraude alcanzar\u00e1n nuevas alturas en los pasillos del Congreso esta semana, cuando los legisladores del estado de Minnesota testificar\u00e1n en Washington, el mi\u00e9rcoles ante la Comisi\u00f3n de Supervisi\u00f3n de la C\u00e1mara de Representantes de Estados Unidos, liderada por los republicanos.<\/p>\n<p><a href=\"https:\/\/oversight.house.gov\/release\/chairman-comer-announces-hearings-on-rampant-fraud-in-minnesotas-social-services-programs\/\">La audiencia<\/a>, centrada en \u201cel fraude y el mal uso de fondos federales\u201d, contar\u00e1 con el testimonio de tres miembros republicanos de la C\u00e1mara de Representantes de Minnesota que, seg\u00fan el presidente de la Comisi\u00f3n de Supervisi\u00f3n, \u201chicieron sonar la alarma\u201d sobre el fraude: Kristin Robbins, Walter Hudson y Marion Rarick.<\/p>\n<p>James Comer, un republicano de Kentucky, invit\u00f3 a Walz y al fiscal general de Minnesota, Keith Ellison, a testificar en una audiencia separada ante el panel de investigaci\u00f3n de la Comisi\u00f3n el 10 de febrero, y afirm\u00f3 que el gobernador \u201cignor\u00f3\u201d las advertencias de fraude de los legisladores estatales.<\/p>\n<p>\u201cM\u00e1s le vale contratar un abogado\u201d, <a href=\"https:\/\/x.com\/RepJamesComer\/status\/2008205204425240855?s=20\">escribi\u00f3<\/a> Comer en X.<\/p>\n<p>\u201cTim Walz y el fiscal general Keith Ellison se han quedado dormidos al volante o han sido c\u00f3mplices de un fraude masivo que involucra dinero de los contribuyentes en los programas de servicios sociales de Minnesota\u201d, subray\u00f3 Comer en la declaraci\u00f3n.<\/p>\n<p><em>Zoe Sottile, Emma Tucker y Jeff Zeleny de CNN contribuyeron a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La administraci\u00f3n Trump ha comenzado a desplegar a alrededor de 2.000 agentes federales en Minneapolis como parte del \u00faltimo esfuerzo del presidente de acabar con la inmigraci\u00f3n irregular, afirmaron a CNN dos funcionarios policiales. Mientras, la ciudad y sus autoridades lidian con un esc\u00e1ndalo de fraude de asistencia social que ha alcanzado un punto \u00e1lgido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469821","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo - Noticias\" \/>\n<meta property=\"og:description\" content=\"La administraci\u00f3n Trump ha comenzado a desplegar a alrededor de 2.000 agentes federales en Minneapolis como parte del \u00faltimo esfuerzo del presidente de acabar con la inmigraci\u00f3n irregular, afirmaron a CNN dos funcionarios policiales. Mientras, la ciudad y sus autoridades lidian con un esc\u00e1ndalo de fraude de asistencia social que ha alcanzado un punto \u00e1lgido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T11:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo\",\"datePublished\":\"2026-01-06T11:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/\"},\"wordCount\":1963,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/\",\"name\":\"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-06T11:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo - Noticias","og_description":"La administraci\u00f3n Trump ha comenzado a desplegar a alrededor de 2.000 agentes federales en Minneapolis como parte del \u00faltimo esfuerzo del presidente de acabar con la inmigraci\u00f3n irregular, afirmaron a CNN dos funcionarios policiales. Mientras, la ciudad y sus autoridades lidian con un esc\u00e1ndalo de fraude de asistencia social que ha alcanzado un punto \u00e1lgido [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-06T11:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/"},"author":{"name":"","@id":""},"headline":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo","datePublished":"2026-01-06T11:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/"},"wordCount":1963,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","name":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-06T11:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"2.000 agentes federales intensifican operaci\u00f3n inmigratoria en Minneapolis. Las claves del operativo","url":"http:\/\/noticiasya.com\/los-angeles\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2026\/01\/06\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-06T11:03:53Z","datePublished":"2026-01-06T11:03:53Z","dateModified":"2026-01-06T11:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"2.000 agentes federales intensifican operaci\\u00f3n inmigratoria en Minneapolis. Las claves del operativo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/01\\\/06\\\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/01\\\/06\\\/agentes-federales-intensifican-operacion-inmigratoria-minneapolis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-06T11:03:53Z\",\"datePublished\":\"2026-01-06T11:03:53Z\",\"dateModified\":\"2026-01-06T11:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470061,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/01\/14\/convocan-audiencia-demanda-operacion-inmigratoria-trax\/","url_meta":{"origin":1469821,"position":0},"title":"Convocan audiencia sobre la demanda contra la operaci\u00f3n inmigratoria en las Ciudades Gemelas. Aqu\u00ed est\u00e1n las \u00faltimas noticias","author":"","date":"enero 14, 2026","format":false,"excerpt":"Se espera que este mi\u00e9rcoles se realice una audiencia sobre la demanda presentada por el estado de Minnesota y las Ciudades Gemelas, Minneapolis\u2013Saint Paul, impugnando la operaci\u00f3n de control de inmigraci\u00f3n de la administraci\u00f3n Trump, que la querella califica como \u201cuna invasi\u00f3n federal\u201d.La audiencia sigue a la renuncia de al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469813,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/01\/05\/trump-ofensiva-ice-minnesota-escandalo-fraude-trax\/","url_meta":{"origin":1469821,"position":1},"title":"Trump planea una gran ofensiva de control inmigratorio en Minnesota en medio de un esc\u00e1ndalo de fraude de asistencia social","author":"","date":"enero 5, 2026","format":false,"excerpt":"El Gobierno de Donald Trump est\u00e1 desplegando alrededor de 2.000 agentes federales en Minneapolis como parte de una ofensiva de control inmigratorio tras un esc\u00e1ndalo de fraude de asistencia social en Minnesota, seg\u00fan informaron dos funcionarios.Altos funcionarios de Trump se han enfocado en Minnesota y su comunidad somal\u00ed tras acusaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470887,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/02\/05\/dhs-retira-700-agentes-minnesota-trax\/","url_meta":{"origin":1469821,"position":2},"title":"El Gobierno de Trump retirar\u00e1 700 agentes de Minnesota, pero todav\u00eda quedar\u00edan alrededor de 2.000 en el terreno","author":"","date":"febrero 5, 2026","format":false,"excerpt":"El Gobierno de Donald Trump anunci\u00f3 que est\u00e1 reduciendo su presencia policial federal en Minnesota y el presidente sugiri\u00f3 imprimir un \u201ctoque m\u00e1s suave\u201d a su agresiva ofensiva inmigratoria, despu\u00e9s del segundo tiroteo fatal de un ciudadano estadounidense por parte de agentes federales en Minneapolis.Minneapolis-Saint Paul han sido el foco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470475,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/01\/25\/trump-endurece-politica-migratoria-coalicion-trax\/","url_meta":{"origin":1469821,"position":3},"title":"Trump endurece su pol\u00edtica migratoria en medio de una crisis interna: surgen las primeras fisuras en su coalici\u00f3n","author":"","date":"enero 25, 2026","format":false,"excerpt":"El presidente Donald Trump y altos funcionarios del Gobierno est\u00e1n redoblando sus pol\u00edticas y ret\u00f3rica de l\u00ednea dura sobre la inmigraci\u00f3n tras el tiroteo fatal de un ciudadano estadounidense por parte de un agente federal en Minneapolis, incluso cuando el incidente ha revelado fisuras en la coalici\u00f3n del presidente..Una falange\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470030,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/01\/13\/minnesota-illinois-demandan-gobierno-trump-inmigracion-trax\/","url_meta":{"origin":1469821,"position":4},"title":"Minnesota e Illinois demandan al Gobierno de Trump por operaciones de inmigraci\u00f3n. Principales afirmaciones de la querella","author":"","date":"enero 13, 2026","format":false,"excerpt":"Minnesota e Illinois presentaron demandas por separado este lunes contra la administraci\u00f3n Trump, argumentando que la represi\u00f3n inmigratoria del presidente est\u00e1 aterrorizando a sus comunidades y violando la Constituci\u00f3n.\u201cHemos visto con horror c\u00f3mo agentes federales sin control han atacado y aterrorizado agresivamente a nuestras comunidades y vecindarios en Illinois, socavando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469827,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/01\/06\/trump-congela-fondos-sociales-estados-democratas-trax\/","url_meta":{"origin":1469821,"position":5},"title":"El Gobierno de Trump congela miles de millones de d\u00f3lares en fondos para servicios sociales en cinco estados dem\u00f3cratas","author":"","date":"enero 6, 2026","format":false,"excerpt":"El Gobierno de Trump decidi\u00f3 recortar US$ 10.000 millones en fondos para servicios sociales y cuidado infantil en cinco estados gobernados por dem\u00f3cratas, confirm\u00f3 a CNN un funcionario del Departamento de Salud y Servicios Humanos (HHS). La agencia insinu\u00f3, sin pruebas, que los fondos se han utilizado de forma fraudulenta.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1469821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1469821"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1469821\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1469821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1469821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1469821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}