{"id":1473498,"date":"2026-04-25T08:03:52","date_gmt":"2026-04-25T15:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/"},"modified":"2026-04-25T08:03:52","modified_gmt":"2026-04-25T15:03:52","slug":"hung-cao-secretario-interino-marina-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/","title":{"rendered":"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por &#171;machos y hembras alfa&#187;. Hoy es el secretario interino de la Marina"},"content":{"rendered":"<p>Como subsecretario de la Marina, Hung Cao \u2014capit\u00e1n retirado de esa fuerza y excandidato republicano al Senado por Virginia\u2014 deb\u00eda tener una amplia cartera de responsabilidades en su calidad de segundo civil de mayor rango en el servicio, que inclu\u00eda cuestiones de personal y la salvaguarda del \u201cesp\u00edritu de combate\u201d de la Marina.<\/p>\n<p>Sin embargo, en la pr\u00e1ctica, Cao sol\u00eda ser excluido del proceso de toma de decisiones por su superior, el secretario de la Marina John Phelan. As\u00ed lo revel\u00f3 a CNN una fuente familiarizada con la situaci\u00f3n, quien a\u00f1adi\u00f3 que Phelan ten\u00eda a Cao \u201ccontrolado\u201d.<\/p>\n<p>Cao permaneci\u00f3 al margen de la toma de decisiones de la Marina y no se le permiti\u00f3 representar a Phelan en las reuniones oficiales a las que este no asist\u00eda, una funci\u00f3n que habitualmente s\u00ed desempe\u00f1a un subsecretario, seg\u00fan indic\u00f3 la misma fuente.<\/p>\n<p>Todo esto cambi\u00f3 tras la repentina <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/22\/eeuu\/marina-phelan-deja-cargo-trax\">destituci\u00f3n de Phelan como secretario de la Marina<\/a> \u2014ordenada esta semana por el presidente Donald Trump y el secretario de Defensa Pete Hegseth\u2014, cargo que ahora ocupa Cao de manera interina. Cao se enter\u00f3 de su ascenso a trav\u00e9s de la oficina principal del Pent\u00e1gono; lo convocaron y le comunicaron: \u201cMuy bien, el puesto es tuyo; hicimos un cambio\u201d, seg\u00fan relat\u00f3 la fuente.<\/p>\n<p>\u201cSe est\u00e1 poniendo al d\u00eda r\u00e1pidamente en todos aquellos asuntos en los que no se le hab\u00eda permitido participar\u201d, a\u00f1adi\u00f3 la fuente.<\/p>\n<p>Oficial condecorado de operaciones especiales, Cao asume el liderazgo civil de la Marina en un momento en que la instituci\u00f3n desempe\u00f1a un papel crucial para impedir que los buques iran\u00edes atraviesen el estrecho de Ormuz. En su calidad de candidato republicano en 2024 para enfrentarse al senador dem\u00f3crata por Virginia Tim Kaine, Cao respald\u00f3 los ataques de Trump y Hegseth contra diversas cuestiones sociales, as\u00ed como su oposici\u00f3n a las iniciativas de diversidad, equidad e inclusi\u00f3n.<\/p>\n<p>Cao emigr\u00f3 a Estados Unidos siendo ni\u00f1o, despu\u00e9s de que su familia huyera de la guerra de Vietnam.<\/p>\n<p>Tras retirarse de la Marina en 2021, se postul\u00f3 al Congreso como republicano en 2022 y desafi\u00f3 a Kaine en 2024. En ambas campa\u00f1as mostr\u00f3 una marcada propensi\u00f3n a realizar declaraciones controvertidas.<\/p>\n<p>\u201cNo queremos que se recurra a una \u2018drag queen\u2019 para reclutar personal para la Marina; esa no es la clase de gente que queremos\u201d, declar\u00f3 Cao durante un debate celebrado en 2024 con Kaine, en respuesta a una pregunta sobre el reclutamiento militar. \u201cLo que necesitamos son machos alfa y hembras alfa que est\u00e9n dispuestos a arrancarse las entra\u00f1as, com\u00e9rselas y pedir una segunda raci\u00f3n. Esos son los j\u00f3venes, hombres y mujeres que ganar\u00e1n las guerras\u201d.<\/p>\n<p>En un comunicado emitido tras su nombramiento como secretario interino, Cao afirm\u00f3 que se centrar\u00eda en impulsar las prioridades de construcci\u00f3n naval de la Marina, precisamente la cuesti\u00f3n que contribuy\u00f3 al cese de Phelan.<\/p>\n<p>\u201cSigo plenamente comprometido con el cumplimiento de la misi\u00f3n fundamental del Departamento de la Marina como organizaci\u00f3n b\u00e9lica de primer nivel, as\u00ed como con brindar un apoyo inquebrantable a nuestros guerreros desplegados en el frente\u201d, declar\u00f3 Cao.<\/p>\n<p>Phelan, empresario y amigo de Trump que recaud\u00f3 fondos para su campa\u00f1a, fue destituido como secretario de la Marina a ra\u00edz de las tensiones con Hegseth, que se hab\u00edan prolongado durante meses. Hegseth consideraba que Phelan avanzaba con demasiada lentitud en la implementaci\u00f3n de las reformas de construcci\u00f3n naval; asimismo, le molestaba la comunicaci\u00f3n directa que Phelan manten\u00eda con Trump, que Hegseth interpretaba como un intento de eludir su autoridad, seg\u00fan inform\u00f3 previamente la CNN.<\/p>\n<p>A\u00fan no est\u00e1 claro si Cao ser\u00e1 propuesto para asumir el cargo de secretario de la Marina de forma permanente.<\/p>\n<p>En un comunicado dirigido a CNN, el portavoz del Pent\u00e1gono, Sean Parnell, afirm\u00f3 que Cao \u201caporta un liderazgo forjado en el combate al cargo m\u00e1s alto de la Marina\u201d y que \u201cencarna la tenacidad inquebrantable y la visi\u00f3n de \u2018Estados Unidos Primero\u2019 (America First) necesarias para mantener la superioridad mar\u00edtima del pa\u00eds\u201d.<\/p>\n<p>Tras emigrar a Estados Unidos en 1975, Cao y su familia se trasladaron posteriormente a \u00c1frica Occidental, donde su padre trabaj\u00f3 como especialista agr\u00edcola para la Agencia de Estados Unidos para el Desarrollo Internacional (USAID), seg\u00fan consta en la biograf\u00eda de Cao publicada por la Marina. Cao regres\u00f3 a Virginia cuando ten\u00eda 12 a\u00f1os.<\/p>\n<p>Posteriormente, en 1989, se alist\u00f3 en la Marina y ascendi\u00f3 a oficial tras graduarse en la Academia Naval de Estados Unidos en 1996. A lo largo de una carrera de tres d\u00e9cadas, Cao se desempe\u00f1\u00f3 como buzo de la Marina y como oficial de desactivaci\u00f3n de artefactos explosivos. Entre sus despliegues se incluyen misiones en Iraq, Afganist\u00e1n y Somalia. Tambi\u00e9n tuvo un periodo de servicio en el Pent\u00e1gono, donde trabaj\u00f3 en cuestiones de presupuestos y adquisiciones.<\/p>\n<p>Cao y Hegseth ya se conoc\u00edan antes de que ambos se incorporaran al Gobierno de Trump; de hecho, Cao acompa\u00f1\u00f3 a Hegseth en un viaje a Vietnam el pasado mes de noviembre.<\/p>\n<p>Durante un mitin celebrado en Virginia en 2024 \u2014apenas unos d\u00edas antes de las elecciones de noviembre\u2014, Trump elogi\u00f3 al candidato al Senado por Virginia y lo invit\u00f3 a subir al escenario para unirse a \u00e9l. \u201cNos complace contar con la presencia de un tipo maravilloso, y con este nombre, realmente creo que ganar\u00e1 el esca\u00f1o en el Senado: Hung Cao\u201d, dijo Trump. Trump gan\u00f3 la Casa Blanca, pero perdi\u00f3 en Virginia, y Kaine derrot\u00f3 a Cao en la contienda por el Senado con un 54 % frente a un 45 %.<\/p>\n<p>Durante su campa\u00f1a para el Senado, Cao critic\u00f3 a menudo las pol\u00edticas de Diversidad, Equidad e Inclusi\u00f3n (DEI) de la administraci\u00f3n Biden, responsabiliz\u00e1ndola de los problemas de reclutamiento de las Fuerzas Armadas.<\/p>\n<p>\u201cEste Gobierno tiene una obsesi\u00f3n creciente con las iniciativas DEI. No es de extra\u00f1ar que tengamos un problema de reclutamiento militar en nuestro pa\u00eds, y eso continuar\u00e1 bajo el mandato de Harris y Walz\u201d, escribi\u00f3 Cao en X en septiembre de 2024.<\/p>\n<p>Cao fue confirmado como subsecretario de la Marina el 1 de octubre. Todos los dem\u00f3cratas votaron en contra de la nominaci\u00f3n de Cao y casi todos los republicanos lo apoyaron: la excepci\u00f3n fue la senadora por Alaska Lisa Murkowski, quien vot\u00f3 en contra.<\/p>\n<p>Ese mismo mes, el jefe de Gabinete de Phelan fue despedido por Hegseth, en parte debido a sus intentos de socavar la oficina del subsecretario de la Marina antes de que Cao asumiera el cargo, seg\u00fan inform\u00f3 Politico el oto\u00f1o pasado.<\/p>\n<p>Como subsecretario, Cao fue designado para ejercer como alto funcionario de Defensa para Guam, lugar al que su familia hab\u00eda llegado d\u00e9cadas atr\u00e1s como refugiados vietnamitas. Tambi\u00e9n dirigi\u00f3 las pol\u00edticas de reclutamiento y personal de la Marina, incluida la implementaci\u00f3n del decreto de Trump para readmitir a los miembros del servicio que hab\u00edan sido dados de baja de las fuerzas armadas debido al mandato de vacunaci\u00f3n contra el covid-19 en 2021.<\/p>\n<p>En enero, <a href=\"https:\/\/www.mynavyhr.navy.mil\/Portals\/55\/Documents\/Apology%20Letter.pdf?ver=7ea2uQ9BF33wqMh5c_dzpg%3D%3D\">Cao escribi\u00f3 una carta pidiendo disculpas a los marineros<\/a> que fueron expulsados \u200b\u200bde las fuerzas armadas como consecuencia de dicho mandato.<\/p>\n<p>\u201cA los marineros e infantes de marina que fueron dados de baja injustamente durante el covid: les fallamos. Nunca permitiremos que esto vuelva a suceder. No bajo mi supervisi\u00f3n\u201d, <a href=\"https:\/\/www.dvidshub.net\/video\/993922\/under-secretary-navy-hung-cao-covid-19-reinstatement\">declar\u00f3 Cao en un video<\/a> en el que firmaba la carta de disculpa. \u201cUstedes son guerreros de conciencia, y necesitamos que personas como ustedes regresen a la fuerza\u201d.<\/p>\n<p>La fuente familiarizada con la situaci\u00f3n se\u00f1al\u00f3 que Cao ha comunicado a los funcionarios del Pent\u00e1gono que no intentar\u00e1 pasar por alto ni a Trump ni a Hegseth. \u201c\u00c9l expresar\u00e1 sus opiniones y sugerencias dentro de la instituci\u00f3n\u201d, afirm\u00f3 la fuente, \u201cy apoyar\u00e1 lealmente cualquier decisi\u00f3n que tome el presidente\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como subsecretario de la Marina, Hung Cao \u2014capit\u00e1n retirado de esa fuerza y excandidato republicano al Senado por Virginia\u2014 deb\u00eda tener una amplia cartera de responsabilidades en su calidad de segundo civil de mayor rango en el servicio, que inclu\u00eda cuestiones de personal y la salvaguarda del \u201cesp\u00edritu de combate\u201d de la Marina. Sin embargo, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473498","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por &quot;machos y hembras alfa&quot;. Hoy es el secretario interino de la Marina - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por &quot;machos y hembras alfa&quot;. Hoy es el secretario interino de la Marina - Noticias\" \/>\n<meta property=\"og:description\" content=\"Como subsecretario de la Marina, Hung Cao \u2014capit\u00e1n retirado de esa fuerza y excandidato republicano al Senado por Virginia\u2014 deb\u00eda tener una amplia cartera de responsabilidades en su calidad de segundo civil de mayor rango en el servicio, que inclu\u00eda cuestiones de personal y la salvaguarda del \u201cesp\u00edritu de combate\u201d de la Marina. Sin embargo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-25T15:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por &#171;machos y hembras alfa&#187;. Hoy es el secretario interino de la Marina\",\"datePublished\":\"2026-04-25T15:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/\"},\"wordCount\":1382,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/\",\"name\":\"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por \\\"machos y hembras alfa\\\". Hoy es el secretario interino de la Marina - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-25T15:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por &#171;machos y hembras alfa&#187;. Hoy es el secretario interino de la Marina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por \"machos y hembras alfa\". Hoy es el secretario interino de la Marina - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por \"machos y hembras alfa\". Hoy es el secretario interino de la Marina - Noticias","og_description":"Como subsecretario de la Marina, Hung Cao \u2014capit\u00e1n retirado de esa fuerza y excandidato republicano al Senado por Virginia\u2014 deb\u00eda tener una amplia cartera de responsabilidades en su calidad de segundo civil de mayor rango en el servicio, que inclu\u00eda cuestiones de personal y la salvaguarda del \u201cesp\u00edritu de combate\u201d de la Marina. Sin embargo, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-25T15:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/"},"author":{"name":"","@id":""},"headline":"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por &#171;machos y hembras alfa&#187;. Hoy es el secretario interino de la Marina","datePublished":"2026-04-25T15:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/"},"wordCount":1382,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/","name":"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por \"machos y hembras alfa\". Hoy es el secretario interino de la Marina - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-25T15:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por &#171;machos y hembras alfa&#187;. Hoy es el secretario interino de la Marina"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Dijo que las Fuerzas Armadas deb\u00edan estar compuestas por &#171;machos y hembras alfa&#187;. Hoy es el secretario interino de la Marina","url":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/hung-cao-secretario-interino-marina-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-25T15:03:52Z","datePublished":"2026-04-25T15:03:52Z","dateModified":"2026-04-25T15:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Dijo que las Fuerzas Armadas deb\\u00edan estar compuestas por &#171;machos y hembras alfa&#187;. Hoy es el secretario interino de la Marina\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/25\\\/hung-cao-secretario-interino-marina-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/25\\\/hung-cao-secretario-interino-marina-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-25T15:03:52Z\",\"datePublished\":\"2026-04-25T15:03:52Z\",\"dateModified\":\"2026-04-25T15:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473422,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/22\/marina-phelan-deja-cargo-trax\/","url_meta":{"origin":1473498,"position":0},"title":"El secretario de la Marina de EE.UU., John Phelan, es destituido mientras contin\u00faa el bloqueo naval de Ir\u00e1n","author":"","date":"abril 22, 2026","format":false,"excerpt":"El secretario de la Marina, John Phelan, fue destituido de su cargo, dijeron a CNN seis fuentes familiarizadas con el asunto, en medio de tensiones con el secretario de Defensa, Pete Hegseth, por la implementaci\u00f3n de reformas a la construcci\u00f3n naval y por la estrecha relaci\u00f3n de Phelan con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470961,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/02\/06\/exclusivo-secretario-marina-john-phelan-avion-epstein-trax\/","url_meta":{"origin":1473498,"position":1},"title":"Exclusivo: el secretario de la Marina, John Phelan, figura como pasajero en el avi\u00f3n privado de Jeffrey Epstein en 2006","author":"","date":"febrero 6, 2026","format":false,"excerpt":"El secretario de la Marina, John Phelan, aparece en un manifiesto de vuelo hallado entre millones de documentos relacionados con el delincuente sexual condenado Jeffrey Epstein que han sido publicados en los \u00faltimos meses, lo que muestra que vol\u00f3 en 2006 de Londres a Nueva York en el avi\u00f3n privado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469514,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/12\/23\/marina-acorazados-trump-trax\/","url_meta":{"origin":1473498,"position":2},"title":"El nuevo plan de acorazados de Trump podr\u00eda transformar la Marina estadounidense\u2026 o hundirla","author":"","date":"diciembre 23, 2025","format":false,"excerpt":"El anuncio del presidente Donald Trump sobre una nueva clase de acorazados que llevar\u00e1n su nombre pone el foco en el programa de construcci\u00f3n naval de Estados Unidos, que en los \u00faltimos a\u00f1os no ha logrado entregar los nuevos buques de guerra a tiempo ni dentro del presupuesto, algo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471302,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/02\/16\/china-construye-submarinos-mas-rapido-trax\/","url_meta":{"origin":1473498,"position":3},"title":"China construye submarinos m\u00e1s r\u00e1pido que nunca, dice un informe. Por qu\u00e9 eso es un problema para Washington","author":"","date":"febrero 16, 2026","format":false,"excerpt":"China increment\u00f3 su producci\u00f3n de submarinos de propulsi\u00f3n nuclear en los \u00faltimos cinco a\u00f1os hasta el punto de estar lanzando submarinos m\u00e1s r\u00e1pido que Estados Unidos, lo que amenaza con anular una ventaja en el poder naval que durante mucho tiempo ha pertenecido a Washington, seg\u00fan un nuevo informe de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467877,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/10\/30\/mexico-coordinacion-maritima-ee-uu-sobreviviente-orix\/","url_meta":{"origin":1473498,"position":4},"title":"M\u00e9xico busca coordinaci\u00f3n mar\u00edtima con EE.UU. y no hay novedades del sobreviviente, dice Sheinbaum tras el ataque del lunes","author":"","date":"octubre 30, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo que su Gobierno busca mantener la coordinaci\u00f3n con Estados Unidos en materia mar\u00edtima, tras el ataque a una embarcaci\u00f3n presuntamente cargada con droga en aguas internacionales ocurrido este lunes. Sheinbaum dijo que a\u00fan no hay novedades sobre el presunto sobreviviente al ataque y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469223,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/12\/12\/marina-castigo-senador-kelly-video-ordenes-ilegales-trax\/","url_meta":{"origin":1473498,"position":5},"title":"La Marina entrega informe a Hegseth sobre posible castigo para el senador Mark Kelly por el video de &#171;\u00f3rdenes ilegales&#187;","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"La Marina de EE.UU. present\u00f3 sus recomendaciones sobre posibles castigos, si los hubiera, para el senador dem\u00f3crata Mark Kelly por su participaci\u00f3n en un video que recordaba a las fuerzas militares estadounidenses que tienen el deber de rechazar \u00f3rdenes ilegales, dijo un funcionario del Pent\u00e1gono a CNN el jueves.Esas recomendaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1473498"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473498\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1473498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1473498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1473498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}