{"id":1473499,"date":"2026-04-25T08:03:52","date_gmt":"2026-04-25T15:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/"},"modified":"2026-04-25T08:03:52","modified_gmt":"2026-04-25T15:03:52","slug":"analisis-intrigas-desencuentros-eeuu-cia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/","title":{"rendered":"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump"},"content":{"rendered":"<p>Hace 43 a\u00f1os, el periodista Manuel Buend\u00eda public\u00f3 el libro \u201cLa CIA en M\u00e9xico\u201d, que cimbr\u00f3 a la sociedad mexicana y sus c\u00edrculos pol\u00edticos. En el libro, Buend\u00eda expone la forma en que operaba la agencia de inteligencia estadounidense en territorio mexicano en labores contrainsurgentes, estableciendo alianzas con actores pol\u00edticos, sociales e incluso criminales para conseguir sus objetivos y, como regla general, de manera encubierta. Sin duda, un libro de cabecera para periodistas y personas interesadas en estos temas.<\/p>\n<p>El 30 de mayo de 1984, un a\u00f1o despu\u00e9s de la publicaci\u00f3n del libro, Buend\u00eda fue asesinado al salir de su oficina, por \u00f3rdenes del entonces director de la extinta Direcci\u00f3n Federal de Seguridad (DFS), Jos\u00e9 Antonio Zorrilla P\u00e9rez, quien fue sentenciado a 35 a\u00f1os de prisi\u00f3n. La DFS era el principal \u00f3rgano de inteligencia del Estado mexicano y, por obvias razones, uno de los enlaces m\u00e1s importantes con las agencias de inteligencia estadounidenses.<\/p>\n<p>Todo esto lo traigo a colaci\u00f3n porque me parece importante exponer que, en el contexto actual, cuando la relaci\u00f3n de M\u00e9xico y Estados Unidos pasa por un desencuentro en materia de seguridad por la presencia de agentes de la CIA en una operaci\u00f3n encubierta, existen antecedentes en el pasado reciente y remoto que demuestran que el tema no es nuevo y tampoco los encuentros y desencuentros.<\/p>\n<p>La muerte de dos agentes de la CIA en las remotas monta\u00f1as de Chihuahua, en el norte de M\u00e9xico, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/19\/mexico\/mueren-instructores-embajada-eeuu-agentes-mexicanos-accidente-operativo-antidrogas-chihuahua-orix\">en un accidente automovil\u00edstico<\/a>, ha desatado una fuerte tensi\u00f3n entre el gobierno de Claudia Sheinbaum y Chihuahua, estado gobernado por la opositora Mar\u00eda Eugenia Campos, con repercusiones en la relaci\u00f3n con Estados Unidos.<\/p>\n<p>La tragedia, en la que tambi\u00e9n fallecieron dos agentes de la Fiscal\u00eda de Chihuahua, supondr\u00eda un extraordinario ejemplo del compromiso y la cooperaci\u00f3n de ambos pa\u00edses en el combate al narcotr\u00e1fico porque, horas antes del accidente carretero, los cuatro agentes participaron, supuestamente, en el desmantelamiento de un complejo de laboratorios de drogas sint\u00e9ticas. Fue uno de los golpes m\u00e1s grandes que se hayan realizado a estas instalaciones clandestinas en M\u00e9xico, un pa\u00eds que hasta hace no mucho tiempo negaba que existieran estos laboratorios en su territorio.<\/p>\n<p>Pero los hechos, en lugar de provocar palabras de reconocimiento al trabajo de los agentes fallecidos, derivaron en una serie de intrigas, tropiezos, versiones encontradas y silencios, que hablan de algo m\u00e1s grande que una simple falta de comunicaci\u00f3n entre autoridades federales y estatales dentro de M\u00e9xico, y entre el gobierno de Sheinbaum y el de Estados Unidos.<\/p>\n<p>Y es que, al parecer, la operaci\u00f3n encubierta de la CIA qued\u00f3 exhibida por el accidente y la tragedia.<\/p>\n<p>La madrugada del domingo 19 de abril, el veh\u00edculo en que viajaban los cuatro agentes, que era parte de un convoy de al menos seis autom\u00f3viles, habr\u00eda perdido el control y ca\u00eddo a un acantilado en la carretera de la Sierra Tarahumara. Los cuatro agentes eran parte de un gran operativo estatal y federal, en el que habr\u00edan participado m\u00e1s de 60 efectivos entre estatales y federales, entre ellos, del Ej\u00e9rcito mexicano.<\/p>\n<p>Una de las primeras reacciones ante la tragedia fue la del embajador de Estados Unidos en M\u00e9xico, Ronald Johnson. Pocas horas despu\u00e9s del accidente, el diplom\u00e1tico <a href=\"https:\/\/x.com\/USAmbMex\/status\/2045966644187722038\">escribi\u00f3 en X<\/a>: \u201cEstamos profundamente entristecidos por la tr\u00e1gica p\u00e9rdida de dos miembros del personal de la Embajada de Estados Unidos, el director de la Agencia Estatal de Investigaci\u00f3n de Chihuahua (AEI) y un oficial de la AEI en este accidente. Honramos su dedicaci\u00f3n y sus incansables esfuerzos por enfrentar uno de los mayores desaf\u00edos de nuestro tiempo. Nuestros pensamientos y oraciones est\u00e1n con ellos y sus seres queridos. Esta tragedia es un recordatorio solemne de los riesgos que enfrentan esos funcionarios mexicanos y estadounidenses dedicados a proteger nuestras comunidades. Fortalece nuestra determinaci\u00f3n de continuar con su misi\u00f3n y avanzar en nuestro compromiso compartido con la seguridad y la justicia, para proteger a nuestra gente\u201d.<\/p>\n<p>Sin embargo, el lunes 20 de abril, la presidenta Sheinbaum asegur\u00f3 en su conferencia matutina que su gobierno <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/20\/mexico\/sheinbaum-operativo-chihuahua-muerte-agentes-eeuu-orix\">no estaba enterado<\/a> de la presencia de agentes estadounidenses en el operativo antinarc\u00f3ticos en Chihuahua. Expres\u00f3 su pesar por la muerte de los agentes, pero destac\u00f3 que la presencia de agentes de la CIA es un tema delicado porque estas acciones est\u00e1n expresamente prohibidas en la Constituci\u00f3n mexicana, donde se establece que estos asuntos son un tema de soberan\u00eda y seguridad nacional, ejes fundamentales para los estatutos del movimiento de la llamada \u201ccuarta transformaci\u00f3n\u201d que gobierna M\u00e9xico.<\/p>\n<p>Para el mismo lunes, la versi\u00f3n del fiscal de Chihuahua, C\u00e9sar J\u00e1uregui, contradec\u00eda la supuesta intervenci\u00f3n de los agentes de la CIA en el operativo. Seg\u00fan su versi\u00f3n, los agentes hab\u00edan participado en un curso a nueve horas de distancia de los operativos contra los laboratorios clandestinos en la Sierra Tarahumara. \u00bfY por qu\u00e9 iban en el convoy accidentado? Porque se encontraron en alg\u00fan punto para llevarlos al aeropuerto para tomar un vuelo, asegur\u00f3.<\/p>\n<p>Al d\u00eda siguiente, Sheinbaum lo refut\u00f3. Dijo que los agentes s\u00ed participaron en el operativo antidrogas e insisti\u00f3 en que su gobierno no tuvo informaci\u00f3n al respecto. Para el mi\u00e9rcoles, la mandataria dijo que hab\u00eda enviado una nota de extra\u00f1amiento a la embajada de Estados Unidos para que explicara por qu\u00e9 los agentes de la CIA participaron en el operativo sin informar a sus contrapartes en el gobierno federal y despu\u00e9s agreg\u00f3 que llamar\u00eda a la gobernadora de Chihuahua <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/23\/mexico\/chihuahua-agentes-eeuu-accidente-sheinbaum-orix\">para pedir una explicaci\u00f3n<\/a>, ante la posibilidad de que el gobierno estatal haya acordado por su propia cuenta la presencia de los agentes estadounidenses y se pudiese haber cometido una violaci\u00f3n al marco constitucional.<\/p>\n<p>Seg\u00fan Sheinbaum, la llamada a la gobernadora se hizo, pero no le contestaron. En todo caso, Campos se reuni\u00f3 con el secretario de Seguridad federal, Omar Garc\u00eda Harfuch, el jueves 23, sin que se ofrecieran detalles sobre el encuentro.<\/p>\n<p>Entre las tantas declaraciones sobre el tema, Sheinbaum ha insistido en que no se trata de un asunto pol\u00edtico contra la gobernadora, pero el tema ha generado muy intensos debates en el Congreso mexicano: el mi\u00e9rcoles 22, la mayor\u00eda oficialista en el Senado aprob\u00f3 citar a comparecer a Campos. Sin embargo, se trata de una \u201cinvitaci\u00f3n\u201d a comparecer porque el Senado no tiene las facultades para citar a un gobernador, de tal forma que Campos puede o no asistir.<\/p>\n<p>Dentro de la discusi\u00f3n, el oficialismo ha puesto sobre la mesa llevar a juicio pol\u00edtico a la gobernadora por posible violaci\u00f3n a la Constituci\u00f3n y delitos tan graves como traici\u00f3n a la patria. La oposici\u00f3n ha respondido argumentando que hay otros gobernadores de Morena que deber\u00edan comparecer para explicar las acusaciones sobre sus presuntos v\u00ednculos con el narcotr\u00e1fico.<\/p>\n<p>Preguntada sobe este incidente, en entrevista con la cadena Fox News, la portavoz de la Casa Blanca, Karoline Leavitt, declar\u00f3 que al presidente Donald Trump le hubiese gustado una mayor empat\u00eda de la presidenta de M\u00e9xico con los agentes ca\u00eddos en el cumplimiento de su deber.<\/p>\n<p>Para M\u00e9xico es delicado porque precisamente esta semana ambos pa\u00edses comenzaron las negociaciones formales para la revisi\u00f3n del tratado comercial al que pertenecen junto con Canad\u00e1, el T-MEC.<\/p>\n<p>Uno pensar\u00eda que el tema de seguridad no tiene que ver con una negociaci\u00f3n comercial, pero desde el primer mandato de Trump est\u00e1 claro que todos los temas pueden mezclarse: migraci\u00f3n, aranceles, seguridad y combate a las drogas son variables que pueden usarse indistintamente como fichas de negociaci\u00f3n, seg\u00fan la doctrina de Trump. Y eso representa un enorme riesgo para los negociadores mexicanos. Sobre todo, cuando Trump ha reclamado reiteradamente que M\u00e9xico no colabora de manera suficiente en el combate al narcotr\u00e1fico y ha cuestionado la actitud tibia de Sheinbaum. Son muchas veces las que Trump se ha referido a la presidenta como una gran mujer y persona, pero que tiene miedo a los carteles de la droga que, seg\u00fan \u00e9l, gobiernan M\u00e9xico.<\/p>\n<p>La colaboraci\u00f3n contra el narcotr\u00e1fico entre M\u00e9xico y Estados Unidos se ha desarrollado bajo un muy delicado marco de protocolos y acuerdos para evitar violar las leyes de los pa\u00edses vecinos. Tambi\u00e9n, por supuesto, se han registrado momentos de desconfianza entre gobiernos y agencias.<\/p>\n<p>El episodio de la detenci\u00f3n del l\u00edder del Cartel de Sinaloa, Ismael \u201cMayo\u201d Zambada, es un buen ejemplo de esas desconfianzas que han provocado grandes fisuras y problemas de seguridad que hasta hoy tienen consecuencias. Y es que la detenci\u00f3n de Zambada, el 25 de julio de 2024, se habr\u00eda logrado gracias a un acuerdo entre las agencias de inteligencia de Estados Unidos y la familia de su exsocio y compadre, Joaqu\u00edn \u201cChapo\u201d Guzm\u00e1n, seg\u00fan la versi\u00f3n del propio Mayo. En esta operaci\u00f3n de \u201csecuestro\u201d de Zambada, como lo define el propio l\u00edder del cartel, las autoridades mexicanas no fueron informadas y no participaron de ninguna manera.<\/p>\n<p>Sin duda, esa detenci\u00f3n fue una de las m\u00e1s importantes de la \u00faltima d\u00e9cada, pero gener\u00f3 una ola de violencia en el norte del pa\u00eds que hasta ahora no tiene control, por la confrontaci\u00f3n entre las dos fracciones del poderoso Cartel de Sinaloa.<\/p>\n<p>Al iniciar su segundo mandato, Trump ubic\u00f3 el combate al narcotr\u00e1fico y particularmente el fentanilo en el centro de sus pol\u00edticas. Declar\u00f3 a los carteles de la droga como actores terroristas y m\u00e1s tarde al fentanilo como un arma de destrucci\u00f3n masiva. Esto tuvo implicaciones importantes en el marco legal estadounidense porque abri\u00f3 la posibilidad de emprender acciones extraterritoriales contra las drogas, lo que anteriormente no se permit\u00eda. Por extensi\u00f3n, el mandato de la CIA de combatir el terrorismo se extendi\u00f3 al narcotr\u00e1fico, relegando a la DEA en muchas operaciones.<\/p>\n<p>Por supuesto, las acciones legales de Estados Unidos no tienen jurisdicci\u00f3n en M\u00e9xico o en cualquier otro pa\u00eds soberano, pero para Washington estas acciones forman parte de su marco de actuaci\u00f3n.<\/p>\n<p>Sin duda, los tiempos y objetivos han cambiado pero, como vemos, hay cosas que se mantienen como hace m\u00e1s de 43 a\u00f1os, cuando Buend\u00eda describi\u00f3 las operaciones de la CIA en M\u00e9xico. Y a pesar de todo esto hay cosas positivas que destacar: los golpes m\u00e1s importantes de los \u00faltimos a\u00f1os en materia de seguridad se han dado precisamente por la colaboraci\u00f3n entre los gobiernos de Sheinbaum y Trump. Decomisos y capturas que han resultado en menos asesinatos en el lado mexicano y menos muertes por sobredosis en Estados Unidos.<\/p>\n<p>Al final, m\u00e1s all\u00e1 de los discursos, los resultados son los que hablan y hablar\u00e1n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace 43 a\u00f1os, el periodista Manuel Buend\u00eda public\u00f3 el libro \u201cLa CIA en M\u00e9xico\u201d, que cimbr\u00f3 a la sociedad mexicana y sus c\u00edrculos pol\u00edticos. En el libro, Buend\u00eda expone la forma en que operaba la agencia de inteligencia estadounidense en territorio mexicano en labores contrainsurgentes, estableciendo alianzas con actores pol\u00edticos, sociales e incluso criminales para [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473499","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hace 43 a\u00f1os, el periodista Manuel Buend\u00eda public\u00f3 el libro \u201cLa CIA en M\u00e9xico\u201d, que cimbr\u00f3 a la sociedad mexicana y sus c\u00edrculos pol\u00edticos. En el libro, Buend\u00eda expone la forma en que operaba la agencia de inteligencia estadounidense en territorio mexicano en labores contrainsurgentes, estableciendo alianzas con actores pol\u00edticos, sociales e incluso criminales para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-25T15:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump\",\"datePublished\":\"2026-04-25T15:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/\"},\"wordCount\":1896,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/\",\"name\":\"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-25T15:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump - Noticias","og_description":"Hace 43 a\u00f1os, el periodista Manuel Buend\u00eda public\u00f3 el libro \u201cLa CIA en M\u00e9xico\u201d, que cimbr\u00f3 a la sociedad mexicana y sus c\u00edrculos pol\u00edticos. En el libro, Buend\u00eda expone la forma en que operaba la agencia de inteligencia estadounidense en territorio mexicano en labores contrainsurgentes, estableciendo alianzas con actores pol\u00edticos, sociales e incluso criminales para [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-25T15:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/"},"author":{"name":"","@id":""},"headline":"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump","datePublished":"2026-04-25T15:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/"},"wordCount":1896,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/","name":"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-25T15:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las intrigas y desencuentros detr\u00e1s de la enredada relaci\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump","url":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/analisis-intrigas-desencuentros-eeuu-cia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-25T15:03:52Z","datePublished":"2026-04-25T15:03:52Z","dateModified":"2026-04-25T15:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las intrigas y desencuentros detr\\u00e1s de la enredada relaci\\u00f3n de Sheinbaum, Chihuahua, la CIA y Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/25\\\/analisis-intrigas-desencuentros-eeuu-cia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/25\\\/analisis-intrigas-desencuentros-eeuu-cia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-25T15:03:52Z\",\"datePublished\":\"2026-04-25T15:03:52Z\",\"dateModified\":\"2026-04-25T15:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456486,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/11\/elenco-actores-cien-anos-de-soledad-showbiz-orix\/","url_meta":{"origin":1473499,"position":0},"title":"\u00bfQui\u00e9n es qui\u00e9n en &#171;Cien a\u00f1os de soledad&#187; de Netflix?: estos son los personajes y actores","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Este mi\u00e9rcoles 11 de diciembre llega \u201cCien a\u00f1os de soledad\u201d a la plataforma de Netflix.La serie es una de las m\u00e1s esperadas en Latinoam\u00e9rica y est\u00e1 basada en la magistral obra del mismo nombre del escritor colombiano y premio Nobel Gabriel Garc\u00eda M\u00e1rquez.\u201cCien a\u00f1os de soledad\u201d tiene como protagonista central\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466049,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/01\/sheinbaum-primer-informe-gobierno-balance-orix\/","url_meta":{"origin":1473499,"position":1},"title":"\u00bfC\u00f3mo llega Sheinbaum a su primer informe de Gobierno? Estas son las cinco claves","author":"","date":"septiembre 1, 2025","format":false,"excerpt":"Claudia Sheinbaum hizo historia el 1 de octubre de 2024 al tomar posesi\u00f3n como la primera presidenta de M\u00e9xico. Este lunes, a un mes de que cumpla un a\u00f1o en el poder, la mandataria presenta su primer informe de Gobierno, manteniendo una alta popularidad en las encuestas y mientras su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456465,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/11\/cien-anos-soledad-suicidio-historia-garcia-marquez-orix\/","url_meta":{"origin":1473499,"position":2},"title":"El suicidio que no fue: la historia de c\u00f3mo Garc\u00eda M\u00e1rquez escribi\u00f3 &#8216;Cien a\u00f1os de soledad&#8217;","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"De Cien a\u00f1os de soledad, considerada por muchos como la novela en espa\u00f1ol m\u00e1s grande desde Don Quijote de la Mancha, se han contado numerosas historias y an\u00e9cdotas a veces dotadas de la magia que el libro inspira. La m\u00e1s famosa, quiz\u00e1, es la epifan\u00eda de Gabriel Garc\u00eda M\u00e1rquez mientras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446540,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/03\/05\/lanzamiento-garcia-marquez-novela-postuma-en-agosto-nos-vemos-orix\/","url_meta":{"origin":1473499,"position":3},"title":"Llega la novela p\u00f3stuma de Garc\u00eda M\u00e1rquez: \u201cEn agosto nos vemos\u201d, el libro que ni termin\u00f3 ni destruy\u00f3","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN) -- Han pasado ya 20 a\u00f1os desde que se public\u00f3 la \u00faltima novela de Gabriel Garc\u00eda M\u00e1rquez, \u201cMemoria de mis putas tristes\u201d. Sin embargo, el legado del autor original de Aracataca, Colombia, no termin\u00f3 ah\u00ed.Exist\u00eda otro trabajo del que poco se sab\u00eda y que tan solo figuraba en los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461685,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/04\/27\/luis-quevedo-se-reunen-miles-de-profesionales-vinculados-al-libro-a-la-edicion-a-la-educacion\/","url_meta":{"origin":1473499,"position":4},"title":"Luis Quevedo: &#171;Se re\u00fanen miles de profesionales vinculados al libro, a la edici\u00f3n, a la educaci\u00f3n&#187;","author":"","date":"abril 27, 2025","format":false,"excerpt":"Luis Quevedo, gerente general de EUDEBA habl\u00f3 este domingo con CNN Radio sobre las novedades que la editorial tendr\u00e1 en la Feria del Libro 2025.En Mundo UBA con Ricardo Branginski indic\u00f3: \u201cTenemos varias novedades. La feria se inaugur\u00f3 el jueves. Toda la semana estuvieron las jornadas profesionales, en donde se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471221,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/02\/14\/bannon-cortejo-epstein-derribar-papa-francisco-trax\/","url_meta":{"origin":1473499,"position":5},"title":"Steve Bannon cortej\u00f3 a Epstein en sus esfuerzos por &#171;derribar&#187; al papa Francisco","author":"","date":"febrero 14, 2026","format":false,"excerpt":"Steve Bannon, exasesor de la Casa Blanca del presidente Donald Trump, discuti\u00f3 estrategias de oposici\u00f3n con el delincuente sexual convicto Jeffrey Epstein contra el papa Francisco, y Bannon afirm\u00f3 que esperaba \u201cderribar\u201d al pont\u00edfice, seg\u00fan archivos recientemente publicados por el Departamento de Justicia de Estados Unidos.Los mensajes enviados entre ambos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1473499"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473499\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1473499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1473499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1473499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}