{"id":1473507,"date":"2026-04-25T16:03:57","date_gmt":"2026-04-25T23:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/"},"modified":"2026-04-25T16:03:57","modified_gmt":"2026-04-25T23:03:57","slug":"muere-policia-chicago-herido-sospechoso-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/","title":{"rendered":"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades"},"content":{"rendered":"<p>Un agente de polic\u00eda de Chicago muri\u00f3 por disparos y otro result\u00f3 gravemente herido este s\u00e1bado por un sospechoso de robo al que escoltaban dentro de un hospital, inform\u00f3 el superintendente de la polic\u00eda de Chicago, Larry Snelling.<\/p>\n<p>No est\u00e1 claro c\u00f3mo el sospechoso \u2014quien, seg\u00fan el hospital, fue sometido a un control con detector de metales al entrar y estuvo escoltado por agentes del orden en todo momento dentro de las instalaciones\u2014 logr\u00f3 hacerse con un arma de fuego. El superintendente declar\u00f3: \u201cEl asunto sigue bajo investigaci\u00f3n\u201d.<\/p>\n<p>El presunto atacante huy\u00f3 del lugar y, de acuerdo con informes, ingres\u00f3 en una vivienda privada a varias manzanas de distancia, de acuerdo con WBBM, afiliada de CNN.<\/p>\n<p>La polic\u00eda y equipos SWAT rodearon r\u00e1pidamente la casa y el sospechoso fue detenido, seg\u00fan WBBM. Tambi\u00e9n se recuper\u00f3 un arma, dijo Snelling.<\/p>\n<p>Los agentes fueron trasladados al Centro M\u00e9dico Advocate Illinois Masonic, a unos kil\u00f3metros de distancia, donde uno fue declarado muerto y el otro \u201cest\u00e1 luchando por su vida\u201d, dijo Snelling.<\/p>\n<p>El ataque tuvo lugar en el Swedish Hospital de Endeavor Health, que fue puesto en confinamiento. El campus permanece cerrado \u201cmientras las fuerzas del orden lideran la investigaci\u00f3n\u201d, indic\u00f3 Endeavor Health. Los pacientes y los miembros del equipo del hospital est\u00e1n a salvo.<\/p>\n<p>El incidente comenz\u00f3 cuando el sospechoso fue llevado al departamento de emergencias para recibir tratamiento, de acuerdo con el <a href=\"https:\/\/x.com\/EndeavorHlth\/status\/2048088826732556695\">Endeavor Health Swedish Hospital.<\/a> A su llegada fue revisado con una varita detectora de metales y estuvo acompa\u00f1ado por las fuerzas del orden, se\u00f1al\u00f3 un portavoz del hospital.<\/p>\n<p>Cuando se le pregunt\u00f3 sobre c\u00f3mo el sospechoso obtuvo un arma de fuego, el superintendente dijo: \u201cNo puedo profundizar demasiado en eso, porque todav\u00eda est\u00e1 bajo investigaci\u00f3n\u201d.<\/p>\n<p>El sospechoso hab\u00eda sido detenido originalmente por un presunto robo, a\u00f1adi\u00f3. Fue trasladado al hospital para \u201cobservaci\u00f3n\u201d, seg\u00fan Snelling.<\/p>\n<p>Las autoridades no han identificado p\u00fablicamente a los dos agentes, a la espera de notificar a sus familias. El agente que falleci\u00f3 ten\u00eda 38 a\u00f1os y llevaba 10 a\u00f1os en el departamento, mientras que el agente herido tiene 57 a\u00f1os y llevaba 21 a\u00f1os en la instituci\u00f3n, de acuerdo con el superintendente.<\/p>\n<p>Snelling lament\u00f3 \u201cla p\u00e9rdida de vida sin sentido de un agente que est\u00e1 ah\u00ed afuera intentando proteger la ciudad\u201d.<\/p>\n<p>\u201cEstos son los peligros de la labor policial\u201d, dijo. \u201cEstos agentes lo saben, lo entienden, pero aun as\u00ed lo hacen\u201d.<\/p>\n<p>El alcalde de Chicago, Brandon Johnson, calific\u00f3 el tiroteo de \u201ctragedia\u201d y agradeci\u00f3 a los agentes de polic\u00eda de Chicago \u201cpor presentarse todos los d\u00edas para la gente de esta ciudad\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un agente de polic\u00eda de Chicago muri\u00f3 por disparos y otro result\u00f3 gravemente herido este s\u00e1bado por un sospechoso de robo al que escoltaban dentro de un hospital, inform\u00f3 el superintendente de la polic\u00eda de Chicago, Larry Snelling. No est\u00e1 claro c\u00f3mo el sospechoso \u2014quien, seg\u00fan el hospital, fue sometido a un control con detector [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473507","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un agente de polic\u00eda de Chicago muri\u00f3 por disparos y otro result\u00f3 gravemente herido este s\u00e1bado por un sospechoso de robo al que escoltaban dentro de un hospital, inform\u00f3 el superintendente de la polic\u00eda de Chicago, Larry Snelling. No est\u00e1 claro c\u00f3mo el sospechoso \u2014quien, seg\u00fan el hospital, fue sometido a un control con detector [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-25T23:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades\",\"datePublished\":\"2026-04-25T23:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/\"},\"wordCount\":492,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/\",\"name\":\"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-25T23:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades - Noticias","og_description":"Un agente de polic\u00eda de Chicago muri\u00f3 por disparos y otro result\u00f3 gravemente herido este s\u00e1bado por un sospechoso de robo al que escoltaban dentro de un hospital, inform\u00f3 el superintendente de la polic\u00eda de Chicago, Larry Snelling. No est\u00e1 claro c\u00f3mo el sospechoso \u2014quien, seg\u00fan el hospital, fue sometido a un control con detector [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-25T23:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/"},"author":{"name":"","@id":""},"headline":"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades","datePublished":"2026-04-25T23:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/"},"wordCount":492,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/","name":"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-25T23:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un polic\u00eda muerto y otro herido cuando un sospechoso abri\u00f3 fuego en un hospital en Chicago, seg\u00fan autoridades","url":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/muere-policia-chicago-herido-sospechoso-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-25T23:03:57Z","datePublished":"2026-04-25T23:03:57Z","dateModified":"2026-04-25T23:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un polic\\u00eda muerto y otro herido cuando un sospechoso abri\\u00f3 fuego en un hospital en Chicago, seg\\u00fan autoridades\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/25\\\/muere-policia-chicago-herido-sospechoso-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/25\\\/muere-policia-chicago-herido-sospechoso-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-25T23:03:57Z\",\"datePublished\":\"2026-04-25T23:03:57Z\",\"dateModified\":\"2026-04-25T23:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1462679,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/05\/22\/quien-es-sospechoso-tiroteo-washington-elias-rodriguez-orix\/","url_meta":{"origin":1473507,"position":0},"title":"\u00bfQui\u00e9n es El\u00edas Rodr\u00edguez, el sospechoso del tiroteo frente al Museo Jud\u00edo Capital en Washington?","author":"","date":"mayo 22, 2025","format":false,"excerpt":"Dos miembros del personal de la Embajada de Israel en Estados Unidos murieron la noche del mi\u00e9rcoles tras un tiroteo frente al Museo Jud\u00edo Capital, en Washington. El hecho ha sido calificado por las autoridades como un \u201cacto de violencia selectiva\u201d, y ha encendido las alarmas en varios pa\u00edses.El sospechoso,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456865,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/12\/22\/muere-pasajera-hombre-fuego-metro-nueva-york-trax\/","url_meta":{"origin":1473507,"position":1},"title":"Detienen a un sospechoso por la muerte de una mujer a quien le prendieron fuego en el metro de Nueva York","author":"","date":"diciembre 22, 2024","format":false,"excerpt":"La Polic\u00eda arrest\u00f3 a un sospechoso de la muerte de una mujer tras prenderle fuego en el metro de la ciudad de Nueva York este domingo por la ma\u00f1ana, informaron las autoridades.Alrededor de las 7:30 a.m., un hombre, que la Polic\u00eda cree que tiene entre 25 y 30 a\u00f1os, se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449537,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/05\/17\/policia-dispara-hombre-armado-atentado-sinagoga-rouen-francia-trax\/","url_meta":{"origin":1473507,"position":2},"title":"La polic\u00eda abate a un hombre armado que intentaba prender fuego una sinagoga en Francia","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN) -- La polic\u00eda abati\u00f3 este viernes a un hombre armado que intentaba prender fuego una sinagoga en Ru\u00e1n, en el norte de Francia, seg\u00fan un portavoz del Ministerio del Interior.El ministro del Interior franc\u00e9s, Gerald Darmanin, tuite\u00f3 su apoyo a los polic\u00edas que intervinieron.\"Esta ma\u00f1ana temprano, agentes de polic\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1436144,"url":"https:\/\/noticiasya.com\/los-angeles\/2022\/12\/12\/arrestan-sospechoso-de-disparar-contra-policia-de-san-diego-durante-una-persecucion\/","url_meta":{"origin":1473507,"position":3},"title":"Arrestan sospechoso de disparar contra polic\u00eda de San Diego durante una persecuci\u00f3n","author":"agomez","date":"diciembre 12, 2022","format":false,"excerpt":"El largo enfrentamiento entre el equipo t\u00e1ctico SWAT y el sospechoso que se atrincher\u00f3 dentro de una casa, dur\u00f3 m\u00e1s de 9 horas.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464487,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/07\/13\/kentucky-tiroteo-muertos-iglesia-trax\/","url_meta":{"origin":1473507,"position":4},"title":"Dos muertos en iglesia de Kentucky tras tiroteo en el que un atacante dispar\u00f3 a un agente estatal; el sospechoso muri\u00f3","author":"agomez","date":"julio 13, 2025","format":false,"excerpt":"Una mujer de 72 a\u00f1os y otra de 32 murieron en un tiroteo este domingo en la iglesia bautista Richmond Road, en Lexington, Kentucky, informaron las autoridades.El atacante, quien tambi\u00e9n muri\u00f3, ya fue identificado, pero la polic\u00eda no revel\u00f3 su nombre porque su familia a\u00fan no ha sido notificada, indicaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448360,"url":"https:\/\/noticiasya.com\/los-angeles\/2024\/04\/22\/detienen-sospechoso-asalto-casa-alcaldesa-los-angeles-karen-bass-trax\/","url_meta":{"origin":1473507,"position":5},"title":"Detienen a un sospechoso que ingres\u00f3 a la casa de la alcaldesa de Los \u00c1ngeles, Karen Bass, dice la Polic\u00eda","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN) -- Un sospechoso se encuentra detenido despu\u00e9s de que la casa de la alcaldesa de Los \u00c1ngeles, Karen Bass, fuera asaltada este domingo por la ma\u00f1ana mientras estaba ocupada, seg\u00fan inform\u00f3 la Polic\u00eda.Alrededor de las 6:40 de la ma\u00f1ana, una persona rompi\u00f3 una ventana para entrar en la Getty\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1473507"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473507\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1473507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1473507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1473507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}