{"id":1473509,"date":"2026-04-25T18:03:56","date_gmt":"2026-04-26T01:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/"},"modified":"2026-04-25T18:03:56","modified_gmt":"2026-04-26T01:03:56","slug":"trump-retirado-cena-corresponsales-casa-blanca-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/","title":{"rendered":"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo"},"content":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, fue escoltado r\u00e1pidamente fuera del escenario por el Servicio Secreto durante la Cena de Corresponsales de la Casa Blanca en Washington, este s\u00e1bado.<\/p>\n<p>El vicepresidente J. D. Vance y algunos miembros del gabinete de Trump que tambi\u00e9n asist\u00edan al evento tambi\u00e9n fueron retirados.<\/p>\n<p>Trump est\u00e1 a salvo, seg\u00fan una fuente familiarizada con el asunto.<\/p>\n<p><em>Noticia en desarrollo\u2026<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Donald Trump, fue escoltado r\u00e1pidamente fuera del escenario por el Servicio Secreto durante la Cena de Corresponsales de la Casa Blanca en Washington, este s\u00e1bado. El vicepresidente J. D. Vance y algunos miembros del gabinete de Trump que tambi\u00e9n asist\u00edan al evento tambi\u00e9n fueron retirados. Trump est\u00e1 a salvo, seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473509","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Estados Unidos, Donald Trump, fue escoltado r\u00e1pidamente fuera del escenario por el Servicio Secreto durante la Cena de Corresponsales de la Casa Blanca en Washington, este s\u00e1bado. El vicepresidente J. D. Vance y algunos miembros del gabinete de Trump que tambi\u00e9n asist\u00edan al evento tambi\u00e9n fueron retirados. Trump est\u00e1 a salvo, seg\u00fan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-26T01:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo\",\"datePublished\":\"2026-04-26T01:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/\"},\"wordCount\":103,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/\",\"name\":\"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-26T01:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo - Noticias","og_description":"El presidente de Estados Unidos, Donald Trump, fue escoltado r\u00e1pidamente fuera del escenario por el Servicio Secreto durante la Cena de Corresponsales de la Casa Blanca en Washington, este s\u00e1bado. El vicepresidente J. D. Vance y algunos miembros del gabinete de Trump que tambi\u00e9n asist\u00edan al evento tambi\u00e9n fueron retirados. Trump est\u00e1 a salvo, seg\u00fan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-26T01:03:56+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/"},"author":{"name":"","@id":""},"headline":"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo","datePublished":"2026-04-26T01:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/"},"wordCount":103,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/","name":"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-26T01:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\u00e1 a salvo","url":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/trump-retirado-cena-corresponsales-casa-blanca-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-26T01:03:56Z","datePublished":"2026-04-26T01:03:56Z","dateModified":"2026-04-26T01:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump fue retirado del escenario en la Cena de Corresponsales de la Casa Blanca. Est\\u00e1 a salvo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/25\\\/trump-retirado-cena-corresponsales-casa-blanca-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/25\\\/trump-retirado-cena-corresponsales-casa-blanca-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-26T01:03:56Z\",\"datePublished\":\"2026-04-26T01:03:56Z\",\"dateModified\":\"2026-04-26T01:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473515,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","url_meta":{"origin":1473509,"position":0},"title":"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca","author":"","date":"abril 26, 2026","format":false,"excerpt":"Wolf Blitzer, de CNN, estaba a solo unos pocos metros de un hombre armado cuando se efectuaron disparos fuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca.Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, fuera del sal\u00f3n de baile del Washington Hilton,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473529,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/27\/incidente-cena-corresponsales-mapas-trax\/","url_meta":{"origin":1473509,"position":1},"title":"El incidente armado en la Cena de Corresponsales, explicado en mapas","author":"","date":"abril 27, 2026","format":false,"excerpt":"Un presunto atacante armado fue detenido el s\u00e1bado despu\u00e9s de atravesar un punto de control de seguridad en el Washington Hilton justo cuando comenzaban los eventos de la Cena anual de Corresponsales de la Casa Blanca. El presidente Donald Trump, el vicepresidente J. D. Vance, la primera dama Melania Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473512,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/wolf-blitzer-cnn-cena-corresponsales-trax\/","url_meta":{"origin":1473509,"position":2},"title":"Wolf Blitzer, de CNN, vive una &#171;terrible&#187; experiencia cuando un hombre armado abre fuego cerca de la Cena de Corresponsales","author":"","date":"abril 25, 2026","format":false,"excerpt":"Wolf Blitzer, de CNN, estaba a solo unos pocos pies de un hombre armado cuando se realizaron disparos afuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca.Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, afuera del sal\u00f3n de baile en el Washington\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473574,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/28\/oz-pearlman-jimmy-kimmel-corresponsales-orix\/","url_meta":{"origin":1473509,"position":3},"title":"Oz Pearlman, el mago que amenizaba la Cena de Corresponsales la noche del tiroteo, no particip\u00f3 el lunes en el show de Kimmel","author":"","date":"abril 28, 2026","format":false,"excerpt":"Oz Pearlman, el mentalista y mago que amenizaba la cena de la Asociaci\u00f3n de Corresponsales de la Casa Blanca el s\u00e1bado en el Washington Hilton cuando un hombre armado abri\u00f3 fuego, no particip\u00f3 el lunes en el programa televisivo \u201cJimmy Kimmel Live!\u201d, en el que estaba anunciado como invitado, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473511,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/sospechoso-tiroteo-cena-corresponsales-casa-blanca-profesor-california-trax\/","url_meta":{"origin":1473509,"position":4},"title":"El sospechoso del tiroteo en la cena de corresponsales de la Casa Blanca trabajaba como profesor en California","author":"","date":"abril 25, 2026","format":false,"excerpt":"Seg\u00fan los registros p\u00fablicos, el hombre sospechoso de abrir fuego en la cena de la Asociaci\u00f3n de Corresponsales de la Casa Blanca este s\u00e1bado por la noche trabajaba como profesor y desarrollador de videojuegos en el sur de California.Cole Tomas Allen, de 31 a\u00f1os, residente de Torrance, un suburbio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473739,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/05\/02\/crece-impulso-reprogramar-cena-corresponsales-tiroteo-trax\/","url_meta":{"origin":1473509,"position":5},"title":"Aumenta el impulso para reprogramar la Cena de Corresponsales de la Casa Blanca tras el tiroteo","author":"","date":"mayo 2, 2026","format":false,"excerpt":"Inmediatamente despu\u00e9s del tiroteo de la semana pasada frente la Cena de Corresponsales de la Casa Blanca, hab\u00eda escepticismo generalizado sobre la posibilidad de reprogramarla en el corto plazo.Pero las actitudes han cambiado en los \u00faltimos d\u00edas, y el consenso ahora es que la cena \u2014que tambi\u00e9n funciona como ceremonia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1473509"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473509\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1473509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1473509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1473509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}