{"id":1473515,"date":"2026-04-26T06:03:57","date_gmt":"2026-04-26T13:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/"},"modified":"2026-04-26T06:03:57","modified_gmt":"2026-04-26T13:03:57","slug":"wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","title":{"rendered":"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca"},"content":{"rendered":"<p>Wolf Blitzer, de CNN, estaba a solo unos pocos metros de un hombre armado cuando se efectuaron disparos fuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca.<\/p>\n<p>Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, fuera del sal\u00f3n de baile del Washington Hilton, cuando vio a un hombre con \u201cun arma muy muy peligrosa\u201d.<\/p>\n<p>\u201cDe repente escuch\u00e9 estos disparos fuertes, muy fuertes, muy aterradores, justo cerca de m\u00ed. Lo siguiente que supe fue que un agente de la Polic\u00eda me tir\u00f3 al suelo y se puso encima de m\u00ed\u201d, dijo Blitzer. Los agentes lo llevaron de vuelta al ba\u00f1o de hombres, donde unos 15 hombres m\u00e1s tambi\u00e9n se estaban refugiando.<\/p>\n<p>El veterano presentador de CNN dijo que el hombre armado estaba a \u201csolo unos pocos metros de distancia\u201d de \u00e9l cuando comenz\u00f3 el tiroteo.<\/p>\n<p>\u201cNo ten\u00eda idea, mientras escuchaba los disparos, a qui\u00e9n estaba apuntando este atacante, o si solo estaba tratando de asustar a todo el mundo\u201d, dijo Blitzer. \u201cY, por supuesto, lo primero que se me pas\u00f3 por la mente fue si me iba a disparar\u201d.<\/p>\n<p>\u201cFue un momento terrible, muy aterrador para m\u00ed\u201d, a\u00f1adi\u00f3 Blitzer.<\/p>\n<p>Una persona est\u00e1 bajo custodia tras un tiroteo cerca del \u00e1rea de control en la Cena de Corresponsales de la Casa Blanca, seg\u00fan el Servicio Secreto de Estados Unidos.<\/p>\n<p>\u201cS\u00ed vi al hombre armado en el suelo despu\u00e9s de que empez\u00f3 a disparar. Los agentes de la Polic\u00eda lo tiraron al suelo, pero \u00e9l segu\u00eda disparando. Y yo pod\u00eda escuchar los disparos\u201d, dijo Blitzer, y a\u00f1adi\u00f3 que hab\u00eda muchos polic\u00edas all\u00ed para ponerlo a salvo r\u00e1pidamente.<\/p>\n<p>El tiroteo ocurri\u00f3 fuera del sal\u00f3n de baile, en un piso superior, cerca del \u00e1rea de control de seguridad del vest\u00edbulo, donde se encuentran los ba\u00f1os.<\/p>\n<p>Un agente del Servicio Secreto recibi\u00f3 un disparo en el incidente, dijeron tres fuentes a CNN. La bala impact\u00f3 en el equipo de protecci\u00f3n del agente y fue trasladado a un hospital local.<\/p>\n<p>El presidente de EE.UU., Donald Trump, y miembros de su gabinete, incluido el vicepresidente J. D. Vance, estaban en el evento que se celebraba en el sal\u00f3n de baile en ese momento y fueron escoltados r\u00e1pidamente fuera del escenario y del lugar.<\/p>\n<p>\u201cVaya noche en DC. El Servicio Secreto y las fuerzas del orden hicieron un trabajo fant\u00e1stico. Actuaron con rapidez y valent\u00eda. El atacante ha sido detenido\u201d, escribi\u00f3 Trump en Truth Social.<\/p>\n<p>Aunque inicialmente dijo que esperaba que el evento continuara, Trump regres\u00f3 a la Casa Blanca a petici\u00f3n de las fuerzas del orden.<\/p>\n<p>Trump dijo que la Cena de Corresponsales de la Casa Blanca ser\u00e1 reprogramada.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wolf Blitzer, de CNN, estaba a solo unos pocos metros de un hombre armado cuando se efectuaron disparos fuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca. Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, fuera del sal\u00f3n de baile del Washington Hilton, cuando vio a un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473515","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wolf Blitzer, de CNN, vive experiencia &quot;aterradora&quot; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wolf Blitzer, de CNN, vive experiencia &quot;aterradora&quot; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca - Noticias\" \/>\n<meta property=\"og:description\" content=\"Wolf Blitzer, de CNN, estaba a solo unos pocos metros de un hombre armado cuando se efectuaron disparos fuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca. Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, fuera del sal\u00f3n de baile del Washington Hilton, cuando vio a un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-26T13:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca\",\"datePublished\":\"2026-04-26T13:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/\"},\"wordCount\":503,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/\",\"name\":\"Wolf Blitzer, de CNN, vive experiencia \\\"aterradora\\\" a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-26T13:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wolf Blitzer, de CNN, vive experiencia \"aterradora\" a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Wolf Blitzer, de CNN, vive experiencia \"aterradora\" a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca - Noticias","og_description":"Wolf Blitzer, de CNN, estaba a solo unos pocos metros de un hombre armado cuando se efectuaron disparos fuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca. Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, fuera del sal\u00f3n de baile del Washington Hilton, cuando vio a un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-26T13:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/"},"author":{"name":"","@id":""},"headline":"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca","datePublished":"2026-04-26T13:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/"},"wordCount":503,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","name":"Wolf Blitzer, de CNN, vive experiencia \"aterradora\" a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-26T13:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca","url":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/26\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-26T13:03:57Z","datePublished":"2026-04-26T13:03:57Z","dateModified":"2026-04-26T13:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Wolf Blitzer, de CNN, vive experiencia &#171;aterradora&#187; a corta distancia del tiroteo en Cena de Corresponsales de la Casa Blanca\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/26\\\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/26\\\/wolf-blitzer-experiencia-aterradora-tiroteo-cena-corresponsales-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-26T13:03:57Z\",\"datePublished\":\"2026-04-26T13:03:57Z\",\"dateModified\":\"2026-04-26T13:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473512,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/25\/wolf-blitzer-cnn-cena-corresponsales-trax\/","url_meta":{"origin":1473515,"position":0},"title":"Wolf Blitzer, de CNN, vive una &#171;terrible&#187; experiencia cuando un hombre armado abre fuego cerca de la Cena de Corresponsales","author":"","date":"abril 25, 2026","format":false,"excerpt":"Wolf Blitzer, de CNN, estaba a solo unos pocos pies de un hombre armado cuando se realizaron disparos afuera del sal\u00f3n principal en la Cena de Corresponsales de la Casa Blanca.Blitzer acababa de salir del ba\u00f1o de hombres en un piso superior, afuera del sal\u00f3n de baile en el Washington\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473513,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/26\/cena-anual-washington-caos-crimen-trax\/","url_meta":{"origin":1473515,"position":1},"title":"C\u00f3mo la cena anual m\u00e1s importante de Washington se transform\u00f3 en caos\u2026 y en una escena del crimen","author":"","date":"abril 26, 2026","format":false,"excerpt":"El presidente Donald Trump y la primera dama Melania Trump estaban sentados en el escenario del enorme sal\u00f3n de baile del Washington Hilton poco despu\u00e9s de las 8:30 p.m. (hora de Miami) del s\u00e1bado por la noche, interactuando de manera juguetona con el artista de la velada, el mentalista Oz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473529,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/27\/incidente-cena-corresponsales-mapas-trax\/","url_meta":{"origin":1473515,"position":2},"title":"El incidente armado en la Cena de Corresponsales, explicado en mapas","author":"","date":"abril 27, 2026","format":false,"excerpt":"Un presunto atacante armado fue detenido el s\u00e1bado despu\u00e9s de atravesar un punto de control de seguridad en el Washington Hilton justo cuando comenzaban los eventos de la Cena anual de Corresponsales de la Casa Blanca. El presidente Donald Trump, el vicepresidente J. D. Vance, la primera dama Melania Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473739,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/05\/02\/crece-impulso-reprogramar-cena-corresponsales-tiroteo-trax\/","url_meta":{"origin":1473515,"position":3},"title":"Aumenta el impulso para reprogramar la Cena de Corresponsales de la Casa Blanca tras el tiroteo","author":"","date":"mayo 2, 2026","format":false,"excerpt":"Inmediatamente despu\u00e9s del tiroteo de la semana pasada frente la Cena de Corresponsales de la Casa Blanca, hab\u00eda escepticismo generalizado sobre la posibilidad de reprogramarla en el corto plazo.Pero las actitudes han cambiado en los \u00faltimos d\u00edas, y el consenso ahora es que la cena \u2014que tambi\u00e9n funciona como ceremonia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473562,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/28\/tiroteo-cena-corresponsales-teorias-conspirativas-trax\/","url_meta":{"origin":1473515,"position":4},"title":"Se multiplican las teor\u00edas conspirativas tras el tiroteo en la Cena de Corresponsales de la Casa Blanca","author":"","date":"abril 28, 2026","format":false,"excerpt":"Apenas un hombre armado intent\u00f3 irrumpir en el sal\u00f3n de baile del Washington Hilton, donde se celebraba la Cena de Corresponsales de la Casa Blanca el s\u00e1bado por la noche, las redes sociales se inundaron de teor\u00edas conspirativas sobre lo que a\u00fan se estaba desarrollando en tiempo real.Desde el derrumbe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473757,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/05\/03\/jeanine-pirro-cena-corresponsales-sospechoso-trax\/","url_meta":{"origin":1473515,"position":5},"title":"Jeanine Pirro dice que sospechoso de la Cena de Corresponsales &#171;definitivamente&#187; hiri\u00f3 a agente del Servicio Secreto","author":"","date":"mayo 3, 2026","format":false,"excerpt":"La fiscal federal del Distrito de Columbia, Jeanine Pirro, dijo este domingo que el agente del Servicio Secreto herido durante la Cena de Corresponsales de la Casa Blanca el fin de semana pasado fue alcanzado por una descarga de escopeta disparada por el sospechoso acusado de intentar matar a Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1473515"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473515\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1473515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1473515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1473515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}