{"id":1473548,"date":"2026-04-27T17:03:55","date_gmt":"2026-04-28T00:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/"},"modified":"2026-04-27T17:03:55","modified_gmt":"2026-04-28T00:03:55","slug":"ceo-disney-prueba-trump-jimmy-kimmel-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/","title":{"rendered":"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel"},"content":{"rendered":"<p>El nuevo CEO de Disney, Josh D\u2019Amaro, quien sucedi\u00f3 a Bob Iger hace apenas seis semanas, est\u00e1 enfrentando su primera gran prueba con Trump.<\/p>\n<p>El presidente Donald Trump est\u00e1 presionando p\u00fablicamente a Disney para que despida a Jimmy Kimmel por un chiste del presentador nocturno de ABC la semana pasada.<\/p>\n<p>No hay indicios de que Disney est\u00e9 pensando en hacerlo. Pero la presi\u00f3n \u2014que tambi\u00e9n proviene de la primera dama Melania Trump y de una serie de aliados de Trump\u2014 ha creado un dolor de cabeza para D\u2019Amaro, quien anteriormente dirig\u00eda los parques tem\u00e1ticos de Disney y ahora tambi\u00e9n supervisa cadenas como ABC.<\/p>\n<p>Un portavoz de D\u2019Amaro no respondi\u00f3 a una solicitud de comentarios. Representantes de ABC y de Kimmel tambi\u00e9n han mantenido silencio desde que estall\u00f3 la controversia.<\/p>\n<p>Los productores de Kimmel estuvieron ocupados el lunes por la tarde preparando el nuevo episodio de esa noche, que est\u00e1 previsto que se emita a las 11:35 p.m. en las estaciones de ABC.<\/p>\n<p>La semana pasada Kimmel promocion\u00f3 a Oz Pearlman, quien iba a ser el artista en la Cena de Corresponsales de la Casa Blanca del s\u00e1bado, como su invitado especial el lunes por la noche.<\/p>\n<p>Pero Pearlman no pudo presentarse frente al presidente y la multitud reunida despu\u00e9s de que un hombre armado abriera fuego afuera del sal\u00f3n de baile donde se celebraba la cena.<\/p>\n<p>Posteriormente, Pearlman se retir\u00f3 de la aparici\u00f3n en Kimmel; ser\u00e1 reemplazado por Jon Lovett, el comediante y podcaster progresista que antes fue redactor de discursos del presidente Barack Obama.<\/p>\n<p>Lovett ha aparecido en \u201cJimmy Kimmel Live!\u201d m\u00faltiples veces en el pasado.<\/p>\n<p>El otro invitado del lunes por la noche que fue promocionado la semana pasada, el actor Anthony Anderson, a\u00fan tiene previsto aparecer en el programa.<\/p>\n<p>Tras bambalinas, es probable que los ejecutivos de ABC y Kimmel est\u00e9n discutiendo lo que podr\u00eda decir en el programa del lunes por la noche sobre la controversia.<\/p>\n<p>Kimmel <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/27\/eeuu\/melania-trump-kimmel-abc-trax\">brome\u00f3<\/a> en el episodio del jueves pasado diciendo que la primera dama ten\u00eda \u201cun resplandor como el de una viuda expectante\u201d.<\/p>\n<p>El chiste \u2014aparentemente sobre la edad del presidente\u2014 fue uno en una larga lista de remates envenenados a expensas de Trump. Kimmel fingi\u00f3 realizar un <em>roast <\/em>del presidente, ya que la cena de corresponsales iba a contar con Pearlman, un mentalista, en lugar de un comediante.<\/p>\n<p>La frase \u201cviuda expectante\u201d fue recontextualizada despu\u00e9s del tiroteo del s\u00e1bado por la noche. El presunto atacante fue acusado el lunes de intentar asesinar a Trump.<\/p>\n<p>Medios e influencers pro-Trump arremetieron contra Kimmel en l\u00ednea, presagiando un esfuerzo concertado por parte del Gobierno de Trump para sacarlo.<\/p>\n<p>La primera dama conden\u00f3 a Kimmel el lunes por la ma\u00f1ana, y el presidente dio seguimiento unas horas despu\u00e9s, calificando el comentario al aire de Kimmel como un \u201cdespreciable llamado a la violencia\u201d y vincul\u00e1ndolo directamente con el incidente del tiroteo.<\/p>\n<p>Para Disney, todo esto se siente un poco como una repetici\u00f3n.<\/p>\n<p>El pasado septiembre, en medio de una campa\u00f1a anterior de presi\u00f3n del Gobierno de Trump contra Kimmel, ABC suspendi\u00f3 el programa \u201cindefinidamente\u201d, solo para traerlo de vuelta menos de una semana despu\u00e9s.<\/p>\n<p>La cadena logr\u00f3 enfurecer tanto a los opositores de Trump por apartar a Kimmel y parecer capitular ante el presidente como a los seguidores de Trump al permitir que Kimmel volviera al aire.<\/p>\n<p>En aquella ocasi\u00f3n, cuando Iger a\u00fan era CEO, ABC sinti\u00f3 que ten\u00eda que actuar r\u00e1pidamente despu\u00e9s de que dos grandes propietarios de estaciones afiliadas a ABC, Nexstar y Sinclair, dijeran que preemptar\u00edan el programa de Kimmel en sus respectivos mercados.<\/p>\n<p>La n\u00famero dos de Iger, Dana Walden, quien tiene una relaci\u00f3n cercana con Kimmel, dijo m\u00e1s tarde que la suspensi\u00f3n fue un esfuerzo por \u201cbajar la temperatura\u201d despu\u00e9s de que Kimmel enfureciera a los conservadores con un comentario sobre el presunto asesino de Charlie Kirk.<\/p>\n<p>\u201cQuer\u00edamos resolver la situaci\u00f3n de cierta manera para proteger a nuestros empleados, para pensar en nuestra audiencia\u201d, le dijo a Bloomberg.<\/p>\n<p>Walden es ahora la n\u00famero 2 de D\u2019Amaro como presidenta y directora creativa principal de Disney.<\/p>\n<p>Nexstar y Sinclair siguen haciendo negocios con ABC y siguen constando oficialmente como que tienen reservas sobre el programa de Kimmel. Pero podr\u00edan dudar en retirar a Kimmel esta vez, ya que la reacci\u00f3n contra su boicot fue tan intensa el pasado septiembre.<\/p>\n<p>Kimmel, quien ha sido un cr\u00edtico abierto del presidente durante a\u00f1os y ha asistido a manifestaciones de No Kings en los \u00faltimos meses, ha argumentado que la pol\u00edtica es \u201cinevitable\u201d para \u00e9l en este momento.<\/p>\n<p>A principios de este mes, en el p\u00f3dcast \u201cIMO\u201d de Michelle Obama, dijo: \u201cCreo que ser\u00eda vergonzoso si no habl\u00e1ramos de esto. Ser\u00eda una verg\u00fcenza\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo CEO de Disney, Josh D\u2019Amaro, quien sucedi\u00f3 a Bob Iger hace apenas seis semanas, est\u00e1 enfrentando su primera gran prueba con Trump. El presidente Donald Trump est\u00e1 presionando p\u00fablicamente a Disney para que despida a Jimmy Kimmel por un chiste del presentador nocturno de ABC la semana pasada. No hay indicios de que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473548","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel - Noticias\" \/>\n<meta property=\"og:description\" content=\"El nuevo CEO de Disney, Josh D\u2019Amaro, quien sucedi\u00f3 a Bob Iger hace apenas seis semanas, est\u00e1 enfrentando su primera gran prueba con Trump. El presidente Donald Trump est\u00e1 presionando p\u00fablicamente a Disney para que despida a Jimmy Kimmel por un chiste del presentador nocturno de ABC la semana pasada. No hay indicios de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-28T00:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel\",\"datePublished\":\"2026-04-28T00:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/\"},\"wordCount\":863,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/\",\"name\":\"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-28T00:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel - Noticias","og_description":"El nuevo CEO de Disney, Josh D\u2019Amaro, quien sucedi\u00f3 a Bob Iger hace apenas seis semanas, est\u00e1 enfrentando su primera gran prueba con Trump. El presidente Donald Trump est\u00e1 presionando p\u00fablicamente a Disney para que despida a Jimmy Kimmel por un chiste del presentador nocturno de ABC la semana pasada. No hay indicios de que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-28T00:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/"},"author":{"name":"","@id":""},"headline":"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel","datePublished":"2026-04-28T00:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/"},"wordCount":863,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/","name":"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-28T00:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel","url":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/27\/ceo-disney-prueba-trump-jimmy-kimmel-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-28T00:03:55Z","datePublished":"2026-04-28T00:03:55Z","dateModified":"2026-04-28T00:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El nuevo CEO de Disney enfrenta su primera gran prueba con Trump: las presiones sobre Jimmy Kimmel\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/27\\\/ceo-disney-prueba-trump-jimmy-kimmel-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/27\\\/ceo-disney-prueba-trump-jimmy-kimmel-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-28T00:03:55Z\",\"datePublished\":\"2026-04-28T00:03:55Z\",\"dateModified\":\"2026-04-28T00:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470854,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/02\/04\/cinco-problemas-afrontar-ceo-disney-trax\/","url_meta":{"origin":1473548,"position":0},"title":"Los cinco problemas que tendr\u00e1 que afrontar el nuevo CEO de Disney","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Las \u00fanicas noticias de Disney que probablemente ver\u00e1n son sobre Josh D\u2019Amaro quien, a partir del pr\u00f3ximo mes, reemplazar\u00e1 a Bob Iger como CEO de Disney. Pero antes de que se hiciera oficial ese anuncio, la compa\u00f1\u00eda present\u00f3 n\u00fameros el lunes por la ma\u00f1ana. (Lo cual, estoy de acuerdo, suena\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473537,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/27\/melania-trump-kimmel-abc-trax\/","url_meta":{"origin":1473548,"position":1},"title":"Melania Trump sugiri\u00f3 que Kimmel deber\u00eda perder su trabajo por broma sobre &#171;viuda en espera&#187;","author":"","date":"abril 27, 2026","format":false,"excerpt":"La primera dama Melania Trump sugiri\u00f3 este lunes que el presentador Jimmy Kimmel deber\u00eda perder su trabajo por bromas que hizo durante un sketch simulado de la Cena de Corresponsales de la Casa Blanca en su programa la semana pasada.El mon\u00f3logo de Kimmel \u2014emitido el jueves en \u201cJimmy Kimmel Live!\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469111,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/12\/09\/jimmy-kimmel-abc-disney-trax\/","url_meta":{"origin":1473548,"position":2},"title":"Jimmy Kimmel continuar\u00e1 con ABC de Disney por al menos un a\u00f1o m\u00e1s","author":"","date":"diciembre 9, 2025","format":false,"excerpt":"Jimmy Kimmel renov\u00f3 su contrato con ABC, propiedad de Disney, para continuar presentando \u201cJimmy Kimmel Live!\u201d durante un a\u00f1o m\u00e1s.Una fuente familiarizada con el acuerdo le dijo a CNN que Kimmel firm\u00f3 una extensi\u00f3n de un a\u00f1o para continuar con su programa nocturno hasta mayo de 2027.CNN se comunic\u00f3 con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466765,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/24\/jimmy-kimmel-ovacion-masiva-grabacion-trax\/","url_meta":{"origin":1473548,"position":3},"title":"Un emocionado Kimmel regresa a ABC y critica los ataques &#171;antiestadounidenses&#187; de Trump contra la libertad de expresi\u00f3n","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"Jimmy Kimmel regres\u00f3 a su programa nocturno este martes por la noche e inst\u00f3 a los espectadores a plantar cara a las amenazas del presidente Trump, quien poco antes de la emisi\u00f3n del programa, envi\u00f3 una nueva amenaza contra la cadena del presentador, ABC.En un mon\u00f3logo elocuente y emotivo, Kimmel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466560,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/17\/retiran-programa-jimmy-kimmel-comentarios-charlie-kirk-trax\/","url_meta":{"origin":1473548,"position":4},"title":"Retiran &#171;indefinidamente&#187; del aire el programa de Jimmy Kimmel tras comentarios sobre Charlie Kirk","author":"","date":"septiembre 17, 2025","format":false,"excerpt":"La cadena de televisi\u00f3n ABC de Disney est\u00e1 retirando del aire indefinidamente el programa de entrevistas nocturno de Jimmy Kimmel en medio de una controversia por sus recientes comentarios sobre el presunto asesino de Charlie Kirk.\u201cJimmy Kimmel Live ser\u00e1 suspendido indefinidamente\u201d, dijo un portavoz de ABC, neg\u00e1ndose a compartir m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466602,"url":"https:\/\/noticiasya.com\/los-angeles\/2025\/09\/18\/detras-de-escena-suspension-kimmel-trax\/","url_meta":{"origin":1473548,"position":5},"title":"Lo que sucedi\u00f3 detr\u00e1s de escena que llev\u00f3 a la suspensi\u00f3n de Kimmel","author":"","date":"septiembre 18, 2025","format":false,"excerpt":"La decisi\u00f3n de sacar del aire el programa de Jimmy Kimmel no fue tan precipitada como podr\u00eda pensarse.El tema se hab\u00eda estado gestando toda la semana en los altos cargos de Disney y ABC, desde que Kimmel hizo comentarios durante su mon\u00f3logo del lunes por la noche sobre el presunto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1473548"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473548\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1473548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1473548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1473548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}