{"id":1473644,"date":"2026-04-29T14:03:47","date_gmt":"2026-04-29T21:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/"},"modified":"2026-04-29T14:03:47","modified_gmt":"2026-04-29T21:03:47","slug":"acusacion-gobernador-sinaloa-ruben-rocha-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/","title":{"rendered":"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas"},"content":{"rendered":"<p>El Gobierno de Estados Unidos acus\u00f3 al gobernador del estado mexicano de Sinaloa, Rub\u00e9n Rocha, de cargos de narcotr\u00e1fico, posesi\u00f3n ilegal de armas y conspiraci\u00f3n para poseer armas, inform\u00f3 este mi\u00e9rcoles el Departamento de Justicia <a href=\"https:\/\/www.justice.gov\/usao-sdny\/pr\/governor-sinaloa-and-nine-other-current-and-former-mexican-officials-charged-drug\">en un comunicado<\/a>.<\/p>\n<p>La acusaci\u00f3n contra Rocha, quien podr\u00eda enfrentar una pena que va de 40 a\u00f1os de prisi\u00f3n a  la cadena perpetua si es hallado culpable, tambi\u00e9n incluye a otras nueve personas, entre las que hay funcionarios y exfuncionarios de Sinaloa.<\/p>\n<p>El Departamento de Justicia sostiene que los acusados se aliaron con el Cartel de Sinaloa, uno de los m\u00e1s poderosos del continente, \u201cpara importar cantidades masivas de narc\u00f3ticos a  Estados Unidos\u201d.<\/p>\n<p>Acerca de Rocha, <a href=\"https:\/\/www.justice.gov\/usao-sdny\/media\/1438611\/dl\">la acusaci\u00f3n<\/a> dice que Los Chapitos, una fracci\u00f3n del Cartel de Sinaloa liderada por los hijos del narcotraficante Joaqu\u00edn \u201cel Chapo\u201d Guzm\u00e1n \u2014condenado a cadena perpetua en Estados Unidos\u2014, lo apoy\u00f3 desde que fue candidato a gobernador. Tambi\u00e9n se\u00f1ala que Rocha presuntamente acudi\u00f3 a reuniones con l\u00edderes de ese grupo delictivo y prometi\u00f3 apoyarlos.<\/p>\n<p>\u201cRocha Moya ha permitido que Los Chapitos operen con impunidad en Sinaloa. Entre otras cosas, Rocha Moya ha permitido a los l\u00edderes de los Chapitos colocar a otros funcionarios corruptos en puestos de poder en el gobierno estatal y local de Sinaloa, as\u00ed como en determinadas agencias estatales y locales encargadas del orden p\u00fablico. A su vez, los funcionarios alineados con los Chapitos en la administraci\u00f3n de Rocha Moya han protegido a los Chapitos y sus operaciones de tr\u00e1fico de drogas\u201d, menciona el documento.<\/p>\n<p>Rocha rechaz\u00f3 las acusaciones <a href=\"https:\/\/x.com\/rochamoya_\/status\/2049577651501723859\">en un mensaje publicado en X<\/a>, en el que asegur\u00f3 que esto representa \u201cun ataque\u201d contra la \u201ccuarta transformaci\u00f3n\u201d, el movimiento que abandera el partido oficialista Morena.<\/p>\n<p>\u201cRechazo categ\u00f3rica y absolutamente las imputaciones formuladas en mi contra por la Fiscal\u00eda Federal del Distrito Sur de Nueva York, ya que carecen de veracidad y fundamento alguno. Y as\u00ed se demostrar\u00e1, con toda contundencia, en el momento oportuno\u201d, dijo.<\/p>\n<p>\u201c(La acusaci\u00f3n) se inscribe en una perversa estrategia para violentar el orden constitucional, espec\u00edficamente la soberan\u00eda nacional que preconiza el art\u00edculo 40 de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos, que nuestro movimiento defiende como principio invariable e innegociable\u201d, agreg\u00f3.<\/p>\n<p>Rocha asumi\u00f3 su cargo de gobernador en 2021 tras ganar las elecciones de ese a\u00f1o postulado por Morena, el mismo partido de la presidenta Claudia Sheinbaum. Su mandato concluye en 2027.<\/p>\n<p>El embajador de Estados Unidos en M\u00e9xico, Ronald Johnson, dijo <a href=\"https:\/\/x.com\/USAmbMex\/status\/2049563802459689003\">en un comunicado<\/a> que la corrupci\u00f3n facilita las actividades criminales y debe ser combatida.<\/p>\n<p>\u201cSi bien no podemos comentar sobre los hechos espec\u00edficos de estas imputaciones y el proceso legal deber\u00e1 seguir su curso, hay algo claro: la corrupci\u00f3n que facilita el crimen organizado y perjudica a ambos pa\u00edses ser\u00e1 investigada y procesada en todos los casos en que aplique la jurisdicci\u00f3n de los Estados Unidos\u201d, se\u00f1al\u00f3.<\/p>\n<p>En <a href=\"https:\/\/www.gob.mx\/sre\/prensa\/sre-recibio-solicitudes-de-detencion-provisional-con-fines-de-extradicion-que-seran-turnadas-a-la-fgr-en-los-documentos-no-se-anexan-pruebas\">un comunicado<\/a>, la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico dijo que este martes recibi\u00f3 de Estados Unidos solicitudes de detenci\u00f3n provisional con fines de extradici\u00f3n contra varias personas, sin especificar nombres, y las envi\u00f3 a la Fiscal\u00eda General de la Rep\u00fablica para que las eval\u00fae.<\/p>\n<p>Agreg\u00f3 que la documentaci\u00f3n entregada por Estados Unidos \u201cno cuenta con elementos de prueba para poder determinar la responsabilidad de las personas de las cuales se solicita la detenci\u00f3n provisional con fines de extradici\u00f3n. Sin embargo, como debe procederse en estos casos, ser\u00e1 la Fiscal\u00eda General de la Rep\u00fablica quien determine si existen elementos probatorios de acuerdo con el sistema jur\u00eddico mexicano y la viabilidad de las solicitudes de detenci\u00f3n provisional con fines de extradici\u00f3n\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Estados Unidos acus\u00f3 al gobernador del estado mexicano de Sinaloa, Rub\u00e9n Rocha, de cargos de narcotr\u00e1fico, posesi\u00f3n ilegal de armas y conspiraci\u00f3n para poseer armas, inform\u00f3 este mi\u00e9rcoles el Departamento de Justicia en un comunicado. La acusaci\u00f3n contra Rocha, quien podr\u00eda enfrentar una pena que va de 40 a\u00f1os de prisi\u00f3n a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473644","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Estados Unidos acus\u00f3 al gobernador del estado mexicano de Sinaloa, Rub\u00e9n Rocha, de cargos de narcotr\u00e1fico, posesi\u00f3n ilegal de armas y conspiraci\u00f3n para poseer armas, inform\u00f3 este mi\u00e9rcoles el Departamento de Justicia en un comunicado. La acusaci\u00f3n contra Rocha, quien podr\u00eda enfrentar una pena que va de 40 a\u00f1os de prisi\u00f3n a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-29T21:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas\",\"datePublished\":\"2026-04-29T21:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/\"},\"wordCount\":672,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/\",\"name\":\"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-29T21:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas - Noticias","og_description":"El Gobierno de Estados Unidos acus\u00f3 al gobernador del estado mexicano de Sinaloa, Rub\u00e9n Rocha, de cargos de narcotr\u00e1fico, posesi\u00f3n ilegal de armas y conspiraci\u00f3n para poseer armas, inform\u00f3 este mi\u00e9rcoles el Departamento de Justicia en un comunicado. La acusaci\u00f3n contra Rocha, quien podr\u00eda enfrentar una pena que va de 40 a\u00f1os de prisi\u00f3n a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-29T21:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/"},"author":{"name":"","@id":""},"headline":"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas","datePublished":"2026-04-29T21:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/"},"wordCount":672,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/","name":"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-29T21:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estados Unidos acusa al gobernador de Sinaloa de narcotr\u00e1fico y posesi\u00f3n de armas","url":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/los-angeles\/2026\/04\/29\/acusacion-gobernador-sinaloa-ruben-rocha-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-29T21:03:47Z","datePublished":"2026-04-29T21:03:47Z","dateModified":"2026-04-29T21:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estados Unidos acusa al gobernador de Sinaloa de narcotr\\u00e1fico y posesi\\u00f3n de armas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/29\\\/acusacion-gobernador-sinaloa-ruben-rocha-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/los-angeles\\\/2026\\\/04\\\/29\\\/acusacion-gobernador-sinaloa-ruben-rocha-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-29T21:03:47Z\",\"datePublished\":\"2026-04-29T21:03:47Z\",\"dateModified\":\"2026-04-29T21:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473726,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/05\/02\/gobernador-sinaloa-pide-separarse-cargo-acusacion-narcotrafico-eeuu-orix\/","url_meta":{"origin":1473644,"position":0},"title":"El gobernador de Sinaloa pide separarse del cargo mientras Fiscal\u00eda de M\u00e9xico investiga acusaci\u00f3n de EE.UU. por narcotr\u00e1fico","author":"","date":"mayo 2, 2026","format":false,"excerpt":"El gobernador del estado mexicano de Sinaloa, Rub\u00e9n Rocha, inform\u00f3 este viernes que pidi\u00f3 licencia al Congreso local para separarse temporalmente del cargo mientras la Fiscal\u00eda General de la Rep\u00fablica (FGR) investiga la acusaci\u00f3n en la que el Gobierno de Estados Unidos le atribuye delitos de narcotr\u00e1fico y armas.Mediante un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473675,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/30\/sheinbaum-acusacion-gobernador-sinaloa-eeuu-pruebas-orix\/","url_meta":{"origin":1473644,"position":1},"title":"Tras acusaci\u00f3n de EE.UU. contra el gobernador de Sinaloa, Sheinbaum exige pruebas y advierte contra injerencias extranjeras","author":"","date":"abril 30, 2026","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, asegur\u00f3 este jueves que no van a \u201cproteger a nadie\u201d pero que \u201ctiene que haber pruebas\u201d, al referirse a la acusaci\u00f3n de Estados Unidos contra el gobernador de Sinaloa y otros funcionarios mexicanos por presuntos v\u00ednculos con el narcotr\u00e1fico.\u201cSolo si existen pruebas contundentes se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473718,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/05\/01\/fiscalia-detener-gobernador-rocha-orix\/","url_meta":{"origin":1473644,"position":2},"title":"Fiscal\u00eda de M\u00e9xico descarta detener al gobernador Rub\u00e9n Rocha, acusado de narcotr\u00e1fico por EE.UU.","author":"","date":"mayo 1, 2026","format":false,"excerpt":"La Fiscal\u00eda General de la Rep\u00fablica de M\u00e9xico (FGR) descart\u00f3 este viernes detener provisionalmente al gobernador del estado de Sinaloa, Rub\u00e9n Rocha, a quien el Gobierno de Estados Unidos solicit\u00f3 arrestar junto con otros nueve hombres para que sean extraditados y procesados por narcotr\u00e1fico y armas, cargos que los involucrados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473688,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/30\/ruben-ochoa-gobernador-sinaloa-acusado-orix\/","url_meta":{"origin":1473644,"position":3},"title":"Qui\u00e9n es Rub\u00e9n Rocha, el gobernador de Sinaloa acusado de narcotr\u00e1fico por EE.UU.","author":"","date":"abril 30, 2026","format":false,"excerpt":"La carrera del gobernador de Sinaloa, Rub\u00e9n Rocha Moya, un acad\u00e9mico curtido en la administraci\u00f3n universitaria y que pas\u00f3 por varios partidos del espectro pol\u00edtico hasta dar el gran salto con la coalici\u00f3n izquierdista encabezada por Morena, dio un vuelco esta semana cuando el funcionario fue acusado por el Departamento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473690,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/04\/30\/estados-unidos-acusa-gobernador-sinaloa-chapitos-orix\/","url_meta":{"origin":1473644,"position":4},"title":"EE.UU. acusa al gobernador de Sinaloa y nueve funcionarios de v\u00ednculos con los Chapitos: esto sabemos","author":"","date":"abril 30, 2026","format":false,"excerpt":"La acusaci\u00f3n del Departamento de Justicia de EE.UU. ha colocado en el centro de la atenci\u00f3n internacional al gobernador de Sinaloa, Rub\u00e9n Rocha Moya, y a nueve funcionarios y exfuncionarios por su presunta colaboraci\u00f3n, seg\u00fan la Casa Blanca, con el Cartel de Sinaloa, particularmente con Los Chapitos, la facci\u00f3n del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473708,"url":"https:\/\/noticiasya.com\/los-angeles\/2026\/05\/01\/analisis-tmec-cia-rocha-eeuu-sheinbaum-orix\/","url_meta":{"origin":1473644,"position":5},"title":"EE.UU. suma presi\u00f3n y pone en aprietos a Sheinbaum con la acusaci\u00f3n contra el Gobernador de Sinaloa","author":"","date":"mayo 1, 2026","format":false,"excerpt":"Con la renegociaci\u00f3n del Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 en puerta, el Gobierno de la presidenta mexicana, Claudia Sheinbaum, ya ten\u00eda un desaf\u00edo este a\u00f1o en su relaci\u00f3n con la administraci\u00f3n de su hom\u00f3logo estadounidense, Donald Trump. Sin embargo, el panorama se le ha complicado m\u00e1s en solo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/los-angeles\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/comments?post=1473644"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/posts\/1473644\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/media?parent=1473644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/categories?post=1473644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/los-angeles\/wp-json\/wp\/v2\/tags?post=1473644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}