{"id":1448366,"date":"2024-04-22T07:03:48","date_gmt":"2024-04-22T14:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/"},"modified":"2024-04-22T07:03:48","modified_gmt":"2024-04-22T14:03:48","slug":"resultados-parciales-referendo-ecuador-consulta-popular-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/","title":{"rendered":"Resultados parciales del referendo y consulta popular en Ecuador"},"content":{"rendered":"<p>(CNN en Espa\u00f1ol) &#8212; La presidenta del Consejo Nacional Electoral de Ecuador, Diana Atamaint inform\u00f3 este domingo en cadena nacional los resultados de conteo r\u00e1pido del referendo celebrado en Ecuador.<\/p>\n<p>Los resultados iniciales, seg\u00fan inform\u00f3 Atamaint, fueron los siguientes:<\/p>\n<p>PREGUNTAS DE REFERENDO<\/p>\n<p>PREGUNTA A:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que se permita el apoyo complementario de las Fuerzas Armadas en las funciones de la Polic\u00eda Nacional para combatir el crimen organizado, reformando parcialmente la Constituci\u00f3n?<\/p>\n<p>S\u00cd: 73.04%<\/p>\n<p>NO: 26.96%<\/p>\n<p>ENMIENDA CONSTITUCIONAL:<\/p>\n<p>B &#8211; PREGUNTA 1:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con permitir la extradici\u00f3n de ecuatorianos, con las condiciones, requisitos, restricciones e impedimentos establecidos en la Constituci\u00f3n, los instrumentos internacionales y en la ley, enmendando la Constituci\u00f3n y reformando las leyes?<\/p>\n<p>S\u00cd: 65.32%<\/p>\n<p>NO: 34.68%<\/p>\n<p>C &#8211; PREGUNTA 2:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con el establecimiento de judicaturas especializadas en materia constitucional, tanto en primera como en segunda instancia, para el conocimiento de las garant\u00edas jurisdiccionales que les corresponda, enmendando la Constituci\u00f3n y reformando la Ley Org\u00e1nica de Garant\u00edas Jurisdiccionales y Control Constitucional?<\/p>\n<p>S\u00cd: 60.32%<\/p>\n<p>NO: 34.68%<\/p>\n<p>D &#8211; PREGUNTA 3:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo que el Estado ecuatoriano reconozca el arbitraje internacional como m\u00e9todo para solucionar controversias en materia de inversi\u00f3n, contractuales o comerciales?<\/p>\n<p>S\u00cd: 36.59%<\/p>\n<p>NO: 63.41%<\/p>\n<p>E &#8211; PREGUNTA 4:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con enmendar la Constituci\u00f3n de la Rep\u00fablica y reformar el C\u00f3digo de Trabajo para el contrato de trabajo a plazo fijo y por horas, cuando se celebre por primera vez entre el mismo empleador y trabajador, sin afectar los derechos adquiridos de los trabajadores?<\/p>\n<p>S\u00cd: 32.67%<\/p>\n<p>NO: 67.33%<\/p>\n<p>En las preguntas de consulta popular los resultados est\u00e1n as\u00ed:<\/p>\n<p>F &#8211; PREGUNTA 1:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que las Fuerzas Armadas realicen control de armas, municiones, explosivos y accesorios, permanentemente, en las rutas, caminos, v\u00edas y corredores autorizados para el ingreso a los centros de rehabilitaci\u00f3n social?<\/p>\n<p>S\u00cd: 70.61%<\/p>\n<p>NO: 29.39%<\/p>\n<p>G &#8211; PREGUNTA 2:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que se incrementen las penas de los delitos de terrorismo y su financiaci\u00f3n, producci\u00f3n y tr\u00e1fico il\u00edcito de sustancias catalogadas sujetas a fiscalizaci\u00f3n, delincuencia organizada, asesinato, sicariato, trata de personas, secuestro extorsivo, tr\u00e1fico de armas, lavado de activos y actividad il\u00edcita de recursos mineros, reformando el C\u00f3digo Org\u00e1nico Integral Penal?<\/p>\n<p>S\u00cd: 68.23%<\/p>\n<p>NO: 31.77%<\/p>\n<p>H &#8211; PREGUNTA 3:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que las personas privadas de la libertad cumplan la totalidad de su pena dentro del centro de rehabilitaci\u00f3n social en los delitos detallados en el Anexo de la pregunta, reformando el C\u00f3digo Org\u00e1nico Integral Penal?<\/p>\n<p>S\u00cd: 67.66%<\/p>\n<p>NO: 32.34%<\/p>\n<p>I &#8211; PREGUNTA 4:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que se tipifique el delito de tenencia o porte de armas, municiones o componentes que son de uso privativo de las Fuerzas Armadas o la Polic\u00eda Nacional, sin afectar a las armas de fuego permitidas para uso civil, reformando el C\u00f3digo Org\u00e1nico Integral Penal?<\/p>\n<p>S\u00cd: 64.97%<\/p>\n<p>NO: 35.04%<\/p>\n<p>J &#8211; PREGUNTA 5:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que las armas, sus partes o piezas, explosivos, municiones o accesorios que fueron instrumentos u objeto material de un delito puedan destinarse al uso inmediato de la Polic\u00eda Nacional o las Fuerzas Armadas, reformando el C\u00f3digo Org\u00e1nico Integral Penal?<\/p>\n<p>S\u00cd: 65.05%<\/p>\n<p>NO: 34.95%<\/p>\n<p>K &#8211; PREGUNTA 6:<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que el Estado proceda a ser el titular (propietario) de los bienes de origen il\u00edcito o injustificado, simplificando el procedimiento de la Ley Org\u00e1nica de Extinci\u00f3n de Dominio?<\/p>\n<p>S\u00cd: 62.09%<\/p>\n<p>NO: 37.91%<\/p>\n<p>Atamaint a\u00f1adi\u00f3 que los resultados se ir\u00e1n actualizando en la p\u00e1gina oficial del Consejo Nacional Electoral.<\/p>\n<p>\u00bfQu\u00e9 implica el refer\u00e9ndum en Ecuador? 3:13<\/p>\n<p>Noticia en desarrollo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN en Espa\u00f1ol) &#8212; La presidenta del Consejo Nacional Electoral de Ecuador, Diana Atamaint inform\u00f3 este domingo en cadena nacional los resultados de conteo r\u00e1pido del referendo celebrado en Ecuador. Los resultados iniciales, seg\u00fan inform\u00f3 Atamaint, fueron los siguientes: PREGUNTAS DE REFERENDO PREGUNTA A: \u00bfEst\u00e1 usted de acuerdo con que se permita el apoyo complementario [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448366","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resultados parciales del referendo y consulta popular en Ecuador - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resultados parciales del referendo y consulta popular en Ecuador - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN en Espa\u00f1ol) &#8212; La presidenta del Consejo Nacional Electoral de Ecuador, Diana Atamaint inform\u00f3 este domingo en cadena nacional los resultados de conteo r\u00e1pido del referendo celebrado en Ecuador. Los resultados iniciales, seg\u00fan inform\u00f3 Atamaint, fueron los siguientes: PREGUNTAS DE REFERENDO PREGUNTA A: \u00bfEst\u00e1 usted de acuerdo con que se permita el apoyo complementario [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T14:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Resultados parciales del referendo y consulta popular en Ecuador\",\"datePublished\":\"2024-04-22T14:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/\"},\"wordCount\":641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/\",\"name\":\"Resultados parciales del referendo y consulta popular en Ecuador - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-22T14:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resultados parciales del referendo y consulta popular en Ecuador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resultados parciales del referendo y consulta popular en Ecuador - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Resultados parciales del referendo y consulta popular en Ecuador - Noticias","og_description":"(CNN en Espa\u00f1ol) &#8212; La presidenta del Consejo Nacional Electoral de Ecuador, Diana Atamaint inform\u00f3 este domingo en cadena nacional los resultados de conteo r\u00e1pido del referendo celebrado en Ecuador. Los resultados iniciales, seg\u00fan inform\u00f3 Atamaint, fueron los siguientes: PREGUNTAS DE REFERENDO PREGUNTA A: \u00bfEst\u00e1 usted de acuerdo con que se permita el apoyo complementario [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-22T14:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/"},"author":{"name":"","@id":""},"headline":"Resultados parciales del referendo y consulta popular en Ecuador","datePublished":"2024-04-22T14:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/"},"wordCount":641,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/","name":"Resultados parciales del referendo y consulta popular en Ecuador - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-22T14:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Resultados parciales del referendo y consulta popular en Ecuador"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Resultados parciales del referendo y consulta popular en Ecuador","url":"http:\/\/noticiasya.com\/lubbock\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-22T14:03:48Z","datePublished":"2024-04-22T14:03:48Z","dateModified":"2024-04-22T14:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Resultados parciales del referendo y consulta popular en Ecuador\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2024\\\/04\\\/22\\\/resultados-parciales-referendo-ecuador-consulta-popular-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2024\\\/04\\\/22\\\/resultados-parciales-referendo-ecuador-consulta-popular-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-22T14:03:48Z\",\"datePublished\":\"2024-04-22T14:03:48Z\",\"dateModified\":\"2024-04-22T14:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448291,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/19\/preguntas-referendo-consulta-popular-ecuador-implicaciones-alcances-orix\/","url_meta":{"origin":1448366,"position":0},"title":"\u00bfCu\u00e1les son las preguntas del referendo y la consulta popular en Ecuador? Esta es una gu\u00eda de sus implicaciones y alcances","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La papeleta electoral que recibir\u00e1n los votantes en Ecuador este domingo 21 de abril durante el referendo y la consulta popular incluir\u00e1 11 preguntas a las que los ciudadanos deber\u00e1n responder \u201cs\u00ed\u201d o \u201cno\u201d, como una expresi\u00f3n de aprobaci\u00f3n o rechazo a la propuesta de reformas legales y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448369,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/","url_meta":{"origin":1448366,"position":1},"title":"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa?","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los ecuatorianos manifestaron este domingo su apoyo a nueve de las 11 propuestas de\u00a0reformas legales y constitucionales planteadas por el presidente Daniel Noboa, espec\u00edficamente las enfocadas en seguridad y justicia, seg\u00fan los resultados oficiales preliminares del conteo r\u00e1pido del referendo y consulta popular que se llevaron adelante.Cerca\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448205,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/17\/ecuador-referendo-consulta-cambios-orix\/","url_meta":{"origin":1448366,"position":2},"title":"\u00bfPor qu\u00e9 hay referendo y consulta este domingo en Ecuador y qu\u00e9 cambios legales y constitucionales propone?","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los ecuatorianos volver\u00e1n a las urnas este domingo 21 de abril para decidir sobre reformas legales y cambios a la Constituci\u00f3n planteados por el presidente Daniel Noboa a trav\u00e9s de 11 preguntas \u2014de referendo y consulta popular\u2014 enfocadas en las \u00e1reas de seguridad, justicia, empleo y arbitrajes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448502,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/25\/casi-7-de-cada-10-ecuatorianos-rechazaron-preguntas-referendo-de-noboa-sobre-economia-y-empleo-trax\/","url_meta":{"origin":1448366,"position":3},"title":"Casi 7 de cada 10 ecuatorianos rechazaron las preguntas del referendo de Noboa sobre econom\u00eda y empleo","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) -- Mientras las preguntas sobre seguridad incluidas en el referendo y la consulta popular impulsados por Daniel Noboa obtuvieron un apoyo mayoritario de los ecuatorianos, aquellas sobre econom\u00eda y empleo fueron rechazadas por casi 7 de cada 10 ciudadanos, de acuerdo con los datos del Consejo Nacional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458508,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/02\/10\/segunda-vuelta-elecciones-ecuador-orix\/","url_meta":{"origin":1448366,"position":4},"title":"\u00bfCu\u00e1ndo se celebrar\u00e1 la segunda vuelta de las elecciones en Ecuador?","author":"","date":"febrero 10, 2025","format":false,"excerpt":"Ecuador se encamina a una segunda vuelta de las elecciones presidenciales que est\u00e1 prevista, seg\u00fan la autoridad electoral, para el 13 de abril.Daniel Noboa, el actual mandatario de centroderecha, y Luisa Gonz\u00e1lez, la candidata apoyada por el expresidente Rafael Correa, lideran la carrera a la Presidencia tras la primera vuelta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445231,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/02\/10\/presidente-de-ecuador-avanza-en-la-realizacion-de-una-consulta-popular-y-un-referendum-en-seguridad-justicia-y-empleo\/","url_meta":{"origin":1448366,"position":5},"title":"Presidente de Ecuador avanza en la realizaci\u00f3n de una consulta popular y un refer\u00e9ndum en Seguridad, Justicia y Empleo","author":"","date":"febrero 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Ecuador, Daniel Noboa, firm\u00f3 este viernes dos decretos ejecutivos que definen las preguntas que compondr\u00e1n la consulta popular y el refer\u00e9ndum que propone para llevar adelante reformas legales en materia de Seguridad, Justicia y Empleo.Seg\u00fan los decretos, las seis preguntas de la consulta se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1448366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1448366"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1448366\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1448366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1448366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1448366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}