{"id":1448390,"date":"2024-04-23T00:03:59","date_gmt":"2024-04-23T07:03:59","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/"},"modified":"2024-04-23T00:03:59","modified_gmt":"2024-04-23T07:03:59","slug":"helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/","title":{"rendered":"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Dos helic\u00f3pteros de la marina de Malasia chocaron en el aire durante un ensayo para un desfile naval este martes, matando a los 10 miembros de la tripulaci\u00f3n a bordo, dijo la marina en un comunicado.<\/p>\n<p>El incidente ocurri\u00f3 en la base naval de Lumut en el estado occidental de Perak a las 9:32 hora local, dijo la marina.<\/p>\n<p>&#171;Se confirm\u00f3 la muerte de todas las v\u00edctimas en el lugar y se las envi\u00f3 al hospital militar de la base naval de Lumut para su identificaci\u00f3n&#187;, dijo la marina.<\/p>\n<p>Un video que circul\u00f3 en los medios locales mostr\u00f3 a varios helic\u00f3pteros volando en formaci\u00f3n, cuando el rotor de uno de los helic\u00f3pteros choc\u00f3 contra otro antes de que ambos aviones se estrellaran contra el suelo. La polic\u00eda local confirm\u00f3 que las im\u00e1genes eran genuinas.<\/p>\n<p>La marina dijo que investigar\u00eda la causa de la colisi\u00f3n.<\/p>\n<p>El ministro de Defensa, Mohamed Khaled Nordin, dijo que los aviones (un helic\u00f3ptero de operaciones mar\u00edtimas y un helic\u00f3ptero militar Fennec) estaban ensayando para un desfile que celebraba el 90\u00ba aniversario de la Marina Real de Malasia, que se celebrar\u00eda el s\u00e1bado.<\/p>\n<p>Se estaban realizando esfuerzos para verificar las identidades de los miembros de la tripulaci\u00f3n asesinados, todos ellos menores de 40 a\u00f1os, dijo a los periodistas.<\/p>\n<p>Noticia en desarrollo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Dos helic\u00f3pteros de la marina de Malasia chocaron en el aire durante un ensayo para un desfile naval este martes, matando a los 10 miembros de la tripulaci\u00f3n a bordo, dijo la marina en un comunicado. El incidente ocurri\u00f3 en la base naval de Lumut en el estado occidental de Perak a las 9:32 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448390","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Dos helic\u00f3pteros de la marina de Malasia chocaron en el aire durante un ensayo para un desfile naval este martes, matando a los 10 miembros de la tripulaci\u00f3n a bordo, dijo la marina en un comunicado. El incidente ocurri\u00f3 en la base naval de Lumut en el estado occidental de Perak a las 9:32 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T07:03:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes\",\"datePublished\":\"2024-04-23T07:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/\"},\"wordCount\":260,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/\",\"name\":\"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-23T07:03:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/","og_locale":"es_ES","og_type":"article","og_title":"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes - Noticias","og_description":"(CNN) &#8212;\u00a0Dos helic\u00f3pteros de la marina de Malasia chocaron en el aire durante un ensayo para un desfile naval este martes, matando a los 10 miembros de la tripulaci\u00f3n a bordo, dijo la marina en un comunicado. El incidente ocurri\u00f3 en la base naval de Lumut en el estado occidental de Perak a las 9:32 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/","og_site_name":"Noticias","article_published_time":"2024-04-23T07:03:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/"},"author":{"name":"","@id":""},"headline":"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes","datePublished":"2024-04-23T07:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/"},"wordCount":260,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/","url":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/","name":"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-23T07:03:59+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Helic\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes","url":"http:\/\/noticiasya.com\/lubbock\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2024\/04\/23\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-23T07:03:59Z","datePublished":"2024-04-23T07:03:59Z","dateModified":"2024-04-23T07:03:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Helic\\u00f3pteros de la marina de Malasia chocan en el aire y mueren 10 tripulantes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2024\\\/04\\\/23\\\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2024\\\/04\\\/23\\\/helicopteros-de-marina-de-malasia-chocan-en-el-aire-y-mueren-10-tripulantes-reux\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-23T07:03:59Z\",\"datePublished\":\"2024-04-23T07:03:59Z\",\"dateModified\":\"2024-04-23T07:03:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473327,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/20\/carguero-irani-incautado-botin-guerra-trax\/","url_meta":{"origin":1448390,"position":0},"title":"El carguero iran\u00ed incautado por Estados Unidos podr\u00eda convertirse en &#171;bot\u00edn de guerra&#187;","author":"","date":"abril 20, 2026","format":false,"excerpt":"Estados Unidos cumpli\u00f3 el domingo su amenaza de abordar e incautar cualquier embarcaci\u00f3n que desafiara su bloqueo de los puertos de Ir\u00e1n, con im\u00e1genes difundidas por las fuerzas armadas que muestran a un destructor lanzamisiles disparando contra el M\/V Touska, vinculado a Ir\u00e1n, y, una vez que qued\u00f3 inutilizado, a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445090,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/02\/08\/continua-la-busqueda-de-5-marines-despues-de-que-su-helicoptero-fuera-encontrado-en-el-sur-de-california\/","url_meta":{"origin":1448390,"position":1},"title":"Contin\u00faa la b\u00fasqueda de 5 marines despu\u00e9s de que su helic\u00f3ptero fuera encontrado en el sur de California","author":"","date":"febrero 8, 2024","format":false,"excerpt":"(CNN) --\u00a0 Contin\u00faa la b\u00fasqueda de cinco marines estadounidenses cuyo helic\u00f3ptero militar fue encontrado en Pine Valley, en el sur de California, esta semana despu\u00e9s de que no lleg\u00f3 a una base de San Diego como estaba previsto.Los marines estaban en un vuelo de entrenamiento a bordo de un CH-53E\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459587,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/06\/tiroteo-pensacola-florida-base-naval-trax\/","url_meta":{"origin":1448390,"position":2},"title":"Autoridades responden a una &#171;situaci\u00f3n de atacante activo&#187; en base naval en Pensacola, Florida","author":"","date":"marzo 6, 2025","format":false,"excerpt":"Personal militar responde en este momento a \u201cuna situaci\u00f3n de atacante activo\u201d en la Estaci\u00f3n Corry, seg\u00fan un post en X de la Estaci\u00f3n A\u00e9rea Naval en Pensacola, Florida.\u201cLas Fuerzas de Seguridad de la Marina de NAS Pensacola y las entidades locales de orden p\u00fablico est\u00e1n respondiendo a una situaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473096,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/13\/marina-estados-unidos-iran-estrecho-ormuz-trax\/","url_meta":{"origin":1448390,"position":3},"title":"As\u00ed es como la Marina de EE.UU. podr\u00eda bloquear los puertos de Ir\u00e1n y desminar el estrecho de Ormuz","author":"","date":"abril 13, 2026","format":false,"excerpt":"Seis semanas despu\u00e9s del inicio de la guerra con Ir\u00e1n, el presidente Donald Trump est\u00e1 encomendando a la Marina de Estados Unidos las tareas m\u00e1s dif\u00edciles del conflicto: bloquear los puertos iran\u00edes y despejar el estrat\u00e9gico estrecho de Ormuz de cualquier mina iran\u00ed.La orden de bloqueo se aplicar\u00eda a todos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473422,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/22\/marina-phelan-deja-cargo-trax\/","url_meta":{"origin":1448390,"position":4},"title":"El secretario de la Marina de EE.UU., John Phelan, es destituido mientras contin\u00faa el bloqueo naval de Ir\u00e1n","author":"","date":"abril 22, 2026","format":false,"excerpt":"El secretario de la Marina, John Phelan, fue destituido de su cargo, dijeron a CNN seis fuentes familiarizadas con el asunto, en medio de tensiones con el secretario de Defensa, Pete Hegseth, por la implementaci\u00f3n de reformas a la construcci\u00f3n naval y por la estrecha relaci\u00f3n de Phelan con el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465725,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/08\/21\/buques-guerra-eeuu-caribe-america-latina-orix\/","url_meta":{"origin":1448390,"position":5},"title":"Este es el potencial de guerra de los buques de EE.UU. desplegados en el Caribe en medio de la tensi\u00f3n con Venezuela","author":"","date":"agosto 21, 2025","format":false,"excerpt":"En una inusual demostraci\u00f3n de poder naval, Estados Unidos ha comenzado a desplegar numerosos buques de guerra y personal militar en aguas de Am\u00e9rica Latina y el Caribe para presuntamente combatir los c\u00e1rteles de la droga, seg\u00fan han dicho funcionarios de Defensa a CNN.A\u00fan no est\u00e1 claro el alcance ni\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1448390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1448390"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1448390\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1448390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1448390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1448390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}