{"id":1451185,"date":"2024-07-16T23:03:51","date_gmt":"2024-07-17T06:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/"},"modified":"2024-07-16T23:03:51","modified_gmt":"2024-07-17T06:03:51","slug":"joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/","title":{"rendered":"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden"},"content":{"rendered":"<p>(CNN) &#8212; Una creciente facci\u00f3n de dem\u00f3cratas de la C\u00e1mara de Representantes, convencidos de que el presidente Joe Biden est\u00e1 demasiado da\u00f1ado pol\u00edticamente para derrotar a Donald Trump en noviembre, est\u00e1 pidiendo al Comit\u00e9 Nacional Dem\u00f3crata que abandone los planes de elegir virtualmente como candidato presidencial dem\u00f3crata a Biden en las pr\u00f3ximas semanas, estableciendo un extraordinario enfrentamiento dentro del partido contra los aliados de Biden que est\u00e1n organizando una silenciosa campa\u00f1a de presi\u00f3n para acelerar la candidatura formal del presidente.<\/p>\n<p>Los dem\u00f3cratas llevan semanas planeando concluir el proceso de candidatura de Biden antes del 7 de agosto, mucho antes de la convenci\u00f3n de Chicago del mes que viene. Pero el representante Jared Huffman, un dem\u00f3crata progresista de California, dijo este martes a CNN que hay un &#171;creciente n\u00famero de miembros&#187; preocupados por la votaci\u00f3n nominal virtual, calific\u00e1ndola de &#171;idea terrible&#187; y &#171;tonter\u00eda&#187;.<\/p>\n<p>&#171;Si las elecciones se celebraran hoy, lo aplastar\u00edan&#187;, dijo Huffman refiri\u00e9ndose a Biden. &#171;Tenemos que hacer algo al respecto&#187;.<\/p>\n<p>CNN tambi\u00e9n ha tenido conocimiento, a trav\u00e9s de m\u00faltiples fuentes, de un borrador de carta que circula entre los dem\u00f3cratas de la C\u00e1mara de Representantes en la que se le pide al partido que frene el proceso, una clara se\u00f1al de la profunda preocupaci\u00f3n del partido por la permanencia de Biden al frente de su candidatura.<\/p>\n<p>\u00bfC\u00f3mo reemplazar\u00edan los dem\u00f3cratas a Biden? 2:35<\/p>\n<p>La expresi\u00f3n p\u00fablica y privada de las preocupaciones se produce en medio de una presi\u00f3n entre algunos aliados de Biden para poner en marcha el proceso de votaci\u00f3n virtual de Biden lo antes posible, seg\u00fan seis funcionarios dem\u00f3cratas familiarizados con las discusiones. Dos importantes comit\u00e9s dem\u00f3cratas tienen previsto reunirse este viernes y domingo pr\u00f3ximos para discutir el calendario exacto para que los delegados de todo el pa\u00eds empiecen a emitir sus votos. Lo m\u00e1s pronto que podr\u00eda comenzar la votaci\u00f3n ser\u00eda despu\u00e9s de la segunda reuni\u00f3n de este domingo.<\/p>\n<p>Si la votaci\u00f3n comenzara este domingo o poco despu\u00e9s, se tratar\u00eda de un calendario agresivo, y la idea ya est\u00e1 suscitando un nuevo escrutinio por parte de otros dem\u00f3cratas deseosos de que Biden reconozca sus desaf\u00edos y se haga a un lado.<\/p>\n<p>&#171;La incredulidad de que aceleren la candidatura es tan generalizada como el reconocimiento de que el DNC est\u00e1 llevando a los dem\u00f3cratas a un incendio con botellas de agua&#187;, dijo un dem\u00f3crata de la C\u00e1mara de Representantes.<\/p>\n<p>Los dem\u00f3cratas analizan c\u00f3mo continuar la campa\u00f1a y salvar la candidatura de Biden tras el intento de magnicidio contra Trump<\/p>\n<p>El proceso de votaci\u00f3n virtual del DNC se puso en marcha inicialmente para que el partido evitara un problema en Ohio que amenazaba con dejar a Biden fuera de la votaci\u00f3n en ese estado. Desde entonces, los legisladores de Ohio han aprobado una ley que anula ese problema, pero el DNC ha se\u00f1alado la posibilidad de que los republicanos de Ohio presenten un recurso legal para seguir adelante con la votaci\u00f3n virtual.<\/p>\n<p>Para los dem\u00f3cratas que temen que Biden pierda ante Trump y se lleve por delante la candidatura dem\u00f3crata, el tiempo se acaba para defender su postura ante el presidente, su familia y un c\u00edrculo de asesores extraordinariamente estrecho. Pero incluso mientras esas s\u00faplicas se hacen a diario entre bastidores, se est\u00e1n haciendo planes para consolidar su posici\u00f3n con la ayuda de las reglas del partido en el proceso de la convenci\u00f3n dem\u00f3crata.<\/p>\n<p>El presidente del Comit\u00e9 Nacional Dem\u00f3crata, Jaime Harrison, rechaz\u00f3 cualquier sugerencia de que se est\u00e9 intentando acelerar la votaci\u00f3n virtual.<\/p>\n<p>Analista de CNN dice que \u201chay p\u00e1nico\u201d entre los dem\u00f3cratas 1:27<\/p>\n<p>&#171;El calendario para el proceso de votaci\u00f3n virtual sigue seg\u00fan lo previsto y sin cambios desde que el DNC tom\u00f3 esa decisi\u00f3n en mayo&#187;, dijo Harrison en un comunicado, pero no dio detalles sobre cu\u00e1ndo espera que comience la votaci\u00f3n.<\/p>\n<p>CNN tambi\u00e9n se ha puesto en contacto con la campa\u00f1a de Biden.<\/p>\n<p>Pelea dentro del partido<\/p>\n<p>Las acaloradas discusiones han abierto una colisi\u00f3n potencialmente turbia e indecorosa entre distintos sectores del Partido Dem\u00f3crata, que se est\u00e1 produciendo incluso cuando los republicanos est\u00e1n reuni\u00e9ndose en torno a su nueva candidatura esta semana en la convenci\u00f3n nacional del Partido Republicano en Milwaukee.<\/p>\n<p>Aunque todav\u00eda no se ha fijado un calendario formal, cualquier indicio de que los l\u00edderes del partido est\u00e1n pisando el acelerador para impulsar la candidatura de Biden de la forma m\u00e1s r\u00e1pida posible generar\u00e1 seguramente m\u00e1s enfado \u2014y una posible rebeli\u00f3n\u2014, dadas las graves preocupaciones existentes en el partido sobre si Biden debe seguir encabezando la candidatura dem\u00f3crata.<\/p>\n<p>Entre los partidarios del partido de celebrar una votaci\u00f3n anticipada, contin\u00faa el intenso debate sobre lo que permiten las normas y c\u00f3mo debe proceder el partido: si se debe dar m\u00e1s tiempo a los legisladores, donantes y sustitutos prominentes para unirse en torno a su candidato, o si el partido debe seguir adelante con una candidatura anticipada para evitar &#171;un sh*tshow en agosto&#187;, seg\u00fan una fuente implicada.<\/p>\n<p>Contin\u00faan los esfuerzos privados para empujar a Biden a retirarse de la carrera presidencial<\/p>\n<p>En medio del creciente revuelo, tres antiguos dirigentes del Comit\u00e9 Nacional Dem\u00f3crata han respaldado el proceso, calific\u00e1ndolo de &#171;lo m\u00e1s sensato&#187;.<\/p>\n<p>La carta, enviada este martes a los miembros del Comit\u00e9 de Reglas del DNC y redactada por los expresidentes del DNC Donna Brazile, Howard Dean y Terry McAuliffe y obtenida por CNN, dice: &#171;Creemos que un proceso virtual \u2013antes de que comience la Convenci\u00f3n en persona en Chicago el 19 de agosto de 2024\u2013 es necesario para garantizar que los candidatos dem\u00f3cratas a presidente y vicepresidente aparezcan en las papeletas en todos los estados y en el distrito de Columbia sin base para impugnaciones legales&#187;.<\/p>\n<p>Los tres expresidentes contin\u00faan diciendo que &#171;un enfoque diferente corre el riesgo de privar del derecho de voto a millones de votantes y enturbiar el camino dem\u00f3crata hacia la victoria&#187;.<\/p>\n<p>En particular, Brazile, Dean y McAuliffe dijeron que la votaci\u00f3n virtual &#171;no tiene por qu\u00e9 ser inmediata&#187;, sino que debe terminar antes del 7 de agosto para no encontrarse con posibles problemas legales relacionados con la capacidad de Biden para entrar en la papeleta electoral en Ohio.<\/p>\n<p>AN\u00c1LISIS | Trump es el favorito, pero Biden a\u00fan puede ganar estas elecciones<\/p>\n<p>El lunes, en una entrevista con Lester Holt, de NBC, a la pregunta de si se sent\u00eda capaz de capear el temporal pol\u00edtico tras su desastrosa actuaci\u00f3n en el debate del mes pasado, Biden se\u00f1al\u00f3 a los votantes de las primarias que le apoyaron.<\/p>\n<p>&#171;Catorce millones de personas votaron por m\u00ed para que fuera el candidato del Partido Dem\u00f3crata. \u00bfLes escucho? Les escucho&#187;, dijo.<\/p>\n<p>Las preguntas sobre si Biden deber\u00eda seguir aspirando a un segundo mandato, que empezaron a intensificarse tras el debate del 27 de junio en CNN, han arrojado una luz brillante sobre el proceso de votaci\u00f3n nominal virtual, un proceso que antes del mes pasado hab\u00eda atra\u00eddo relativamente poca atenci\u00f3n. Ahora, con el futuro pol\u00edtico de Biden en el aire, existe confusi\u00f3n y preocupaci\u00f3n entre algunos delegados sobre la ley de Ohio que impuls\u00f3 al DNC a seguir adelante con la votaci\u00f3n nominal antes de la convenci\u00f3n de Chicago.<\/p>\n<p>Biden llama a la unidad y dice que se har\u00e1 una investigaci\u00f3n independiente sobre el ataque contra Trump en Pensilvania 2:23<\/p>\n<p>A ra\u00edz de la titubeante actuaci\u00f3n de Biden en el debate, algunos dem\u00f3cratas discutieron la posibilidad de retrasar o cancelar la reuni\u00f3n del 21 de julio para permitir que la agitaci\u00f3n siguiera su curso.<\/p>\n<p>Pero el hecho de que el DNC siga adelante con el plan original a la vista de los \u00faltimos acontecimientos ha despertado la frustraci\u00f3n en todo el Partido Dem\u00f3crata, desde los legisladores que quieren que Biden reconsidere su candidatura hasta los delegados que quieren emitir su voto en persona, seg\u00fan tres fuentes conocedoras de la situaci\u00f3n.<\/p>\n<p>Mientras tanto, algunos dem\u00f3cratas influyentes con estrechos v\u00ednculos con la Casa Blanca han fijado p\u00fablicamente el inicio oficial de la convenci\u00f3n nacional del partido a mediados de agosto como fecha l\u00edmite para que Biden decida si sigue adelante con su candidatura.<\/p>\n<p>&#171;Si decide cambiar de opini\u00f3n m\u00e1s adelante, entonces responder\u00edamos a eso&#187;, dijo el representante James Clyburn, dem\u00f3crata de Carolina del Sur, en una entrevista televisiva la semana pasada. &#171;Tenemos hasta el 19 de agosto para abrir nuestra convenci\u00f3n&#187;.<\/p>\n<p>Algunos dem\u00f3cratas de la C\u00e1mara de Representantes quieren ralentizar el proceso<\/p>\n<p>Un borrador de carta que circula entre los miembros dem\u00f3cratas de la C\u00e1mara de Representantes y otros delegados est\u00e1 pidiendo al partido que ralentice el proceso, seg\u00fan dijeron m\u00faltiples fuentes a CNN.<\/p>\n<p>&#171;No hay justificaci\u00f3n legal para esta acci\u00f3n extraordinaria y sin precedentes que acelerar\u00eda el proceso de nominaci\u00f3n en casi un mes&#187;, dice la carta.<\/p>\n<p>Entre bastidores, los dem\u00f3cratas que apoyan una conclusi\u00f3n anticipada han dejado flotar la posibilidad de que el senador J.D. Vance, ahora oficialmente compa\u00f1ero de f\u00f3rmula de Trump y n\u00famero dos efectivo de los republicanos, pueda presionar para que se presenten nuevas impugnaciones al acceso de Biden a las urnas en su estado natal, una noci\u00f3n que los funcionarios estatales niegan rotundamente.<\/p>\n<p>AN\u00c1LISIS | As\u00ed es como se podr\u00eda reemplazar a Biden, seg\u00fan las normas de los dem\u00f3cratas<\/p>\n<p>&#171;La cuesti\u00f3n est\u00e1 resuelta en Ohio, y los apoderados dem\u00f3cratas lo saben y deber\u00edan dejar de intentar convertir a Ohio en el chivo expiatorio del mal funcionamiento de su propio partido&#187;, explica a CNN Ben Kindel, secretario de prensa del secretario de Estado de Ohio, Frank LaRose.<\/p>\n<p>La carta redactada por Huffman \u2014que confirm\u00f3 su autenticidad y dijo que no estaba claro cu\u00e1ndo pensaban enviarla\u2014 coincide en que el asunto est\u00e1 resuelto.<\/p>\n<p>&#171;En este momento no hay ninguna amenaza seria para que la candidatura dem\u00f3crata nominada en orden regular en la convenci\u00f3n del DNC del mes que viene aparezca en las papeletas de Ohio o de cualquier otro estado&#187;, dice la carta.<\/p>\n<p>Aunque es probable que el borrador cambie, expone las preocupaciones del partido sobre seguir adelante con el proceso de candidatura mientras se debate el futuro de Biden.<\/p>\n<p>El presidente Joe Biden llega a la cumbre de la OTAN en Washington el 10 de julio de 2024. (Cr\u00e9dito: Jacquelyn Martin\/AP)<\/p>\n<p>&#171;El Partido Dem\u00f3crata \u2014no s\u00f3lo los funcionarios electos y los delegados, sino tambi\u00e9n millones de votantes de base\u2014 est\u00e1 actualmente inmerso en una cuidadosa consideraci\u00f3n y debate sobre el imperativo absoluto de derrotar a Donald Trump y ganar el control del Congreso&#187;, dice la carta. &#171;Como miembros dem\u00f3cratas del Congreso, representamos el espectro de opiniones sobre esta cuesti\u00f3n. Algunos de nosotros hemos pedido al presidente Biden que se haga a un lado, otros le han instado a permanecer en la carrera, y otros tienen profundas preocupaciones sobre el estado de la campa\u00f1a del presidente, pero a\u00fan no han tomado una posici\u00f3n sobre lo que deber\u00eda suceder&#187;.<\/p>\n<p>&#171;Todos, sin embargo, estamos de acuerdo en que sofocar el debate y cerrar prematuramente cualquier posible cambio en la candidatura dem\u00f3crata mediante un &#8216;pase de lista virtual&#8217; innecesario y sin precedentes en los pr\u00f3ximos d\u00edas es una idea terrible. Podr\u00eda minar profundamente la moral y la unidad de los dem\u00f3cratas \u2013desde delegados, voluntarios, organizadores de base y donantes hasta votantes de a pie\u2013 en el peor momento posible&#187;.<\/p>\n<p>Estamos escuchando la negaci\u00f3n<\/p>\n<p>En una entrevista telef\u00f3nica este martes, Huffman dijo que los miembros &#171;cubren todo el espectro de nuestro caucus&#187; y que habr\u00eda una reacci\u00f3n &#171;bastante grande&#187; si el DNC sigue adelante con los planes.<\/p>\n<p>Huffman se\u00f1al\u00f3 que hay una &#171;gran diferencia de entusiasmo&#187; entre Trump y Biden: &#171;No se consigue energ\u00eda y entusiasmo por la fuerza bruta&#187;, refiri\u00e9ndose a adelantar la votaci\u00f3n nominal para nominar oficialmente a Biden.<\/p>\n<p>Huffman dijo que todav\u00eda no est\u00e1 pidiendo que Biden sea sustituido, sino que quiere dar m\u00e1s tiempo al presidente para infundir confianza a los dem\u00f3cratas en su campa\u00f1a. Ser\u00eda mucho m\u00e1s dif\u00edcil reemplazar a Biden una vez que sea formalmente el candidato.<\/p>\n<p>&#171;Estamos oyendo una negaci\u00f3n y un intento de cerrar el debate&#187;, dijo Huffman.<\/p>\n<p>En una reciente rueda de prensa, se pregunt\u00f3 a Biden si los delegados del partido tendr\u00edan libertad para votar a un candidato alternativo en la convenci\u00f3n nacional si as\u00ed lo deseaban.<\/p>\n<p>&#171;Ese es el proceso democr\u00e1tico&#187;, dijo Biden sobre la capacidad de los delegados para cambiar de opini\u00f3n, antes de a\u00f1adir con seguridad: &#171;No va a ocurrir&#187;.<\/p>\n<p>&#8212; Haley Talbot y Lauren Fox de CNN han contribuido a este reportaje.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Una creciente facci\u00f3n de dem\u00f3cratas de la C\u00e1mara de Representantes, convencidos de que el presidente Joe Biden est\u00e1 demasiado da\u00f1ado pol\u00edticamente para derrotar a Donald Trump en noviembre, est\u00e1 pidiendo al Comit\u00e9 Nacional Dem\u00f3crata que abandone los planes de elegir virtualmente como candidato presidencial dem\u00f3crata a Biden en las pr\u00f3ximas semanas, estableciendo un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451185","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Una creciente facci\u00f3n de dem\u00f3cratas de la C\u00e1mara de Representantes, convencidos de que el presidente Joe Biden est\u00e1 demasiado da\u00f1ado pol\u00edticamente para derrotar a Donald Trump en noviembre, est\u00e1 pidiendo al Comit\u00e9 Nacional Dem\u00f3crata que abandone los planes de elegir virtualmente como candidato presidencial dem\u00f3crata a Biden en las pr\u00f3ximas semanas, estableciendo un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-17T06:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden\",\"datePublished\":\"2024-07-17T06:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/\"},\"wordCount\":2268,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/\",\"name\":\"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-17T06:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden - Noticias","og_description":"(CNN) &#8212; Una creciente facci\u00f3n de dem\u00f3cratas de la C\u00e1mara de Representantes, convencidos de que el presidente Joe Biden est\u00e1 demasiado da\u00f1ado pol\u00edticamente para derrotar a Donald Trump en noviembre, est\u00e1 pidiendo al Comit\u00e9 Nacional Dem\u00f3crata que abandone los planes de elegir virtualmente como candidato presidencial dem\u00f3crata a Biden en las pr\u00f3ximas semanas, estableciendo un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-17T06:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/"},"author":{"name":"","@id":""},"headline":"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden","datePublished":"2024-07-17T06:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/"},"wordCount":2268,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/","name":"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-17T06:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una creciente facci\u00f3n de dem\u00f3cratas se rebela contra la virtual pr\u00f3xima candidatura de Biden","url":"http:\/\/noticiasya.com\/lubbock\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2024\/07\/16\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-17T06:03:51Z","datePublished":"2024-07-17T06:03:51Z","dateModified":"2024-07-17T06:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una creciente facci\\u00f3n de dem\\u00f3cratas se rebela contra la virtual pr\\u00f3xima candidatura de Biden\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2024\\\/07\\\/16\\\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2024\\\/07\\\/16\\\/joe-biden-democratas-contra-nominacion-democrata-elecciones-2024-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-17T06:03:51Z\",\"datePublished\":\"2024-07-17T06:03:51Z\",\"dateModified\":\"2024-07-17T06:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451248,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/18\/escrutinio-salud-edad-biden-futuro-politico-trax\/","url_meta":{"origin":1451185,"position":0},"title":"Aumenta el escrutinio sobre la salud y la edad de Biden en medio de interrogantes sobre su futuro pol\u00edtico","author":"","date":"julio 18, 2024","format":false,"excerpt":"Washington (CNN) -- Mientras el presidente Joe Biden se a\u00edsla en su casa de playa de Delaware despu\u00e9s de dar positivo por covid-19, est\u00e1 cada vez m\u00e1s aislado de muchos sectores de su Partido Dem\u00f3crata mientras se enfrenta a profundas preguntas sobre si debe continuar su campa\u00f1a de reelecci\u00f3n.El anuncio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446546,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/03\/05\/quien-es-jason-palmer-democrata-biden-primera-derrota-primarias-trax\/","url_meta":{"origin":1451185,"position":1},"title":"\u00bfQui\u00e9n es Jason Palmer, el dem\u00f3crata que le propin\u00f3 a Biden su primera derrota en las primarias?","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN) -- El presidente Joe Biden sufri\u00f3 su primera derrota hasta ahora en las primarias presidenciales dem\u00f3cratas a manos de un hombre que muy pocos conoc\u00edan antes de este martes por la noche: el capitalista de riesgo Jason Palmer.CNN proyect\u00f3 este martes por la noche que el candidato poco conocido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451300,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/21\/por-que-biden-se-retiro-como-candidato-orix\/","url_meta":{"origin":1451185,"position":2},"title":"\u00bfPor qu\u00e9 Biden se retir\u00f3 como candidato dem\u00f3crata? Los momentos que dinamitaron su candidatura","author":"","date":"julio 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El retiro de Joe Biden de la campa\u00f1a presidencial se produjo despu\u00e9s semanas de preocupaci\u00f3n sobre la resistencia f\u00edsica y las capacidades mentales del presidente de 81 a\u00f1os y de escepticismo sobre su habilidad para hacer campa\u00f1a eficazmente contra el expresidente Donald Trump, as\u00ed como las inquietudes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451031,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/11\/analisis-posicion-politica-biden-conferencia-prensa-critica-trax\/","url_meta":{"origin":1451185,"position":3},"title":"AN\u00c1LISIS | La posici\u00f3n pol\u00edtica de Biden se deteriora r\u00e1pidamente ante la inminencia de una conferencia de prensa cr\u00edtica","author":"","date":"julio 11, 2024","format":false,"excerpt":"(CNN) -- Las asombrosas 24 horas que han agrietado los cimientos pol\u00edticos de la candidatura de Joe Biden a la reelecci\u00f3n lo enfrentan este jueves a la conferencia de prensa presidencial de mayor presi\u00f3n de la historia moderna.Lo que estaba en juego en la comparecencia en solitario de Biden al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450883,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/04\/trump-planea-futuro-incierto-biden-trax\/","url_meta":{"origin":1451185,"position":4},"title":"&#171;El caos es nuestro amigo&#187;: c\u00f3mo Trump planea en silencio en torno al futuro incierto de Biden","author":"","date":"julio 4, 2024","format":false,"excerpt":"(CNN) -- Durante gran parte del a\u00f1o pasado, Donald Trump y sus aliados han especulado que Joe Biden no terminar\u00eda como el candidato presidencial dem\u00f3crata, sugiriendo sin pruebas que renunciar\u00eda antes de la convenci\u00f3n y ser\u00eda reemplazado por otro candidato.Ahora, con Biden enfrent\u00e1ndose a un futuro pol\u00edtico cada vez m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451018,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/10\/legisladores-democratas-preocupacion-joe-biden-candidato-trax\/","url_meta":{"origin":1451185,"position":5},"title":"Legisladores dem\u00f3cratas mantienen su preocupaci\u00f3n sobre la posici\u00f3n de Joe Biden como candidato presidencial del partido","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN) -- Los legisladores dem\u00f3cratas siguen cuestionando la candidatura presidencial del presidente Joe Biden dos d\u00edas despu\u00e9s de que \u00e9ste afirmara su \"firme compromiso\" de seguir en la carrera en una carta destinada a consolidar su apoyo, y muchos sugieren amablemente que podr\u00eda cambiar de opini\u00f3n si las encuestas siguen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1451185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1451185"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1451185\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1451185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1451185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1451185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}