{"id":1457685,"date":"2025-01-21T02:03:42","date_gmt":"2025-01-21T10:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/"},"modified":"2025-01-21T02:03:42","modified_gmt":"2025-01-21T10:03:42","slug":"trump-firma-decretos-transformar-gobierno-federal-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/","title":{"rendered":"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal"},"content":{"rendered":"<p>El presidente Donald Trump dio este lunes los primeros pasos para implementar su amplia agenda con una serie de drecretos que se espera que inicien su prometida transformaci\u00f3n del gobierno federal.<\/p>\n<p>El primer d\u00eda de su segundo mandato, Trump se tom\u00f3 un momento durante su primer mitin posterior a su toma de posesi\u00f3n para firmar varias acciones que retiran a Estados Unidos del acuerdo clim\u00e1tico de Par\u00eds, congelan las contrataciones en el gobierno federal y requieren que los trabajadores federales regresen a la oficina.<\/p>\n<p>Y en el Despacho Oval, horas despu\u00e9s, Trump firm\u00f3 acciones que indultaron a los acusados \u200b\u200bde delitos relacionados con el <a href=\"https:\/\/www.cnn.com\/2025\/01\/20\/politics\/january-6-2021-capitol-riot-pardons-trump\/index.html\">ataque al Capitolio del 6 de enero de 2021<\/a>, retras\u00f3 la prohibici\u00f3n de TikTok y trabaj\u00f3 para renovar el sistema de inmigraci\u00f3n estadounidense.<\/p>\n<p>\u201cCon estas acciones, iniciaremos la restauraci\u00f3n completa de Estados Unidos y la revoluci\u00f3n del sentido com\u00fan\u201d, dijo Trump durante su discurso inaugural tras ser juramentado como el 47\u00ba presidente del pa\u00eds. Agreg\u00f3: \u201cLa edad de oro de Estados Unidos comienza ahora mismo\u201d.<\/p>\n<p>Las medidas son la culminaci\u00f3n de m\u00faltiples promesas que Trump hizo en su exitosa campa\u00f1a para 2024 y otras iniciativas que se plantearon durante su primer mandato pero que finalmente no se materializaron. No todas tienen un camino claro hacia su realizaci\u00f3n y es probable que algunas de las medidas m\u00e1s importantes sean impugnadas en los tribunales.<\/p>\n<p>Estas son algunas de las acciones que Trump tom\u00f3 en su primer d\u00eda en el cargo:<\/p>\n<p>Uno de los primeros actos que anunci\u00f3 Trump durante su segundo mandato fue el indulto para la mayor\u00eda de los acusados \u200b\u200bpor el ataque del 6 de enero de 2021 al Capitolio de Estados Unidos.<\/p>\n<p>Este lunes, en la Oficina Oval<em>,<\/em> Trump dijo que sus indultos cubrir\u00edan \u201caproximadamente 1.500 para un indulto, un indulto completo\u201d.<\/p>\n<p>Los fiscales acusaron a m\u00e1s de 1.580 personas por presuntas acciones relacionadas con el 6 de enero y lograron aproximadamente 1.270 condenas. Eso significa que Trump dijo que casi todos los que han sido acusados \u200b\u200bde un delito relacionado con el ataque ser\u00e1n indultados, lo que esencialmente pone fin a todos los casos del 6 de enero.<\/p>\n<p>Catorce personas, incluidos l\u00edderes de alto perfil de los Proud Boys y Oath Keepers que fueron condenados por su papel en el ataque, vieron sus sentencias conmutadas por tiempo cumplido.<\/p>\n<p>El drecreto de Trump fue el cumplimiento de una promesa que hizo en repetidas ocasiones durante la campa\u00f1a electoral y apenas unas horas antes de firmar los indultos totales. Pero Trump nunca dio una pista sobre la extraordinaria escala de los indultos que estaba imaginando.<\/p>\n<p>Hablando en el Capital One Arena eSTE lunes por la noche, Trump dijo que firmar\u00eda indultos para los \u201crehenes del J6 (6 de enero)\u201d.<\/p>\n<p>\u201cEsta noche voy a firmar los indultos de los rehenes del J6 (6 de enero), y tan pronto como me vaya, ir\u00e9 al Despacho Oval y firmaremos indultos para mucha gente\u201d, dijo Trump en el mitin posterior a la inauguraci\u00f3n.<\/p>\n<p>Trump hizo ese comentario mientras estaba frente a un gran grupo de familiares de israel\u00edes que fueron tomados como rehenes por Hamas durante el ataque del grupo militante a Israel el 7 de octubre de 2023.<\/p>\n<p>Como lo prometi\u00f3 el d\u00eda antes de retomar el cargo, Trump firm\u00f3 este lunes un drecreto que extendi\u00f3 el plazo para que la empresa matriz de TikTok encuentre un nuevo propietario o enfrente una prohibici\u00f3n en Estados Unidos.<\/p>\n<p>La medida ordena al Departamento de Justicia de Estados Unidos no aplicar la Ley de Aplicaciones Controladas por Adversarios Extranjeros, que se aprob\u00f3 con un amplio apoyo bipartidista en el Congreso y fue firmada en abril por el expresidente Joe Biden. Esa ley exig\u00eda que TikTok fuera prohibido en Estados Unidos antes del 19 de enero a menos que vendiera a un comprador de Estados Unidos o de uno de sus aliados.<\/p>\n<p>Justo antes de esa fecha l\u00edmite, TikTok dej\u00f3 de funcionar brevemente para sus 170 millones de usuarios estadounidenses, pero luego volvi\u00f3 a estar disponible despu\u00e9s de que Trump prometiera el domingo por la ma\u00f1ana encontrar una manera de reactivarla.<\/p>\n<p>Pero el destino final de TikTok en Estados Unidos sigue siendo incierto. No est\u00e1 claro si el propietario de TikTok con sede en China, ByteDance, querr\u00eda vender a un comprador, incluso si se tratara de un acuerdo negociado por Trump.<\/p>\n<p>La acci\u00f3n de Trump extiende el plazo de TikTok por 75 d\u00edas.<\/p>\n<p>Trump <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/01\/initial-rescissions-of-harmful-executive-orders-and-actions\/\">anul\u00f3 78 drecretos de la era Biden<\/a>, muchas de las cuales Joe Biden firm\u00f3 el primer d\u00eda de su administraci\u00f3n.<\/p>\n<p>Las pol\u00edticas revocadas incluyen: un decreto que requer\u00eda que las agencias federales extendieran las prohibiciones sobre discriminaci\u00f3n sexual para incluir la orientaci\u00f3n sexual y la identidad de g\u00e9nero; un decreto que requer\u00eda que los designados por el poder ejecutivo firmaran un compromiso \u00e9tico; otro decreto que permit\u00eda a las personas transg\u00e9nero servir en las Fuerzas Armada de EE.UU.; y una orden que prohib\u00eda la renovaci\u00f3n de los contratos de prisiones privadas.<\/p>\n<p>Otros decretos de la era Biden revocadas por Trump este lunes incluyeron acciones que retiraron la designaci\u00f3n de Cuba como estado patrocinador del terrorismo, aplicaron sanciones a los colonos jud\u00edos en la Ribera Occidental y buscaron reducir los riesgos de la inteligencia artificial.<\/p>\n<p>Biden elimin\u00f3 recientemente a Cuba de la lista de pa\u00edses terroristas. La lista de decretos revocados que Trump firm\u00f3 este lunes no especificaba los motivos individuales para revertir las medidas de Biden.<\/p>\n<p>Biden aplic\u00f3 las sanciones a ciertos colonos jud\u00edos acusados \u200b\u200bde fomentar la violencia en la Ribera Occidental en febrero de 2024.<\/p>\n<p>Y su orden sobre inteligencia artificial de 2023 ten\u00eda como objetivo monitorear y regular los riesgos de la inteligencia artificial.<\/p>\n<p>Gran parte de la agenda del primer d\u00eda de Trump se centr\u00f3 en la inmigraci\u00f3n, un tema que desde hace tiempo ha sido central para su identidad pol\u00edtica.<\/p>\n<p>Durante su discurso inaugural, Trump anunci\u00f3 que iba a declarar una emergencia nacional en la frontera sur. Trump firm\u00f3 esa orden en el Despacho Oval este lunes por la noche, lo que activ\u00f3 el uso de recursos y personal del Pent\u00e1gono que se desplegar\u00e1n y utilizar\u00e1n para construir el muro fronterizo.<\/p>\n<p>En sus primeros minutos, la administraci\u00f3n Trump puso fin al uso de una aplicaci\u00f3n que permite a los migrantes notificar a la Oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos que tienen la intenci\u00f3n de ingresar a Estados Unidos y les permite programar citas para solicitar asilo ante las autoridades fronterizas.<\/p>\n<p>Trump tambi\u00e9n firm\u00f3 un decreto que buscaba redefinir la ciudadan\u00eda por derecho de nacimiento, el proceso mediante el cual a todas las personas nacidas en Estados Unidos se les otorga autom\u00e1ticamente la ciudadan\u00eda estadounidense.<\/p>\n<p>Un decreto de Trump proh\u00edbe a las agencias federales emitir ciertos documentos que normalmente se proporcionar\u00edan a un ciudadano estadounidense, seg\u00fan una hoja informativa obtenida por CNN.<\/p>\n<p>Un decreto, que se aplica a los ni\u00f1os nacidos despu\u00e9s de 30 d\u00edas de la medida, se aplica en circunstancias en las que los padres est\u00e1n presentes ilegalmente en EE.UU. y en situaciones en las que la madre est\u00e1 temporalmente en el pa\u00eds, como con una visa, y el padre es un no ciudadano.<\/p>\n<p>Este decreto se basa en la frase \u201csujeto a su jurisdicci\u00f3n\u201d de la Enmienda 14. Algunos partidarios de la l\u00ednea dura en materia de inmigraci\u00f3n argumentaron que los hijos de inmigrantes indocumentados no est\u00e1n \u201csujetos a la jurisdicci\u00f3n\u201d de Estados Unidos y no deber\u00edan ser considerados <a href=\"https:\/\/www.cnn.com\/2018\/10\/31\/us\/14th-amendment-birthright-citizenship-explainer-trnd\/index.html\">ciudadanos seg\u00fan la Constituci\u00f3n.<\/a><\/p>\n<p>Expertos legales dijeron previamente a CNN que eran esc\u00e9pticos de que tal argumento fuera aceptado en el tribunal, argumentando que el lenguaje relevante estaba dirigido a los hijos de diplom\u00e1ticos extranjeros que estaban sujetos a las leyes estadounidenses y a situaciones en las que una naci\u00f3n extranjera ha invadido y est\u00e1 ocupando parte del pa\u00eds. Los aliados y funcionarios de Trump son muy conscientes de que la medida probablemente enfrentar\u00e1 apelaciones legales y eventualmente llegar\u00e1 a la Corte Suprema.<\/p>\n<p>Trump tambi\u00e9n firm\u00f3 una ley que declara a dos importantes c\u00e1rteles de la droga como organizaciones terroristas, una ley que <a href=\"https:\/\/www.cnn.com\/2025\/01\/08\/politics\/donald-trump-mexican-cartels\/index.html\">podr\u00eda preceder<\/a> al uso de la fuerza militar estadounidense en suelo mexicano.<\/p>\n<p>Las medidas iniciales de Trump en materia de inmigraci\u00f3n se producen en un momento en que los cruces fronterizos han ido disminuyendo de manera constante, desplom\u00e1ndose el a\u00f1o pasado despu\u00e9s de que Biden firmara decretos para restringir las solicitudes de asilo.<\/p>\n<p>Trump comienza su segundo mandato heredando una frontera en la que hay menos cruces que cuando dej\u00f3 el cargo.<\/p>\n<p>Trump anunci\u00f3 este lunes que retirar\u00e1 a Estados Unidos de la Organizaci\u00f3n Mundial de la Salud, una medida significativa que corta lazos con la agencia de salud p\u00fablica de la ONU.<\/p>\n<p>Trump critic\u00f3 a la OMS durante mucho tiempo y su administraci\u00f3n anunci\u00f3 en julio de 2020 que se retirar\u00eda de la organizaci\u00f3n a medida que la pandemia de covid-19 segu\u00eda propag\u00e1ndose. Biden finalmente detuvo esa medida con <a href=\"https:\/\/www.cnn.com\/interactive\/2021\/politics\/biden-executive-orders\/\">su propi<\/a>o decreto.<\/p>\n<p>El decreto cita \u201cel mal manejo por parte de la organizaci\u00f3n de la pandemia de covid-19 que surgi\u00f3 de Wuhan, China, y otras crisis de salud globales, su fracaso en adoptar reformas urgentemente necesarias y su incapacidad para demostrar independencia de la influencia pol\u00edtica inapropiada de los estados miembros de la OMS\u201d, como razones para la retirada de Estados Unidos.<\/p>\n<p>\u201cEs un asunto muy importante\u201d, le dijo Trump a un asistente mientras comenzaba a firmar el decreto, se\u00f1alando su decisi\u00f3n de 2020 y su creencia de que Estados Unidos estaba pagando demasiado dinero a la organizaci\u00f3n en comparaci\u00f3n con otros pa\u00edses.<\/p>\n<p>El decreto tambi\u00e9n dice que la OMS \u201csigue exigiendo pagos injustamente onerosos\u201d a Estados Unidos.<\/p>\n<p>CNN se puso en contacto con la OMS para solicitar comentarios.<\/p>\n<p>Trump firm\u00f3 un decreto que congela las contrataciones de empleados del gobierno federal a trav\u00e9s del Poder Ejecutivo.<\/p>\n<p>\u201cComo parte de esta congelaci\u00f3n, no se podr\u00e1 cubrir ning\u00fan puesto civil federal que est\u00e9 vacante al mediod\u00eda del 20 de enero de 2025, y no se podr\u00e1 crear ning\u00fan puesto nuevo, salvo que se disponga lo contrario en este memorando o en otra ley aplicable\u201d, se lee en un memorando de la Casa Blanca. La medida exime a los puestos en las Fuerzar Armadas y \u201crelacionados con la aplicaci\u00f3n de la ley de inmigraci\u00f3n, la seguridad nacional o la seguridad p\u00fablica\u201d.<\/p>\n<p>La acci\u00f3n ordena al director de la Oficina de Administraci\u00f3n y Presupuesto, en consulta con el nuevo Departamento de Eficiencia Gubernamental de Trump, presentar un plan dentro de los 90 d\u00edas para reducir el tama\u00f1o de la fuerza laboral del gobierno federal \u201ca trav\u00e9s de mejoras de eficiencia y deserci\u00f3n\u201d.<\/p>\n<p>Otro decreto firmado por Trump este lunes requiere que todos los departamentos y agencias federales \u201ctomen todas las medidas necesarias para terminar los acuerdos de trabajo remoto y requieran que los empleados regresen a trabajar en persona en sus respectivos lugares de trabajo a tiempo completo, siempre que los jefes de departamento y agencia hagan las exenciones que consideren necesarias\u201d. Trump tambi\u00e9n firm\u00f3 un decreto destinado a <a href=\"https:\/\/www.cnn.com\/2025\/01\/20\/politics\/federal-employee-protections-trump-executive-order\/index.html\">darle m\u00e1s control sobre la fuerza laboral federal<\/a>.<\/p>\n<p>La nueva orden revive un decreto <a href=\"https:\/\/www.cnn.com\/2020\/10\/23\/politics\/trump-executive-order-federal-employees\/index.html\">que<\/a> Trump firm\u00f3 poco antes de las elecciones de 2020 para crear una categor\u00eda para los empleados federales involucrados en pol\u00edticas, conocida como Schedule F, que facilitar\u00eda el despido de esos trabajadores. Biden hab\u00eda revertido r\u00e1pidamente esa orden y luego, el a\u00f1o pasado, finaliz\u00f3 una <a href=\"https:\/\/www.cnn.com\/2024\/04\/04\/politics\/rule-protecting-federal-workers\/index.html\">nueva regla<\/a> que reforzaba a\u00fan m\u00e1s las protecciones para los trabajadores federales de carrera. Sin embargo, el \u00faltimo decreto de Trump ordena a la Oficina de Gesti\u00f3n de Personal que rescinda cualquier cambio realizado por la regla que impida o afecte la implementaci\u00f3n de la directiva de Trump de 2020.<\/p>\n<p>Al igual que el decreto de 2020, se espera que la nueva directiva de Trump termine r\u00e1pidamente en los tribunales. Tradicionalmente, deshacer o revisar un decreto requiere una nueva norma, un proceso que puede llevar meses y no puede hacerse mediante un decreto, dijeron los expertos.<\/p>\n<p>Trump tambi\u00e9n estableci\u00f3 formalmente el nuevo Departamento de Eficiencia Gubernamental como una entidad dentro del gobierno federal en un decreto.<\/p>\n<p>El decreto cambia temporalmente el nombre del Servicio Digital de Estados Unidos a Servicio DOGE de Estados Unidos durante 18 meses y ordena a la entidad que revise el software utilizado en las agencias federales como parte de una \u201cIniciativa de Modernizaci\u00f3n de Software\u201d con el fin de \u201cmaximizar la eficiencia y productividad gubernamentales\u201d. Sin embargo, el decreto no incluye referencias a recortar el presupuesto federal, la fuerza laboral o las regulaciones, que Trump promocion\u00f3 como las principales directivas de DOGE cuando <a href=\"https:\/\/www.cnn.com\/2024\/11\/12\/politics\/elon-musk-vivek-ramaswamy-department-of-government-efficiency-trump\/index.html\">anunci\u00f3 la iniciativa<\/a> en noviembre. Otras \u00f3rdenes ejecutivas a\u00fan podr\u00edan abordar esos objetivos.<\/p>\n<p>Seg\u00fan dos fuentes familiarizadas con los planes de DOGE, la incorporaci\u00f3n de DOGE a la rama ejecutiva es una novedad de los \u00faltimos d\u00edas. La medida plantea interrogantes sobre c\u00f3mo encajar\u00e1 en la estructura Elon Musk, que hab\u00eda sido elegido para dirigir DOGE y cuyas empresas tienen miles de millones de d\u00f3lares en contratos federales.<\/p>\n<p>Horas despu\u00e9s de asumir el cargo, Trump emiti\u00f3 dos decretos que ordenaban a su Departamento de Justicia y a la Oficina del Director de Inteligencia Nacional que abrieran amplias investigaciones sobre la \u201ccensura de la libertad de expresi\u00f3n\u201d o el \u201cuso como arma\u201d de las fuerzas del orden y las agencias de inteligencia por parte de la administraci\u00f3n Biden.<\/p>\n<p>En conjunto, los dos decretos reflejan la promesa reiterada de Trump durante su campa\u00f1a de perseguir lo que consideraba esfuerzos indebidos de la administraci\u00f3n Biden para perseguir criminalmente a sus aliados u otros conservadores. Pero el propio Trump prometi\u00f3 buscar venganza contra sus propios oponentes pol\u00edticos, y su elecci\u00f3n para algunos puestos importantes de la administraci\u00f3n indica que planea mantener esa prioridad.<\/p>\n<p>\u201cEl pueblo estadounidense fue testigo de c\u00f3mo la administraci\u00f3n anterior se ha involucrado en una campa\u00f1a sistem\u00e1tica contra sus percibidos oponentes pol\u00edticos, utilizando como arma la fuerza legal de numerosas agencias federales encargadas de hacer cumplir la ley y la comunidad de inteligencia contra esos percibidos oponentes pol\u00edticos en forma de investigaciones, procesamientos, acciones de cumplimiento civil y otras acciones relacionadas\u201d, se lee en uno de los decretos.<\/p>\n<p>El presidente tambi\u00e9n firm\u00f3 este lunes un decreto <a href=\"https:\/\/www.cnn.com\/2025\/01\/20\/politics\/trump-revokes-security-clearances-former-officials-hunter-biden-laptop-letter\/index.html\">revocando la autorizaci\u00f3n de seguridad<\/a> de 51 exfuncionarios de inteligencia que firmaron una carta de 2020 argumentando que los correos electr\u00f3nicos de una computadora port\u00e1til perteneciente a Hunter Biden ten\u00edan \u201ctodas las caracter\u00edsticas cl\u00e1sicas de una operaci\u00f3n de informaci\u00f3n rusa\u201d y la de su exasesor de Seguridad Nacional John Bolton.<\/p>\n<p>Muchos de los exfuncionarios est\u00e1n retirados desde hace mucho tiempo y ya no tienen autorizaciones activas, lo que significa que la medida puede tener un impacto pr\u00e1ctico limitado en sus carreras, pero la orden sugiere, no obstante, que Trump tiene la intenci\u00f3n de actuar sobre las amenazas que ha hecho de penalizar a los profesionales de inteligencia y seguridad nacional a quienes considera sus enemigos.<\/p>\n<p>En los cuatro a\u00f1os transcurridos desde que se escribi\u00f3 la carta, sus autores se han convertido en un blanco clave para los legisladores republicanos y los aliados de Trump. Bolton, por su parte, caus\u00f3 la ira de Trump por una autobiograf\u00eda sobre su \u00e9poca en el Consejo de Seguridad Nacional en la que criticaba profundamente al presidente.<\/p>\n<p>CNN se comunic\u00f3 con Bolton para solicitarle comentarios.<\/p>\n<p>Este lunes, Trump tom\u00f3 medidas sobre los nombres de lugares emblem\u00e1ticos de Estados Unidos, incluido el cambio de nombre de Denali y el golfo de M\u00e9xico, una medida que, seg\u00fan su Casa Blanca, \u201chonrar\u00e1 la grandeza estadounidense\u201d.<\/p>\n<p>\u201cEs de inter\u00e9s nacional promover el extraordinario patrimonio de nuestra naci\u00f3n y garantizar que las futuras generaciones de ciudadanos estadounidenses celebren el legado de nuestros h\u00e9roes estadounidenses\u201d, dice el decreto.<\/p>\n<p>El drecreto exige espec\u00edficamente el cambio de nombre del pico m\u00e1s alto del pa\u00eds, el Denali de Alaska, que el entonces presidente Barack Obama <a href=\"https:\/\/www.cnn.com\/2015\/08\/30\/politics\/obama-alaska-denali-climate-change\/index.html\">rebautiz\u00f3<\/a> en 2015 como monte McKinley en homenaje a la poblaci\u00f3n nativa de la regi\u00f3n.<\/p>\n<p>El decreto califica la decisi\u00f3n de Obama como \u201cuna afrenta a la vida del presidente McKinley, a sus logros y a su sacrificio\u201d. Estableciendo paralelismos con Trump, el decreto se\u00f1ala que McKinley \u201cdefendi\u00f3 los aranceles\u201d y muri\u00f3 \u201cen un ataque a los valores de nuestra naci\u00f3n y a nuestro \u00e9xito\u201d.<\/p>\n<p>Tambi\u00e9n pide al secretario del Interior que \u201ctrabaje con entidades nativas de Alaska y organizaciones estatales y locales para adoptar nombres para lugares emblem\u00e1ticos que honren la historia y la cultura del pueblo de Alaska\u201d.<\/p>\n<p>Y en un gui\u00f1o a las contribuciones del golfo de M\u00e9xico a la econom\u00eda estadounidense, Trump est\u00e1 \u201cordenando que se le cambie oficialmente el nombre a golfo de Am\u00e9rica\u201d. El decreto exige que todos los mapas y documentos del gobierno federal \u201creflejen su cambio de nombre\u201d.<\/p>\n<p>El decreto tambi\u00e9n apunta a los miembros actuales de la Junta de Nombres Geogr\u00e1ficos de Estados Unidos, que depende del Servicio Geol\u00f3gico de Estados Unidos y establece nombres uniformes en torno a caracter\u00edsticas geogr\u00e1ficas, ordenando a los jefes de las agencias gubernamentales nombrar miembros para la revisi\u00f3n de los miembros existentes de la junta y \u201cconsiderar reemplazar a esos designados\u201d.<\/p>\n<p>Trump firm\u00f3 este lunes un acuerdo <a href=\"https:\/\/www.cnn.com\/2025\/01\/20\/climate\/trump-paris-agreement-energy-orders\/index.html\">que retira nuevamente a Estados Unidos del acuerdo clim\u00e1tico de Par\u00eds<\/a>, el acuerdo de reducci\u00f3n de emisiones anterior a su primer mandato en el que casi 200 naciones se comprometieron a mantener el calentamiento global por debajo de los dos grados cent\u00edgrados por encima de los niveles preindustriales y, si es posible, por debajo de los 1,5 grados.<\/p>\n<p>Trump se retir\u00f3 del acuerdo durante su primer mandato, y una de las primeras acciones de Biden como presidente fue volver a sumarse al mismo. Trump dijo este lunes que se retirar\u00eda del acuerdo, al que calific\u00f3 de \u201cunilateral\u201d, una vez m\u00e1s.<\/p>\n<p>En su discurso inaugural, Trump prometi\u00f3 declarar una \u201cemergencia energ\u00e9tica nacional\u201d y agilizar los procesos de permisos y revisi\u00f3n ambiental que, seg\u00fan su administraci\u00f3n, \u201cimponen cargas indebidas a la producci\u00f3n y el uso de energ\u00eda\u201d.<\/p>\n<p>Sus comentarios se producen a pesar del hecho de que Estados Unidos produce actualmente m\u00e1s petr\u00f3leo <a href=\"https:\/\/www.eia.gov\/todayinenergy\/detail.php?id=61545\">que cualquier otro pa\u00eds en la historia del mundo<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump dio este lunes los primeros pasos para implementar su amplia agenda con una serie de drecretos que se espera que inicien su prometida transformaci\u00f3n del gobierno federal. El primer d\u00eda de su segundo mandato, Trump se tom\u00f3 un momento durante su primer mitin posterior a su toma de posesi\u00f3n para firmar [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457685","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump dio este lunes los primeros pasos para implementar su amplia agenda con una serie de drecretos que se espera que inicien su prometida transformaci\u00f3n del gobierno federal. El primer d\u00eda de su segundo mandato, Trump se tom\u00f3 un momento durante su primer mitin posterior a su toma de posesi\u00f3n para firmar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T10:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal\",\"datePublished\":\"2025-01-21T10:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/\"},\"wordCount\":3196,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/\",\"name\":\"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-21T10:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal - Noticias","og_description":"El presidente Donald Trump dio este lunes los primeros pasos para implementar su amplia agenda con una serie de drecretos que se espera que inicien su prometida transformaci\u00f3n del gobierno federal. El primer d\u00eda de su segundo mandato, Trump se tom\u00f3 un momento durante su primer mitin posterior a su toma de posesi\u00f3n para firmar [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-21T10:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/"},"author":{"name":"","@id":""},"headline":"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal","datePublished":"2025-01-21T10:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/"},"wordCount":3196,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/","name":"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-21T10:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump firma decretos del primer d\u00eda en su intento por transformar el gobierno federal","url":"http:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-firma-decretos-transformar-gobierno-federal-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-21T10:03:42Z","datePublished":"2025-01-21T10:03:42Z","dateModified":"2025-01-21T10:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump firma decretos del primer d\\u00eda en su intento por transformar el gobierno federal\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/01\\\/21\\\/trump-firma-decretos-transformar-gobierno-federal-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/01\\\/21\\\/trump-firma-decretos-transformar-gobierno-federal-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-21T10:03:42Z\",\"datePublished\":\"2025-01-21T10:03:42Z\",\"dateModified\":\"2025-01-21T10:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457517,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/14\/presidente-guatemala-plan-migrantes-deportados-orix\/","url_meta":{"origin":1457685,"position":0},"title":"El presidente de Guatemala, Bernardo Ar\u00e9valo, anuncia plan para atender a migrantes guatemaltecos deportados","author":"","date":"enero 14, 2025","format":false,"excerpt":"El presidente de Guatemala, Bernardo Ar\u00e9valo, anunci\u00f3 este martes que su gobierno implementar\u00e1 una serie de acciones para apoyar a los migrantes que ser\u00e1n deportados, principalmente desde Estados Unidos y M\u00e9xico, en su informe de Gobierno presentado ante el Congreso, en el primer aniversario al frente del Ejecutivo.Ar\u00e9valo dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458073,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/31\/gobierno-trump-reunira-maduro-trax\/","url_meta":{"origin":1457685,"position":1},"title":"Exclusivo: representante del Gobierno de Trump se reunir\u00e1 con el presidente Nicol\u00e1s Maduro este viernes","author":"","date":"enero 31, 2025","format":false,"excerpt":"Se espera que Richard Grenell, enviado del presidente Donald Trump a misiones especiales, se re\u00fana este viernes con el presidente de Venezuela, Nicol\u00e1s Maduro, dijo a CNN una fuente familiarizada con el asunto.Se espera que Grenell discuta con el l\u00edder venezolano los vuelos de deportaci\u00f3n, entre otras cosas. Trump ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461679,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/27\/encuesta-cnn-aprobacion-trump-100-dias-trax\/","url_meta":{"origin":1457685,"position":2},"title":"Aprobaci\u00f3n de Trump a los 100 d\u00edas es la m\u00e1s baja para un presidente en al menos siete d\u00e9cadas, seg\u00fan encuesta de CNN","author":"","date":"abril 27, 2025","format":false,"excerpt":"Donald Trump gan\u00f3 las elecciones de 2024 y asumi\u00f3 el control del Gobierno de EE.Uu. en medio de los n\u00fameros de encuestas m\u00e1s fuertes de su carrera pol\u00edtica, pero a medida que se acerca la marca de 100 d\u00edas de su presidencia, las opiniones de los estadounidenses sobre lo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457646,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/19\/trump-dia-uno-presidencia-decretos-acciones-trax\/","url_meta":{"origin":1457685,"position":3},"title":"Inmigraci\u00f3n, energ\u00eda y hasta aranceles: lo que Trump prepara para impulsar desde el d\u00eda 1 de su presidencia","author":"","date":"enero 19, 2025","format":false,"excerpt":"El lunes a mediod\u00eda comienza una nueva era de Donald Trump en Estados Unidos.Una serie de acciones dise\u00f1adas para reformular la pol\u00edtica gubernamental esperar\u00e1n la firma del nuevo presidente tan pronto como preste juramento, una demostraci\u00f3n dram\u00e1tica de fuerza destinada a marcar el tono para los pr\u00f3ximos cuatro a\u00f1os.Es poco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466283,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/09\/5-cosas-9-de-septiembre-orix\/","url_meta":{"origin":1457685,"position":4},"title":"Las 5 cosas que debes saber este 9 de septiembre: nacionalizaci\u00f3n de empresas, inmigraci\u00f3n y despliegue militar de Venezuela","author":"","date":"septiembre 9, 2025","format":false,"excerpt":"Trump intensifica los operativos contra la inmigraci\u00f3n ilegal. Venezuela reforzar\u00e1 el despliegue militar en cinco estados. \u00bfQu\u00e9 esperar del nuevo iPhone? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99 Escucha las 5 cosas de CNNCuando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464283,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/07\/07\/acciones-tesla-desploman-trump-musk-trax\/","url_meta":{"origin":1457685,"position":5},"title":"Acciones de Tesla se desploman despu\u00e9s de que Trump dijera que Musk estaba &#171;fuera de control&#187; con su plan de crear un partido","author":"","date":"julio 7, 2025","format":false,"excerpt":"Las acciones de Tesla se desplomaron hasta un 7,6 % en la sesi\u00f3n previa a la apertura del mercado este lunes despu\u00e9s de que su director ejecutivo, Elon Musk, anunciara la formaci\u00f3n de un nuevo partido pol\u00edtico estadounidense, lo que provoc\u00f3 una respuesta airada del presidente Donald Trump.Las acciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1457685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1457685"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1457685\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1457685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1457685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1457685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}