{"id":1457689,"date":"2025-01-21T05:03:51","date_gmt":"2025-01-21T13:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/"},"modified":"2025-01-21T05:03:51","modified_gmt":"2025-01-21T13:03:51","slug":"trump-salida-oms-estados-unidos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","title":{"rendered":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;"},"content":{"rendered":"<p>La Organizaci\u00f3n Mundial de la Salud (OMS) espera que el presidente de Estados Unidos, Donald Trump, reconsidere su decisi\u00f3n de retirar a su pa\u00eds del organismo, seg\u00fan dijo este martes en un comunicado.<\/p>\n<p>\u201cLa Organizaci\u00f3n Mundial de la Salud lamenta el anuncio de que Estados Unidos de Am\u00e9rica tiene la intenci\u00f3n de retirarse de la organizaci\u00f3n\u201d, dice el comunicado publicado por el director general de la OMS, el doctor Tedros Adhanom Ghebreyesus.<\/p>\n<p>Este lunes, en su primer d\u00eda de vuelta en el cargo, Trump firm\u00f3 un decreto para retirarse de la agencia de salud de las Naciones Unidas, citando su presunta \u201cmala gesti\u00f3n de la pandemia de covid-19 que surgi\u00f3 en Wuhan, China, y otras crisis sanitarias mundiales, su incapacidad para adoptar reformas urgentemente necesarias y su incapacidad para demostrar independencia de la influencia pol\u00edtica inapropiada de los Estados miembros de la OMS\u201d.<\/p>\n<p>La declaraci\u00f3n de la OMS subrayaba que \u201cdesempe\u00f1a un papel crucial en la protecci\u00f3n de la salud y la seguridad de la poblaci\u00f3n mundial, incluidos los estadounidenses, abordando las causas profundas de las enfermedades, creando sistemas de salud m\u00e1s s\u00f3lidos y detectando, previniendo y respondiendo a las emergencias sanitarias, incluidos los brotes de enfermedades, a menudo en lugares peligrosos donde otros no pueden ir\u201d.<\/p>\n<p>Tambi\u00e9n se\u00f1al\u00f3 que Estados Unidos fue miembro fundador de la organizaci\u00f3n en 1948.<\/p>\n<p>\u201cEsperamos que Estados Unidos lo reconsidere y deseamos entablar un di\u00e1logo constructivo para mantener la asociaci\u00f3n entre EE.UU. y la OMS, en beneficio de la salud y el bienestar de millones de personas en todo el mundo\u201d, declar\u00f3 la agencia.<\/p>\n<p>Trump lleva tiempo siendo cr\u00edtico con la agencia sanitaria de Naciones Unidas, y su administraci\u00f3n <a href=\"https:\/\/www.cnn.com\/2020\/07\/07\/politics\/us-withdrawing-world-health-organization\/index.html\">inici\u00f3 formalmente la retirada de la OMS <\/a>en julio de 2020, mientras la pandemia del covid-19 segu\u00eda extendi\u00e9ndose. Pero hace cuatro a\u00f1os, el entonces presidente Joe Biden fren\u00f3 la salida de Estados Unidos del organismo encargado de coordinar la respuesta internacional a las emergencias sanitarias en una de sus primeras medidas tras hacerse cargo de la Casa Blanca.<\/p>\n<p>El Dr. Ashish Jha, que sirvi\u00f3 como coordinador de respuesta al covid-19 de la Casa Blanca durante la administraci\u00f3n Biden, calific\u00f3 la decisi\u00f3n de Trump de retirarse de la OMS en su segundo mandato como un \u201cerror estrat\u00e9gico\u201d.<\/p>\n<p>\u201cLa OMS es una organizaci\u00f3n bastante esencial, y con la retirada de Estados Unidos, crea un vac\u00edo pol\u00edtico que solo un pa\u00eds puede llenar , y ese es China\u201d, dijo Jha en una entrevista con CNN elste lunes.<\/p>\n<p>Predijo que China dar\u00e1 un paso adelante en la organizaci\u00f3n en ausencia de financiaci\u00f3n y liderazgo estadounidenses, lo que a su vez podr\u00eda \u201cdar a China m\u00e1s influencia pol\u00edtica en todo el mundo\u201d.<\/p>\n<p>Lawrence Gostin, profesor de Derecho de Salud P\u00fablica en la Universidad de Georgetown, dijo en un <a href=\"https:\/\/archive.ph\/o\/R0Tvi\/https:\/\/x.com\/lawrencegostin\/status\/1881461929811783886?s=46\">post en X<\/a> que la retirada de Trump de la OMS es \u201cla m\u00e1s trascendental de todas\u201d las acciones ejecutivas de Trump elste lunes.<\/p>\n<p>\u201cEs una decisi\u00f3n presidencial catacl\u00edsmica. La retirada es una herida grave para la salud mundial, pero una herida a\u00fan m\u00e1s profunda para Estados Unidos\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Jha advirti\u00f3 que retirarse de la OMS debilita a la organizaci\u00f3n porque depende en gran medida del personal y la experiencia de Estados Unidos, en particular en el seguimiento de la gripe mundial.<\/p>\n<p>El decreto de Trump insta al secretario de Estado y al director de la Oficina de Gesti\u00f3n y Presupuesto a \u201cpausar la transferencia futura de cualquier fondo, apoyo o recurso del Gobierno de Estados Unidos\u201d para la OMS. Sin embargo, se necesita un a\u00f1o para retirarse totalmente del organismo, y existe la obligaci\u00f3n de que Estados Unidos siga financi\u00e1ndolo durante un a\u00f1o.<\/p>\n<p>\u201c\u00bfPero qui\u00e9n va a hacer cumplir la obligaci\u00f3n? Se va a acobardar Donald Trump ante las normas mundiales en torno a estas cosas?\u201d, pregunt\u00f3 Jha.<\/p>\n<p>Gostin dijo en un <a href=\"https:\/\/archive.ph\/o\/R0Tvi\/https:\/\/x.com\/LawrenceGostin\/status\/1881542651348234663\">post posterior<\/a> que la acci\u00f3n est\u00e1 \u201cplagada de errores legales y f\u00e1cticos\u201d.<\/p>\n<p>\u201cTrump no est\u00e1 esperando un a\u00f1o como exig\u00eda el Congreso. Est\u00e1 deshaciendo el compromiso y la financiaci\u00f3n de Estados Unidos ahora. Eso es ilegal y un grave error estrat\u00e9gico\u201d, a\u00f1adi\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Organizaci\u00f3n Mundial de la Salud (OMS) espera que el presidente de Estados Unidos, Donald Trump, reconsidere su decisi\u00f3n de retirar a su pa\u00eds del organismo, seg\u00fan dijo este martes en un comunicado. \u201cLa Organizaci\u00f3n Mundial de la Salud lamenta el anuncio de que Estados Unidos de Am\u00e9rica tiene la intenci\u00f3n de retirarse de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457689","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &quot;Esperamos que Estados Unidos reconsidere&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &quot;Esperamos que Estados Unidos reconsidere&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Organizaci\u00f3n Mundial de la Salud (OMS) espera que el presidente de Estados Unidos, Donald Trump, reconsidere su decisi\u00f3n de retirar a su pa\u00eds del organismo, seg\u00fan dijo este martes en un comunicado. \u201cLa Organizaci\u00f3n Mundial de la Salud lamenta el anuncio de que Estados Unidos de Am\u00e9rica tiene la intenci\u00f3n de retirarse de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T13:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;\",\"datePublished\":\"2025-01-21T13:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/\"},\"wordCount\":768,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/\",\"name\":\"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: \\\"Esperamos que Estados Unidos reconsidere\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-21T13:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: \"Esperamos que Estados Unidos reconsidere\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: \"Esperamos que Estados Unidos reconsidere\" - Noticias","og_description":"La Organizaci\u00f3n Mundial de la Salud (OMS) espera que el presidente de Estados Unidos, Donald Trump, reconsidere su decisi\u00f3n de retirar a su pa\u00eds del organismo, seg\u00fan dijo este martes en un comunicado. \u201cLa Organizaci\u00f3n Mundial de la Salud lamenta el anuncio de que Estados Unidos de Am\u00e9rica tiene la intenci\u00f3n de retirarse de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-21T13:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/"},"author":{"name":"","@id":""},"headline":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;","datePublished":"2025-01-21T13:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/"},"wordCount":768,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","name":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: \"Esperamos que Estados Unidos reconsidere\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-21T13:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump anuncia la retirada del pa\u00eds de la OMS y la organizaci\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;","url":"http:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-salida-oms-estados-unidos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-21T13:03:51Z","datePublished":"2025-01-21T13:03:51Z","dateModified":"2025-01-21T13:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump anuncia la retirada del pa\\u00eds de la OMS y la organizaci\\u00f3n responde: &#171;Esperamos que Estados Unidos reconsidere&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/01\\\/21\\\/trump-salida-oms-estados-unidos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/01\\\/21\\\/trump-salida-oms-estados-unidos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-21T13:03:51Z\",\"datePublished\":\"2025-01-21T13:03:51Z\",\"dateModified\":\"2025-01-21T13:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470400,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/22\/estados-unidos-oficializa-salida-organizacion-mundial-salud-oms-trax\/","url_meta":{"origin":1457689,"position":0},"title":"Estados Unidos oficializa su salida de la Organizaci\u00f3n Mundial de la Salud","author":"","date":"enero 22, 2026","format":false,"excerpt":"El Departamento de Salud y Servicios Humanos de EE.UU. (HHS por sus siglas en ingl\u00e9s), confirm\u00f3 el jueves que Estados Unidos complet\u00f3 su retiro definitivo de la Organizaci\u00f3n Mundial de la Salud (OMS). Con este anuncio, se materializa uno de los objetivos m\u00e1s ambiciosos y controvertidos del Gobierno del presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458413,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/02\/07\/milei-argentina-oms-que-significa-orix\/","url_meta":{"origin":1457689,"position":1},"title":"\u00c1NALISIS | Tras los pasos de Trump, Milei busca sacar a Argentina de la OMS: \u00bfqu\u00e9 significa para el pa\u00eds?","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Dos semanas despu\u00e9s de que el presidente Donald Trump anunci\u00f3 que buscar\u00e1 retirar a Estados Unidos de la Organizaci\u00f3n Mundial de la Salud (OMS), su hom\u00f3logo argentino Javier Milei replic\u00f3 para su pa\u00eds esta decisi\u00f3n, con argumentos similares.\u201cLa mala gesti\u00f3n de la organizaci\u00f3n ante la pandemia de covid-19 y otras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458273,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/02\/05\/milei-retira-oms-orix\/","url_meta":{"origin":1457689,"position":2},"title":"Javier Milei retira a Argentina de la OMS","author":"","date":"febrero 5, 2025","format":false,"excerpt":"El Gobierno de Argentina anunci\u00f3 este mi\u00e9rcoles que el pa\u00eds se retirar\u00e1 de la Organizaci\u00f3n Mundial de Salud (OMS), seg\u00fan confirm\u00f3 el portavoz de la Presidencia, Manuel Adorni, durante una conferencia de prensa.Adorni remarc\u00f3 que fue un pedido del presidente de Argentina, Javier Milei, al canciller argentino, Gerardo Werthein.Dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464751,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/07\/22\/trump-retira-pais-unesco-trax\/","url_meta":{"origin":1457689,"position":3},"title":"EE.UU. se retirar\u00e1 nuevamente de la agencia cient\u00edfica y cultural de la ONU, Unesco, dice la Casa Blanca","author":"","date":"julio 22, 2025","format":false,"excerpt":"El presidente Donald Trump retirar\u00e1 a Estados Unidos de la Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura (Unesco, por sus siglas en ingl\u00e9s), dijo a CNN una funcionaria de la Casa Blanca.La decisi\u00f3n se produce mientras el presidente contin\u00faa retirando al pa\u00eds de organismos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451905,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/16\/oms-casos-de-viruela-simica-europa-trax\/","url_meta":{"origin":1457689,"position":4},"title":"La OMS advierte de que es probable que haya m\u00e1s casos de viruela s\u00edmica en Europa en los pr\u00f3ximos d\u00edas y semanas","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN)-- La Organizaci\u00f3n Mundial de la Salud (OMS) ha advertido de que es probable que en los pr\u00f3ximos d\u00edas y semanas se produzcan m\u00e1s casos de viruela s\u00edmica en Europa.La advertencia se produjo despu\u00e9s de que Suecia confirmara este jueves su primer caso de la cepa Clade I del virus,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458964,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/02\/20\/carlos-regazzoni-ningun-pais-pudo-resolver-los-problemas-de-salud-sin-un-robusto-sistema-publico\/","url_meta":{"origin":1457689,"position":5},"title":"Carlos Regazzoni: &#171;Ning\u00fan pa\u00eds pudo resolver los problemas de salud sin un robusto sistema p\u00fablico&#187;","author":"","date":"febrero 20, 2025","format":false,"excerpt":"Carlos Regazzoni, m\u00e9dico y exdirector Ejecutivo del PAMI, visit\u00f3 los estudios de CNN Radio y analiz\u00f3 la situaci\u00f3n del pa\u00eds, especialmente en el sector salud.En CNN Primera Ma\u00f1ana, cont\u00f3 que est\u00e1 \u201cretomando la senda de la pol\u00edtica, pero focalizado en la salud, donde la Argentina tiene una situaci\u00f3n muy delicada,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1457689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1457689"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1457689\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1457689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1457689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1457689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}