{"id":1457715,"date":"2025-01-21T14:03:38","date_gmt":"2025-01-21T22:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/"},"modified":"2025-01-21T14:03:38","modified_gmt":"2025-01-21T22:03:38","slug":"trump-cierra-frontera-solicitantes-asilo-limbo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/","title":{"rendered":"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo"},"content":{"rendered":"<p>La frontera entre Estados Unidos y M\u00e9xico se cerr\u00f3 efectivamente a los migrantes que buscan asilo en Estados Unidos pocas horas despu\u00e9s de que el presidente Donald Trump asumiera el cargo, una desviaci\u00f3n extraordinaria de los protocolos anteriores que ha dejado en el limbo a muchos migrantes preocupados.<\/p>\n<p>Se trata de una rara combinaci\u00f3n de dos pol\u00edticas, una del expresidente Joe Biden y otra de Trump, que pr\u00e1cticamente han cerrado la frontera sur de Estados Unidos a los solicitantes de asilo. Al suspenderse tambi\u00e9n las admisiones de refugiados, las personas que buscan refugio en Estados Unidos disponen de pocas v\u00edas, si es que tienen alguna.<\/p>\n<p>La acci\u00f3n ejecutiva de Biden del verano boreal pasado, que restring\u00eda el asilo a las personas que cruzaban ilegalmente la frontera, fue condenada por los dem\u00f3cratas y los defensores de los inmigrantes. Los funcionarios del gobierno de Biden argumentaron que los inmigrantes a\u00fan ten\u00edan una opci\u00f3n disponible a trav\u00e9s de la aplicaci\u00f3n fronteriza conocida como <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/21\/eeuu\/cbp-one-migrantes-que-es-inhabilitacion-orix\">CBP One<\/a> para concertar una cita en un puerto de entrada legal.<\/p>\n<p>Esa opci\u00f3n se cerr\u00f3 minutos despu\u00e9s de la toma de posesi\u00f3n de Trump, dejando a miles de migrantes en el limbo y dando lugar a una frontera en gran medida sellada a los solicitantes de asilo.<\/p>\n<p>Los migrantes que hab\u00edan estado esperando sus citas a lo largo de la frontera norte de M\u00e9xico expresaron su conmoci\u00f3n y decepci\u00f3n.<\/p>\n<p>Luis, un migrante venezolano que ha vivido en la ciudad fronteriza mexicana de Ciudad Ju\u00e1rez durante los \u00faltimos nueve meses, dijo a Valeria Le\u00f3n, de CNN, que estaba \u201ctratando de hacer las cosas de la manera correcta\u201d, antes de enterarse de que su cita programada para el lunes a trav\u00e9s de la aplicaci\u00f3n CBP One se hab\u00eda cancelado abruptamente.<\/p>\n<p>La venezolana Yenyile D\u00edaz, que tambi\u00e9n ha pasado meses viviendo en Ciudad Ju\u00e1rez con su familia, dijo que todos hab\u00edan perdido sus citas tras el cierre de CBP One.<\/p>\n<p>\u201cLa administraci\u00f3n de Biden hab\u00eda conseguido restringir el asilo abriendo algunas otras v\u00edas legales y esperando que se mantuvieran en los tribunales. A partir de hoy, casi no hay forma de obtener protecci\u00f3n en la frontera estadounidense ni en ninguna parte de la ruta hacia Estados Unidos\u201d, declar\u00f3 Andrew Selee, presidente del grupo de reflexi\u00f3n Migration Policy Institute. \u201cEs un cambio enorme\u201d.<\/p>\n<p>Los republicanos han argumentado que en los \u00faltimos a\u00f1os se han aprovechado del sistema de asilo estadounidense, afirmando que los inmigrantes solicitan asilo aunque no se ajusten a la definici\u00f3n y que, en cambio, pueden venir a Estados Unidos por motivos econ\u00f3micos.<\/p>\n<p>Cuando las personas solicitan asilo, se supone que buscan protecci\u00f3n frente a la violencia o la persecuci\u00f3n que les impiden sentirse seguros en su pa\u00eds de origen o les impiden regresar sanos y salvos a su pa\u00eds de origen. El proceso para obtener asilo puede durar a\u00f1os, y algunas solicitudes acaban siendo denegadas.<\/p>\n<p>En un decreto firmado el lunes, Trump suspendi\u00f3 de forma efectiva la ley de asilo estadounidense hasta que cese lo que ha calificado de \u201cinvasi\u00f3n en la frontera sur\u201d. Tambi\u00e9n orden\u00f3 a las agencias federales que \u201crechazaran, repatriaran o expulsaran\u201d a los migrantes que cruzaran la frontera.<\/p>\n<p>\u201cLa decisi\u00f3n de eliminar todas las v\u00edas para solicitar asilo, incluso para las familias con ni\u00f1os que huyen para salvar sus vidas, es un hecho asombroso, que se burla de nuestro compromiso posterior a la Segunda Guerra Mundial de no devolver nunca sumariamente a la gente al peligro\u201d, declar\u00f3 en un comunicado Lee Gelernt, abogado de la ACLU que dirigi\u00f3 muchas de las impugnaciones de las pol\u00edticas fronterizas de Trump en la primera administraci\u00f3n.<\/p>\n<p>Las restricciones de la era covid a lo largo de la frontera, conocidas como T\u00edtulo 42, tambi\u00e9n prohib\u00edan el asilo y permit\u00edan a las autoridades fronterizas devolver a los migrantes. Esa pol\u00edtica fue impugnada ante los tribunales.<\/p>\n<p>Trump hereda una frontera relativamente tranquila, ya que las restricciones al asilo de Biden hicieron que los cruces de inmigrantes cayeran en picada.<\/p>\n<p>En los primeros d\u00edas del primer mandato de Trump, los cruces fronterizos se mantuvieron bajos mientras los migrantes esperaban a ver y jugar sus acciones. Pero finalmente aumentaron.<\/p>\n<p>Aunque es dif\u00edcil predecir los patrones migratorios, los funcionarios de Seguridad Nacional advierten que eso podr\u00eda volver a ocurrir.<\/p>\n<p>\u201cPuede que esperen un tiempo a ver qu\u00e9 ocurre. Esperen un d\u00eda o unos meses, si est\u00e1n tan lejos y comprometidos, al final lo intentar\u00e1n de todos modos\u201d, dijo el funcionario de Seguridad Nacional, refiri\u00e9ndose a los migrantes.<\/p>\n<p>Johana Conde, de Cuba, dijo a CNNE desde la ciudad fronteriza mexicana de Piedras Negras que ahora planea regresar a su pa\u00eds, pero no est\u00e1 segura de lo que le depara el futuro.<\/p>\n<p>\u201cDicen que s\u00ed quieren inmigrantes en Estados Unidos, pero legales. Obviamente, hicimos todo esto legalmente\u2026 Ahora mismo no sabemos qu\u00e9 va a pasar\u201d, dijo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La frontera entre Estados Unidos y M\u00e9xico se cerr\u00f3 efectivamente a los migrantes que buscan asilo en Estados Unidos pocas horas despu\u00e9s de que el presidente Donald Trump asumiera el cargo, una desviaci\u00f3n extraordinaria de los protocolos anteriores que ha dejado en el limbo a muchos migrantes preocupados. Se trata de una rara combinaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457715","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo - Noticias\" \/>\n<meta property=\"og:description\" content=\"La frontera entre Estados Unidos y M\u00e9xico se cerr\u00f3 efectivamente a los migrantes que buscan asilo en Estados Unidos pocas horas despu\u00e9s de que el presidente Donald Trump asumiera el cargo, una desviaci\u00f3n extraordinaria de los protocolos anteriores que ha dejado en el limbo a muchos migrantes preocupados. Se trata de una rara combinaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T22:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo\",\"datePublished\":\"2025-01-21T22:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/\"},\"wordCount\":900,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/\",\"name\":\"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-21T22:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo - Noticias","og_description":"La frontera entre Estados Unidos y M\u00e9xico se cerr\u00f3 efectivamente a los migrantes que buscan asilo en Estados Unidos pocas horas despu\u00e9s de que el presidente Donald Trump asumiera el cargo, una desviaci\u00f3n extraordinaria de los protocolos anteriores que ha dejado en el limbo a muchos migrantes preocupados. Se trata de una rara combinaci\u00f3n de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-21T22:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/"},"author":{"name":"","@id":""},"headline":"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo","datePublished":"2025-01-21T22:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/"},"wordCount":900,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/","name":"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-21T22:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump cierra la frontera entre EE.UU. y M\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo","url":"http:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/01\/21\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-21T22:03:38Z","datePublished":"2025-01-21T22:03:38Z","dateModified":"2025-01-21T22:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump cierra la frontera entre EE.UU. y M\\u00e9xico a los solicitantes de asilo, dejando a los migrantes en el limbo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/01\\\/21\\\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/01\\\/21\\\/trump-cierra-frontera-solicitantes-asilo-limbo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-21T22:03:38Z\",\"datePublished\":\"2025-01-21T22:03:38Z\",\"dateModified\":\"2025-01-21T22:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472503,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/24\/corte-suprema-examinara-politica-asilo-frontera-sur-trax\/","url_meta":{"origin":1457715,"position":0},"title":"La Corte Suprema examinar\u00e1 una antigua pol\u00edtica que permit\u00eda rechazar a los solicitantes de asilo en la frontera sur","author":"","date":"marzo 24, 2026","format":false,"excerpt":"La Corte Suprema examinar\u00e1 este martes la legalidad de una pol\u00edtica impulsada por el presidente Donald Trump durante su primer mandato que impidi\u00f3 que un gran n\u00famero de migrantes que llegaban a la frontera sur iniciaran el proceso de solicitud de asilo.La pol\u00edtica fue originalmente presentada bajo la presidencia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457390,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/09\/migrantes-frontera-eeuu-mexico-trump-trax\/","url_meta":{"origin":1457715,"position":1},"title":"Migrantes se apresuran a llegar a la frontera entre EE.UU. y M\u00e9xico antes de que Trump asuma el cargo","author":"","date":"enero 9, 2025","format":false,"excerpt":"Cuando Altagracia sali\u00f3 de Honduras para emprender un viaje de meses hacia la frontera entre Estados Unidos y M\u00e9xico, ten\u00eda dos objetivos claros en mente: llegar a EE.UU. para solicitar asilo y reunirse con sus hijos que viven all\u00ed.Pero despu\u00e9s de dejar su ciudad natal de Siguatepeque, en las tierras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470304,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/20\/varados-frontera-trump-peticionarios-asilo-orix\/","url_meta":{"origin":1457715,"position":2},"title":"Varados en la frontera: el d\u00eda que el regreso de Trump a la Casa Blanca cambi\u00f3 el panorama de miles de peticionarios de asilo","author":"","date":"enero 20, 2026","format":false,"excerpt":"La madrugada del 20 de enero de 2025, en Ciudad Ju\u00e1rez, Chihuahua, al norte de M\u00e9xico, el clima congelante no deten\u00eda al grupo de peticionarios de asilo formados en el puente fronterizo que conecta con El Paso, Texas. Ese era uno de los puntos donde ser\u00edan procesados para ingresar legalmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444542,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump\/","url_meta":{"origin":1457715,"position":3},"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","author":"","date":"enero 28, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444544,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump-2\/","url_meta":{"origin":1457715,"position":4},"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","author":"","date":"enero 28, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444545,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/01\/28\/biden-endurece-medidas-fronterizas-mientras-intenta-defenderse-de-los-ataques-de-trump-3\/","url_meta":{"origin":1457715,"position":5},"title":"Biden endurece medidas fronterizas mientras intenta defenderse de los ataques de Trump","author":"","date":"enero 28, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, est\u00e1 adoptando medidas fronterizas m\u00e1s duras, incluido el cierre de la frontera entre Estados Unidos y M\u00e9xico, lo que marca un marcado cambio con respecto a sus primeros d\u00edas en el cargo mientras intenta defenderse de los ataques del expresidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1457715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1457715"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1457715\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1457715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1457715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1457715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}