{"id":1457763,"date":"2025-01-22T10:03:48","date_gmt":"2025-01-22T18:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/"},"modified":"2025-01-22T10:03:48","modified_gmt":"2025-01-22T18:03:48","slug":"gaza-guerra-mapas-graficos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/","title":{"rendered":"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos"},"content":{"rendered":"<p>El domingo entr\u00f3 en vigor un fr\u00e1gil alto el fuego entre Israel y Hamas, y las primeras seis semanas del acuerdo marcan el comienzo de una pausa en los combates, la liberaci\u00f3n escalonada de rehenes israel\u00edes y prisioneros palestinos y la llegada de ayuda a Gaza. El alto el fuego <a href=\"https:\/\/www.cnn.com\/2025\/01\/14\/middleeast\/israel-hamas-gaza-ceasefire-hostage-deal-explainer-intl\/index.html\">en tres fases<\/a> ha suscitado cautelosas esperanzas de que la guerra llegue a su fin.<\/p>\n<p>Los bombardeos israel\u00edes de Gaza desde los ataques del 7 de octubre liderados por Hamas han tenido un impacto devastador en el territorio, y las agencias de ayuda advierten que los da\u00f1os a la infraestructura cr\u00edtica, incluidas escuelas, hospitales, agua y centros de atenci\u00f3n de la salud, tardar\u00e1n a\u00f1os en reconstruirse.<\/p>\n<p>A continuaci\u00f3n, se muestra un vistazo (en 6 gr\u00e1ficos) a c\u00f3mo est\u00e1 Gaza despu\u00e9s de 15 meses de guerra.<\/p>\n<p>Seg\u00fan el Ministerio de Salud palestino, a\u00fan no se sabe nada de otras 11.000 personas, probablemente desaparecidas o a\u00fan no encontradas bajo los escombros.<\/p>\n<p>Sin embargo, investigaciones recientes sugieren que el n\u00famero de muertos podr\u00eda ser mucho mayor que las estimaciones actuales. Un estudio de la London School of Hygiene &#038; Tropical Medicine (LSHTM) que tambi\u00e9n se public\u00f3 en la revista The Lancet este mes concluy\u00f3 que el Ministerio de Salud palestino<a href=\"https:\/\/www.cnn.com\/2025\/01\/09\/middleeast\/gaza-death-toll-underreported-study-intl\/index.html\"> ha subestimado el n\u00famero de muertos en aproximadamente un 41%<\/a>. En octubre de 2024, se pensaba que el n\u00famero de habitantes de Gaza muertos por la violencia superaba los 70.000, seg\u00fan el estudio.<\/p>\n<p>Mientras tanto, el Ministerio de Salud dijo en octubre que un tercio de los muertos en el primer a\u00f1o de la guerra eran ni\u00f1os.<\/p>\n<p>Los ataques militares israel\u00edes han arrasado la mayor parte de Gaza, siendo la ciudad de Gaza la m\u00e1s destruida. Seg\u00fan las Naciones Unidas, alrededor de 436.000 viviendas han sido destruidas o da\u00f1adas en toda Gaza.<\/p>\n<p>Alrededor de 1,9 millones de palestinos, o aproximadamente el 90% de la poblaci\u00f3n, est\u00e1n desplazados internamente, seg\u00fan la ONU. Muchas personas en Gaza han sido desplazadas varias veces, algunas hasta 10 veces.<\/p>\n<p>Las Fuerzas de Defensa de Israel (FDI) ordenaron evacuaciones regularmente de una zona de peligro a otra, seg\u00fan la ONU, que ha <a href=\"https:\/\/www.un.org\/unispal\/document\/statement-on-gaza-27may24\/\">dicho <\/a>repetidamente que \u201cno hay ning\u00fan lugar seguro en Gaza\u201d. Se emitieron \u00f3rdenes de evacuaci\u00f3n en el 67% de Gaza durante el curso de la guerra, seg\u00fan datos del Instituto para el Estudio de la Guerra.<\/p>\n<p>Esas \u00f3rdenes a menudo fueron lanzadas desde el aire por las FDI, un m\u00e9todo que Amnist\u00eda Internacional <a href=\"https:\/\/www.amnesty.org\/en\/latest\/news\/2023\/10\/israel-opt-israeli-army-threats-ordering-residents-of-northern-gaza-to-leave-may-amount-to-war-crimes\/\">dijo que \u201cno era una advertencia efectiva para los civiles\u201d<\/a>, o publicadas en las redes sociales, una forma de comunicaci\u00f3n inaccesible para muchos habitantes de Gaza sin electricidad ni Internet.<\/p>\n<p>Las FDI han dicho que hacen todo lo posible para minimizar las bajas civiles en Gaza, incluso enviando mensajes de texto, haciendo llamadas telef\u00f3nicas y lanzando folletos de evacuaci\u00f3n para advertir a los civiles antes de los ataques.<\/p>\n<p>Al-Mawasi, un \u00e1rea de 67 kil\u00f3metros cuadrados, aproximadamente el tama\u00f1o de Manhattan, se ha convertido en la principal zona de desplazamiento y refugio para cientos de miles de palestinos a los que el ej\u00e9rcito israel\u00ed ha ordenado abandonar sus hogares. Antes de la guerra, hab\u00eda 9.000 personas viviendo all\u00ed. Para julio de 2024, la poblaci\u00f3n del campamento hab\u00eda aumentado a 1,7 millones, seg\u00fan la Red de Sistemas de Alerta Temprana contra la Hambruna respaldada por la ONU. En octubre, la poblaci\u00f3n del campamento se estim\u00f3 en 730.000, seg\u00fan UNICEF.<\/p>\n<p>A pesar de haber sido designada como zona humanitaria por Israel, Al-Mawasi ha sido blanco de repetidos ataques a\u00e9reos israel\u00edes.<\/p>\n<p>Muchas personas en Gaza han tenido dificultades para acceder a los alimentos durante m\u00e1s de un a\u00f1o.<\/p>\n<p>Antes de la guerra, Gaza era \u201cen gran medida autosuficiente\u201d en productos frescos, seg\u00fan la ONU. La operaci\u00f3n militar de Israel ha da\u00f1ado o destruido hasta el 96% de los activos agr\u00edcolas, incluidas granjas y huertos, seg\u00fan el Banco Mundial. Las Fuerzas de Defensa de Israel (FDI) dijeron a CNN que \u201cno da\u00f1an intencionalmente las tierras agr\u00edcolas y buscan mitigar el impacto ambiental en ausencia de necesidad operativa\u201d.<\/p>\n<p>La mayor parte de Gaza depende de la ayuda humanitaria, pero las autoridades israel\u00edes han cerrado muchos puntos de entrada de ayuda a Gaza durante la guerra.<\/p>\n<p>Eso incluye el cruce de Rafah con Egipto, el \u00fanico cruce fronterizo entre Gaza y Egipto, y que alguna vez fue uno de los cruces de ayuda m\u00e1s grandes e importantes hacia Gaza, que ha estado cerrado desde mayo de 2024, cuando Israel tom\u00f3 el control del mismo. Otros puntos de entrada de ayuda han estado abiertos con un acceso extremadamente limitado.<\/p>\n<p>La ONU dijo en noviembre que la gente est\u00e1 \u201cefectivamente muriendo de hambre mientras el conflicto se desata, y las organizaciones humanitarias tienen prohibido entregar asistencia a los necesitados\u201d.<\/p>\n<p>Antes de la guerra, entraban en Gaza una media de 500 camiones al d\u00eda (unos 15.000 al mes) con ayuda y mercanc\u00edas comerciales.<\/p>\n<p>La Oficina de las Naciones Unidas para la Coordinaci\u00f3n de Asuntos Humanitarios (OCHA) <a href=\"https:\/\/www.ochaopt.org\/content\/reported-impact-snapshot-gaza-strip-31-december-2024\">inform\u00f3 <\/a>el martes en una actualizaci\u00f3n que s\u00f3lo 2.205 camiones de ayuda hab\u00edan entrado en Gaza en el mes de diciembre, sin contar los veh\u00edculos comerciales y el combustible.<\/p>\n<p>Israel cuestion\u00f3 esa cifra, afirmando que no hay l\u00edmite a la cantidad de ayuda que puede entrar en Gaza y que m\u00e1s de 5.000 camiones hab\u00edan entrado en el transcurso del mes, seg\u00fan un <a href=\"https:\/\/x.com\/cogatonline\/status\/1874502254255800776\">comunicado <\/a>de la Coordinaci\u00f3n de Actividades Gubernamentales en los Territorios (COGAT), que gestiona el flujo de ayuda a Gaza.<\/p>\n<p>Mientras tanto, los camiones que entran a Gaza enfrentan ahora desaf\u00edos adicionales para moverse a trav\u00e9s del territorio: aproximadamente el 68% de la red vial ha sido da\u00f1ada, seg\u00fan el an\u00e1lisis de im\u00e1genes satelitales de UNOSAT.<\/p>\n<p>Y las bandas criminales siguen saqueando los convoyes que transportan alimentos.<\/p>\n<p>El sistema de salud de Gaza est\u00e1 en ruinas. Antes de octubre de 2023, hab\u00eda 36 hospitales operativos en Gaza. Ahora, ni un solo hospital en Gaza est\u00e1 completamente funcional.<\/p>\n<p>El patr\u00f3n de ataques de Israel ha \u201cllevado al sistema de salud al borde del colapso total\u201d, seg\u00fan un informe de la ONU de diciembre. Hasta la fecha, la Organizaci\u00f3n Mundial de la Salud (OMS) ha verificado 654 ataques a instalaciones de atenci\u00f3n m\u00e9dica en Gaza, que resultaron en 886 muertos y 1.349 heridos.<\/p>\n<p>Las FDI han <a href=\"https:\/\/www.un.org\/unispal\/wp-content\/uploads\/2024\/12\/israel-comments-gaza-hospitals-report-2024.pdf\">dicho <\/a>que los combatientes de Hamas se infiltran en los hospitales y almacenan armas en ellos.<\/p>\n<p>Solo la mitad de los hospitales de Gaza est\u00e1n parcialmente operativos y dependen \u00fanicamente de la ayuda y el suministro de combustible para funcionar.<\/p>\n<p>La escasez de combustible sigue amenazando la atenci\u00f3n de unos 2.000 pacientes, seg\u00fan el<a href=\"https:\/\/www.unocha.org\/publications\/report\/occupied-palestinian-territory\/humanitarian-situation-update-255-gaza-strip-enar\"> grupo de salud de la OMS, <\/a>alrededor del 10% de los cuales est\u00e1n en unidades de cuidados intensivos. Adem\u00e1s, se estima que m\u00e1s de 12.000 pacientes requieren una evacuaci\u00f3n m\u00e9dica urgente al extranjero.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo entr\u00f3 en vigor un fr\u00e1gil alto el fuego entre Israel y Hamas, y las primeras seis semanas del acuerdo marcan el comienzo de una pausa en los combates, la liberaci\u00f3n escalonada de rehenes israel\u00edes y prisioneros palestinos y la llegada de ayuda a Gaza. El alto el fuego en tres fases ha suscitado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457763","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos - Noticias\" \/>\n<meta property=\"og:description\" content=\"El domingo entr\u00f3 en vigor un fr\u00e1gil alto el fuego entre Israel y Hamas, y las primeras seis semanas del acuerdo marcan el comienzo de una pausa en los combates, la liberaci\u00f3n escalonada de rehenes israel\u00edes y prisioneros palestinos y la llegada de ayuda a Gaza. El alto el fuego en tres fases ha suscitado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-22T18:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos\",\"datePublished\":\"2025-01-22T18:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/\"},\"wordCount\":1215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/\",\"name\":\"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-22T18:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos - Noticias","og_description":"El domingo entr\u00f3 en vigor un fr\u00e1gil alto el fuego entre Israel y Hamas, y las primeras seis semanas del acuerdo marcan el comienzo de una pausa en los combates, la liberaci\u00f3n escalonada de rehenes israel\u00edes y prisioneros palestinos y la llegada de ayuda a Gaza. El alto el fuego en tres fases ha suscitado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-22T18:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/"},"author":{"name":"","@id":""},"headline":"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos","datePublished":"2025-01-22T18:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/"},"wordCount":1215,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/","name":"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-22T18:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gaza tras 15 meses de guerra: una instant\u00e1nea en mapas y gr\u00e1ficos","url":"http:\/\/noticiasya.com\/lubbock\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/01\/22\/gaza-guerra-mapas-graficos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-22T18:03:48Z","datePublished":"2025-01-22T18:03:48Z","dateModified":"2025-01-22T18:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gaza tras 15 meses de guerra: una instant\\u00e1nea en mapas y gr\\u00e1ficos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/01\\\/22\\\/gaza-guerra-mapas-graficos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/01\\\/22\\\/gaza-guerra-mapas-graficos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-22T18:03:48Z\",\"datePublished\":\"2025-01-22T18:03:48Z\",\"dateModified\":\"2025-01-22T18:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1460308,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/23\/muertos-gaza-guerra-israel-hamas-ministerio-salud-trax\/","url_meta":{"origin":1457763,"position":0},"title":"50.000 personas han muerto en Gaza desde el inicio de la guerra entre Israel y Hamas, dice Ministerio de Salud","author":"","date":"marzo 23, 2025","format":false,"excerpt":"M\u00e1s de 50.000 palestinos han muerto en Gaza desde que comenz\u00f3 la guerra de Israel con Hamas, dijo este domingo el Ministerio de Salud del territorio, un hito sombr\u00edo para una guerra sin final a la vista mientras Israel reanuda los combates y advierte de d\u00edas a\u00fan m\u00e1s dif\u00edciles por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461335,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/17\/hamas-rechaza-oferta-alto-el-fuego-escalada-gaza-trax\/","url_meta":{"origin":1457763,"position":1},"title":"Hamas rechaza la oferta de cese del fuego mientras los legisladores israel\u00edes de extrema derecha piden una escalada en Gaza","author":"","date":"abril 17, 2025","format":false,"excerpt":"Hamas rechaz\u00f3 la oferta israel\u00ed de cese del fuego presentada a principios de esta semana, seg\u00fan un alto funcionario de Hamas, pidiendo en su lugar una propuesta \u201cintegral\u201d para poner fin a la guerra.El funcionario declar\u00f3 a CNN: \u201cRechazamos la oferta en su totalidad y en detalle\u201d.El rechazo llev\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451884,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/15\/40-000-palestinos-murieron-10-meses-gaza-trax\/","url_meta":{"origin":1457763,"position":2},"title":"M\u00e1s de 40.000 palestinos murieron en los 10 meses de la guerra en Gaza, seg\u00fan el Ministerio de Salud","author":"","date":"agosto 15, 2024","format":false,"excerpt":"(CNN) -- M\u00e1s de 40.000 palestinos han muerto en Gaza desde que Israel lanz\u00f3 su guerra contra Hamas, seg\u00fan inform\u00f3 este jueves el Ministerio de Salud del enclave, otro hito oscuro en el conflicto que ya lleva 10 meses.El ministerio dijo que 40 personas murieron en Gaza durante las \u00faltimas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457623,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/18\/acuerdo-alto-fuego-rehenes-gaza-trax\/","url_meta":{"origin":1457763,"position":3},"title":"El acuerdo de alto el fuego y liberaci\u00f3n de rehenes entrar\u00e1 en vigor el domingo, poniendo un freno a meses de enfrentamientos","author":"","date":"enero 18, 2025","format":false,"excerpt":"El largamente esperado acuerdo de alto el fuego y liberaci\u00f3n de rehenes entre el Gobierno de Israel y Hamas entrar\u00e1 en vigor el domingo, lo que podr\u00eda marcar un nuevo cap\u00edtulo en un sangriento conflicto de 15 meses que ha inflamado Medio Oriente.El acuerdo, que consta de tres fases, entrar\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461664,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/26\/dirigentes-hamas-el-cairo-negociar-alto-el-fuego-trax\/","url_meta":{"origin":1457763,"position":4},"title":"Altos dirigentes de Hamas llegan a El Cairo para negociar un alto el fuego. Trump afirma: &#171;Tenemos que ser buenos con Gaza&#187;","author":"","date":"abril 26, 2025","format":false,"excerpt":"Una delegaci\u00f3n de alto rango de Hamas lleg\u00f3 a El Cairo temprano este s\u00e1bado para conversaciones con funcionarios egipcios con el objetivo de negociar un acuerdo de alto el fuego, seg\u00fan un comunicado de Hamas.La delegaci\u00f3n, encabezada por el presidente del Consejo de Liderazgo de Hamas, Muhammad Darwish, incluye a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1454973,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/10\/06\/que-ha-pasado-ano-guerra-israel-hamas-muertos-situacion-en-gaza-orix\/","url_meta":{"origin":1457763,"position":5},"title":"Qu\u00e9 ha pasado en un a\u00f1o de guerra entre Israel y Hamas, cu\u00e1ntos muertos ha dejado y cu\u00e1l es la situaci\u00f3n en Gaza","author":"","date":"octubre 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Con miles de palestinos e israel\u00edes muertos, la guerra entre Israel y Hamas cumple un a\u00f1o este lunes sin que haya perspectivas sobre el fin de este enfrentamiento. Todo lo contrario, el conflicto se intensifica y expande cada vez m\u00e1s en Medio Oriente. Han sido meses de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1457763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1457763"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1457763\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1457763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1457763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1457763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}