{"id":1466522,"date":"2025-09-16T13:03:38","date_gmt":"2025-09-16T20:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/"},"modified":"2025-09-16T13:03:38","modified_gmt":"2025-09-16T20:03:38","slug":"armand-mondo-duplantis-record-dinero-atletismo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/","title":{"rendered":"\u00bfCu\u00e1nto dinero gan\u00f3 Armand &#171;Mondo&#187; Duplantis por su nueva medalla de oro en el Mundial de Atletismo?"},"content":{"rendered":"<p>Armand \u201cMondo\u201d Duplantis sigue haciendo historia en la disciplina del salto con p\u00e9rtiga.<\/p>\n<p>El sueco de 25 a\u00f1os gan\u00f3 la medalla de oro en el Mundial de Atletismo disputado en Jap\u00f3n y, al mismo tiempo, sum\u00f3 su r\u00e9cord del mundo n\u00famero 14.<\/p>\n<p>Desde que super\u00f3 la marca mundial por primera vez el 8 de febrero de 2020, Duplantis ha conseguido romper su propia marca en 13 ocasiones m\u00e1s, y en cada una de estas le ha sumado un cent\u00edmetro de altura.<\/p>\n<p>En lo que va de 2025, el sueco ya rompi\u00f3 cuatro veces su propio r\u00e9cord. Su mejor salto hasta el momento es el del Mundial de Atletismo de Tokio, donde registr\u00f3 una altura de 6,30 metros.<\/p>\n<p>\u201cCreo que es mi mejor temporada. He roto una mayor cantidad de r\u00e9cords mundiales que en otros a\u00f1os, por lo que estoy claramente muy feliz. Me siento muy bien f\u00edsicamente. No he tenido el tiempo para procesar toda esta campa\u00f1a, quiero decir, como un todo. Incluso parece que a\u00fan no ha terminado. Reci\u00e9n termina. Pero estoy muy agradecido, y s\u00ed, esta es la mejor temporada que he realizado hasta el momento\u201d, indic\u00f3 Duplantis tras conseguir la medalla de oro en el salto con p\u00e9rtiga en Tokio.<\/p>\n<p>La gloria deportiva no es el \u00fanico incentivo que Mondo Duplantis tiene a la hora de buscar superar sus propias marcas mundiales.<\/p>\n<p>World Athletics (WA), la organizaci\u00f3n que supervisa todos los eventos relacionados al atletismo a nivel mundial, anunci\u00f3 nuevos incentivos econ\u00f3micos para los deportistas a partir de los Juegos Ol\u00edmpicos de Par\u00eds 2024.<\/p>\n<p>La WA entreg\u00f3 un premio de US$ 50.000 a Duplantis por conseguir la medalla de oro en el salto con p\u00e9rtiga en Par\u00eds 2024, donde gan\u00f3 con un salto de 6,25 metros.<\/p>\n<p>En el Mundial de Atletismo 2025, la WA no solo vuelve a entregar premios por la obtenci\u00f3n de medallas, sino que tambi\u00e9n otorga un bonus a los deportistas que consigan r\u00e9cords del mundo.<\/p>\n<p>Por su nueva medalla de oro, Duplantis se gan\u00f3 un premio de US$ 70.000 y por el nuevo r\u00e9cord otros US$100.000.<\/p>\n<p>Es decir que, con solo dos de sus marcas, una vez que se confirme su r\u00e9cord de 6,30 metros, el sueco se llevar\u00e1 un total de US$ 220.000, solo contando dos de las 14 marcas que ha conseguido en su carrera. Pero Duplantis no descarta la posibilidad de seguir superando sus l\u00edmites.<\/p>\n<p>\u201cCreo que depende. Si soy honesto, probablemente voy a elevar la vara un cent\u00edmetro m\u00e1s de lo que sea mi registro antes del pr\u00f3ximo Mundial de Atletismo. Esa es la respuesta simple y, probablemente, la respuesta correcta tambi\u00e9n\u201d, dijo Duplantis en Tokio.<\/p>\n<ul>\n<li>6,17 metros &#8211; 8 de febrero de 2020<\/li>\n<li>6,18 metros &#8211; 15 de febrero de 2020<\/li>\n<li>6,19 metros &#8211; 7 de marzo de 2022<\/li>\n<li>6,20 metros &#8211; 20 de marzo de 2022<\/li>\n<li>6,21 metros &#8211; 24 de julio de 2022<\/li>\n<li>6,22 metros &#8211; 25 de febrero de 2023<\/li>\n<li>6,23 metros &#8211; 17 de septiembre de 2023<\/li>\n<li>6,24 metros &#8211; 20 de abril de 2024<\/li>\n<li>6,25 metros &#8211; 5 de agosto de 2024<\/li>\n<li>6,26 metros &#8211; 25 de agosto de 2024<\/li>\n<li>6,27 metros &#8211; 28 de febrero de 2025<\/li>\n<li>6,28 metros &#8211; 15 de junio de 2025<\/li>\n<li>6,29 metros &#8211; 12 de agosto de 2025<\/li>\n<li>6,30 metros &#8211; 15 de septiembre de 2025<\/li>\n<\/ul>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Armand \u201cMondo\u201d Duplantis sigue haciendo historia en la disciplina del salto con p\u00e9rtiga. El sueco de 25 a\u00f1os gan\u00f3 la medalla de oro en el Mundial de Atletismo disputado en Jap\u00f3n y, al mismo tiempo, sum\u00f3 su r\u00e9cord del mundo n\u00famero 14. Desde que super\u00f3 la marca mundial por primera vez el 8 de febrero [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466522","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1nto dinero gan\u00f3 Armand &quot;Mondo&quot; Duplantis por su nueva medalla de oro en el Mundial de Atletismo? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1nto dinero gan\u00f3 Armand &quot;Mondo&quot; Duplantis por su nueva medalla de oro en el Mundial de Atletismo? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Armand \u201cMondo\u201d Duplantis sigue haciendo historia en la disciplina del salto con p\u00e9rtiga. El sueco de 25 a\u00f1os gan\u00f3 la medalla de oro en el Mundial de Atletismo disputado en Jap\u00f3n y, al mismo tiempo, sum\u00f3 su r\u00e9cord del mundo n\u00famero 14. Desde que super\u00f3 la marca mundial por primera vez el 8 de febrero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T20:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfCu\u00e1nto dinero gan\u00f3 Armand &#171;Mondo&#187; Duplantis por su nueva medalla de oro en el Mundial de Atletismo?\",\"datePublished\":\"2025-09-16T20:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/\"},\"wordCount\":556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/\",\"name\":\"\u00bfCu\u00e1nto dinero gan\u00f3 Armand \\\"Mondo\\\" Duplantis por su nueva medalla de oro en el Mundial de Atletismo? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-16T20:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1nto dinero gan\u00f3 Armand &#171;Mondo&#187; Duplantis por su nueva medalla de oro en el Mundial de Atletismo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1nto dinero gan\u00f3 Armand \"Mondo\" Duplantis por su nueva medalla de oro en el Mundial de Atletismo? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1nto dinero gan\u00f3 Armand \"Mondo\" Duplantis por su nueva medalla de oro en el Mundial de Atletismo? - Noticias","og_description":"Armand \u201cMondo\u201d Duplantis sigue haciendo historia en la disciplina del salto con p\u00e9rtiga. El sueco de 25 a\u00f1os gan\u00f3 la medalla de oro en el Mundial de Atletismo disputado en Jap\u00f3n y, al mismo tiempo, sum\u00f3 su r\u00e9cord del mundo n\u00famero 14. Desde que super\u00f3 la marca mundial por primera vez el 8 de febrero [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-16T20:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfCu\u00e1nto dinero gan\u00f3 Armand &#171;Mondo&#187; Duplantis por su nueva medalla de oro en el Mundial de Atletismo?","datePublished":"2025-09-16T20:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/"},"wordCount":556,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/","name":"\u00bfCu\u00e1nto dinero gan\u00f3 Armand \"Mondo\" Duplantis por su nueva medalla de oro en el Mundial de Atletismo? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-16T20:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1nto dinero gan\u00f3 Armand &#171;Mondo&#187; Duplantis por su nueva medalla de oro en el Mundial de Atletismo?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfCu\u00e1nto dinero gan\u00f3 Armand &#171;Mondo&#187; Duplantis por su nueva medalla de oro en el Mundial de Atletismo?","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/16\/armand-mondo-duplantis-record-dinero-atletismo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-16T20:03:38Z","datePublished":"2025-09-16T20:03:38Z","dateModified":"2025-09-16T20:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfCu\\u00e1nto dinero gan\\u00f3 Armand &#171;Mondo&#187; Duplantis por su nueva medalla de oro en el Mundial de Atletismo?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/16\\\/armand-mondo-duplantis-record-dinero-atletismo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/16\\\/armand-mondo-duplantis-record-dinero-atletismo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-16T20:03:38Z\",\"datePublished\":\"2025-09-16T20:03:38Z\",\"dateModified\":\"2025-09-16T20:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465443,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/08\/12\/mondo-duplantis-record-mundial-salto-pertiga-orix\/","url_meta":{"origin":1466522,"position":0},"title":"Mondo Duplantis lo hizo de nuevo: bati\u00f3 el r\u00e9cord mundial de salto con p\u00e9rtiga por 13\u00b0 vez","author":"","date":"agosto 12, 2025","format":false,"excerpt":"El atleta Armand \u201cMondo\u201d Duplantis pronto va a necesitar un libro de r\u00e9cords para \u00e9l solo. Este martes, durante el Gyulai Istv\u00e1n Memorial de Budapest, en Hungr\u00eda, el sueco de 25 a\u00f1os rompi\u00f3 el r\u00e9cord mundial de salto con p\u00e9rtiga por decimotercera vez en su ya muy prol\u00edfica carrera. Fueron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451782,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/12\/recordaremos-juegos-olimpicos-paris-2024-trax\/","url_meta":{"origin":1466522,"position":1},"title":"Lo que siempre recordaremos de los Juegos Ol\u00edmpicos de Par\u00eds 2024","author":"","date":"agosto 12, 2024","format":false,"excerpt":"Par\u00eds (CNN) -- Los Juegos Ol\u00edmpicos de Par\u00eds 2024 fueron realmente incre\u00edbles.Es dif\u00edcil condensar un periodo de dos semanas tan repleto de momentos memorables como estos incre\u00edbles Juegos Ol\u00edmpicos de Par\u00eds, pero \u00e9ste es nuestro mejor intento.Estas son las 12 cosas que siempre recordaremos de los Juegos Ol\u00edmpicos de Verano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466542,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/17\/5-cosas-17-septiembre-orix\/","url_meta":{"origin":1466522,"position":2},"title":"Las 5 cosas que debes saber este 17 de septiembre: asesinato de Kirk, guerra en Gaza y muerte de Robert Redford","author":"","date":"septiembre 17, 2025","format":false,"excerpt":"Palestinos huyen de la Ciudad de Gaza en medio del ataque terrestre de Israel. Petro critic\u00f3 la descertificaci\u00f3n de EE.UU. Astr\u00f3nomos descubren una cuasiluna cerca de la Tierra. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.\ufeffSuscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473328,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/20\/gout-gout-rompe-record-usain-bolt-trax\/","url_meta":{"origin":1466522,"position":3},"title":"Gout Gout, la joven promesa del sprint, rompi\u00f3 uno de los r\u00e9cords de Usain Bolt y recibi\u00f3 un consejo del jamaicano","author":"","date":"abril 20, 2026","format":false,"excerpt":"La leyenda del atletismo Usain Bolt declar\u00f3 a CNN Sports que espera que el joven prodigio Gout Gout \u201cencuentre a las personas adecuadas\u201d a su alrededor, mientras el joven de 18 a\u00f1os contin\u00faa su mete\u00f3rico ascenso en el mundo del atletismo.El australiano ha revolucionado el deporte con una serie de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451608,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/05\/rebeca-andrade-gimnasta-brasilena-derroto-simone-biles-trax\/","url_meta":{"origin":1466522,"position":4},"title":"Qui\u00e9n es Rebeca Andrade, la gimnasta brasile\u00f1a que derrot\u00f3 a Simone Biles","author":"","date":"agosto 5, 2024","format":false,"excerpt":"(CNN) -- Simone Biles, once veces medallista ol\u00edmpica, es dif\u00edcil de batir, pero no imposible.La gimnasta brasile\u00f1a Rebeca Andrade lo demostr\u00f3 al superar a su rival estadounidense en la final de suelo de los Juegos Ol\u00edmpicos de Par\u00eds. Biles se llev\u00f3 la medalla de plata.Fue un momento de catarsis para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465188,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/08\/06\/kenny-bednarek-noah-lyles-empujon-atletismo-trax\/","url_meta":{"origin":1466522,"position":5},"title":"El velocista Kenny Bednarek se reconcili\u00f3 con Noah Lyles tras el empuj\u00f3n, pero espera un &#171;gran espect\u00e1culo&#187; en Polonia","author":"","date":"agosto 6, 2025","format":false,"excerpt":"La estrella de la velocidad Kenny Bednarek dijo a CNN Sports que ha aclarado las cosas con Noah Lyles tras el tenso final de su carrera de 200 metros en el Campeonato de Atletismo de EE.UU.Lyles termin\u00f3 justo por delante de Bednarek en la prueba del domingo, mirando a su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466522"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466522\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}