{"id":1466525,"date":"2025-09-16T14:03:45","date_gmt":"2025-09-16T21:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/"},"modified":"2025-09-16T14:03:45","modified_gmt":"2025-09-16T21:03:45","slug":"bolsonaro-llevado-hospital-brasil-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/","title":{"rendered":"Llevan a Bolsonaro al hospital tras &#171;sentirse mal&#187;, dice su hijo"},"content":{"rendered":"<p>El expresidente de Brasil, Jair Bolsonaro, fue llevado al hospital el martes despu\u00e9s de sentirse mal, seg\u00fan dijo su hijo mayor, el senador Fl\u00e1vio Bolsonaro, en X.<\/p>\n<p>Seg\u00fan su hijo, el exmandatario sufr\u00eda un fuerte ataque de hipo, v\u00f3mitos y presi\u00f3n arterial baja.<\/p>\n<p>\u201cPido las oraciones de todos para que no sea nada grave\u201d, dijo el joven Bolsonaro.<\/p>\n<p>La noticia llega menos de una semana despu\u00e9s de que el expresidente fuera condenado por planear un golpe de Estado, que seg\u00fan los fiscales inclu\u00eda planes para potencialmente asesinar al actual presidente Luiz In\u00e1cio Lula da Silva.<\/p>\n<p>Bolsonaro, de 70 a\u00f1os, fue sentenciado a m\u00e1s de 27 a\u00f1os de prisi\u00f3n. \u00c9l ha negado haber cometido alg\u00fan delito.<\/p>\n<p>El pol\u00edtico de extrema derecha ha sido hospitalizado anteriormente por dolores relacionados con una herida sufrida cuando fue apu\u00f1alado durante la campa\u00f1a electoral hace siete a\u00f1os.<\/p>\n<p>No est\u00e1 claro si su m\u00e1s reciente hospitalizaci\u00f3n est\u00e1 relacionada con ese ataque.<\/p>\n<p>CNN ha contactado al hospital para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El expresidente de Brasil, Jair Bolsonaro, fue llevado al hospital el martes despu\u00e9s de sentirse mal, seg\u00fan dijo su hijo mayor, el senador Fl\u00e1vio Bolsonaro, en X. Seg\u00fan su hijo, el exmandatario sufr\u00eda un fuerte ataque de hipo, v\u00f3mitos y presi\u00f3n arterial baja. \u201cPido las oraciones de todos para que no sea nada grave\u201d, dijo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466525","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Llevan a Bolsonaro al hospital tras &quot;sentirse mal&quot;, dice su hijo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Llevan a Bolsonaro al hospital tras &quot;sentirse mal&quot;, dice su hijo - Noticias\" \/>\n<meta property=\"og:description\" content=\"El expresidente de Brasil, Jair Bolsonaro, fue llevado al hospital el martes despu\u00e9s de sentirse mal, seg\u00fan dijo su hijo mayor, el senador Fl\u00e1vio Bolsonaro, en X. Seg\u00fan su hijo, el exmandatario sufr\u00eda un fuerte ataque de hipo, v\u00f3mitos y presi\u00f3n arterial baja. \u201cPido las oraciones de todos para que no sea nada grave\u201d, dijo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T21:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Llevan a Bolsonaro al hospital tras &#171;sentirse mal&#187;, dice su hijo\",\"datePublished\":\"2025-09-16T21:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/\"},\"wordCount\":212,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/\",\"name\":\"Llevan a Bolsonaro al hospital tras \\\"sentirse mal\\\", dice su hijo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-16T21:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Llevan a Bolsonaro al hospital tras &#171;sentirse mal&#187;, dice su hijo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Llevan a Bolsonaro al hospital tras \"sentirse mal\", dice su hijo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Llevan a Bolsonaro al hospital tras \"sentirse mal\", dice su hijo - Noticias","og_description":"El expresidente de Brasil, Jair Bolsonaro, fue llevado al hospital el martes despu\u00e9s de sentirse mal, seg\u00fan dijo su hijo mayor, el senador Fl\u00e1vio Bolsonaro, en X. Seg\u00fan su hijo, el exmandatario sufr\u00eda un fuerte ataque de hipo, v\u00f3mitos y presi\u00f3n arterial baja. \u201cPido las oraciones de todos para que no sea nada grave\u201d, dijo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-16T21:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/"},"author":{"name":"","@id":""},"headline":"Llevan a Bolsonaro al hospital tras &#171;sentirse mal&#187;, dice su hijo","datePublished":"2025-09-16T21:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/"},"wordCount":212,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/","name":"Llevan a Bolsonaro al hospital tras \"sentirse mal\", dice su hijo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-16T21:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Llevan a Bolsonaro al hospital tras &#171;sentirse mal&#187;, dice su hijo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Llevan a Bolsonaro al hospital tras &#171;sentirse mal&#187;, dice su hijo","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/16\/bolsonaro-llevado-hospital-brasil-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-16T21:03:45Z","datePublished":"2025-09-16T21:03:45Z","dateModified":"2025-09-16T21:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Llevan a Bolsonaro al hospital tras &#171;sentirse mal&#187;, dice su hijo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/16\\\/bolsonaro-llevado-hospital-brasil-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/16\\\/bolsonaro-llevado-hospital-brasil-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-16T21:03:45Z\",\"datePublished\":\"2025-09-16T21:03:45Z\",\"dateModified\":\"2025-09-16T21:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472216,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/15\/funcion-renal-expresidente-jair-bolsonaro-mejora-cuidados-intensivos-ap\/","url_meta":{"origin":1466525,"position":0},"title":"La funci\u00f3n renal de Jair Bolsonaro mejora, pero el expresidente de Brasil sigue en cuidados intensivos","author":"","date":"marzo 15, 2026","format":false,"excerpt":"La funci\u00f3n renal del expresidente de Brasil Jair Bolsonaro mejor\u00f3, pero permanecer\u00e1 en la unidad de cuidados intensivos debido a una neumon\u00eda, seg\u00fan inform\u00f3 este domingo un hospital de la capital del pa\u00eds, Brasilia.El expresidente, de 70 a\u00f1os, tambi\u00e9n ha recibido m\u00e1s antibi\u00f3ticos desde el s\u00e1bado, seg\u00fan un comunicado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461076,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/11\/hospitalizan-expresidente-bolsonaro-brasil-trax\/","url_meta":{"origin":1466525,"position":1},"title":"Hospitalizan al expresidente de Brasil Jair Bolsonaro tras un fuerte dolor abdominal","author":"","date":"abril 11, 2025","format":false,"excerpt":"El expresidente de Brasil Jair Bolsonaro fue hospitalizado tras experimentar un \u201cfuerte dolor abdominal\u201d, seg\u00fan inform\u00f3 este viernes su hijo Carlos en X.Carlos Bolsonaro dijo que su padre fue evaluado por adherencias en el \u00e1rea del abdomen, donde fue apu\u00f1alado en 2018, y fue sedado para que le realizaran pruebas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468605,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/11\/22\/expresidente-brasil-bolsonaro-arrestado-trax\/","url_meta":{"origin":1466525,"position":2},"title":"La polic\u00eda federal arresta a Jair Bolsonaro, expresidente de Brasil, en su domicilio","author":"","date":"noviembre 22, 2025","format":false,"excerpt":"El expresidente de Brasil Jair Bolsonaro fue detenido el s\u00e1bado en su residencia en Brasilia, la capital del pa\u00eds, d\u00edas antes de que comenzara a cumplir una sentencia de prisi\u00f3n por liderar un intento de golpe de Estado, seg\u00fan CNN Brasil, afiliada de CNN.En un comunicado, la Polic\u00eda Federal indic\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469126,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/12\/09\/expresidente-brasileno-encarcelado-jair-bolsonaro-pelicula-trax\/","url_meta":{"origin":1466525,"position":3},"title":"El expresidente de Brasil, Jair Bolsonaro, condenado a 27 a\u00f1os de prisi\u00f3n, ser\u00e1 interpretado por Jim Caviezel en una pel\u00edcula","author":"","date":"diciembre 9, 2025","format":false,"excerpt":"Jair Bolsonaro estar\u00e1 en los cines.No literalmente, ya que el expresidente de Brasil a\u00fan cumple una condena de 27 a\u00f1os de prisi\u00f3n por planear un golpe de Estado para mantenerse en el poder tras perder su reelecci\u00f3n en 2022. Pero una nueva pel\u00edcula sobre su carrera est\u00e1 en camino, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466374,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/11\/brasil-tribunal-mayoria-condena-jair-bolsonaro-orix\/","url_meta":{"origin":1466525,"position":4},"title":"La Justicia de Brasil condena a Jair Bolsonaro a 27 a\u00f1os de prisi\u00f3n por tentativa de golpe de Estado","author":"","date":"septiembre 11, 2025","format":false,"excerpt":"El Supremo Tribunal de Brasil alcanz\u00f3 este jueves una mayor\u00eda de cuatro votos para condenar al expresidente Jair Bolsonaro por liderar un intento de golpe de Estado tras las elecciones de 2022, en un panel de cinco miembros. La Justicia conden\u00f3 al exmandatario a 27 a\u00f1os con tres meses de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468633,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/11\/23\/bolsonaro-policia-detencion-alucinaciones-tobillera-orix\/","url_meta":{"origin":1466525,"position":5},"title":"Bolsonaro fue visto en las instalaciones de la Polic\u00eda Federal un d\u00eda despu\u00e9s de su detenci\u00f3n","author":"","date":"noviembre 23, 2025","format":false,"excerpt":"El expresidente de Brasil Jair Bolsonaro fue visto brevemente este domingo en la entrada de la sede de la Polic\u00eda Federal en Brasilia, un d\u00eda despu\u00e9s de haber sido detenido para evitar lo que las autoridades calificaron como un \u201cintento de fuga\u201d, seg\u00fan im\u00e1genes obtenidas por CNN Brasil.Bolsonaro, que permanece\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466525"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466525\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}