{"id":1466540,"date":"2025-09-17T00:03:56","date_gmt":"2025-09-17T07:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/"},"modified":"2025-09-17T00:03:56","modified_gmt":"2025-09-17T07:03:56","slug":"calor-cambio-climatico-muertes-europa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/","title":{"rendered":"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio"},"content":{"rendered":"<p>El cambio clim\u00e1tico provoc\u00f3 el brutal calor que sufri\u00f3 Europa este verano y caus\u00f3 16.500 muertes adicionales en 854 ciudades, lo que supone m\u00e1s del triple de la cifra de fallecidos, seg\u00fan un an\u00e1lisis publicado este mi\u00e9rcoles por el Imperial College de Londres y la London School of Hygiene &#038; Tropical Medicine.<\/p>\n<p>Los investigadores utilizaron modelos clim\u00e1ticos, datos meteorol\u00f3gicos, datos de mortalidad y m\u00e9todos de investigaci\u00f3n revisados por pares para calcular c\u00f3mo el cambio clim\u00e1tico influy\u00f3 en las temperaturas de cada ciudad y afect\u00f3 al n\u00famero de muertes.<\/p>\n<p>Descubrieron que el cambio clim\u00e1tico gener\u00f3 un aumento de la temperatura de hasta 3,6 grados cent\u00edgrados (6,5 grados Fahrenheit) y fue responsable del 68 % de las 24.400 muertes estimadas por calor este verano. El informe probablemente solo ofrece una instant\u00e1nea del n\u00famero real de muertes, ya que las ciudades analizadas solo representan alrededor del 30 % de la poblaci\u00f3n total de Europa, se\u00f1alaron los investigadores.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cambio clim\u00e1tico provoc\u00f3 el brutal calor que sufri\u00f3 Europa este verano y caus\u00f3 16.500 muertes adicionales en 854 ciudades, lo que supone m\u00e1s del triple de la cifra de fallecidos, seg\u00fan un an\u00e1lisis publicado este mi\u00e9rcoles por el Imperial College de Londres y la London School of Hygiene &#038; Tropical Medicine. Los investigadores utilizaron [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466540","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio - Noticias\" \/>\n<meta property=\"og:description\" content=\"El cambio clim\u00e1tico provoc\u00f3 el brutal calor que sufri\u00f3 Europa este verano y caus\u00f3 16.500 muertes adicionales en 854 ciudades, lo que supone m\u00e1s del triple de la cifra de fallecidos, seg\u00fan un an\u00e1lisis publicado este mi\u00e9rcoles por el Imperial College de Londres y la London School of Hygiene &#038; Tropical Medicine. Los investigadores utilizaron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T07:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio\",\"datePublished\":\"2025-09-17T07:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/\"},\"wordCount\":198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/\",\"name\":\"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-17T07:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio - Noticias","og_description":"El cambio clim\u00e1tico provoc\u00f3 el brutal calor que sufri\u00f3 Europa este verano y caus\u00f3 16.500 muertes adicionales en 854 ciudades, lo que supone m\u00e1s del triple de la cifra de fallecidos, seg\u00fan un an\u00e1lisis publicado este mi\u00e9rcoles por el Imperial College de Londres y la London School of Hygiene &#038; Tropical Medicine. Los investigadores utilizaron [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-17T07:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/"},"author":{"name":"","@id":""},"headline":"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio","datePublished":"2025-09-17T07:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/"},"wordCount":198,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/","name":"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-17T07:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El calor generado por el cambio clim\u00e1tico caus\u00f3 16.500 muertes adicionales en Europa este verano, seg\u00fan un nuevo estudio","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/17\/calor-cambio-climatico-muertes-europa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-17T07:03:56Z","datePublished":"2025-09-17T07:03:56Z","dateModified":"2025-09-17T07:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El calor generado por el cambio clim\\u00e1tico caus\\u00f3 16.500 muertes adicionales en Europa este verano, seg\\u00fan un nuevo estudio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/17\\\/calor-cambio-climatico-muertes-europa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/17\\\/calor-cambio-climatico-muertes-europa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-17T07:03:56Z\",\"datePublished\":\"2025-09-17T07:03:56Z\",\"dateModified\":\"2025-09-17T07:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464350,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/07\/09\/europa-ola-de-calor-muertos-calentamiento-global-trax\/","url_meta":{"origin":1466540,"position":0},"title":"El calor extremo es mortal. Una reciente ola de calor demuestra lo peligroso que se est\u00e1 volviendo","author":"","date":"julio 9, 2025","format":false,"excerpt":"El calor extremo es asesino y su impacto se est\u00e1 volviendo mucho, mucho m\u00e1s letal a medida que la crisis clim\u00e1tica causada por los humanos aumenta las temperaturas, seg\u00fan un nuevo estudio, que estima que el calentamiento global triplic\u00f3 el n\u00famero de muertes en la reciente ola de calor europea.Durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450079,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/","url_meta":{"origin":1466540,"position":1},"title":"El jefe de la ONU dice que el mundo est\u00e1 en la &#171;autopista hacia el infierno clim\u00e1tico&#187;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes","author":"","date":"junio 5, 2024","format":false,"excerpt":"(CNN) -- El planeta acaba de marcar un nuevo hito \"impactante\", al soportar 12 meses consecutivos de calor sin precedentes, seg\u00fan los nuevos datos de Copernicus, el servicio de vigilancia clim\u00e1tica de la Uni\u00f3n Europea.Seg\u00fan los datos de Copernicus, todos los meses comprendidos entre junio de 2023 y mayo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452496,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/09\/06\/verano-mas-caluroso-jamas-registrado-trax\/","url_meta":{"origin":1466540,"position":2},"title":"El planeta vive el verano m\u00e1s caluroso jam\u00e1s registrado por segundo a\u00f1o consecutivo","author":"","date":"septiembre 6, 2024","format":false,"excerpt":"(CNN) -- El verano rompi\u00f3 r\u00e9cords globales de calor por segundo a\u00f1o consecutivo, confirmaron los cient\u00edficos, lo que pone a 2024 firmemente en camino de ser el a\u00f1o m\u00e1s caluroso en la historia registrada.El per\u00edodo entre junio y agosto, verano en el hemisferio norte, fue el m\u00e1s caluroso desde que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464118,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/07\/01\/torre-eiffel-cerrada-calor-temperaturas-europa-trax\/","url_meta":{"origin":1466540,"position":3},"title":"La Torre Eiffel est\u00e1 cerrada a los turistas por el calor mientras las altas temperaturas azotan a Europa","author":"","date":"julio 1, 2025","format":false,"excerpt":"Una ola de calor en el mar Mediterr\u00e1neo se est\u00e1 combinando con una poderosa c\u00fapula de altas temperaturas que hacen que Europa est\u00e9 sofocada.Es un patr\u00f3n que aparece con frecuencia a medida que el planeta se calienta: la influencia de las olas de calor marinas del Mediterr\u00e1neo ha sido m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443423,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/01\/09\/el-calentamiento-global-en-2023-se-acerco-al-limite-que-el-mundo-esta-tratando-de-evitar\/","url_meta":{"origin":1466540,"position":4},"title":"El calentamiento global en 2023 se acerc\u00f3 al l\u00edmite que el mundo est\u00e1 tratando de evitar","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN) -- El calentamiento global en 2023 alcanz\u00f3 los 1,48 grados Celsius, seg\u00fan muestran los datos publicados este martes, mientras el a\u00f1o m\u00e1s caluroso registrado impuls\u00f3 al mundo a solo cent\u00e9simas de grado de un umbral clim\u00e1tico cr\u00edtico.Los an\u00e1lisis del a\u00f1o pasado ya hab\u00edan confirmado que 2023 fue el m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443438,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/01\/09\/el-calentamiento-global-en-2023-se-acerco-al-limite-que-el-mundo-esta-tratando-de-evitar-2\/","url_meta":{"origin":1466540,"position":5},"title":"El calentamiento global en 2023 se acerc\u00f3 al l\u00edmite que el mundo est\u00e1 tratando de evitar","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN) -- El calentamiento global en 2023 alcanz\u00f3 los 1,48 grados Celsius, seg\u00fan muestran los datos publicados este martes, mientras el a\u00f1o m\u00e1s caluroso registrado impuls\u00f3 al mundo a solo cent\u00e9simas de grado de un umbral clim\u00e1tico cr\u00edtico.Los an\u00e1lisis del a\u00f1o pasado ya hab\u00edan confirmado que 2023 fue el m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466540"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466540\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}