{"id":1466581,"date":"2025-09-18T09:03:46","date_gmt":"2025-09-18T16:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/"},"modified":"2025-09-18T09:03:46","modified_gmt":"2025-09-18T16:03:46","slug":"congreso-brasil-proyecto-amnistia-bolsonaro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/","title":{"rendered":"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro"},"content":{"rendered":"<p>La C\u00e1mara de Diputados de Brasil aprob\u00f3 este mi\u00e9rcoles la adopci\u00f3n de un \u201cr\u00e9gimen de urgencia\u201d para la votaci\u00f3n de un proyecto de ley que para concederle amnist\u00eda a los seguidores del expresidente Jair Bolsonaro que asaltaron las sedes de los tres podres en Brasilia en 2023 y que podr\u00eda ser modificado para beneficiar tambi\u00e9n al exmandatario, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/11\/latinoamerica\/brasil-tribunal-mayoria-condena-jair-bolsonaro-orix\">condenado la semana pasada<\/a> por intento de golpe de Estado.<\/p>\n<p>La medida, que env\u00eda directamente el proyecto al pleno de la C\u00e1mara sin pasar por comisi\u00f3n, <a href=\"https:\/\/www.camara.leg.br\/noticias\/1201418-camara-aprova-regime-de-urgencia-para-projeto-sobre-anistia\">fue votada<\/a> por amplia mayor\u00eda (311 a favor, 163 en contra y 7 abstenciones) horas despu\u00e9s de que los m\u00e9dicos de Bolsonaro informen que le diagnosticaron un <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/17\/latinoamerica\/detectan-bolsonaro-cancer-piel-estado-temprano-observacion-efe\">c\u00e1ncer de piel<\/a> en estado temprano.<\/p>\n<p>Varios legisladores de la oposici\u00f3n ven\u00edan pidiendo que la iniciativa de amnist\u00eda tenga prioridad y fue acogida por el presidente de la C\u00e1mara Baja, Hugo Motta.<\/p>\n<p>El texto beneficia a aquellos que participaron en los actos vand\u00e1licos del 8 de enero, pero est\u00e1 sujeto a modificaciones que podr\u00edan extender la amnist\u00eda a otros condenados por golpismo. M\u00e1s de 600 personas han sido sentenciadas por ese asedio.<\/p>\n<p>Motta dijo que este jueves ser\u00e1 nominado un relator (quien podr\u00eda hacer las modificaciones al texto) y sostuvo que buscar\u00e1 construir un proyecto que \u201cbusque la pacificaci\u00f3n nacional y el respeto a las instituciones\u201d.<\/p>\n<p>El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, declar\u00f3 este mi\u00e9rcoles que en caso de que el Congreso apruebe el proyecto y se la env\u00ede para sanci\u00f3n, \u00e9l la vetar\u00e1.<\/p>\n<p>\u201cSi me la env\u00edan para vetar, puede estar seguro de que la vetar\u00e9\u201d, dijo en entrevista con BBC News.<\/p>\n<p>El expresidente, de 70 a\u00f1os, fue condenado a 27 a\u00f1os de c\u00e1rcel por los cargos de tentativa de golpe y organizaci\u00f3n criminal, abolici\u00f3n violenta del Estado democr\u00e1tico de derecho, da\u00f1o al patrimonio p\u00fablico y deterioro de bienes protegidos. El l\u00edder ultraderechista est\u00e1 actualmente bajo prisi\u00f3n domiciliaria y puede apelar la sentencia ante el pleno del Supremo Tribunal Federal.<\/p>\n<p>Bolsonaro fue hospitalizado de urgencia el martes y dado de alta el mi\u00e9rcoles. De acuerdo a los m\u00e9dicos, ingres\u00f3 con un cuadro de \u201canemia persistente y alteraci\u00f3n de la funci\u00f3n renal\u201d, que le causaron una crisis de v\u00f3mitos, mareos y presi\u00f3n baja.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de Diputados de Brasil aprob\u00f3 este mi\u00e9rcoles la adopci\u00f3n de un \u201cr\u00e9gimen de urgencia\u201d para la votaci\u00f3n de un proyecto de ley que para concederle amnist\u00eda a los seguidores del expresidente Jair Bolsonaro que asaltaron las sedes de los tres podres en Brasilia en 2023 y que podr\u00eda ser modificado para beneficiar tambi\u00e9n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466581","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro - Noticias\" \/>\n<meta property=\"og:description\" content=\"La C\u00e1mara de Diputados de Brasil aprob\u00f3 este mi\u00e9rcoles la adopci\u00f3n de un \u201cr\u00e9gimen de urgencia\u201d para la votaci\u00f3n de un proyecto de ley que para concederle amnist\u00eda a los seguidores del expresidente Jair Bolsonaro que asaltaron las sedes de los tres podres en Brasilia en 2023 y que podr\u00eda ser modificado para beneficiar tambi\u00e9n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-18T16:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro\",\"datePublished\":\"2025-09-18T16:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/\",\"name\":\"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-18T16:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro - Noticias","og_description":"La C\u00e1mara de Diputados de Brasil aprob\u00f3 este mi\u00e9rcoles la adopci\u00f3n de un \u201cr\u00e9gimen de urgencia\u201d para la votaci\u00f3n de un proyecto de ley que para concederle amnist\u00eda a los seguidores del expresidente Jair Bolsonaro que asaltaron las sedes de los tres podres en Brasilia en 2023 y que podr\u00eda ser modificado para beneficiar tambi\u00e9n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-18T16:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/"},"author":{"name":"","@id":""},"headline":"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro","datePublished":"2025-09-18T16:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/","name":"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-18T16:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Congreso de Brasil acelera un proyecto de ley de aminist\u00eda que podr\u00eda beneficiar a Jair Bolsonaro","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-18T16:03:46Z","datePublished":"2025-09-18T16:03:46Z","dateModified":"2025-09-18T16:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Congreso de Brasil acelera un proyecto de ley de aminist\\u00eda que podr\\u00eda beneficiar a Jair Bolsonaro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/18\\\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/18\\\/congreso-brasil-proyecto-amnistia-bolsonaro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-18T16:03:46Z\",\"datePublished\":\"2025-09-18T16:03:46Z\",\"dateModified\":\"2025-09-18T16:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469383,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/12\/18\/congreso-brasil-ley-reducir-pena-jair-bolsonaro-efe\/","url_meta":{"origin":1466581,"position":0},"title":"El Congreso de Brasil aprueba el proyecto que busca reducir la pena de Bolsonaro","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"El Senado brasile\u00f1o aprob\u00f3 este mi\u00e9rcoles el proyecto de ley que busca reducir las penas del expresidente ultraderechista Jair Bolsonaro, condenado a 27 a\u00f1os de prisi\u00f3n, y de otros participantes en la conspiraci\u00f3n golpista ocurrida tras las elecciones de 2022.El proyecto, que hab\u00eda sido aprobado la semana pasada en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444638,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/01\/30\/policia-federal-de-brasil-allana-la-casa-de-carlos-bolsonaro-uno-de-los-hijos-del-expresidente-jair-bolsonaro\/","url_meta":{"origin":1466581,"position":1},"title":"Polic\u00eda Federal de Brasil allana la casa de Carlos Bolsonaro, uno de los hijos del expresidente Jair Bolsonaro","author":"","date":"enero 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La Polic\u00eda Federal de Brasil allan\u00f3 este lunes la casa de Carlos Bolsonaro, concejal de la ciudad de R\u00edo de Janeiro y uno de los hijos del expresidente Jair Bolsonaro, dentro del marco de una investigaci\u00f3n sobre una presunta intervenci\u00f3n ilegal de comunicaciones que se habr\u00eda realizado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460504,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/27\/jair-bolsonaro-a-juicio-por-intento-de-golpe-de-estado-el-analisis-de-un-especialista\/","url_meta":{"origin":1466581,"position":2},"title":"Jair Bolsonaro, a juicio por intento de golpe de Estado: el an\u00e1lisis de un especialista","author":"","date":"marzo 27, 2025","format":false,"excerpt":"Thiago de Aragao, analista de pol\u00edtica internacional, habl\u00f3 este jueves desde Washington sobre las acusaciones en contra del expresidente de Brasil Jair Bolsonaro y aclar\u00f3 que \u201cla principal es por tentativa de golpe de Estado\u201d.En tanto, el especialista consider\u00f3 en Regreso CNN que \u201cfue interesante escuchar la defensa de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458886,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/02\/18\/acusan-jair-bolsonaro-brasil-presunto-golpe-de-estado-trax\/","url_meta":{"origin":1466581,"position":3},"title":"Acusan al expresidente de Brasil Jair Bolsonaro en relaci\u00f3n con un presunto intento de golpe de Estado","author":"","date":"febrero 18, 2025","format":false,"excerpt":"El expresidente de Brasil Jair Bolsonaro fue acusado en relaci\u00f3n con un intento de golpe de Estado, seg\u00fan documentos presentados por fiscales este martes por la noche.Bolsonaro estaba entre las 34 personas acusadas de cargos, incluidos los de organizaci\u00f3n criminal armada, intento de abolici\u00f3n violenta del estado de derecho democr\u00e1tico,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447123,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/03\/19\/acusan-expresidente-brasil-jair-bolsonaro-presunto-fraude-datos-vacunacion-covid-19-trax\/","url_meta":{"origin":1466581,"position":4},"title":"Acusan al expresidente de Brasil Jair Bolsonaro de presunto fraude en los datos de vacunaci\u00f3n de covid-19","author":"","date":"marzo 19, 2024","format":false,"excerpt":"(CNN) -- La Polic\u00eda Federal de Brasil acus\u00f3 al expresidente Jair Bolsonaro de presunto fraude despu\u00e9s de que \u00e9l, como presidente, supuestamente ordenara a uno de sus colaboradores m\u00e1s cercanos ingresar datos falsos de vacunaci\u00f3n contra el covid-19 en el sistema del Ministerio de Salud para su beneficio y el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472216,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/15\/funcion-renal-expresidente-jair-bolsonaro-mejora-cuidados-intensivos-ap\/","url_meta":{"origin":1466581,"position":5},"title":"La funci\u00f3n renal de Jair Bolsonaro mejora, pero el expresidente de Brasil sigue en cuidados intensivos","author":"","date":"marzo 15, 2026","format":false,"excerpt":"La funci\u00f3n renal del expresidente de Brasil Jair Bolsonaro mejor\u00f3, pero permanecer\u00e1 en la unidad de cuidados intensivos debido a una neumon\u00eda, seg\u00fan inform\u00f3 este domingo un hospital de la capital del pa\u00eds, Brasilia.El expresidente, de 70 a\u00f1os, tambi\u00e9n ha recibido m\u00e1s antibi\u00f3ticos desde el s\u00e1bado, seg\u00fan un comunicado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466581"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466581\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}