{"id":1466591,"date":"2025-09-18T13:03:40","date_gmt":"2025-09-18T20:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/"},"modified":"2025-09-18T13:03:40","modified_gmt":"2025-09-18T20:03:40","slug":"hamas-gaza-rehenes-nunca-regresen-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/","title":{"rendered":"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen"},"content":{"rendered":"<p>El ala militar de Hamas dijo este jueves que la incursi\u00f3n terrestre del primer ministro de Israel, Benjamin Netanyahu, en la Ciudad de Gaza implicar\u00e1 que Israel pierda cualquier posibilidad de recuperar a sus rehenes del territorio, ya sea vivos o muertos.<\/p>\n<p>En su mensaje m\u00e1s contundente sobre los rehenes desde que el l\u00edder israel\u00ed anunci\u00f3 la operaci\u00f3n militar ampliada en la Ciudad de Gaza el martes, las Brigadas Al-Qassam dijeron que Netanyahu hab\u00eda emitido efectivamente una sentencia de muerte para los rehenes.<\/p>\n<p>En un mensaje escrito en hebreo y dirigido al ej\u00e9rcito y a la dirigencia israel\u00ed, el grupo dijo: \u201cSus prisioneros est\u00e1n distribuidos dentro de los barrios de la Ciudad de Gaza, y no nos preocuparemos por sus vidas si Netanyahu ha decidido matarlos. El inicio de esta operaci\u00f3n criminal y su expansi\u00f3n implica que no recibir\u00e1n a ning\u00fan prisionero, ni vivo ni muerto, y que su destino ser\u00e1 el mismo que el de (Ron Arad)\u201d.<\/p>\n<p>Ron Arad fue un agente de sistemas de armas de la Fuerza A\u00e9rea de Israel que desapareci\u00f3 en acci\u00f3n en 1986 en el L\u00edbano. Se cree que fue capturado por el grupo militar Amal, y que m\u00e1s tarde fue entregado a Hezbollah.<\/p>\n<p>En una declaraci\u00f3n posterior, Hamas dijo que se estaban preparando para luchar y a\u00f1adi\u00f3: \u201cGaza ser\u00e1 un cementerio para sus soldados\u201d.<\/p>\n<p>Mientras tanto, en una sesi\u00f3n informativa con periodistas de este jueves, el portavoz de las Fuerzas de Defensa de Israel (FDI) dijo que \u201clos rehenes siempre est\u00e1n en nuestros pensamientos\u201d y que \u201charemos todo para evitar hacerles da\u00f1o\u201d.<\/p>\n<p>El portavoz de las FDI respond\u00eda a una pregunta de un reportero del Canal 13 que hab\u00eda dicho: \u201cSeg\u00fan informaci\u00f3n recibida por las familias de las FDI, las fuerzas no saben d\u00f3nde se encuentran los rehenes\u201d.<\/p>\n<p>El reportero tambi\u00e9n pidi\u00f3 que las FDI le den garant\u00edas a las familias.<\/p>\n<p>CNN se ha puesto en contacto con la Oficina del Primer Ministro de Israel para recibir comentarios, pero hasta ahora no ha recibido respuestas.<\/p>\n<p>El martes, Israel dijo que lanz\u00f3 una incursi\u00f3n terrestre en la Ciudad de Gaza, aunque testigos presenciales e im\u00e1genes satelitales revelaron que, al menos hasta el mi\u00e9rcoles, los tanques a\u00fan no hab\u00edan entrado en el \u00e1rea central de la ciudad.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ala militar de Hamas dijo este jueves que la incursi\u00f3n terrestre del primer ministro de Israel, Benjamin Netanyahu, en la Ciudad de Gaza implicar\u00e1 que Israel pierda cualquier posibilidad de recuperar a sus rehenes del territorio, ya sea vivos o muertos. En su mensaje m\u00e1s contundente sobre los rehenes desde que el l\u00edder israel\u00ed [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466591","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ala militar de Hamas dijo este jueves que la incursi\u00f3n terrestre del primer ministro de Israel, Benjamin Netanyahu, en la Ciudad de Gaza implicar\u00e1 que Israel pierda cualquier posibilidad de recuperar a sus rehenes del territorio, ya sea vivos o muertos. En su mensaje m\u00e1s contundente sobre los rehenes desde que el l\u00edder israel\u00ed [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-18T20:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen\",\"datePublished\":\"2025-09-18T20:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/\"},\"wordCount\":436,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/\",\"name\":\"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-18T20:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen - Noticias","og_description":"El ala militar de Hamas dijo este jueves que la incursi\u00f3n terrestre del primer ministro de Israel, Benjamin Netanyahu, en la Ciudad de Gaza implicar\u00e1 que Israel pierda cualquier posibilidad de recuperar a sus rehenes del territorio, ya sea vivos o muertos. En su mensaje m\u00e1s contundente sobre los rehenes desde que el l\u00edder israel\u00ed [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-18T20:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/"},"author":{"name":"","@id":""},"headline":"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen","datePublished":"2025-09-18T20:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/"},"wordCount":436,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/","name":"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-18T20:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hamas dice que la incursi\u00f3n terrestre en la Ciudad de Gaza implicar\u00e1 que los rehenes nunca regresen","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/hamas-gaza-rehenes-nunca-regresen-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-18T20:03:40Z","datePublished":"2025-09-18T20:03:40Z","dateModified":"2025-09-18T20:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hamas dice que la incursi\\u00f3n terrestre en la Ciudad de Gaza implicar\\u00e1 que los rehenes nunca regresen\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/18\\\/hamas-gaza-rehenes-nunca-regresen-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/18\\\/hamas-gaza-rehenes-nunca-regresen-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-18T20:03:40Z\",\"datePublished\":\"2025-09-18T20:03:40Z\",\"dateModified\":\"2025-09-18T20:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465746,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/08\/21\/netanyahu-negociaciones-rehenes-mientras-operativos-ciudad-gaza-trax\/","url_meta":{"origin":1466591,"position":0},"title":"Netanyahu ordena &#171;negociaciones inmediatas&#187; para liberar a rehenes mientras Israel avanza en operativos en la Ciudad de Gaza","author":"","date":"agosto 21, 2025","format":false,"excerpt":"El primer ministro Benjamin Netanyahu afirma que orden\u00f3 establecer negociaciones para la liberaci\u00f3n de todos los rehenes y el fin de la guerra en Gaza \u201cen t\u00e9rminos aceptables para Israel\u201d.Las fuerzas israel\u00edes a\u00fan tienen la intenci\u00f3n de avanzar con los planes para tomar el control de la Ciudad de Gaza,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466648,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/20\/director-hospital-gaza-cadaveres-familiares-trax\/","url_meta":{"origin":1466591,"position":1},"title":"El director de un hospital de Gaza recibi\u00f3 durante su servicio los cad\u00e1veres de su hermano y otros familiares","author":"","date":"septiembre 20, 2025","format":false,"excerpt":"El viernes, el Dr. Mohammed Abu Salmiya sali\u00f3 de la casa de su familia para cumplir con su turno como director del hospital Al-Shifa. Un d\u00eda despu\u00e9s, los cad\u00e1veres de seis miembros de su familia llegaron a ese mismo hospital mientras \u00e9l a\u00fan estaba de servicio.Un bombardeo israel\u00ed alcanz\u00f3 su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465827,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/08\/25\/netanyahu-estrategia-alto-el-fuego-hamas-trax\/","url_meta":{"origin":1466591,"position":2},"title":"Siguiendo el ejemplo de Trump, Netanyahu cambia su estrategia sobre el alto el fuego incluso despu\u00e9s de que Hamas lo aceptara","author":"","date":"agosto 25, 2025","format":false,"excerpt":"Casi una semana despu\u00e9s de que Hamas aceptara la \u00faltima propuesta de cese del fuego en Gaza de los mediadores qatar\u00edes y egipcios, Israel a\u00fan no ha respondido, incluso cuando el primer ministro Benjamin Netanyahu afirma que est\u00e1 iniciando \u201cinmediatamente\u201d negociaciones para liberar a todos los rehenes y poner fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445310,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/02\/12\/israel-dice-que-dos-rehenes-fueron-rescatados-de-gaza-en-una-operacion-especial-128-dias-despues-de-su-captura\/","url_meta":{"origin":1466591,"position":3},"title":"Israel dice que dos rehenes fueron rescatados de Gaza en una operaci\u00f3n especial, 128 d\u00edas despu\u00e9s de su captura","author":"","date":"febrero 12, 2024","format":false,"excerpt":"(CNN) -- El ej\u00e9rcito de Israel dijo este lunes que rescat\u00f3 a dos rehenes durante una operaci\u00f3n especial realizada durante la madrugada en Rafah, una ciudad en el sur de Gaza que fue objeto de ataques a\u00e9reos israel\u00edes sostenidos durante toda la madrugada.Los rehenes son Fernando Simon Marman, de 60\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445330,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/02\/12\/israel-dice-que-dos-rehenes-fueron-rescatados-de-gaza-en-una-operacion-especial-128-dias-despues-de-su-captura-2\/","url_meta":{"origin":1466591,"position":4},"title":"Israel dice que dos rehenes fueron rescatados de Gaza en una operaci\u00f3n especial, 128 d\u00edas despu\u00e9s de su captura","author":"","date":"febrero 12, 2024","format":false,"excerpt":"(CNN) -- El ej\u00e9rcito de Israel dijo este lunes que rescat\u00f3 a dos rehenes durante una operaci\u00f3n especial realizada durante la madrugada en Rafah, una ciudad en el sur de Gaza que fue objeto de ataques a\u00e9reos israel\u00edes sostenidos durante toda la madrugada.Los rehenes son Fernando Simon Marman, de 60\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466206,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/06\/trump-rehenes-muerto-recientemente-evacuar-gaza-trax\/","url_meta":{"origin":1466591,"position":5},"title":"Mientras siguen los llamados a evacuar Ciudad de Gaza, Trump dice que algunos rehenes pueden haber &#171;muerto recientemente&#187;","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, dijo que algunos de los 20 rehenes que se presume que est\u00e1n vivos en Gaza pueden haber \u201cmuerto recientemente\u201d, mientras Israel llama a los palestinos que viven en la Ciudad de Gaza a evacuar antes de un asalto amplio a la ciudad m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466591"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466591\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}