{"id":1466601,"date":"2025-09-18T22:03:49","date_gmt":"2025-09-19T05:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/"},"modified":"2025-09-18T22:03:49","modified_gmt":"2025-09-19T05:03:49","slug":"restos-humanos-travis-decker-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/restos-humanos-travis-decker-trax\/","title":{"rendered":"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas"},"content":{"rendered":"<p>Se han encontrado restos humanos que se cree que pertenecen a Travis Decker, el hombre del estado de Washington acusado de matar a sus tres hijas, seg\u00fan la Oficina del Sheriff del Condado de Chelan.<\/p>\n<p>Los restos fueron localizados en una zona boscosa remota al sur de la ciudad de Leavenworth, Washington, dijo la oficina del sheriff en un comunicado obtenido por <a href=\"https:\/\/komonews.com\/news\/local\/human-remains-travis-decker-leavenworth-multi-agency-search-court-documents-evelyn-paityn-olivia-chelan-county-murder-charges-dna-evidence-investigators\">KOMO,<\/a> afiliada de CNN, y compartido con CNN.<\/p>\n<p>\u201cSi bien a\u00fan no se ha confirmado la identificaci\u00f3n positiva, los hallazgos preliminares sugieren que los restos pertenecen a Travis Decker\u201d, se\u00f1ala el comunicado.<\/p>\n<p>CNN se ha comunicado con la Oficina del Sheriff del Condado de Chelan y el Servicio de Alguaciles de EE.UU. para obtener m\u00e1s detalles.<\/p>\n<p>Se ha llevado a cabo una intensa b\u00fasqueda durante meses para encontrar a Decker, acusado de asfixiar a sus tres hijas: Olivia, de 5 a\u00f1os, Evelyn, de 8, y Paityn, de 9. Sus cuerpos fueron encontrados con m\u00faltiples bolsas de pl\u00e1stico sobre la cabeza en un campamento abandonado en el estado de Washington.<\/p>\n<p>Las hermanas hab\u00edan sido reportadas como desaparecidas por su madre d\u00edas antes cuando Decker no logr\u00f3 traerlas a casa el 30 de mayo despu\u00e9s de lo que se supon\u00eda que ser\u00eda una visita de tres horas ordenada por un acuerdo de custodia.<\/p>\n<p>La camioneta de Decker fue encontrada abandonada en la zona del Camping Rock Island, un camping en las Cascadas, <a href=\"https:\/\/www.cnn.com\/2025\/06\/08\/us\/travis-decker-daughters-washington-manhunt\">el 2 de junio<\/a> . Los cuerpos de sus hijas estaban a casi 90 metros de distancia, en un peque\u00f1o terrapl\u00e9n, junto con bridas y bolsas de pl\u00e1stico esparcidas por toda la zona, seg\u00fan una declaraci\u00f3n jurada de la polic\u00eda.<\/p>\n<p>Las muestras de ADN obtenidas de las bolsas y bridas halladas cerca de sus cuerpos coincid\u00edan con el perfil de Decker, seg\u00fan inform\u00f3 la oficina del sheriff. No se encontr\u00f3 ning\u00fan otro ADN en las bolsas ni en las bridas, informaron las autoridades en ese momento.<\/p>\n<p>En las semanas transcurridas desde entonces, funcionarios locales, estatales y federales han <a href=\"https:\/\/www.cnn.com\/2025\/06\/08\/us\/travis-decker-daughters-washington-manhunt\">buscado a Decker , un veterano del ej\u00e9rcito experto en supervivencia en la naturaleza, sin saber si <\/a><a href=\"https:\/\/www.cnn.com\/2025\/06\/28\/us\/travis-decker-manhunt-update\">todav\u00eda<\/a> est\u00e1 vivo .<\/p>\n<p><em>Esta es una historia en desarrollo.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se han encontrado restos humanos que se cree que pertenecen a Travis Decker, el hombre del estado de Washington acusado de matar a sus tres hijas, seg\u00fan la Oficina del Sheriff del Condado de Chelan. Los restos fueron localizados en una zona boscosa remota al sur de la ciudad de Leavenworth, Washington, dijo la oficina [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466601","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se han encontrado restos humanos que se cree que pertenecen a Travis Decker, el hombre del estado de Washington acusado de matar a sus tres hijas, seg\u00fan la Oficina del Sheriff del Condado de Chelan. Los restos fueron localizados en una zona boscosa remota al sur de la ciudad de Leavenworth, Washington, dijo la oficina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-19T05:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas\",\"datePublished\":\"2025-09-19T05:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/\",\"name\":\"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-19T05:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas - Noticias","og_description":"Se han encontrado restos humanos que se cree que pertenecen a Travis Decker, el hombre del estado de Washington acusado de matar a sus tres hijas, seg\u00fan la Oficina del Sheriff del Condado de Chelan. Los restos fueron localizados en una zona boscosa remota al sur de la ciudad de Leavenworth, Washington, dijo la oficina [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-19T05:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/"},"author":{"name":"","@id":""},"headline":"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas","datePublished":"2025-09-19T05:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/","name":"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-19T05:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/18\/restos-humanos-travis-decker-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/restos-humanos-travis-decker-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/restos-humanos-travis-decker-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/18\/restos-humanos-travis-decker-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-19T05:03:49Z","datePublished":"2025-09-19T05:03:49Z","dateModified":"2025-09-19T05:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Encuentran restos humanos que se cree que corresponden a Travis Decker, el hombre acusado de matar a sus tres hijas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/18\\\/restos-humanos-travis-decker-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/18\\\/restos-humanos-travis-decker-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-19T05:03:49Z\",\"datePublished\":\"2025-09-19T05:03:49Z\",\"dateModified\":\"2025-09-19T05:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455058,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/10\/12\/colorado-identifican-restos-humanos-congelador-chica-desaparecida-2005-trax\/","url_meta":{"origin":1466601,"position":0},"title":"Identifican restos humanos hallados en un congelador en Colorado como los de una chica de 16 a\u00f1os desaparecida durante casi 20 a\u00f1os","author":"","date":"octubre 12, 2024","format":false,"excerpt":"(CNN) -- La cabeza y las manos humanas descubiertas en el congelador de una casa de Colorado en enero fueron identificadas como pertenecientes a una chica de 16 a\u00f1os que llevaba casi 20 a\u00f1os desaparecida, seg\u00fan las autoridades locales.Amanda Overstreet fue identificada como la v\u00edctima mediante pruebas de ADN, seg\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444240,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/01\/21\/investigadores-esperan-identificar-la-cabeza-y-las-manos-humanas-halladas-en-el-congelador-de-una-casa-en-colorado\/","url_meta":{"origin":1466601,"position":1},"title":"Investigadores esperan identificar la cabeza y las manos humanas halladas en el congelador de una casa en Colorado","author":"","date":"enero 21, 2024","format":false,"excerpt":"(CNN) -- Las personas que limpiaban el congelador de una casa recientemente vendida en el oeste de Colorado hicieron un espeluznante descubrimiento: una cabeza y unas manos humanas.La Oficina del Sheriff del Condado de Mesa anunci\u00f3 por primera vez el descubrimiento de \"posibles restos humanos\" en un comunicado de prensa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465559,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/08\/16\/rio-mississippi-1967-desaparecido-trax\/","url_meta":{"origin":1466601,"position":2},"title":"Un pescador crey\u00f3 ver un auto en el fondo del r\u00edo Mississippi. Puede que haya ayudado a resolver un caso de 1967","author":"","date":"agosto 16, 2025","format":false,"excerpt":"Dos pescadores de Minnesota hicieron un descubrimiento inesperado en el fondo del r\u00edo Mississippi esta semana, cuando la tecnolog\u00eda de sonar los llev\u00f3 a lo que las autoridades dicen que podr\u00eda ser un avance en un caso sin resolver de varias d\u00e9cadas.Brody Loch, uno de los pescadores, dijo a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448683,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/29\/caso-sussan-morphew-causa-muerte-homicidio-coctel-drogas-trax\/","url_meta":{"origin":1466601,"position":3},"title":"Una mujer de Colorado que desapareci\u00f3 durante un paseo en bicicleta muri\u00f3 por homicidio y ten\u00eda un c\u00f3ctel de drogas en su organismo, seg\u00fan el forense","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN) -- La autopsia realizada a los restos de una mujer de Colorado que desapareci\u00f3 mientras daba un paseo en bicicleta en 2020 y fue hallada muerta tres a\u00f1os despu\u00e9s determin\u00f3 que muri\u00f3 por homicidio y que ten\u00eda en su organismo un c\u00f3ctel de drogas que se utilizan para inmovilizar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452085,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/22\/hombre-arizona-amenazas-trump-trax\/","url_meta":{"origin":1466601,"position":4},"title":"Arrestan a un hombre de Arizona vinculado con amenazas contra el expresidente Donald Trump, seg\u00fan la polic\u00eda","author":"","date":"agosto 22, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un hombre de Arizona que estaba siendo buscado por presuntamente hacer amenazas contra el expresidente Donald Trump ahora est\u00e1 bajo custodia, seg\u00fan la polic\u00eda.Ronald Syvrud, quien est\u00e1 acusado de amenazar con matar a Trump en m\u00faltiples publicaciones en redes sociales durante las \u00faltimas semanas, fue detenido este jueves\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451113,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/15\/hombre-acusado-doble-asesinato-restos-humanos-maletas-puente-reino-unido-trax\/","url_meta":{"origin":1466601,"position":5},"title":"Arrestan a un colombiano acusado de doble asesinato en Reino Unido","author":"","date":"julio 15, 2024","format":false,"excerpt":"(CNN) -- Un hombre fue acusado este lunes de dos cargos de asesinato tras el hallazgo de restos humanos en unas maletas en un emblem\u00e1tico puente del Reino Unido la semana pasada.Seg\u00fan un comunicado de la Polic\u00eda Metropolitana de Londres, los restos humanos eran los de Albert Alfonso, de 62\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466601"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466601\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}