{"id":1466620,"date":"2025-09-19T13:03:50","date_gmt":"2025-09-19T20:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/"},"modified":"2025-09-19T13:03:50","modified_gmt":"2025-09-19T20:03:50","slug":"desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/","title":{"rendered":"Desapariciones en Venezuela no son &#171;irregularidades&#187; sino una &#171;estrategia del Gobierno para mostrar poder&#187;, dice reporte"},"content":{"rendered":"<p>Un <a href=\"https:\/\/rfkhumanrights.org\/wp-content\/uploads\/2025\/09\/Electoral-Repression-Enforced-Disappearances-and-Political-Control-in-Venezuela.pdf\">reciente informe<\/a> de la organizaci\u00f3n estadounidense Robert F. Kennedy Human Rights y la organizaci\u00f3n venezolana Foro Penal revela que la desaparici\u00f3n forzada en Venezuela no es un fen\u00f3meno aislado ni incidental, sino una \u201cestrategia deliberada y adaptativa\u201d del Estado para controlar y reprimir a la oposici\u00f3n, especialmente en el marco de procesos electorales.<\/p>\n<p>El documento \u201cRepresi\u00f3n electoral, desapariciones forzadas y control pol\u00edtico en Venezuela\u201d  establece que esta pr\u00e1ctica est\u00e1 integrada en el sistema pol\u00edtico del pa\u00eds y ha sido \u201ccalibrada\u201d para \u201cneutralizar\u201d a la oposici\u00f3n, fortalecer el control del Gobierno del presidente Nicol\u00e1s Maduro y mostrar poder.<\/p>\n<p>\u201cLas desapariciones forzadas en Venezuela no son un fen\u00f3meno incidental o aislado, sino una estrategia deliberada y adaptativa de represi\u00f3n estatal\u201d, afirma el informe. \u201cLejos de ser el resultado de deficiencias procesales, esta pr\u00e1ctica est\u00e1 incrustada en el orden pol\u00edtico del pa\u00eds y ha sido calibrada a lo largo del tiempo para neutralizar la disidencia, consolidar el control y proyectar fuerza\u201d, agrega.<\/p>\n<p>El documento dice que este <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/13\/venezuela\/derechos-humanos-onu-preocupacion-saab-orix\">patr\u00f3n de represi\u00f3n<\/a> no es producto del azar sino que \u201capunta a su prop\u00f3sito pol\u00edtico\u201d y sostiene que las desapariciones y detenciones se intensifican en momentos de mayor confrontaci\u00f3n pol\u00edtica, como ocurri\u00f3 en las elecciones presidenciales de julio de 2024 y las municipales y parlamentarias de 2025.<\/p>\n<p>El reporte se basa en dos conjuntos de datos recolectados y verificados por Foro Penal, que incluyen testimonios de v\u00edctimas, informaci\u00f3n de familiares y documentaci\u00f3n legal.<\/p>\n<p>Aunque el an\u00e1lisis abarca ese periodo completo, el primer conjunto de datos se centra en una muestra verificada de 96 casos documentados entre el 12 de mayo y el 18 de julio de 2025. Esta muestra, que incluye tanto ciudadanos venezolanos como extranjeros, no busca representar la totalidad de las detenciones, sino ofrecer una visi\u00f3n detallada de c\u00f3mo se desplegaron t\u00e1cticas represivas durante los meses previos a las elecciones.<\/p>\n<p>El segundo conjunto, de 109 casos adicionales, se centra espec\u00edficamente en extranjeros y ciudadanos con doble nacionalidad, quienes han sido objeto de detenci\u00f3n desde julio de 2024 en adelante.<\/p>\n<p>CNN contact\u00f3 al Ministerio de Comunicaci\u00f3n y a la Fiscal\u00eda General de Venezuela para pedir comentarios sobre el informe y est\u00e1 en espera de respuesta. En <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/27\/venezuela\/alto-comisionado-onu-expresa-preocupacion-derechos-humanos-orix\">junio<\/a>, tras otro informe sobre desapariciones forzadas en Venezuela \u2014esta vez de la ONU\u2014, Caracas calific\u00f3 las denuncias de \u201cirresponsables, sesgadas y profundamente polarizadas\u201d, mientras que el fiscal general, Tarek William Saab, afirm\u00f3 que la ONU estaba incurriendo en \u201cuna nueva agresi\u00f3n diplom\u00e1tica e intervencionista contra la soberan\u00eda venezolana y el sistema de justicia\u201d.<\/p>\n<p>En julio, Saab <a href=\"https:\/\/www.swissinfo.ch\/spa\/la-fiscal%c3%ada-de-venezuela-califica-de-%22falso%22-informe-de-ai-sobre-desapariciones-forzadas\/89704359\">calific\u00f3 <\/a>adem\u00e1s como \u201cfalso\u201d un informe de Amnist\u00eda Internacional que sostiene que tras las elecciones presidenciales de 2024 hay \u201celementos del crimen de lesa humanidad de desaparici\u00f3n forzada\u201d. Saab afirm\u00f3 que las acciones del Estado se basan en principios constitucionales que rigen al pa\u00eds sudamericano y en la \u201cdefensa de la paz y la autodeterminaci\u00f3n\u201d.<\/p>\n<p>El informe de las organizaciones Robert F. Kennedy Human Rights y Foro Penal sostiene que estas desapariciones y detenciones no son errores o excesos aislados, sino \u201cuna pol\u00edtica de Estado organizada para sostener un r\u00e9gimen autoritario a trav\u00e9s del miedo y la negaci\u00f3n de derechos\u201d.<\/p>\n<p>M\u00e1s del 85 % de las detenciones se atribuyen a cuatro cuerpos de seguridad: la Direcci\u00f3n General de Contrainteligencia Militar (DGCIM), el Servicio Bolivariano de Inteligencia Nacional (SEBIN), la Polic\u00eda Nacional Bolivariana (PNB) y la Guardia Nacional Bolivariana (GNB). Entre ellos, la DGCIM y el SEBIN son identificados como \u201cpilares perdurables de la represi\u00f3n\u201d, con un rol particularmente creciente del SEBIN en 2025.<\/p>\n<p>Para las v\u00edctimas, la desaparici\u00f3n forzada representa \u201cun ataque profundo a la dignidad y los derechos humanos\u201d, independientemente de su duraci\u00f3n, y el informe resalta que tanto desapariciones breves como prolongadas generan un clima de temor y incertidumbre. Tambi\u00e9n se\u00f1ala que los extranjeros y personas con doble nacionalidad enfrentan da\u00f1os debido a su situaci\u00f3n vulnerable, a menudo sometidos a procesos en idiomas y contextos desconocidos.<\/p>\n<p>Los testimonios y los datos recopilados por las organizaciones indican que esta pr\u00e1ctica se dirige selectivamente contra \u201cgrupos considerados amenazantes para el r\u00e9gimen, periodistas, activistas pol\u00edticos, personal militar y, cada vez m\u00e1s, ciudadanos extranjeros o con doble nacionalidad, cuya detenci\u00f3n tiene peso diplom\u00e1tico\u201d.<\/p>\n<p>Lejos de ser \u201cuna irregularidad procesal\u201d, esta pr\u00e1ctica es \u201cel resultado de una pol\u00edtica estatal que entrelaza la represi\u00f3n con la gobernanza\u201d. Por ello, el informe demanda \u201cno solo documentaci\u00f3n, sino esfuerzos sostenidos de rendici\u00f3n de cuentas a nivel nacional, regional e internacional\u201d.<\/p>\n<p>En este marco, las elecciones de julio de 2024, que ratificaron la segunda reelecci\u00f3n de Nicol\u00e1s Maduro en medio de cuestionamientos de observadores internacionales como el Centro Carter y un panel de expertos de Naciones Unidas, estuvieron acompa\u00f1adas por un aumento en la represi\u00f3n.<\/p>\n<p>La oposici\u00f3n denunci\u00f3 fraude y convoc\u00f3 a protestas, mientras que el Consejo Nacional Electoral y el Tribunal Supremo de Justicia ratificaron la legitimidad del proceso sin presentar las actas electorales.<\/p>\n<p>Este contexto ha sumido a la oposici\u00f3n en una profunda crisis: l\u00edderes perseguidos o exiliados, como Juan Guaid\u00f3, y otros que han debido pasar a la clandestinidad, como Mar\u00eda Corina Machado, quien sostiene que su lucha \u201cse ha trasladado de forma organizada y en resistencia a la clandestinidad\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un reciente informe de la organizaci\u00f3n estadounidense Robert F. Kennedy Human Rights y la organizaci\u00f3n venezolana Foro Penal revela que la desaparici\u00f3n forzada en Venezuela no es un fen\u00f3meno aislado ni incidental, sino una \u201cestrategia deliberada y adaptativa\u201d del Estado para controlar y reprimir a la oposici\u00f3n, especialmente en el marco de procesos electorales. El [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466620","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desapariciones en Venezuela no son &quot;irregularidades&quot; sino una &quot;estrategia del Gobierno para mostrar poder&quot;, dice reporte - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desapariciones en Venezuela no son &quot;irregularidades&quot; sino una &quot;estrategia del Gobierno para mostrar poder&quot;, dice reporte - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un reciente informe de la organizaci\u00f3n estadounidense Robert F. Kennedy Human Rights y la organizaci\u00f3n venezolana Foro Penal revela que la desaparici\u00f3n forzada en Venezuela no es un fen\u00f3meno aislado ni incidental, sino una \u201cestrategia deliberada y adaptativa\u201d del Estado para controlar y reprimir a la oposici\u00f3n, especialmente en el marco de procesos electorales. El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-19T20:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Desapariciones en Venezuela no son &#171;irregularidades&#187; sino una &#171;estrategia del Gobierno para mostrar poder&#187;, dice reporte\",\"datePublished\":\"2025-09-19T20:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/\"},\"wordCount\":950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/\",\"name\":\"Desapariciones en Venezuela no son \\\"irregularidades\\\" sino una \\\"estrategia del Gobierno para mostrar poder\\\", dice reporte - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-19T20:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desapariciones en Venezuela no son &#171;irregularidades&#187; sino una &#171;estrategia del Gobierno para mostrar poder&#187;, dice reporte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desapariciones en Venezuela no son \"irregularidades\" sino una \"estrategia del Gobierno para mostrar poder\", dice reporte - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/","og_locale":"es_ES","og_type":"article","og_title":"Desapariciones en Venezuela no son \"irregularidades\" sino una \"estrategia del Gobierno para mostrar poder\", dice reporte - Noticias","og_description":"Un reciente informe de la organizaci\u00f3n estadounidense Robert F. Kennedy Human Rights y la organizaci\u00f3n venezolana Foro Penal revela que la desaparici\u00f3n forzada en Venezuela no es un fen\u00f3meno aislado ni incidental, sino una \u201cestrategia deliberada y adaptativa\u201d del Estado para controlar y reprimir a la oposici\u00f3n, especialmente en el marco de procesos electorales. El [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/","og_site_name":"Noticias","article_published_time":"2025-09-19T20:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/"},"author":{"name":"","@id":""},"headline":"Desapariciones en Venezuela no son &#171;irregularidades&#187; sino una &#171;estrategia del Gobierno para mostrar poder&#187;, dice reporte","datePublished":"2025-09-19T20:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/"},"wordCount":950,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/","url":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/","name":"Desapariciones en Venezuela no son \"irregularidades\" sino una \"estrategia del Gobierno para mostrar poder\", dice reporte - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-19T20:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Desapariciones en Venezuela no son &#171;irregularidades&#187; sino una &#171;estrategia del Gobierno para mostrar poder&#187;, dice reporte"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Desapariciones en Venezuela no son &#171;irregularidades&#187; sino una &#171;estrategia del Gobierno para mostrar poder&#187;, dice reporte","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/19\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-19T20:03:50Z","datePublished":"2025-09-19T20:03:50Z","dateModified":"2025-09-19T20:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Desapariciones en Venezuela no son &#171;irregularidades&#187; sino una &#171;estrategia del Gobierno para mostrar poder&#187;, dice reporte\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/19\\\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/19\\\/desapariciones-forzadas-venezuela-estrategia-deliberada-del-gobierno-dicen-organizaciones-de-dd-hh\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-19T20:03:50Z\",\"datePublished\":\"2025-09-19T20:03:50Z\",\"dateModified\":\"2025-09-19T20:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461813,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/30\/hrw-asesinatos-desapariciones-forzadas-detenciones-elecciones-orix\/","url_meta":{"origin":1466620,"position":0},"title":"Human Rights Watch denuncia &#171;asesinatos, desapariciones forzadas y detenciones arbitrarias&#187; en Venezuela tras elecciones","author":"","date":"abril 30, 2025","format":false,"excerpt":"La organizaci\u00f3n Human Rights Watch (HRW) denunci\u00f3 que \u201casesinatos, desapariciones forzadas y detenciones arbitrarias\u201d se cometieron en Venezuela despu\u00e9s de las elecciones de 2024, en un informe publicado este mi\u00e9rcoles instando a otros gobiernos a apoyar los esfuerzos para garantizar la responsabilidad de \u201clos perpetradores de violaciones de derechos humanos\u201d.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456582,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/12\/13\/derechos-humanos-onu-preocupacion-saab-orix\/","url_meta":{"origin":1466620,"position":1},"title":"El Alto Comisionado para los Derechos Humanos de la ONU expresa preocupaci\u00f3n por la situaci\u00f3n pol\u00edtica en Venezuela","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"El Alto Comisionado para los Derechos Humanos de la Organizaci\u00f3n de las Naciones Unidas (ONU), Volker T\u00fcrk, dijo estar \u201cprofundamente preocupado\u201d por la situaci\u00f3n pol\u00edtica en Venezuela, a cuatro meses y medio de las controvertidas elecciones presidenciales del 28 de julio y a menos de un mes del comienzo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466165,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/04\/venezolanos-calma-esperanza-tension-eeuu-orix\/","url_meta":{"origin":1466620,"position":2},"title":"En medio de las tensiones con EE.UU., los venezolanos mantienen la calma y siguen adelante mientras susurran esperanzas","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"El trabajo comienza temprano para los pescadores de Chichiriviche de la Costa, un remoto pueblo en la costa caribe\u00f1a de Venezuela, a unas dos horas de carretera sin asfaltar desde la capital, Caracas.El jueves, Eduard Ulloa, de 47 a\u00f1os, lleg\u00f3 a la orilla antes de las seis de la ma\u00f1ana,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460871,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/05\/onu-proceso-desapariciones-forzadas-generalizada-sistematica-orix\/","url_meta":{"origin":1466620,"position":3},"title":"La ONU abre proceso por las desapariciones forzadas en M\u00e9xico que ocurren &#171;de manera generalizada o sistem\u00e1tica&#187;","author":"","date":"abril 5, 2025","format":false,"excerpt":"El Comit\u00e9 contra la Desaparici\u00f3n Forzada de la ONU (CED, por sus siglas en ingl\u00e9s) anunci\u00f3 este viernes que abri\u00f3 un proceso con car\u00e1cter de urgente sobre la situaci\u00f3n de desapariciones forzadas en M\u00e9xico, que podr\u00eda llevar estos casos a la consideraci\u00f3n de la Asamblea General de la ONU.El presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464185,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/07\/03\/ley-desapariciones-forzadas-mexico-registro-biometrico-orix\/","url_meta":{"origin":1466620,"position":4},"title":"M\u00e9xico aprob\u00f3 una reforma a la ley de desaparici\u00f3n forzada. Esto debes saber sobre los registros biom\u00e9tricos","author":"","date":"julio 3, 2025","format":false,"excerpt":"La reforma a la Ley General en Materia de Desaparici\u00f3n Forzada de Personas fue aprobada por el Congreso de M\u00e9xico este lunes con 417 votos a favor y 60 en contra y fue enviada al Ejecutivo para su promulgaci\u00f3n.El paquete legislativo aprobado reforma tambi\u00e9n la Ley General de Poblaci\u00f3n, al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452761,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/09\/17\/venezuela-informe-onu-violaciones-derechos-humanos-orix\/","url_meta":{"origin":1466620,"position":5},"title":"La represi\u00f3n ordenada por Maduro tras las elecciones en Venezuela podr\u00eda constituir cr\u00edmenes contra la humanidad, seg\u00fan un informe de la ONU","author":"","date":"septiembre 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un nuevo informe de la Misi\u00f3n Internacional Independiente de Determinaci\u00f3n de los Hechos de la ONU sobre la Rep\u00fablica Bolivariana de Venezuela afirma que la represi\u00f3n ordenada por el Gobierno del presidente Nicol\u00e1s Maduro entre el 1 de septiembre de 2023 y el 31 de agosto de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466620"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466620\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}