{"id":1466634,"date":"2025-09-19T19:03:39","date_gmt":"2025-09-20T02:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/"},"modified":"2025-09-19T19:03:39","modified_gmt":"2025-09-20T02:03:39","slug":"alcalde-chicago-gas-lacrimogeno-protesta-ice-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/","title":{"rendered":"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE"},"content":{"rendered":"<p>Un alcalde dem\u00f3crata que se postulaba al Congreso por Illinois fue rociado con gas lacrim\u00f3geno la ma\u00f1ana de este viernes durante <a href=\"https:\/\/www.cnn.com\/2025\/09\/17\/politics\/trump-rico-liberal-groups\">una peque\u00f1a protesta<\/a> frente a las instalaciones del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en las afueras de Chicago, seg\u00fan declar\u00f3 \u00e9l mismo.<\/p>\n<p>Al menos otra persona, que <a href=\"https:\/\/x.com\/KatAbughazaleh\/status\/1969086310435430873\">se identific\u00f3 en redes sociales <\/a>como Kat Abughazaleh, una experiodista que tambi\u00e9n se postula para el Congreso, cay\u00f3 al suelo durante el enfrentamiento despu\u00e9s de que un <a href=\"https:\/\/www.cnn.com\/2025\/08\/25\/us\/masks-arrests-ice-tactics-immigration\">agente federal vestido con uniforme de camuflaje,<\/a> con el rostro completamente cubierto, lentes de sol y casco, la empujara, seg\u00fan muestra un video de la cadena WBBM, afiliada de CNN.<\/p>\n<p>Cuando Abughazaleh y otras personas dijeron: \u201cNo pueden secuestrar a nuestros vecinos\u201d, los agentes federales \u201csalieron con toda su fuerza, con equipo de combate completo\u201d, declar\u00f3 a WBBM tras el incidente, y a\u00f1adi\u00f3 que los manifestantes desarmados que llevaban pancartas se encontraron con agentes federales que disparaban bolas de gas pimienta al suelo.<\/p>\n<p>\u201cS\u00ed, voy a tener un moret\u00f3n en el costado, pero nada de lo que estamos viviendo aqu\u00ed se puede comparar con lo que est\u00e1n pasando las personas que est\u00e1n atrapadas en esas instalaciones\u201d, dijo. \u201cNo deber\u00edan estar all\u00ed m\u00e1s de 12 horas. Los retienen durante d\u00edas o semanas. Tenemos que conseguir que lo cierren\u201d.<\/p>\n<p>CNN se puso en contacto con Abughazaleh.<\/p>\n<p>Las instalaciones de la peque\u00f1a ciudad de Broadview han sido objeto de peque\u00f1as protestas <a href=\"https:\/\/www.cnn.com\/2025\/09\/04\/us\/chicago-national-guard-deployment-preparations\">desde que sus dirigentes <\/a>se enteraron a principios de septiembre de que \u201cpronto se pondr\u00e1 en marcha una campa\u00f1a de aplicaci\u00f3n de la ley a gran escala\u201d como parte de la amplia agenda de inmigraci\u00f3n que ayud\u00f3 a asegurar un segundo mandato al presidente Donald Trump, pero a la que <a href=\"https:\/\/www.washingtonpost.com\/politics\/2025\/09\/19\/trump-poll-crime-immigration-economy-tariffs\/\">se oponen la mayor\u00eda de los estadounidenses.<\/a><\/p>\n<p>\u201cEstoy de vuelta en las instalaciones del ICE en Broadview, donde hace unos minutos particip\u00e9 en una protesta\u201d, dice el alcalde de Evanston, Daniel Biss, en un video publicado la ma\u00f1ana del viernes<a href=\"https:\/\/x.com\/DanielBiss\/status\/1969055769568964687\"> en su cuenta de X<\/a>. \u201cNo solo vinieron con armas y violencia, haciendo alarde de su fuerza y embisti\u00e9ndonos con una furgoneta, sino que adem\u00e1s nos lanzaron gases lacrim\u00f3genos, y tengo que decirles que fue aterrador\u201d.<\/p>\n<p>\u201cEra imposible respirar y daba mucho, mucho miedo\u201d, contin\u00faa. \u201cPero la cuesti\u00f3n es que est\u00e1n intentando intimidarnos, impedir que nos levantemos y formemos parte de una resistencia no violenta, y no nos dejaremos intimidar\u201d.<\/p>\n<p>\u201cPero la cuesti\u00f3n es que est\u00e1n tratando de intimidarnos, de impedir que nos levantemos y formemos parte de una resistencia no violenta, y no nos dejaremos intimidar\u201d, contin\u00faa.<\/p>\n<p>El Departamento de Seguridad Nacional conden\u00f3 a los manifestantes: \u201cLos pol\u00edticos desesperados quieren sus 15 minutos de fama y est\u00e1n dispuestos a hacerlo a costa de nuestras fuerzas del orden\u201d,<a href=\"https:\/\/x.com\/DHSgov\/status\/1969058623738306692\"> public\u00f3 la agencia en X <\/a>este viernes, junto a un video de una noticia sobre una protesta contra el ICE en Chicago. \u201cLos est\u00e1n poniendo en mayor riesgo para salir en la televisi\u00f3n, solo para conseguir un tuit viral. Es bastante despreciable\u201d.<\/p>\n<p>Las protestas frente a las instalaciones de Broadview continuaron este viernes al mediod\u00eda, con un grupo peque\u00f1o de manifestantes sosteniendo carteles y tel\u00e9fonos m\u00f3viles frente a una valla rodeada con alambre de p\u00faas, seg\u00fan muestra un video de la escena. Se espera que contin\u00faen durante la noche de este viernes, inform\u00f3 WBBM.<\/p>\n<p>Evanston es un <a href=\"https:\/\/www.cnn.com\/2024\/06\/05\/us\/evanston-reparations-lawsuit-reaj\">basti\u00f3n progresista <\/a>y sede de la Universidad Northwestern, a unos 24 kil\u00f3metros al norte del Loop de Chicago y a unos 48 kil\u00f3metros de Broadview.<\/p>\n<p>CNN se ha puesto en contacto con la oficina de Biss y con ICE.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un alcalde dem\u00f3crata que se postulaba al Congreso por Illinois fue rociado con gas lacrim\u00f3geno la ma\u00f1ana de este viernes durante una peque\u00f1a protesta frente a las instalaciones del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en las afueras de Chicago, seg\u00fan declar\u00f3 \u00e9l mismo. Al menos otra persona, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466634","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un alcalde dem\u00f3crata que se postulaba al Congreso por Illinois fue rociado con gas lacrim\u00f3geno la ma\u00f1ana de este viernes durante una peque\u00f1a protesta frente a las instalaciones del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en las afueras de Chicago, seg\u00fan declar\u00f3 \u00e9l mismo. Al menos otra persona, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-20T02:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE\",\"datePublished\":\"2025-09-20T02:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/\"},\"wordCount\":675,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/\",\"name\":\"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-20T02:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE - Noticias","og_description":"Un alcalde dem\u00f3crata que se postulaba al Congreso por Illinois fue rociado con gas lacrim\u00f3geno la ma\u00f1ana de este viernes durante una peque\u00f1a protesta frente a las instalaciones del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en las afueras de Chicago, seg\u00fan declar\u00f3 \u00e9l mismo. Al menos otra persona, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-20T02:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/"},"author":{"name":"","@id":""},"headline":"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE","datePublished":"2025-09-20T02:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/"},"wordCount":675,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/","name":"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-20T02:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\u00f3geno durante protesta contra ICE","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/19\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-20T02:03:39Z","datePublished":"2025-09-20T02:03:39Z","dateModified":"2025-09-20T02:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Alcalde de un pueblo al oeste de Chicago afirma que agentes federales le lanzaron gas lacrim\\u00f3geno durante protesta contra ICE\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/19\\\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/19\\\/alcalde-chicago-gas-lacrimogeno-protesta-ice-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-20T02:03:39Z\",\"datePublished\":\"2025-09-20T02:03:39Z\",\"dateModified\":\"2025-09-20T02:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467119,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/05\/dhs-agentes-chicago-embistio-vehiculo-policial-trax\/","url_meta":{"origin":1466634,"position":0},"title":"DHS dice que agentes en Chicago dispararon a conductora que &#171;embisti\u00f3 el veh\u00edculo de las fuerzas del orden&#187;","author":"","date":"octubre 5, 2025","format":false,"excerpt":"Agentes federales dispararon a una mujer despu\u00e9s de que embistiera un veh\u00edculo de las fuerzas del orden en Chicago, seg\u00fan el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), en medio de crecientes protestas contra el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459851,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/12\/periodista-argentino-grave-herida-granada-protestas-orix\/","url_meta":{"origin":1466634,"position":1},"title":"Periodista argentino es herido de gravedad por una granada de gas lacrim\u00f3geno en las protestas en Argentina","author":"","date":"marzo 12, 2025","format":false,"excerpt":"El fotorreportero argentino Pablo Grillo result\u00f3 herido de gravedad en una protesta frente al Congreso en Buenos Aires y debi\u00f3 ser operado de urgencia, inform\u00f3 su padre.En un video difundido en redes sociales se ve el momento en el que un hombre con una c\u00e1mara en mano recibe el impacto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467441,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/16\/jueza-respuesta-trump-violencia-chicago-trax\/","url_meta":{"origin":1466634,"position":2},"title":"Jueza exige respuestas al Gobierno de Trump sobre cumplimiento de orden para evitar la violencia con manifestantes en Chicago","author":"","date":"octubre 16, 2025","format":false,"excerpt":"Una jueza de Illinois declar\u00f3 tener \u201cserias preocupaciones\u201d sobre si los agentes federales est\u00e1n cumpliendo con su orden de evitar situaciones violentas con manifestantes y periodistas en Chicago.\u201cFrancamente, estoy un poco sorprendida. Desde el jueves, cuando present\u00e9 la orden de restricci\u00f3n temporal la semana pasada, estoy recibiendo im\u00e1genes y viendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470849,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/04\/agentes-federales-gases-lacrimogenos-protestas-ice-portland-trax\/","url_meta":{"origin":1466634,"position":3},"title":"Los agentes federales deben limitar por ahora gases lacrim\u00f3genos en protestas frente edificio de ICE en Portland, dice juez","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Un juez federal en Oregon restringi\u00f3 temporalmente el martes el uso de gases lacrim\u00f3genos por parte de agentes federales en las protestas en el edificio de Inmigraci\u00f3n y Control de Aduanas en Portland, apenas d\u00edas despu\u00e9s de que los agentes lanzaran gases contra una multitud de manifestantes, incluidos ni\u00f1os peque\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470202,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/17\/familia-minneapolis-gas-lacrimogeno-ice-trax\/","url_meta":{"origin":1466634,"position":4},"title":"Seis ni\u00f1os de una familia de Minneapolis fueron alcanzados por gas lacrim\u00f3geno tras quedar atrapados en protesta contra ICE","author":"","date":"enero 17, 2026","format":false,"excerpt":"Una familia que intentaba regresar a casa despu\u00e9s del partido de baloncesto de su hijo en Minneapolis el mi\u00e9rcoles se encontr\u00f3 entre manifestantes y agentes federales, antes de ser alcanzados por gas lacrim\u00f3geno en su autom\u00f3vil y que la madre tuviera que realizar RCP a su beb\u00e9.Destiny Jackson, de 26\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459878,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/13\/protesta-jubilados-violencia-fotografo-herido-orix\/","url_meta":{"origin":1466634,"position":5},"title":"Qu\u00e9 pas\u00f3 en la protesta de jubilados en Argentina que acab\u00f3 con violencia policial y un fotoperiodista gravemente herido","author":"","date":"marzo 13, 2025","format":false,"excerpt":"Las manifestaciones que se llevaron a cabo este mi\u00e9rcoles frente al Congreso de Argentina en reclamo por los recortes a las pensiones de los jubilados terminaron con cientos de detenidos y decenas de heridos.Ya van varias semanas en las que los d\u00edas mi\u00e9rcoles los jubilados se concentran frente al Congreso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466634"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466634\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}