{"id":1466658,"date":"2025-09-21T00:03:38","date_gmt":"2025-09-21T07:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/"},"modified":"2025-09-21T00:03:38","modified_gmt":"2025-09-21T07:03:38","slug":"gobierno-india-prometio-eliminar-tuberculosis-2025-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/","title":{"rendered":"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien"},"content":{"rendered":"<p>La tos incesante resuena en el suburbio de Govandi, en Mumbai, donde las familias viven hacinadas bajo lonas y madera recuperada. Los estrechos callejones est\u00e1n inundados y sin ventilaci\u00f3n, y aqu\u00ed, en la capital financiera de la India, una enfermedad mortal acecha en cada puerta.<\/p>\n<p>Los m\u00e9dicos en el terreno estiman que la <a href=\"https:\/\/cnnespanol.cnn.com\/2021\/03\/24\/dia-mundial-tuberculosis-sintomas-trax#:~:text=S%C3%ADntomas%3A%20Los%20s%C3%ADntomas%20de%20la,%2C%20fiebre%2C%20escalofr%C3%ADos%20y%20fatiga.\">tuberculosis<\/a> ha infiltrado casi una de cada dos viviendas en este complejo urbano del este, matando a residentes y privando a muchas familias de su sustento.<\/p>\n<p>La crisis local es un microcosmos de una crisis nacional de salud. India alberga el 27 % de los <a href=\"https:\/\/cnnespanol.cnn.com\/video\/tuberculosis-salud-epidemia-paises-afectados-mundo-perspectivas-buenos-aires\">casos de tuberculosis del mundo<\/a> y registra un promedio de dos muertes relacionadas con esta enfermedad infecciosa cada tres minutos, seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS).<\/p>\n<p>El Gobierno se ha comprometido a eliminar la enfermedad para finales de este a\u00f1o, pero los expertos dicen que esa meta est\u00e1 peligrosamente fuera de alcance, debido a las deficiencias del sistema de salud y las barreras socioecon\u00f3micas que frenan los esfuerzos.<\/p>\n<p>Mehboob Sheikh fue diagnosticado con tuberculosis hace seis meses, m\u00e1s de una d\u00e9cada despu\u00e9s de que su esposa muriera por la enfermedad. Para \u00e9l, las realidades de vivir con ella son demasiado tangibles.<\/p>\n<p>\u201cHe perdido mucho peso, apenas puedo caminar ahora y me quedo sin aliento si hablo mucho\u201d, le dijo a CNN, su rostro demacrado y ojos hundidos son s\u00edntomas de su situaci\u00f3n.<\/p>\n<p>La enfermedad ya le cost\u00f3 su trabajo en una imprenta: la fatiga y debilidad constantes le impidieron soportar los largos turnos de pie. Sheikh ha estado en un tratamiento prolongado de antibi\u00f3ticos durante nueve meses, pero a solo tres meses de terminar, su cuerpo sigue fr\u00e1gil. Cualquier se\u00f1al de recuperaci\u00f3n es dif\u00edcil de ver.<\/p>\n<p>Sus hijos \u2014desnutridos, vulnerables y demasiado peque\u00f1os para entender\u2014 rondan cerca mientras \u00e9l tose.<\/p>\n<p>Antes ganaba 15.000 rupias (US$ 171) al mes; ahora lucha por pagar las cuotas escolares de sus hijos.<\/p>\n<p>\u201cSi mi cuerpo resiste, seguir\u00e9 viviendo. Si no\u2026 ese ser\u00e1 el final\u201d.<\/p>\n<p>En 2018, el primer ministro Narendra Modi sorprendi\u00f3 a los c\u00edrculos de salud globales al comprometerse a eliminar la tuberculosis para 2025, cinco a\u00f1os antes de la meta global de la OMS. Eliminar significa reducir los nuevos casos de tuberculosis en un 80 % y las muertes en un 90 % en comparaci\u00f3n con los niveles de 2015.<\/p>\n<p>Los expertos consideraron la meta del Gobierno para 2025 como un desaf\u00edo monumental y, a pocos meses de la fecha l\u00edmite, la tuberculosis sigue siendo una de las crisis de salud p\u00fablica m\u00e1s persistentes de la India.<\/p>\n<p>Seg\u00fan los expertos, la lucha de la India contra la enfermedad se ve impulsada por una potente combinaci\u00f3n de biolog\u00eda, pobreza y deficiencias sist\u00e9micas en el sistema de salud.<\/p>\n<p>\u201cSomos una naci\u00f3n con alta carga de la enfermedad\u201d, dijo el Dr. Lancelot Pinto, experto en pulmones y sistema respiratorio, en Mumbai. \u201cNo necesariamente tenemos todos los recursos necesarios para ampliar y eliminar la tuberculosis para 2025\u201d.<\/p>\n<p>La bacteria que causa la enfermedad, Mycobacterium tuberculosis, ha perseguido a la humanidad durante milenios, con rastros encontrados en momias egipcias. Puede permanecer inactiva dentro del cuerpo durante a\u00f1os y desarrollar resistencia a los medicamentos, lo que dificulta su erradicaci\u00f3n.<\/p>\n<p>La enfermedad prospera en los sectores densamente poblados y empobrecidos de la India, donde las personas tienen poco acceso a atenci\u00f3n m\u00e9dica constante.<\/p>\n<p>Despu\u00e9s de 10 a\u00f1os trabajando en Govandi, la trabajadora de la salud Pramila Pramod dice que el n\u00famero de pacientes con tuberculosis que ve cada mes se ha mantenido igual.<\/p>\n<p>Los callejones del suburbio crean la v\u00eda de transmisi\u00f3n perfecta, sin ventilaci\u00f3n cruzada, desag\u00fces abiertos obstruidos con basura y familias de seis personas hacinadas en una sola habitaci\u00f3n. El miedo al estigma social hace que algunos pacientes oculten el diagn\u00f3stico a sus vecinos, escuelas e incluso a sus c\u00f3nyuges.<\/p>\n<p>\u201cA veces hay una joven en edad de casarse. Sus padres no le dicen a nadie que tiene tuberculosis\u201d, dijo Pramod, quien es voluntaria en Alert India, una organizaci\u00f3n no gubernamental que trabaja con personas afectadas por enfermedades infecciosas. \u201c\u00bfC\u00f3mo van a encontrarle un esposo si no?\u201d, recuerda que le preguntan.<\/p>\n<p>Esta vulnerabilidad se agrava por un sistema de salud en crisis, donde el sector p\u00fablico sufre d\u00e9cadas de falta de inversi\u00f3n, escasez de personal e instalaciones obsoletas. El vasto pero no regulado sector privado del pa\u00eds, aunque brinda servicios esenciales y cruciales, puede ser costoso de acceder.<\/p>\n<p>La estrategia de diagn\u00f3stico de la India es otro gran obst\u00e1culo. Casi tres cuartas partes de los diagn\u00f3sticos a\u00fan dependen de la microscop\u00eda de esputo, un m\u00e9todo introducido hace unos 140 a\u00f1os, que puede pasar por alto casos activos. Las pruebas moleculares m\u00e1s modernas \u2014que detectan con precisi\u00f3n el ADN de la bacteria\u2014 se utilizan en poco m\u00e1s de 1 de cada 4 diagn\u00f3sticos, seg\u00fan Pinto.<\/p>\n<p>Esta brecha significa que innumerables infecciones quedan sin tratar y cepas peligrosas y resistentes a los medicamentos se propagan sin ser detectadas. \u201cAs\u00ed que, a menos que detectemos y tratemos de manera proactiva \u2014no solo esperando los s\u00edntomas\u2014 seguiremos perdiendo casos\u201d, dijo Pinto.<\/p>\n<p>Dolores en el pecho, fiebre, fuertes dolores de cabeza y escalofr\u00edos atormentaron a Sufiya Syed, de 15 a\u00f1os, durante m\u00e1s de un a\u00f1o antes de que los m\u00e9dicos finalmente la diagnosticaran hace dos meses.<\/p>\n<p>Mientras la tuberculosis se apoderaba de su cuerpo, su peso baj\u00f3 de 40 a 25 kilos. Durante ese tiempo, segu\u00eda yendo a la escuela. Ahora, dice que no puede concentrarse en sus estudios, con n\u00e1useas y noches sin dormir que dejan a su cuerpo luchando por combatir la enfermedad.<\/p>\n<p>\u201cCada d\u00eda cuando me despierto, siento que me voy a desmayar y que todo se pone negro\u201d, dijo. \u201cA veces no tengo comida durante cuatro o cinco d\u00edas. Mi mam\u00e1 me obliga a comer\u201d.<\/p>\n<p>El Gobierno ha intensificado los esfuerzos ofreciendo pruebas gratuitas de tuberculosis y medicamentos a trav\u00e9s de centros de salud p\u00fablicos, con el objetivo de garantizar un diagn\u00f3stico y tratamiento temprano, llegando incluso a las poblaciones m\u00e1s vulnerables.<\/p>\n<p>Se han logrado algunos avances.<\/p>\n<p>India ha reducido los casos en un 17,7 % desde 2015, casi el doble del promedio mundial de disminuci\u00f3n, y las muertes han bajado de 28 a 22 por cada 100.000 personas, seg\u00fan datos del Ministerio de Salud y Bienestar Familiar de la India.<\/p>\n<p>Pero, a solo meses de la fecha l\u00edmite del Gobierno a finales de 2025, su promesa se est\u00e1 desmoronando.<\/p>\n<p>Grandes desaf\u00edos, como la escasez de personal para mantener un tratamiento integral, la vulnerabilidad en el mapeo de \u00e1reas de alto riesgo y la baja b\u00fasqueda de atenci\u00f3n m\u00e9dica, han permitido que la enfermedad persista, seg\u00fan un informe parlamentario de 2023 sobre el impulso de erradicaci\u00f3n del Gobierno.<\/p>\n<p>La pandemia de covid-19 empeor\u00f3 la situaci\u00f3n. Los confinamientos detuvieron los ex\u00e1menes, interrumpieron el suministro de medicamentos y desviaron a los trabajadores de la salud, seg\u00fan el informe.<\/p>\n<p>CNN ha contactado a la Direcci\u00f3n General de Servicios de Salud del gobierno indio para obtener una respuesta.<\/p>\n<p>Durante a\u00f1os, diagnosticar la tuberculosis en las comunidades remotas de la India ha sido una carrera perdida contra el tiempo, donde las grandes distancias a las cl\u00ednicas, la escasez cr\u00f3nica de radi\u00f3logos y la dependencia de pruebas de esputo obsoletas permit\u00edan que las infecciones pasaran desapercibidas, a menudo hasta que estaban peligrosamente avanzadas.<\/p>\n<p>Desde 1998, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/03\/mundo\/que-es-usaid-paises-financia-orix\">USAID<\/a> ha cubierto parte de la brecha en la lucha contra la tuberculosis en la India, canalizando m\u00e1s de US$ 140 millones para financiar redes comunitarias en los rincones m\u00e1s dif\u00edciles de alcanzar del pa\u00eds. Pero los recientes recortes de fondos estadounidenses han amenazado con deshacer estos logros arduamente conseguidos.<\/p>\n<p>Aunque no ha reconocido p\u00fablicamente el d\u00e9ficit, la India aument\u00f3 los presupuestos nacionales y est\u00e1 desplegando un arsenal de nuevas herramientas, como radiograf\u00edas impulsadas por inteligencia artificial, unidades m\u00f3viles de pruebas y drones que transportan muestras.<\/p>\n<p>La inteligencia artificial se utiliza cada vez m\u00e1s para acelerar la lucha contra la tuberculosis. Herramientas como el software de radiograf\u00edas de t\u00f3rax de Qure.ai pueden escanear r\u00e1pidamente im\u00e1genes pulmonares y se\u00f1alar a los pacientes que podr\u00edan tener tuberculosis activa, un paso crucial en pa\u00edses donde los radi\u00f3logos capacitados son escasos.<\/p>\n<p>Las pruebas confirmatorias que analizan el esputo o detectan la tuberculosis a nivel molecular son m\u00e1s precisas, pero requieren laboratorios, equipos y tiempo, recursos que a menudo no est\u00e1n disponibles en los barrios marginales y zonas rurales de la India. Integradas en m\u00e1quinas port\u00e1tiles, las radiograf\u00edas impulsadas por inteligencia artificial ayudan a cerrar esa brecha al identificar posibles casos de tuberculosis, permitiendo que los trabajadores de la salud remitan r\u00e1pidamente a esos pacientes para pruebas confirmatorias, reduciendo los retrasos que a menudo cuestan vidas.<\/p>\n<p>Sin embargo, los expertos en salud advierten de que estos esc\u00e1neres no diagnostican la tuberculosis ni revelan si la enfermedad es sensible o resistente a los medicamentos. En cambio, funcionan como una herramienta de detecci\u00f3n y triaje: identifican casos antes, reducen el n\u00famero de casos que se pierden con los controles b\u00e1sicos de s\u00edntomas y aseguran que los pacientes sean remitidos para pruebas adecuadas de esputo o moleculares antes de iniciar el tratamiento.<\/p>\n<p>Esa rapidez y alcance son importantes en la India, el pa\u00eds m\u00e1s poblado del mundo, donde las condiciones de hacinamiento hacen que la detecci\u00f3n temprana sea crucial para detener la propagaci\u00f3n de la tuberculosis.<\/p>\n<p>\u201cEstas m\u00e1quinas pesan menos de 3,5 kilos y se pueden llevar en una mochila\u201d, dijo el director m\u00e9dico de salud global de Qure.ai, el Dr. Shibu Vijayan. \u201cFuncionan con bater\u00edas, as\u00ed que puedes examinar a toda una comunidad en un d\u00eda sin necesidad de electricidad\u201d.<\/p>\n<p>Los dispositivos est\u00e1n facilitando el acceso a personas que de otro modo quedar\u00edan fuera del sistema. En la capital, Nueva Delhi, por ejemplo, la Clinton Health Access Initiative ha desplegado m\u00e1s de 30 m\u00e1quinas del tama\u00f1o de una mochila en \u00e1reas de dif\u00edcil acceso, y cientos m\u00e1s en todo el pa\u00eds.<\/p>\n<p>\u201cSabemos que ciertos grupos son los m\u00e1s vulnerables: habitantes de barrios marginales, trabajadores migrantes, personas expuestas al polvo\u201d, dijo Vijayan. \u201cLas peque\u00f1as radiograf\u00edas hacen posible ofrecerles pruebas en sus propias comunidades\u201d.<\/p>\n<p>El costo es otro avance: las unidades port\u00e1tiles cuestan la mitad que las m\u00e1quinas tradicionales de rayos X de hospital.<\/p>\n<p>El Gobierno indio ha adoptado este enfoque, incorporando la detecci\u00f3n con inteligencia artificial en su estrategia nacional. Ha realizado casi 5 millones de radiograf\u00edas con estos dispositivos, seg\u00fan Vijayan, y las autoridades est\u00e1n adquiriendo m\u00e1s equipos.<\/p>\n<p>\u201cTener la meta y alinear las acciones es tan importante como cumplir el plazo\u201d, dijo Pinto. \u201cMientras nos lleve en la direcci\u00f3n correcta, debemos considerar estas peque\u00f1as victorias como verdaderos logros y esforzarnos a\u00fan m\u00e1s\u201d.<\/p>\n<p>Pero para personas como Sheikh, hay poco que celebrar.<\/p>\n<p>Contin\u00faa su tratamiento gratuito en un hospital p\u00fablico cada mes, con la ayuda de su hijo para llevar los medicamentos a casa. Pero la ayuda termina ah\u00ed. Dice que no ha recibido la asistencia econ\u00f3mica mensual a la que tienen derecho los pacientes con tuberculosis como parte de un programa federal.<\/p>\n<p>\u201cNadie ha venido a ayudarnos\u201d, dijo. \u201cNo me queda dinero. Tengo que mantenerme y alimentarme mientras est\u00e9 vivo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tos incesante resuena en el suburbio de Govandi, en Mumbai, donde las familias viven hacinadas bajo lonas y madera recuperada. Los estrechos callejones est\u00e1n inundados y sin ventilaci\u00f3n, y aqu\u00ed, en la capital financiera de la India, una enfermedad mortal acecha en cada puerta. Los m\u00e9dicos en el terreno estiman que la tuberculosis ha [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466658","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien - Noticias\" \/>\n<meta property=\"og:description\" content=\"La tos incesante resuena en el suburbio de Govandi, en Mumbai, donde las familias viven hacinadas bajo lonas y madera recuperada. Los estrechos callejones est\u00e1n inundados y sin ventilaci\u00f3n, y aqu\u00ed, en la capital financiera de la India, una enfermedad mortal acecha en cada puerta. Los m\u00e9dicos en el terreno estiman que la tuberculosis ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-21T07:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien\",\"datePublished\":\"2025-09-21T07:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/\"},\"wordCount\":1992,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/\",\"name\":\"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-21T07:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien - Noticias","og_description":"La tos incesante resuena en el suburbio de Govandi, en Mumbai, donde las familias viven hacinadas bajo lonas y madera recuperada. Los estrechos callejones est\u00e1n inundados y sin ventilaci\u00f3n, y aqu\u00ed, en la capital financiera de la India, una enfermedad mortal acecha en cada puerta. Los m\u00e9dicos en el terreno estiman que la tuberculosis ha [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-21T07:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien","datePublished":"2025-09-21T07:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/"},"wordCount":1992,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/","name":"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-21T07:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de este pa\u00eds prometi\u00f3 eliminar la tuberculosis para finales de 2025. No est\u00e1 yendo bien","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/21\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-21T07:03:38Z","datePublished":"2025-09-21T07:03:38Z","dateModified":"2025-09-21T07:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de este pa\\u00eds prometi\\u00f3 eliminar la tuberculosis para finales de 2025. No est\\u00e1 yendo bien\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/21\\\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/21\\\/gobierno-india-prometio-eliminar-tuberculosis-2025-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-21T07:03:38Z\",\"datePublished\":\"2025-09-21T07:03:38Z\",\"dateModified\":\"2025-09-21T07:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460605,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/30\/tuberculosis-infecciosa-muerte-fondos-usaid-trump-trax\/","url_meta":{"origin":1466658,"position":0},"title":"La tuberculosis es la principal causa infecciosa de muerte en el mundo. La congelaci\u00f3n de fondos podr\u00eda empeorar el escenario","author":"","date":"marzo 30, 2025","format":false,"excerpt":"Cuando los trabajadores de la salud dejaron de visitar su casa en Pakist\u00e1n para administrarle medicamentos contra la tuberculosis, Ratna Jamni comenz\u00f3 a arrastrarse hasta una cl\u00ednica \u201cpaso a paso con dolor, cuando incluso permanecer de pie se siente imposible\u201d.El hombre de 40 a\u00f1os hab\u00eda estado recibiendo tratamiento y apoyo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465054,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/08\/01\/trasladan-prision-401-presos-tuberculosis-ecuador-orix\/","url_meta":{"origin":1466658,"position":1},"title":"Trasladan de una prisi\u00f3n a otra a 401 presos con tuberculosis en Ecuador","author":"","date":"agosto 1, 2025","format":false,"excerpt":"Autoridades de seguridad y sanitarias de Ecuador reubicaron de una prisi\u00f3n a otra a 401 presos diagnosticados con tuberculosis, inform\u00f3 este viernes el Servicio Nacional de Atenci\u00f3n Integral a Personas Adultas Privadas de la Libertad y a Adolescentes Infractores (SNAI).Entre el 28 y el 31 de julio, los internos fueron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469354,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/12\/17\/hacinamiento-tuberculosis-carceles-ecuador-orix\/","url_meta":{"origin":1466658,"position":2},"title":"Hacinamiento, tuberculosis y violencia: el peligroso combo que afecta a las c\u00e1rceles de Ecuador y provoca decenas de muertes","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Al menos 30 presos murieron en una c\u00e1rcel del sur de Ecuador el pasado 9 de noviembre por presunta asfixia. Apenas un mes despu\u00e9s, en la misma prisi\u00f3n se registraron 13 muertes luego de la explosi\u00f3n de un artefacto en los exteriores del centro sin que se aclare su conexi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458903,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/02\/19\/neumonologo-asegura-que-el-papa-francisco-tiene-dos-problemas-que-complican-y-aumentan-el-riesgo-de-una-neumonia-grave\/","url_meta":{"origin":1466658,"position":3},"title":"Neumon\u00f3logo asegura que el papa Francisco &#171;tiene dos problemas que complican y aumentan el riesgo de una neumon\u00eda grave&#187;","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Carlos Luna, neumon\u00f3logo (MN 46.388) explic\u00f3 qu\u00e9 es una neumon\u00eda bilateral, c\u00f3mo es su tratamiento y las complejidades que puede tener en una persona como el papa Francisco, que tiene 88 a\u00f1os y una operaci\u00f3n pulmonar en la juventud.En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201cla neumon\u00eda es una infecci\u00f3n bastante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462159,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/05\/09\/carlos-regazzoni-exdirector-del-pami-los-problemas-financieros-son-muy-serios\/","url_meta":{"origin":1466658,"position":4},"title":"Carlos Regazzoni, exdirector del PAMI: &#171;Los problemas financieros son muy serios&#187;","author":"","date":"mayo 9, 2025","format":false,"excerpt":"Carlos Regazzoni, m\u00e9dico y exdirector Ejecutivo del PAMI, se refiri\u00f3 a algunas de las enfermedades que m\u00e1s preocupan al sistema sanitario y analiz\u00f3 la situaci\u00f3n de la obra social de los jubilados, luego de la denuncia de una exfuncionaria que asegura haber sido v\u00edctima de un sistema corrupto que exige\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459835,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/12\/dia-mundial-del-glaucoma-una-enfermedad-silenciosa-que-puede-causar-ceguera\/","url_meta":{"origin":1466658,"position":5},"title":"D\u00eda Mundial del Glaucoma: una enfermedad silenciosa que puede causar ceguera","author":"","date":"marzo 12, 2025","format":false,"excerpt":"Gerardo Valvecchia, oftalm\u00f3logo y embajador en Latinoam\u00e9rica de la Fundaci\u00f3n Elena Barraquer, habl\u00f3 este mi\u00e9rcoles en CNN Radio sobre su lucha contra la ceguera y aclar\u00f3 que \u201choy control\u00e1ndolo y con tratamiento nadie deber\u00eda quedarse ciego\u201d.\u201cHay chicos que nacen con glaucoma, pero no es lo habitual. Es m\u00e1s com\u00fan que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466658"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466658\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}