{"id":1466680,"date":"2025-09-22T04:03:51","date_gmt":"2025-09-22T11:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/"},"modified":"2025-09-22T04:03:51","modified_gmt":"2025-09-22T11:03:51","slug":"trump-leyes-migratorias-ia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/","title":{"rendered":"&#171;Como Prime, pero con seres humanos&#187;: C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias"},"content":{"rendered":"<p>La administraci\u00f3n Trump est\u00e1 ampliando dr\u00e1sticamente el uso de inteligencia artificial en la aplicaci\u00f3n de leyes migratorias, utilizando la tecnolog\u00eda no s\u00f3lo para rastrear a los migrantes sino tambi\u00e9n para ayudar a determinar qui\u00e9nes son objeto de deportaci\u00f3n.<\/p>\n<p>Para impulsar la aplicaci\u00f3n de las leyes migratorias \u2014una <a href=\"https:\/\/www.cnn.com\/2025\/08\/28\/politics\/ice-deportations-immigrants-trump\">prioridad pol\u00edtica fundamental<\/a> para el presidente Donald Trump\u2014, la administraci\u00f3n est\u00e1 implementando algoritmos de inteligencia artificial para analizar una amplia gama de registros. Los funcionarios dicen que estas herramientas pueden identificar posibles infracciones, priorizar pistas y orientar a los agentes sobre los siguientes pasos, acelerando procesos que antes depend\u00edan de revisiones manuales m\u00e1s lentas.<\/p>\n<p>El director interino de Inmigraci\u00f3n y Control de Aduanas, Todd Lyons, describi\u00f3 una visi\u00f3n de escuadrones de camiones recogiendo inmigrantes con la eficiencia de las rutas de entrega de Amazon: \u201cComo Prime, pero con seres humanos\u201d, dijo en abril durante la Expo de Seguridad Fronteriza en Phoenix.<\/p>\n<p>ImmigrationOS, una nueva plataforma que consolida estas herramientas en una \u00fanica interfaz, impulsa esta visi\u00f3n. El sistema, que el DHS empezar\u00e1 a utilizar este jueves, incluye flujos de trabajo que permiten a los agentes aprobar redadas, registrar arrestos, generar documentos legales y dirigir a las personas a vuelos de deportaci\u00f3n o centros de detenci\u00f3n, todo desde un mismo lugar.<\/p>\n<p>\u201cNo solo recopila datos: tambi\u00e9n estructura lo que los agentes hacen con ellos\u201d, dijo un alto funcionario del DHS.<\/p>\n<p>Si bien parte de la tecnolog\u00eda se ha utilizado previamente de forma fragmentada en iniciativas de inmigraci\u00f3n, la escala de este proyecto no tiene precedentes. El sistema tambi\u00e9n se nutre de fuentes de datos tradicionalmente ajenas a la inmigraci\u00f3n, como los Informes de Actividades Sospechosas y las transacciones financieras se\u00f1aladas bajo la Ley de Secreto Bancario. Estas herramientas, m\u00e1s com\u00fanmente empleadas en casos de antiterrorismo o blanqueo de capitales, ahora se est\u00e1n reutilizando para identificar posibles objetivos de las autoridades migratorias, desde personas sospechosas de fraude de identidad hasta quienes trabajan sin autorizaci\u00f3n.<\/p>\n<p>Algunos expertos advierten de que la creciente dependencia de algoritmos opacos plantea serias preocupaciones. El sesgo, la extralimitaci\u00f3n y la reducci\u00f3n de la supervisi\u00f3n humana son posibles, especialmente a medida que el Departamento de Seguridad Nacional intensifica las deportaciones y los decretos <a href=\"https:\/\/www.cnn.com\/2025\/07\/23\/tech\/ai-action-plan-trump\">impulsan la adopci\u00f3n de la IA,<\/a> al tiempo que desmantelan los llamados sistemas \u201cwoke\u201d o regulados.<\/p>\n<p>\u201cLo que estamos observando en estos pr\u00f3ximos contratos es un cambio\u201d, dijo Steven Hubbard, cient\u00edfico de datos del Consejo Americano de Inmigraci\u00f3n, una organizaci\u00f3n sin fines de lucro que promueve la inmigraci\u00f3n. \u201cAnteriormente, las herramientas de IA se utilizaban principalmente para mejorar la eficiencia, marcando un caso para su revisi\u00f3n o facilitando el reconocimiento facial. Pero los nuevos sistemas descritos parecen ser m\u00e1s prescriptivos, orientando a los agentes sobre las medidas a tomar en lugar de simplemente apoyar su toma de decisiones\u201d.<\/p>\n<p>Bajo la administraci\u00f3n Biden, el DHS comenz\u00f3 a publicar \u201cinventarios\u201d de IA para revelar c\u00f3mo las agencias utilizan la inteligencia artificial. Estos informes revelan que las herramientas de IA ya est\u00e1n integradas en la verificaci\u00f3n de identidad, la detecci\u00f3n de fraude, los registros para alternativas a la detenci\u00f3n e incluso en chatbots para uso interno.<\/p>\n<p>Ahora ese esfuerzo se est\u00e1 intensificando, con la ayuda de Palantir, un <a href=\"https:\/\/www.cnn.com\/2025\/08\/07\/business\/what-is-palantir-nightcap\">importante contratista del Gobierno<\/a> tambi\u00e9n utilizado por el Departamento de Defensa.<\/p>\n<p>A principios de este a\u00f1o, <a href=\"https:\/\/www.fpds.gov\/ezsearch\/fpdsportal?q=PIID:%2270CTD022FR0000170%22&#038;s=FPDS.GOV&#038;templateName=1.5.3&#038;indexName=awardfull&#038;x=0&#038;y=0&#038;sortBy=SIGNED_DATE&#038;desc=Y\">el ICE otorg\u00f3 a la empresa<\/a> casi US$ 30 millones para desarrollar ImmigrationOS. El sistema est\u00e1 dise\u00f1ado no solo para recopilar informaci\u00f3n, sino tambi\u00e9n para influir en las decisiones de aplicaci\u00f3n de la ley, una medida que, seg\u00fan los cr\u00edticos, externaliza el criterio al software y genera inquietudes sobre la supervisi\u00f3n y la rendici\u00f3n de cuentas.<\/p>\n<p>CNN se ha comunicado con DHS y Palantir para solicitar comentarios. Palantir ha dicho que cree que la IA <a href=\"https:\/\/www.palantir.com\/pcl\/palantir-ai-ethics\/#principle5\">deber\u00eda utilizarse<\/a> para \u201cmejorar la ejecuci\u00f3n y la toma de decisiones humanas en lugar de reemplazarlas\u201d <a href=\"https:\/\/www.palantir.com\/pcl\/\">y que<\/a> \u201ces esencial preservar los principios fundamentales de privacidad y libertades civiles al utilizar datos\u201d.<\/p>\n<p>Un exfuncionario del DHS que trabaj\u00f3 en la actual administraci\u00f3n Trump declar\u00f3 a CNN que ImmigrationOS marca un cambio fundamental en la infraestructura de control migratorio. \u201cEst\u00e1n combinando conjuntos de datos del Tesoro y otras agencias en una plataforma de observabilidad\u201d, dijo el funcionario.<\/p>\n<p>El exfuncionario a\u00f1adi\u00f3 que la nueva plataforma tambi\u00e9n utilizar\u00e1 datos del Servicio de Impuestos Internos (IRS) y del censo. Incluye flujos de trabajo integrados que permiten a los agentes aprobar redadas, registrar arrestos, generar documentos legales y dirigir a las personas a vuelos de deportaci\u00f3n o centros de detenci\u00f3n, todo desde una \u00fanica interfaz.<\/p>\n<p>\u201cPuedes entrar y, ya sabes, hacer una redada y arrestar, y obtener tu aprobaci\u00f3n en el sistema\u201d, dijo el funcionario. \u201cLuego, los dirigir\u00e1 a detenci\u00f3n o expulsi\u00f3n. Todo ese ciclo de vida est\u00e1 integrado en el software\u201d.<\/p>\n<p>El exfuncionario tambi\u00e9n alert\u00f3 sobre la creciente dependencia del ICE de Palantir. \u201cUna de las cosas que nos ha preocupado es que depender tanto de un proveedor principal\u2026 significa que uno est\u00e1 atado a su ecosistema\u201d, dijo. \u201cGran parte de la infraestructura de TI ahora requiere las herramientas de Palantir para funcionar\u201d.<\/p>\n<p>M\u00e1s all\u00e1 de la dependencia de un proveedor, el sistema tambi\u00e9n marca una descentralizaci\u00f3n de la autoridad. Bajo las nuevas directivas de la era Trump, ImmigrationOS ser\u00e1 accesible directamente para los agentes en el terreno, no solo en la sede. \u201cLa idea es llevar la IA a los operadores\u201d, dijo el funcionario. \u201cDeja que los agentes en el terreno la usen como mejor les parezca, en lugar de gestionarla centralmente\u201d.<\/p>\n<p>Hubbard advierte de que, si bien la atenci\u00f3n se centra a menudo en el reconocimiento facial o la vigilancia, el verdadero impacto puede residir en un nivel m\u00e1s profundo: en las decisiones silenciosas y automatizadas que afectan a las personas que son blanco de ataques, detenidas o deportadas. \u201cSi la IA se convierte en la base de las medidas de control, la supervisi\u00f3n no es opcional, sino urgente\u201d, dijo.<\/p>\n<p>El exdirector interino del ICE, John Sandweg, quien sirvi\u00f3 durante la administraci\u00f3n Obama, dijo que el debate no gira en torno a si la IA puede ser \u00fatil, sino a c\u00f3mo se implementa. \u201cEstas herramientas pueden usarse para bien o para mal\u201d, dijo Sandweg. \u201cEsta administraci\u00f3n ha dejado claro que quiere aumentar los arrestos; ellos mismos lo han dicho\u201d.<\/p>\n<p>Sandweg se\u00f1al\u00f3 que la adopci\u00f3n de la tecnolog\u00eda por parte del ICE no es nueva. \u201cLas herramientas de IA existen desde hace m\u00e1s de una d\u00e9cada. Pueden desempe\u00f1ar un papel fundamental en la identificaci\u00f3n de amenazas y terroristas. El ICE siempre ha adoptado la tecnolog\u00eda; antes, se centraba en las amenazas terroristas\u201d.<\/p>\n<p>Pero cuestion\u00f3 la necesidad de la IA en ciertas operaciones policiales cotidianas. \u201cNo se necesita IA para ir a Home Depot y arrestar a la gente\u201d, dijo.<\/p>\n<p>Adem\u00e1s, un ex alto funcionario del DHS, hablando en un panel de cumplimiento migratorio bajo las reglas de Chatham House, dijo que el ICE \u201cahora cuenta con una nueva herramienta de inteligencia artificial para realizar el trabajo de los auditores del formulario I-9 de forma m\u00e1s r\u00e1pida y eficaz\u201d. Estos auditores se encargan de revisar los formularios de elegibilidad de empleo (conocidos como I-9) para verificar que los trabajadores est\u00e9n legalmente autorizados para trabajar en Estados Unidos. Revisan documentos como pasaportes, tarjetas de residencia y visas, e identifican discrepancias o posibles infracciones.<\/p>\n<p>Pero los cr\u00edticos dicen que esa misma eficiencia, si no se controla, podr\u00eda dejar de lado el juicio humano en favor de la velocidad algor\u00edtmica, con consecuencias reales para personas reales.<\/p>\n<p>\u201cNo se puede tomar la IA como una verdad absoluta\u201d, dijo otro exfuncionario del DHS. \u201cLa IA es buena, pero no tan buena como un ser humano\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La administraci\u00f3n Trump est\u00e1 ampliando dr\u00e1sticamente el uso de inteligencia artificial en la aplicaci\u00f3n de leyes migratorias, utilizando la tecnolog\u00eda no s\u00f3lo para rastrear a los migrantes sino tambi\u00e9n para ayudar a determinar qui\u00e9nes son objeto de deportaci\u00f3n. Para impulsar la aplicaci\u00f3n de las leyes migratorias \u2014una prioridad pol\u00edtica fundamental para el presidente Donald Trump\u2014, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466680","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Como Prime, pero con seres humanos&quot;: C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Como Prime, pero con seres humanos&quot;: C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias - Noticias\" \/>\n<meta property=\"og:description\" content=\"La administraci\u00f3n Trump est\u00e1 ampliando dr\u00e1sticamente el uso de inteligencia artificial en la aplicaci\u00f3n de leyes migratorias, utilizando la tecnolog\u00eda no s\u00f3lo para rastrear a los migrantes sino tambi\u00e9n para ayudar a determinar qui\u00e9nes son objeto de deportaci\u00f3n. Para impulsar la aplicaci\u00f3n de las leyes migratorias \u2014una prioridad pol\u00edtica fundamental para el presidente Donald Trump\u2014, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T11:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Como Prime, pero con seres humanos&#187;: C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias\",\"datePublished\":\"2025-09-22T11:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/\"},\"wordCount\":1392,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/\",\"name\":\"\\\"Como Prime, pero con seres humanos\\\": C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-22T11:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Como Prime, pero con seres humanos&#187;: C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Como Prime, pero con seres humanos\": C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"Como Prime, pero con seres humanos\": C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias - Noticias","og_description":"La administraci\u00f3n Trump est\u00e1 ampliando dr\u00e1sticamente el uso de inteligencia artificial en la aplicaci\u00f3n de leyes migratorias, utilizando la tecnolog\u00eda no s\u00f3lo para rastrear a los migrantes sino tambi\u00e9n para ayudar a determinar qui\u00e9nes son objeto de deportaci\u00f3n. Para impulsar la aplicaci\u00f3n de las leyes migratorias \u2014una prioridad pol\u00edtica fundamental para el presidente Donald Trump\u2014, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-22T11:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;Como Prime, pero con seres humanos&#187;: C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias","datePublished":"2025-09-22T11:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/"},"wordCount":1392,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/","name":"\"Como Prime, pero con seres humanos\": C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-22T11:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Como Prime, pero con seres humanos&#187;: C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Como Prime, pero con seres humanos&#187;: C\u00f3mo la administraci\u00f3n Trump usa la IA para reforzar la aplicaci\u00f3n de leyes migratorias","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/22\/trump-leyes-migratorias-ia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-22T11:03:51Z","datePublished":"2025-09-22T11:03:51Z","dateModified":"2025-09-22T11:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Como Prime, pero con seres humanos&#187;: C\\u00f3mo la administraci\\u00f3n Trump usa la IA para reforzar la aplicaci\\u00f3n de leyes migratorias\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/22\\\/trump-leyes-migratorias-ia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/22\\\/trump-leyes-migratorias-ia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-22T11:03:51Z\",\"datePublished\":\"2025-09-22T11:03:51Z\",\"dateModified\":\"2025-09-22T11:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467796,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/27\/gobierno-trump-cambios-ice-bajo-numero-arrestos-migratorios-trax\/","url_meta":{"origin":1466680,"position":0},"title":"El Gobierno de Trump planea cambios en ICE en medio de frustraciones por el bajo n\u00famero de arrestos migratorios","author":"","date":"octubre 27, 2025","format":false,"excerpt":"El Gobierno de Trump est\u00e1 planeando otro cambio en el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en medio de frustraciones por el bajo n\u00famero de arrestos migratorios, seg\u00fan cuatro fuentes familiarizadas con las discusiones.La Casa Blanca fij\u00f3 una meta ambiciosa de 3.000 arrestos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463107,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/06\/02\/dhs-elimina-lista-jurisdicciones-santuario-trax\/","url_meta":{"origin":1466680,"position":1},"title":"DHS elimina lista de &#171;jurisdicciones santuario&#187; de su sitio web tras quejas de autoridades policiales y dudas de su precisi\u00f3n","author":"","date":"junio 2, 2025","format":false,"excerpt":"El Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) elimin\u00f3 el jueves de su sitio web una lista de cientos de las llamadas jurisdicciones santuario, luego de que surgieran dudas sobre su precisi\u00f3n y fuertes cr\u00edticas de un importante grupo que representa a las fuerzas del orden.El DHS\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462314,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/05\/13\/gobierno-trump-aumentar-agentes-arrestar-inmigrantes-trax\/","url_meta":{"origin":1466680,"position":2},"title":"EE.UU. planea desplegar cientos de agentes federales adicionales para intensificar la aplicaci\u00f3n de la ley migratoria","author":"","date":"mayo 13, 2025","format":false,"excerpt":"La administraci\u00f3n de Trump planea desplegar cientos de agentes federales adicionales para intensificar los arrestos de inmigrantes indocumentados esta misma semana, seg\u00fan dos fuentes familiarizadas con la planificaci\u00f3n, incluyendo la asignaci\u00f3n de agentes de la Patrulla Fronteriza para desplegarlos por todo el pa\u00eds.La medida, que tambi\u00e9n se espera que incluya\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462188,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/05\/10\/trump-conversaciones-suspension-habeas-corpus-trax\/","url_meta":{"origin":1466680,"position":3},"title":"Trump participa en conversaciones sobre la suspensi\u00f3n del habeas corpus, seg\u00fan fuentes","author":"","date":"mayo 10, 2025","format":false,"excerpt":"El presidente Donald Trump particip\u00f3 personalmente en conversaciones dentro de la administraci\u00f3n sobre la posible suspensi\u00f3n del habeas corpus, un procedimiento legal que permite a las personas impugnar su detenci\u00f3n en los tribunales, seg\u00fan informaron a CNN dos personas familiarizadas con el tema.Uno de los principales asesores de Trump, Stephen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463505,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/06\/12\/decision-trump-fuerzas-armadas-leyes-migratorias-meses-trax\/","url_meta":{"origin":1466680,"position":4},"title":"La decisi\u00f3n de Trump de usar a las Fuerzas Armadas para la aplicaci\u00f3n de leyes inmigratorias se prepar\u00f3 durante meses","author":"","date":"junio 12, 2025","format":false,"excerpt":"Cuando el presidente Donald Trump puso a 2.000 miembros de la Guardia Nacional bajo su control el s\u00e1bado por la noche y los envi\u00f3 a Los \u00c1ngeles, se present\u00f3 como una respuesta urgente para sofocar las protestas. Pero tambi\u00e9n fue una medida que llevaba meses gest\u00e1ndose.Detr\u00e1s de escena, la Casa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464348,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/07\/09\/los-angeles-demanda-administracion-trump-redadas-migratorias-trax\/","url_meta":{"origin":1466680,"position":5},"title":"Los \u00c1ngeles busca sumarse a demanda contra administraci\u00f3n Trump por redadas migratorias","author":"","date":"julio 9, 2025","format":false,"excerpt":"La ciudad y el condado Los \u00c1ngeles, junto con varios municipios del sur de California, buscan unirse a una demanda presentada contra la administraci\u00f3n Trump por las recientes redadas de inmigraci\u00f3n que provocaron varios d\u00edas de protestas y la federalizaci\u00f3n de la Guardia Nacional.La demanda, presentada la semana pasada por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466680"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466680\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}