{"id":1466757,"date":"2025-09-23T18:03:43","date_gmt":"2025-09-24T01:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/"},"modified":"2025-09-23T18:03:43","modified_gmt":"2025-09-24T01:03:43","slug":"google-trabajadores-tecnologicos-uso-ia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/","title":{"rendered":"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo"},"content":{"rendered":"<p>La gran mayor\u00eda de los trabajadores de la industria tecnol\u00f3gica utiliza inteligencia artificial en el trabajo para tareas como escribir y modificar c\u00f3digo, seg\u00fan un nuevo estudio de Google.<\/p>\n<p>El informe, proveniente de la divisi\u00f3n de investigaci\u00f3n DORA de Google y con base en 5.000 respuestas de profesionales de la tecnolog\u00eda de todo el mundo, encontr\u00f3 que el 90 % de los encuestados est\u00e1 usando IA en su trabajo, un aumento del 14 % respecto al a\u00f1o pasado.<\/p>\n<p>Los hallazgos llegan mientras el auge de la IA ha generado una mezcla de preocupaci\u00f3n, expectativas y promesas sobre c\u00f3mo la tecnolog\u00eda podr\u00eda impactar los empleos y la econom\u00eda. El CEO de Anthropic, Dario Amodei, fue noticia en mayo cuando dijo que la IA podr\u00eda llevar a un <a href=\"https:\/\/www.cnn.com\/2025\/05\/29\/tech\/ai-anthropic-ceo-dario-amodei-unemployment#:~:text=See%20More%20Videos,of%20the%20Covid%2D19%20pandemic.\">incremento del desempleo<\/a>, un sentimiento que otros profesionales de la <a href=\"https:\/\/www.cnn.com\/2025\/07\/21\/tech\/ai-replace-human-workers-tech-insiders-split\">industria tecnol\u00f3gica<\/a> han minimizado desde entonces. Pero algunos datos s\u00ed sugieren que cada vez es m\u00e1s dif\u00edcil para los trabajadores reci\u00e9n graduados encontrar empleos en ingenier\u00eda de software, una <a href=\"https:\/\/www.cnn.com\/2025\/08\/28\/tech\/computer-science-graduates-job-hunt-ai\">tendencia<\/a> que se da en medio de una ola de despidos en el sector tecnol\u00f3gico.<\/p>\n<p>Google es una de las muchas empresas que buscan capitalizar el cambio hacia el desarrollo de software asistido por IA; ofrece herramientas que van desde gratuitas hasta US$ 45 por mes para ayudar con la generaci\u00f3n de c\u00f3digo y el despliegue de agentes que pueden encargarse de tareas de desarrollo de software.<\/p>\n<p>La empresa enfrenta una competencia generalizada, no solo de rivales como Microsoft, OpenAI y Anthropic, sino tambi\u00e9n de startups de codificaci\u00f3n con IA como Replit y Anysphere, que est\u00e1n viendo dispararse sus <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2025-09-10\/ai-coding-startup-replit-valued-at-3-billion-with-new-funding?srnd=phx-technology\">valoraciones<\/a> a medida que las empresas tecnol\u00f3gicas adoptan cada vez m\u00e1s la IA.<\/p>\n<p>Ryan J. Salva, quien supervisa las herramientas de codificaci\u00f3n de Google como Gemini Code Assist, dijo que la \u201cgran mayor\u00eda\u201d de los equipos en Google est\u00e1 usando IA, y que la tecnolog\u00eda se ha integrado en todo, desde la forma en que se escribe la documentaci\u00f3n hasta los editores de c\u00f3digo de Google.<\/p>\n<p>\u201cSi eres ingeniero en Google, es inevitable que uses IA como parte de tu trabajo diario\u201d, dijo en una entrevista con CNN antes de la publicaci\u00f3n del informe.<\/p>\n<p>Pero el hecho de que los programadores usen IA no significa necesariamente que todos encuentren valor en ella. El 46 % de los profesionales tecnol\u00f3gicos que participaron en la encuesta dijo que \u201cconf\u00eda algo\u201d en la calidad del c\u00f3digo generado por IA, mientras que el 23 % dijo que solo conf\u00eda \u201cun poco\u201d y el 20 % dijo que conf\u00eda \u201cmucho\u201d. Y el 31 % dijo que la IA \u201cmejor\u00f3 ligeramente\u201d la calidad del c\u00f3digo, mientras que el 30 % dijo que no tuvo \u201cning\u00fan impacto\u201d.<\/p>\n<p>Salva dice que, en una escala del uno al cinco, donde uno es la predicci\u00f3n b\u00e1sica de texto y cinco es la capacidad de dar a la IA una orden general y vaga, el desarrollo de software con IA est\u00e1 en alg\u00fan punto entre la etapa tres y cuatro. Es decir, la IA puede solucionar problemas entre sistemas, pero todav\u00eda necesita revisi\u00f3n humana y \u201cmuchas redes de seguridad\u201d.<\/p>\n<p>La adopci\u00f3n de herramientas de IA llega en un momento desafiante para los trabajadores tecnol\u00f3gicos reci\u00e9n graduados. La tasa de desempleo para los empleados de este nivel en ciencias de la computaci\u00f3n e ingenier\u00eda inform\u00e1tica es ahora m\u00e1s alta que la de campos como historia del arte e ingl\u00e9s, seg\u00fan la <a href=\"https:\/\/www.newyorkfed.org\/research\/college-labor-market#--:explore:outcomes-by-major\">Reserva Federal de Nueva York<\/a>, y las ofertas de empleo para roles de ingenier\u00eda de software en Indeed <a href=\"https:\/\/fred.stlouisfed.org\/series\/IHLIDXUSTPSOFTDEVE\">cayeron un 71 %<\/a> entre febrero de 2022 y agosto de 2025.<\/p>\n<p>Los reci\u00e9n graduados en ciencias de la computaci\u00f3n que <a href=\"https:\/\/www.cnn.com\/2025\/08\/28\/tech\/computer-science-graduates-job-hunt-ai\">hablaron con CNN<\/a> a principios de este a\u00f1o se mostraron en general optimistas sobre sus perspectivas profesionales futuras, pero reconocieron que la IA est\u00e1 cambiando la naturaleza del trabajo. Un reci\u00e9n graduado, Julio Rodr\u00edguez, dijo que postul\u00f3 a m\u00e1s de 150 empleos antes de conseguir un puesto.<\/p>\n<p>Aunque la adopci\u00f3n de la IA avanza r\u00e1pido, Salva est\u00e1 en el grupo de quienes creen que hay partes cr\u00edticas del desarrollo de software que no pueden ser automatizadas y que la IA agilizar\u00e1 las partes que los trabajadores consideran mundanas.<\/p>\n<p>Pero reconoce que al menos parte del aumento en la adopci\u00f3n de IA probablemente provenga del entusiasmo que rodea a la tecnolog\u00eda.<\/p>\n<p>\u201cEl desarrollo de software es una industria de la moda\u2026 Todos estamos persiguiendo el pr\u00f3ximo estilo de jeans\u201d, coment\u00f3. \u201cY cuando hay tanta conversaci\u00f3n al respecto, todos est\u00e1n emocionados por probar lo nuevo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gran mayor\u00eda de los trabajadores de la industria tecnol\u00f3gica utiliza inteligencia artificial en el trabajo para tareas como escribir y modificar c\u00f3digo, seg\u00fan un nuevo estudio de Google. El informe, proveniente de la divisi\u00f3n de investigaci\u00f3n DORA de Google y con base en 5.000 respuestas de profesionales de la tecnolog\u00eda de todo el mundo, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466757","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo - Noticias\" \/>\n<meta property=\"og:description\" content=\"La gran mayor\u00eda de los trabajadores de la industria tecnol\u00f3gica utiliza inteligencia artificial en el trabajo para tareas como escribir y modificar c\u00f3digo, seg\u00fan un nuevo estudio de Google. El informe, proveniente de la divisi\u00f3n de investigaci\u00f3n DORA de Google y con base en 5.000 respuestas de profesionales de la tecnolog\u00eda de todo el mundo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T01:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo\",\"datePublished\":\"2025-09-24T01:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/\"},\"wordCount\":824,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/\",\"name\":\"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-24T01:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo - Noticias","og_description":"La gran mayor\u00eda de los trabajadores de la industria tecnol\u00f3gica utiliza inteligencia artificial en el trabajo para tareas como escribir y modificar c\u00f3digo, seg\u00fan un nuevo estudio de Google. El informe, proveniente de la divisi\u00f3n de investigaci\u00f3n DORA de Google y con base en 5.000 respuestas de profesionales de la tecnolog\u00eda de todo el mundo, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-24T01:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/"},"author":{"name":"","@id":""},"headline":"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo","datePublished":"2025-09-24T01:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/"},"wordCount":824,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/","name":"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-24T01:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Google dice que el 90 % de los trabajadores tecnol\u00f3gicos ya usan IA en el trabajo","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/23\/google-trabajadores-tecnologicos-uso-ia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-24T01:03:43Z","datePublished":"2025-09-24T01:03:43Z","dateModified":"2025-09-24T01:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Google dice que el 90 % de los trabajadores tecnol\\u00f3gicos ya usan IA en el trabajo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/23\\\/google-trabajadores-tecnologicos-uso-ia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/23\\\/google-trabajadores-tecnologicos-uso-ia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-24T01:03:43Z\",\"datePublished\":\"2025-09-24T01:03:43Z\",\"dateModified\":\"2025-09-24T01:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464444,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/07\/11\/ceo-nvidia-ia-perdida-de-empleos-trax\/","url_meta":{"origin":1466757,"position":0},"title":"El CEO de Nvidia dice que la IA podr\u00eda causar p\u00e9rdida de empleos &#171;si el mundo se queda sin ideas&#187;","author":"","date":"julio 11, 2025","format":false,"excerpt":"El CEO del principal fabricante de chips del mundo advirti\u00f3 que, aunque la inteligencia artificial aumentar\u00e1 significativamente la productividad en el trabajo, podr\u00eda derivar en p\u00e9rdida de empleos si las industrias carecen de innovaci\u00f3n.\u201cSi el mundo se queda sin ideas, entonces las ganancias de productividad se traducen en p\u00e9rdida de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463179,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/06\/04\/ceo-deepmind-google-preocupaciones-inteligencia-artificial-trax\/","url_meta":{"origin":1466757,"position":1},"title":"El CEO de DeepMind, de Google, tiene dos preocupaciones en cuanto a la IA. Perder empleos no es una de ellas","author":"","date":"junio 4, 2025","format":false,"excerpt":"Demis Hassabis, CEO de DeepMind, la divisi\u00f3n de investigaci\u00f3n en inteligencia artificial de Google, y premio Nobel, no est\u00e1 demasiado preocupado por un \u201capocalipsis laboral\u201d en el \u00e1mbito de la inteligencia artificial.En lugar de preocuparse por que la IA reemplace puestos de trabajo, le preocupa que la tecnolog\u00eda caiga en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471033,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/09\/ia-empleos-no-reemplaza-trabajadores-trax\/","url_meta":{"origin":1466757,"position":2},"title":"Este trabajo se ha convertido en el ejemplo definitivo de por qu\u00e9 la IA no reemplazar\u00e1 a los humanos","author":"","date":"febrero 9, 2026","format":false,"excerpt":"\u00bfQuieres entender c\u00f3mo la inteligencia artificial podr\u00eda cambiar tu empleo? Considera la radiolog\u00eda como una pista.La radiolog\u00eda se ha convertido en un tema de conversaci\u00f3n reciente en la carrera de la IA. Fue mencionada en m\u00faltiples ocasiones el mes pasado por ejecutivos tecnol\u00f3gicos en el Foro Econ\u00f3mico Mundial de Davos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472935,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/reporte-desempleo-ia-cicatrices-largo-plazo-trax\/","url_meta":{"origin":1466757,"position":3},"title":"Perder tu trabajo a manos de la IA deja otras cicatrices duraderas adem\u00e1s del desempleo, seg\u00fan nueva investigaci\u00f3n","author":"","date":"abril 7, 2026","format":false,"excerpt":"La p\u00e9rdida de empleos impulsada por la IA no solo podr\u00eda dificultar que los trabajadores afectados encuentren trabajo a corto plazo, sino que tambi\u00e9n podr\u00eda dejar una \u201ccicatriz\u201d de a\u00f1os de duraci\u00f3n, marcada por ingresos deprimidos, un retraso en la adquisici\u00f3n de vivienda e incluso una menor probabilidad de contraer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459331,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/02\/28\/empleos-mas-rapido-crecimiento-estados-unidos-gracias-chatgpt-trax\/","url_meta":{"origin":1466757,"position":4},"title":"Estos son los empleos de m\u00e1s r\u00e1pido crecimiento en Estados Unidos\u2026 gracias a ChatGPT","author":"","date":"febrero 28, 2025","format":false,"excerpt":"\u00bfBuscas un nuevo trabajo? Desarrollar tecnolog\u00eda de inteligencia artificial (IA) podr\u00eda ser una opci\u00f3n segura.El mercado de trabajo en el sector de la IA se dispar\u00f3 en los dos \u00faltimos a\u00f1os, seg\u00fan un reciente an\u00e1lisis de la Universidad de Maryland y la empresa de b\u00fasqueda de empleo LinkUp, el \u00faltimo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452966,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/09\/23\/tecnologia-impulsada-ia-podria-ayudar-personas-discapacidades-habla-trabajar-remoto-trax\/","url_meta":{"origin":1466757,"position":5},"title":"La tecnolog\u00eda impulsada por IA podr\u00eda ayudar a las personas con discapacidades del habla a trabajar de forma remota","author":"","date":"septiembre 23, 2024","format":false,"excerpt":"(CNN) -- Probablemente hayas experimentado la frustraci\u00f3n de que un altavoz inteligente o un asistente de inteligencia artificial no te escuchen o te entiendan bien. Para las personas con un habla no convencional, esto puede suceder en casi todas las interacciones con este tipo de tecnolog\u00eda. La empresa israel\u00ed Voiceitt\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466757"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466757\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}