{"id":1466783,"date":"2025-09-24T13:03:38","date_gmt":"2025-09-24T20:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/"},"modified":"2025-09-24T13:03:38","modified_gmt":"2025-09-24T20:03:38","slug":"israel-bloquea-puente-ribera-occidental-palestinos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/","title":{"rendered":"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior"},"content":{"rendered":"<p>La decisi\u00f3n repentina de Israel de cerrar indefinidamente el \u00fanico paso terrestre que permite a m\u00e1s de 3 millones de palestinos en la ocupada Ribera Occidental acceder a viajes internacionales ha intensificado los temores de m\u00e1s restricciones, en medio de las amenazas israel\u00edes de represalias ante el <a href=\"https:\/\/www.cnn.com\/2025\/09\/23\/middleeast\/recognizing-palestinian-state-explainer-intl-latam\">reconocimiento<\/a> occidental de un Estado palestino.<\/p>\n<p>El cierre del paso ha dejado varados a palestinos en el extranjero, mientras que pacientes que recib\u00edan tratamiento m\u00e9dico en Jordania se vieron obligados a extender su estad\u00eda con presupuestos limitados. Familias han quedado separadas por la decisi\u00f3n abrupta de Israel, y miles siguen sin saber cu\u00e1ndo se reabrir\u00e1 la frontera.<\/p>\n<p>Ismail Tamimi, un padre en Jordania, dijo que el cierre de la frontera lo ha separado de sus hijas peque\u00f1as, quienes estaban visitando a familiares en la ciudad de Hebr\u00f3n, en la Ribera Occidental.<\/p>\n<p>\u201cUna de mis hijas es diab\u00e9tica\u2026 Hoy perdi\u00f3 su chequeo en Jordania, y no puedo traerla aqu\u00ed porque la frontera est\u00e1 cerrada\u201d, dijo, agregando que \u201clas escuelas tambi\u00e9n est\u00e1n por empezar, as\u00ed que mis hijos perder\u00e1n el inicio\u201d.<\/p>\n<p>Otro palestino de Hebr\u00f3n, Rami Al Quwasmi, dijo que tuvo que alquilar una casa en Jordania mientras espera la reapertura de la frontera.<\/p>\n<p>\u201cNo s\u00e9 a d\u00f3nde ir, hay miles como yo\u201d, afirm\u00f3. M\u00e1s de la mitad de la poblaci\u00f3n de Jordania, de 10 millones, es de ascendencia palestina, y el pa\u00eds alberga a m\u00e1s de 2 millones de refugiados palestinos registrados.<\/p>\n<p>El Gobierno de Israel, que controla el paso fronterizo, a\u00fan no ha explicado por qu\u00e9 se cerr\u00f3 la frontera. La Autoridad de Aeropuertos de Israel, que administra el paso, dice que fue una decisi\u00f3n tomada por el nivel pol\u00edtico. Esto ocurre varios d\u00edas despu\u00e9s de que un conductor de cami\u00f3n jordano que transportaba ayuda humanitaria destinada a Gaza abriera fuego en el paso, matando a dos soldados israel\u00edes. Las fuerzas israel\u00edes dijeron que investigar\u00edan el incidente.<\/p>\n<p>Los palestinos sienten que el cierre es una represalia y est\u00e1 dise\u00f1ado para castigarlos por una decisi\u00f3n tomada esta semana por varios pa\u00edses occidentales de reconocer a Palestina como un pa\u00eds independiente.<\/p>\n<p>\u201cEs una venganza contra el pueblo, y se parece mucho a los puestos de control que se extienden por toda la Ribera Occidental. Esto nos hace sentir que vivimos en una gran prisi\u00f3n\u201d, dijo a CNN Tharwat Shaqra, periodista palestino que vive en la Ribera Occidental.<\/p>\n<p>Reino Unido, Francia, Canad\u00e1, Australia y varias otras naciones occidentales declararon formalmente el lunes su <a href=\"https:\/\/www.cnn.com\/2025\/09\/22\/middleeast\/france-palestine-state-recognition-united-nations-intl-latam\">reconocimiento de un Estado palestino<\/a>, una medida condenada por Israel y su primer ministro, Benjamin Netanyahu, quien dijo que la decisi\u00f3n otorgar\u00e1 un \u201cpremio enorme al terrorismo\u201d.<\/p>\n<p>Durante d\u00e9cadas, los palestinos han dependido del Cruce Allenby, tambi\u00e9n conocido como Puente Rey Hussein o Cruce Al-Karama, como la principal v\u00eda de salida de la Ribera Occidental sin tener que entrar a Israel. Los viajeros de la Ribera Occidental suelen utilizar el paso para acceder a aeropuertos internacionales en la vecina Jordania, visitar a familiares que residen en ese pa\u00eds o recibir tratamiento m\u00e9dico.<\/p>\n<p>El puente fue nombrado en honor al general brit\u00e1nico Edmund Allenby, quien lider\u00f3 a las fuerzas aliadas en la captura de Palestina del Imperio Otomano hace m\u00e1s de un siglo. Fue destruido en varias ocasiones a lo largo de su historia, incluso por un terremoto en 1927, un ataque de paramilitares jud\u00edos en 1946 y durante la Guerra de los Seis D\u00edas de 1967 entre Israel y Estados \u00e1rabes.<\/p>\n<p>Israel controla el puente desde esa guerra y lo cierra en d\u00edas festivos religiosos o por motivos de seguridad. La semana pasada, el paso fue cerrado tras la muerte de los dos soldados israel\u00edes antes de reabrirse unos d\u00edas despu\u00e9s. Un ataque similar el a\u00f1o pasado tambi\u00e9n llev\u00f3 al cierre del paso.<\/p>\n<p>Pero la \u00faltima decisi\u00f3n de Israel de cerrar el paso, descrita como un cierre indefinido, ha generado preocupaci\u00f3n entre los palestinos, quienes afirman que parece ser parte de un patr\u00f3n de medidas recientes para confinar a la poblaci\u00f3n palestina.<\/p>\n<p>\u201cLos estudiantes no pueden ir a sus universidades, y aquellos que estudian en el extranjero no pueden regresar. Las familias han sido separadas\u201d, dijo a CNN el destacado pol\u00edtico palestino Mustafa Barghouti, antes de agregar que \u201clos pacientes que necesitan tratamiento en Jordania ahora tienen prohibido viajar\u201d.<\/p>\n<p>El Gobierno israel\u00ed ha discutido la posibilidad de anexar toda o parte de la Ribera Occidental, y los ministros de extrema derecha han presionado por una anexi\u00f3n completa. Ha construido m\u00e1s bloqueos y ha instalado decenas de portones de hierro en todo el territorio ocupado, dificultando el movimiento interno.<\/p>\n<p>\u201cEsto est\u00e1 convirtiendo a todos los peque\u00f1os pueblos y aldeas en prisiones y guetos m\u00e1s peque\u00f1os como parte del plan de Israel para dividir la tierra y presionar a la gente para que eventualmente abandone Palestina\u201d, dijo Barghouti.<\/p>\n<p>El puente brinda a los territorios palestinos una l\u00ednea de vida econ\u00f3mica, entregando bienes esenciales a la regi\u00f3n en dificultades y, m\u00e1s recientemente, permitiendo que camiones transporten ayuda humanitaria clave desde Jordania hacia Gaza, el territorio palestino devastado por la mortal campa\u00f1a militar de Israel (que ha matado a m\u00e1s de 65.000 personas, seg\u00fan el Ministerio de Salud en el enclave) lanzada en represalia por un ataque mortal contra ciudades israel\u00edes perpetrado hace casi dos a\u00f1os por Hamas, el grupo militante palestino que mat\u00f3 a 1.200 personas y tom\u00f3 como rehenes a 251 personas ese d\u00eda.<\/p>\n<p>\u201cEl cierre de la frontera es un castigo colectivo y es una medida desorientada de Netanyahu, quien ha llevado a Israel al aislamiento internacional\u201d, dijo a CNN Ahmad Tibi, un miembro \u00e1rabe del Knesset.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La decisi\u00f3n repentina de Israel de cerrar indefinidamente el \u00fanico paso terrestre que permite a m\u00e1s de 3 millones de palestinos en la ocupada Ribera Occidental acceder a viajes internacionales ha intensificado los temores de m\u00e1s restricciones, en medio de las amenazas israel\u00edes de represalias ante el reconocimiento occidental de un Estado palestino. El cierre [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466783","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior - Noticias\" \/>\n<meta property=\"og:description\" content=\"La decisi\u00f3n repentina de Israel de cerrar indefinidamente el \u00fanico paso terrestre que permite a m\u00e1s de 3 millones de palestinos en la ocupada Ribera Occidental acceder a viajes internacionales ha intensificado los temores de m\u00e1s restricciones, en medio de las amenazas israel\u00edes de represalias ante el reconocimiento occidental de un Estado palestino. El cierre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T20:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior\",\"datePublished\":\"2025-09-24T20:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/\"},\"wordCount\":1021,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/\",\"name\":\"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-24T20:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior - Noticias","og_description":"La decisi\u00f3n repentina de Israel de cerrar indefinidamente el \u00fanico paso terrestre que permite a m\u00e1s de 3 millones de palestinos en la ocupada Ribera Occidental acceder a viajes internacionales ha intensificado los temores de m\u00e1s restricciones, en medio de las amenazas israel\u00edes de represalias ante el reconocimiento occidental de un Estado palestino. El cierre [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-24T20:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/"},"author":{"name":"","@id":""},"headline":"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior","datePublished":"2025-09-24T20:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/"},"wordCount":1021,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/","name":"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-24T20:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Palestinos temen m\u00e1s restricciones tras el cierre de Israel del \u00fanico acceso de la Ribera Occidental al mundo exterior","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/24\/israel-bloquea-puente-ribera-occidental-palestinos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-24T20:03:38Z","datePublished":"2025-09-24T20:03:38Z","dateModified":"2025-09-24T20:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Palestinos temen m\\u00e1s restricciones tras el cierre de Israel del \\u00fanico acceso de la Ribera Occidental al mundo exterior\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/24\\\/israel-bloquea-puente-ribera-occidental-palestinos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/24\\\/israel-bloquea-puente-ribera-occidental-palestinos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-24T20:03:38Z\",\"datePublished\":\"2025-09-24T20:03:38Z\",\"dateModified\":\"2025-09-24T20:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452272,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/29\/ribera-occidental-violencia-situacion-critica-trax\/","url_meta":{"origin":1466783,"position":0},"title":"Mientras el mundo centra su atenci\u00f3n en Gaza, la Ribera Occidental alcanza una situaci\u00f3n cr\u00edtica","author":"","date":"agosto 29, 2024","format":false,"excerpt":"(CNN) -- El asalto de Israel a Gaza desde el ataque del 7 de octubre dirigido por Hamas ha matado a m\u00e1s de 40.000 personas, seg\u00fan las autoridades palestinas, lo que ha provocado la condena internacional. Pero a s\u00f3lo 100 kil\u00f3metros de distancia, otra gran escalada de violencia tambi\u00e9n se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471263,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/15\/israel-registro-tierras-ribera-occidental-anexion-facto-trax\/","url_meta":{"origin":1466783,"position":1},"title":"Israel designa varias partes de la Ribera Occidental como territorio estatal; critican la medida como una &#171;anexi\u00f3n de facto&#187;","author":"","date":"febrero 15, 2026","format":false,"excerpt":"El gobierno de Israel avanza en la inscripci\u00f3n de territorio en la Ribera Occidental como tierra estatal, en una medida que los palestinos han denunciado como una \u201canexi\u00f3n de facto\u201d.Por primera vez desde que Israel ocup\u00f3 el territorio en 1967, el Gobierno crear\u00e1 un mecanismo para registrar oficialmente grandes extensiones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452271,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/29\/israel-comandante-jihad-islamica-redada-ribera-occidental-trax\/","url_meta":{"origin":1466783,"position":2},"title":"Israel dice haber matado a un comandante de la Jihad Isl\u00e1mica en una mezquita, mientras contin\u00faa la redada en la Ribera Occidental","author":"","date":"agosto 29, 2024","format":false,"excerpt":"(CNN) --\u00a0 El ej\u00e9rcito israel\u00ed dijo este jueves que termin\u00f3 con la vida de cinco militantes palestinos, incluido un comandante de la Jihad Isl\u00e1mica, durante un intercambio de fuego \"dentro y cerca de una mezquita\" en la ciudad ocupada de Tulkarem, en la Ribera Occidental.El tiroteo se produjo despu\u00e9s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469574,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/12\/25\/aprobacion-asentamientos-ribera-occidental-israel-condena-trax\/","url_meta":{"origin":1466783,"position":3},"title":"12 pa\u00edses europeos, Canad\u00e1 y Jap\u00f3n condenan la aprobaci\u00f3n de nuevos asentamientos israel\u00edes en la Ribera Occidental","author":"","date":"diciembre 25, 2025","format":false,"excerpt":"Doce pa\u00edses europeos, as\u00ed como Canad\u00e1 y Jap\u00f3n, condenaron la decisi\u00f3n de Israel, tomada a principios de mes, de aprobar 19 nuevos asentamientos jud\u00edos en la Ribera Occidental ocupada, al considerar que la medida perjudica las perspectivas de una paz y seguridad duraderas en la regi\u00f3n.\u201cEste tipo de acciones unilaterales,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452253,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/28\/estados-unidos-sanciona-grupo-individuo-israelies-actos-violentos-palestinos-ribera-occidental-trax\/","url_meta":{"origin":1466783,"position":4},"title":"Estados Unidos sanciona a un grupo y a un individuo israel\u00edes por presuntos actos violentos contra palestinos en la Ribera Occidental","author":"","date":"agosto 28, 2024","format":false,"excerpt":"(CNN) -- Estados Unidos anunci\u00f3 este mi\u00e9rcoles sanciones contra una organizaci\u00f3n israel\u00ed, Hashomer Yosh, presuntamente responsable de apoyar la violencia de los colonos en Ribera Occidental contra los palestinos, seg\u00fan un portavoz del Departamento de Estado.\"Despu\u00e9s de que los 250 residentes palestinos de Khirbet Zanuta [un pueblo de Ribera Occidental]\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457885,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/25\/trump-sugiere-plan-gaza-es-limpiar-todo-trax\/","url_meta":{"origin":1466783,"position":5},"title":"Trump sugiere que su plan para Gaza es &#171;limpiar todo&#187;","author":"","date":"enero 25, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, indic\u00f3 este s\u00e1bado que hab\u00eda hablado con el rey de Jordania sobre la posibilidad de construir viviendas y trasladar a m\u00e1s de un mill\u00f3n de palestinos de Gaza a pa\u00edses vecinos, una propuesta notable de un presidente de Estados Unidos en funciones.Trump dijo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466783"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466783\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}