{"id":1466805,"date":"2025-09-25T05:03:39","date_gmt":"2025-09-25T12:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/"},"modified":"2025-09-25T05:03:39","modified_gmt":"2025-09-25T12:03:39","slug":"bukele-agradece-trump-barrio-18-onu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/","title":{"rendered":"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista"},"content":{"rendered":"<p>El presidente de El Salvador, Nayib Bukele, agradeci\u00f3 el martes a Donald Trump por los elogios durante su discurso ante la ONU y celebr\u00f3 la decisi\u00f3n de la Casa Blanca de declarar organizaci\u00f3n terrorista extranjera a la pandilla Barrio 18.<\/p>\n<p>\u201cEn El Salvador, ya hab\u00edamos dado este paso al designarlos formalmente como terroristas\u201d, escribi\u00f3 el <a href=\"https:\/\/x.com\/nayibbukele\/status\/1970662191045972452\">mandatario salvadore\u00f1o en X<\/a>, al tiempo que reiter\u00f3 que \u201cla mayor\u00eda de sus miembros se encuentran actualmente presos en el CECOT, el Centro de Confinamiento del Terrorismo, dise\u00f1ado espec\u00edficamente para enfrentar este tipo de amenaza\u201d.<\/p>\n<p>\u201cSu mensaje subraya la importancia de trabajar juntos con determinaci\u00f3n en la lucha contra el terrorismo, y nos complace ver que nuestros gobiernos est\u00e1n plenamente alineados con esta causa\u201d, agrega la <a href=\"https:\/\/x.com\/nayibbukele\/status\/1970662191045972452\">respuesta<\/a> en X del mandatario salvadore\u00f1o a Trump.<\/p>\n<p>Barrio 18 es considerada una de las pandillas m\u00e1s grandes y ha organizado ataques contra personal de seguridad, funcionarios p\u00fablicos y civiles en El Salvador, Guatemala y Honduras, de acuerdo con el <a href=\"https:\/\/www.state.gov\/translations\/spanish\/hoy-barrio-18-ha-sido-designado-terrorista\">comunicado<\/a> del departamento de Estado de los Estados Unidos.<\/p>\n<p>La decisi\u00f3n de Estados Unidos <a href=\"https:\/\/www.state.gov\/translations\/spanish\/hoy-barrio-18-ha-sido-designado-terrorista\">busca<\/a> \u201cgarantizar la seguridad del pueblo estadounidense\u201d del accionar de pandillas como la \u201cBarrio 18\u201d, dividida entre las facciones sure\u00f1os y revolucionarios. Adem\u00e1s, es el principal rival de la <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/01\/designating-cartels-and-other-organizations-as-foreign-terrorist-organizations-and-specially-designated-global-terrorists\/\">Mara Salvatrucha MS13<\/a>, que desde el pasado enero es considerada una organizaci\u00f3n terrorista extranjera.<\/p>\n<p>Bukele, cuya presencia en la ONU estaba programada para la tarde del martes, pero no ocurri\u00f3, <a href=\"https:\/\/x.com\/nayibbukele\/status\/1970662191045972452\">dijo<\/a> a su vez que la cooperaci\u00f3n \u201ces clave para erradicar estas estructuras criminales y garantizar un futuro de paz y seguridad para nuestros pueblos\u201d.<\/p>\n<p>Trump <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/16\/latinoamerica\/el-salvador-miembros-tren-aragua-megaprision-bukele-orix\">agradeci\u00f3<\/a> el martes a Bukele por \u201crecibir y encarcelar a tantos delincuentes que ingresaron a nuestro pa\u00eds\u201d, en referencia a los venezolanos que Estados Unidos envi\u00f3 a mediados de marzo al Centro de Confinamiento del Terrorismo (Cecot).<\/p>\n<p>Los venezolanos fueron <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/18\/eeuu\/estados-unidos-venezuela-intercambio-prisioneros-trax\">liberados<\/a> a mediados de julio como parte de un intercambio de prisioneros entre Estados Unidos y Venezuela.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de El Salvador, Nayib Bukele, agradeci\u00f3 el martes a Donald Trump por los elogios durante su discurso ante la ONU y celebr\u00f3 la decisi\u00f3n de la Casa Blanca de declarar organizaci\u00f3n terrorista extranjera a la pandilla Barrio 18. \u201cEn El Salvador, ya hab\u00edamos dado este paso al designarlos formalmente como terroristas\u201d, escribi\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466805","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de El Salvador, Nayib Bukele, agradeci\u00f3 el martes a Donald Trump por los elogios durante su discurso ante la ONU y celebr\u00f3 la decisi\u00f3n de la Casa Blanca de declarar organizaci\u00f3n terrorista extranjera a la pandilla Barrio 18. \u201cEn El Salvador, ya hab\u00edamos dado este paso al designarlos formalmente como terroristas\u201d, escribi\u00f3 el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T12:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista\",\"datePublished\":\"2025-09-25T12:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/\"},\"wordCount\":369,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/\",\"name\":\"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-25T12:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista - Noticias","og_description":"El presidente de El Salvador, Nayib Bukele, agradeci\u00f3 el martes a Donald Trump por los elogios durante su discurso ante la ONU y celebr\u00f3 la decisi\u00f3n de la Casa Blanca de declarar organizaci\u00f3n terrorista extranjera a la pandilla Barrio 18. \u201cEn El Salvador, ya hab\u00edamos dado este paso al designarlos formalmente como terroristas\u201d, escribi\u00f3 el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-25T12:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/"},"author":{"name":"","@id":""},"headline":"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista","datePublished":"2025-09-25T12:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/"},"wordCount":369,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/","name":"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-25T12:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\u00f3n de pandilla barrio 18 como organizaci\u00f3n terrorista","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/bukele-agradece-trump-barrio-18-onu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-25T12:03:39Z","datePublished":"2025-09-25T12:03:39Z","dateModified":"2025-09-25T12:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Bukele agradece a Trump por sus elogios en la ONU y celebra declaraci\\u00f3n de pandilla barrio 18 como organizaci\\u00f3n terrorista\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/25\\\/bukele-agradece-trump-barrio-18-onu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/25\\\/bukele-agradece-trump-barrio-18-onu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-25T12:03:39Z\",\"datePublished\":\"2025-09-25T12:03:39Z\",\"dateModified\":\"2025-09-25T12:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460203,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/20\/que-ganan-el-salvador-bukele-deportados-ee-uu-orix\/","url_meta":{"origin":1466805,"position":0},"title":"\u00bfQu\u00e9 ganan El Salvador y Bukele recibiendo deportados de EE.UU.?","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Con las cabezas rapadas, encorvados y esposados de pies y manos. As\u00ed ingresaron al Centro de Confinamiento de Terrorismo (Cecot) de El Salvador los 261 inmigrantes deportados por Estados Unidos bajo \u00f3rdenes del presidente Donald Trump.Funcionarios estadounidenses describieron a algunos de los expulsados como presuntos miembros de la organizaci\u00f3n criminal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460327,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/24\/lider-pandilla-ms13-eeuu-deportacion-salvador-trax\/","url_meta":{"origin":1466805,"position":1},"title":"&#171;P\u00e9rdida hist\u00f3rica&#187;: presunto l\u00edder de pandilla MS-13 evade la justicia de EE.UU. con deportaci\u00f3n a El Salvador","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Como parte de los vuelos de deportaci\u00f3n de presuntos terroristas, que se encuentran en el centro de una tormenta legal y pol\u00edtica, Estados Unidos retir\u00f3 en silencio los cargos contra un presunto l\u00edder clave de la pandilla MS-13 y lo devolvi\u00f3 al presidente pro-Trump de El Salvador, Nayib Bukele.C\u00e9sar Humberto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461723,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/28\/trump-el-salvador-negociaciones-deportados-cecot-trax\/","url_meta":{"origin":1466805,"position":2},"title":"Gobierno de Trump propuso en negociaciones enviar hasta 500 presuntos miembros de pandillas a megaprisi\u00f3n de El Salvador","author":"","date":"abril 28, 2025","format":false,"excerpt":"Estados Unidos propuso enviar hasta 500 inmigrantes venezolanos con presuntos v\u00ednculos con la pandilla Tren de Aragua a El Salvador mientras los dos gobiernos buscan llegar a un acuerdo sobre el uso de la megaprisi\u00f3n de la naci\u00f3n centroamericana, seg\u00fan correos electr\u00f3nicos vistos por CNN.Los detalles del acuerdo, que no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461347,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/18\/kilmar-abrego-garcia-nayib-bukele-tuit-orix\/","url_meta":{"origin":1466805,"position":3},"title":"El pol\u00e9mico tuit de Bukele sobre \u00c1brego Garc\u00eda: &#171;Milagrosamente resucitado de los \u2018campos de muerte\u2019 y \u2018tortura\u2019&#187;","author":"","date":"abril 18, 2025","format":false,"excerpt":"Mientras la situaci\u00f3n de Kilmar \u00c1brego Garc\u00eda, el salvadore\u00f1o deportado de Estados Unidos por error, sigue su curso en los tribunales, el senador dem\u00f3crata Chris Van Hollen logr\u00f3 reunirse con \u00e9l en El Salvador este jueves. El presidente Nayib Bukele aprovech\u00f3 la oportunidad para ironizar sobre la situaci\u00f3n.\u201c\u00a1Kilmar \u00c1brego Garc\u00eda,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470264,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/20\/barrio-18-mara-salvatrucha-pandillas-guatemala-orix\/","url_meta":{"origin":1466805,"position":4},"title":"\u00bfQu\u00e9 son y c\u00f3mo operan Barrio 18 y la Mara Salvatrucha, las dos pandillas con mayor presencia en Guatemala?","author":"","date":"enero 20, 2026","format":false,"excerpt":"Guatemala vive el segundo de los 30 d\u00edas de estado de sitio declarados por el presidente Bernardo Ar\u00e9valo tras el asesinato de nueve polic\u00edas. Desde hace varios a\u00f1os, el pa\u00eds centroamericano es escenario de las operaciones criminales de dos principales pandillas, la Mara Salvatrucha (MS-13) y Barrio 18, que a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459994,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/03\/16\/el-salvador-miembros-tren-aragua-megaprision-bukele-orix\/","url_meta":{"origin":1466805,"position":5},"title":"El Salvador recibe a 238 supuestos miembros del Tren de Aragua y los env\u00eda a la megaprisi\u00f3n de Bukele","author":"","date":"marzo 16, 2025","format":false,"excerpt":"El presidente de El Salvador, Nayib Bukele, anunci\u00f3 este domingo que su pa\u00eds ha recibido a 238 supuestos miembros de la organizaci\u00f3n criminal Tren de Aragua, quienes fueron trasladados desde Estados Unidos bajo \u00f3rdenes del presidente Donald Trump.\u201cQuiero expresar mi sincero agradecimiento al presidente Nayib Bukele de El Salvador por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466805"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466805\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}