{"id":1466819,"date":"2025-09-25T11:03:52","date_gmt":"2025-09-25T18:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/"},"modified":"2025-09-25T11:03:52","modified_gmt":"2025-09-25T18:03:52","slug":"amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/","title":{"rendered":"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime"},"content":{"rendered":"<p>Amazon lleg\u00f3 a un hist\u00f3rico acuerdo de US$ 2.500 millones con la Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s), anunci\u00f3 este jueves la agencia, con lo que pone fin a una<a href=\"https:\/\/www.cnn.com\/2025\/09\/22\/tech\/amazon-ftc-trial\"> disputa de dos a\u00f1os<\/a> por acusaciones de que la compa\u00f1\u00eda enga\u00f1\u00f3 a consumidores para inscribirse en su servicio de suscripci\u00f3n Prime y luego dificult\u00f3 la cancelaci\u00f3n.<\/p>\n<p>Como parte del acuerdo, Amazon pagar\u00e1 una multa civil de US$ 1.000 millones y entregar\u00e1 US$ 1.500 millones en reembolsos a unos 35 millones de clientes que fueron \u201cperjudicados por sus pr\u00e1cticas enga\u00f1osas de inscripci\u00f3n a Prime\u201d, dijo la FTC en un comunicado de prensa.<\/p>\n<p>El acuerdo se produce pocos d\u00edas despu\u00e9s del inicio del juicio entre la FTC y Amazon. La demanda se present\u00f3 en 2023, durante el Gobierno de Biden, por las pol\u00edticas de cancelaci\u00f3n de la empresa.<\/p>\n<p>\u201cHoy, la FTC de Trump-Vance hizo historia y asegur\u00f3 una victoria monumental y sin precedentes para los millones de estadounidenses cansados de suscripciones enga\u00f1osas que parecen imposibles de cancelar\u201d, dijo el presidente de la FTC, Andrew Ferguson.<\/p>\n<p>\u201cLa evidencia mostr\u00f3 que Amazon utiliz\u00f3 trampas de suscripci\u00f3n sofisticadas dise\u00f1adas para manipular a los consumidores para inscribirse en Prime, y luego hizo extremadamente dif\u00edcil que los consumidores terminaran su suscripci\u00f3n\u201d, agreg\u00f3.<\/p>\n<p>\u201cAmazon y nuestros ejecutivos siempre hemos cumplido con la ley y este acuerdo nos permite seguir adelante y enfocarnos en innovar para los clientes\u201d, dijo Mark Blafkin, portavoz de Amazon, en un comunicado. \u201cTrabajamos con enorme esfuerzo para que sea claro y sencillo tanto inscribirse como cancelar la membres\u00eda de Prime, y para ofrecer un valor sustancial a nuestros muchos millones de fieles miembros de Prime en todo el mundo\u201d.<\/p>\n<p>La FTC se\u00f1al\u00f3 que Amazon tampoco podr\u00e1 seguir usando un bot\u00f3n que diga \u201cNo, no quiero el env\u00edo gratis\u201d. La compa\u00f1\u00eda deber\u00e1 incluir \u201cdivulgaciones claras y visibles\u201d sobre los t\u00e9rminos de Prime durante el proceso de inscripci\u00f3n y ofrecer \u201cformas sencillas\u201d de cancelar el programa.<\/p>\n<p>Prime, que cuesta US$ 14,99 al mes o US$ 139 al a\u00f1o, es uno de los servicios emblem\u00e1ticos de la empresa y genera miles de millones de d\u00f3lares. El servicio comenz\u00f3 como un complemento para entregas r\u00e1pidas y desde entonces se ha convertido en una plataforma multifac\u00e9tica que incluye entretenimiento en streaming, entrega de v\u00edveres, beneficios en combustible y comida, as\u00ed como ofertas exclusivas para suscriptores.<\/p>\n<p>El pago de US$ 2.500 millones representa el 5,6 % de los ingresos por suscripciones de Prime el a\u00f1o pasado, que alcanzaron los US$ 44.000 millones, seg\u00fan el analista de Emarketer Zak Stambor. Agreg\u00f3 que el acuerdo podr\u00eda \u201cagilizar el proceso de cancelaci\u00f3n de Prime, pero no afectar\u00e1 el dominio del programa\u201d.<\/p>\n<p>Amazon no revela cu\u00e1ntos suscriptores estadounidenses tiene, pero un <a href=\"https:\/\/cirpamazon.substack.com\/p\/updated-us-amazon-prime-member-estimate\">an\u00e1lisis externo<\/a> de Consumer Intelligence Research Partners estima que ten\u00eda 197 millones de clientes en marzo de 2025.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amazon lleg\u00f3 a un hist\u00f3rico acuerdo de US$ 2.500 millones con la Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s), anunci\u00f3 este jueves la agencia, con lo que pone fin a una disputa de dos a\u00f1os por acusaciones de que la compa\u00f1\u00eda enga\u00f1\u00f3 a consumidores para inscribirse en su servicio de suscripci\u00f3n Prime [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466819","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime - Noticias\" \/>\n<meta property=\"og:description\" content=\"Amazon lleg\u00f3 a un hist\u00f3rico acuerdo de US$ 2.500 millones con la Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s), anunci\u00f3 este jueves la agencia, con lo que pone fin a una disputa de dos a\u00f1os por acusaciones de que la compa\u00f1\u00eda enga\u00f1\u00f3 a consumidores para inscribirse en su servicio de suscripci\u00f3n Prime [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T18:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime\",\"datePublished\":\"2025-09-25T18:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/\"},\"wordCount\":530,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/\",\"name\":\"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-25T18:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime - Noticias","og_description":"Amazon lleg\u00f3 a un hist\u00f3rico acuerdo de US$ 2.500 millones con la Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s), anunci\u00f3 este jueves la agencia, con lo que pone fin a una disputa de dos a\u00f1os por acusaciones de que la compa\u00f1\u00eda enga\u00f1\u00f3 a consumidores para inscribirse en su servicio de suscripci\u00f3n Prime [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-25T18:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/"},"author":{"name":"","@id":""},"headline":"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime","datePublished":"2025-09-25T18:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/"},"wordCount":530,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/","name":"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-25T18:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Amazon pagar\u00e1 un hist\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\u00f1ar a clientes para suscribirse a Prime","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-25T18:03:52Z","datePublished":"2025-09-25T18:03:52Z","dateModified":"2025-09-25T18:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Amazon pagar\\u00e1 un hist\\u00f3rico acuerdo de US$ 2.500 millones por presuntamente enga\\u00f1ar a clientes para suscribirse a Prime\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/25\\\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/25\\\/amazon-pagara-millonario-acuerdo-enganar-clientes-suscripcion-prime-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-25T18:03:52Z\",\"datePublished\":\"2025-09-25T18:03:52Z\",\"dateModified\":\"2025-09-25T18:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466885,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/26\/reembolso-historico-acuerdo-amazon-prime-trax\/","url_meta":{"origin":1466819,"position":0},"title":"As\u00ed puedes obtener un reembolso del hist\u00f3rico acuerdo de Amazon Prime","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"Amazon pronto tendr\u00e1 que reembolsar a algunos miembros Prime como parte de un acuerdo de US$ 2.500 millones con la Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s), de los cuales US$ 1.500 millones ser\u00e1n devueltos directamente a los clientes. Es el mayor acuerdo de la FTC y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446023,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/02\/26\/gobierno-ee-uu-demanda-fusion-supermercados-trax\/","url_meta":{"origin":1466819,"position":1},"title":"Gobierno de EE.UU. busca bloquear con una demanda la mayor fusi\u00f3n de supermercados de la historia","author":"","date":"febrero 26, 2024","format":false,"excerpt":"Nueva York (CNN) -- La Comisi\u00f3n Federal de Comercio (FTC, por sus siglas en ingl\u00e9s) present\u00f3 este lunes una demanda para bloquear el acuerdo por US$ 25.000 millones entre Kroger y Albertsons, y advirti\u00f3 que la mayor fusi\u00f3n de supermercados de la historia de Estados Unidos podr\u00eda llevar a precios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456444,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/12\/10\/jueza-bloquea-fusion-supermercados-kroger-trax\/","url_meta":{"origin":1466819,"position":2},"title":"Una jueza federal bloquea la fusi\u00f3n m\u00e1s grande de supermercados de la historia","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"Una jueza federal de Oregon bloque\u00f3 la propuesta de fusi\u00f3n de Kroger con Albertsons, por valor de US$ 25.000 millones, al dictaminar que la mayor fusi\u00f3n en la historia de los supermercados estadounidenses limitar\u00eda la competencia y perjudicar\u00eda a los consumidores.El fallo supone un importante rev\u00e9s para las cadenas y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465558,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/08\/16\/att-reclamo-pago-clientes-trax\/","url_meta":{"origin":1466819,"position":3},"title":"AT&#038;T podr\u00eda pagar a clientes hasta US$ 7.500 en un acuerdo de US$ 177 millones por filtraci\u00f3n de datos","author":"","date":"agosto 16, 2025","format":false,"excerpt":"Millones de clientes de AT&T pueden presentar reclamos por hasta US$ 7.500 en pagos en efectivo como parte de un acuerdo de US$ 177 millones relacionado con una filtraci\u00f3n de datos en 2024.La empresa de telecomunicaciones enfrent\u00f3 un par de filtraciones de datos, anunciadas en marzo y julio de 2024,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468481,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/11\/18\/meta-no-es-monopolio-dice-juez-trax\/","url_meta":{"origin":1466819,"position":4},"title":"Victoria para Meta: un juez dictamin\u00f3 que el gigante de las redes sociales no es un monopolio ilegal","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"Meta obtuvo una gran victoria este martes despu\u00e9s de que un juez federal dictaminara que la empresa no es un monopolio de redes sociales, desestimando un argumento de la Comisi\u00f3n Federal de Comercio de EE.UU. que buscaba obligar a la compa\u00f1\u00eda a desprenderse de dos de sus plataformas m\u00e1s populares.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451148,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/15\/google-mayor-adquisicion-historia-comprar-wiz-trax\/","url_meta":{"origin":1466819,"position":5},"title":"Google est\u00e1 cerca de realizar la mayor adquisici\u00f3n de su historia: una startup llamada Wiz","author":"","date":"julio 15, 2024","format":false,"excerpt":"(CNN) -- Alphabet, propietaria de Google, est\u00e1 en conversaciones avanzadas para comprar la startup de ciberseguridad Wiz, de r\u00e1pido crecimiento, por unos US$ 23.000 millones, confirm\u00f3 a CNN una persona familiarizada con el asunto.La adquisici\u00f3n de Wiz, que fabrica software de ciberseguridad para servicios en la nube, supondr\u00eda una importante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466819"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466819\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}