{"id":1466831,"date":"2025-09-25T17:03:52","date_gmt":"2025-09-26T00:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/"},"modified":"2025-09-25T17:03:52","modified_gmt":"2025-09-26T00:03:52","slug":"muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/","title":{"rendered":"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n"},"content":{"rendered":"<p>Ismael Ayala Uribe, mexicano que fue detenido en una operaci\u00f3n migratoria el pasado 17 de agosto en California, falleci\u00f3 el lunes mientras se encontraba en un centro m\u00e9dico bajo la custodia del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus sus siglas en ingl\u00e9s) de Estados Unidos.<\/p>\n<p>Luego de ser detenido, el mexicano de 39 a\u00f1os, quien fue beneficiario del programa de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA, por sus siglas en ingl\u00e9s) de 2012 a 2016, fue llevado al Centro de Detenci\u00f3n de ICE de Adelanto, tambi\u00e9n en California, el 22 de agosto, seg\u00fan un <a href=\"https:\/\/www.ice.gov\/news\/releases\/mexican-national-dies-ice-custody-after-being-referred-local-hospital-day-prior\">comunicado<\/a> del ICE.<\/p>\n<p>Casi un mes despu\u00e9s, el 18 de septiembre, el ICE dijo que Ayala Uribe fue evaluado por un m\u00e9dico de guardia y le dio medicamento, tras lo cual regres\u00f3 a su dormitorio. La agencia migratoria estadounidense no mencion\u00f3 por qu\u00e9 el mexicano acudi\u00f3 a revisi\u00f3n m\u00e9dica, pero se\u00f1al\u00f3 que \u201cera hipertenso y presentaba taquicardia anormal\u201d.<\/p>\n<p>Las <a href=\"https:\/\/www.ice.gov\/doclib\/detention-standards\/2025\/nds2025.pdf\">normas de detenci\u00f3n del ICE<\/a> indican que los detenidos deben recibir, m\u00e1ximo 12 horas despu\u00e9s de ser puestos bajo custodia, una evaluaci\u00f3n inicial m\u00e9dica, dental y mental; en tanto, en los siguientes 14 d\u00edas, el centro de detenci\u00f3n tiene que documentar una evaluaci\u00f3n integral de salud de cada detenido. En los siguientes tres meses despu\u00e9s de cualquier fallecimiento bajo custodia, el ICE debe hacer p\u00fablicos todos los detalles en materia de salud.<\/p>\n<p>Tras la revisi\u00f3n del m\u00e9dico de guardia, Ayala Uribe fue remitido el 21 de septiembre al mediod\u00eda al Centro M\u00e9dico Global Victor Valley por un absceso en su gl\u00fateo y se le program\u00f3 para cirug\u00eda. Sin embargo, poco m\u00e1s de 12 horas despu\u00e9s, ICE dijo que el personal del hospital encontr\u00f3 al mexicano \u201cincosciente y tom\u00f3 medidas para salvarle la vida\u201d. Ayala Uribe fue declarado muerto la madrugada del lunes.<\/p>\n<p>ICE tampoco inform\u00f3 las razones del deterioro en la salud de Ayala Uribe mientras estaba hospitalizado o por qu\u00e9 fue encontrado \u201csin respuesta\u201d, e indic\u00f3 que la causa del fallecimiento sigue bajo investigaci\u00f3n.<\/p>\n<p>Del 21 de enero a la fecha \u2014es decir, durante los primeros ocho meses del segundo mandato de Donald Trump como presidente de Estados Unidos\u2014, se han registrado 14 muertes de migrantes bajo la custodia del ICE, incluida la de Ismael Ayala, seg\u00fan <a href=\"https:\/\/www.ice.gov\/detain\/detainee-death-reporting\">datos<\/a> de la agencia migratoria.<\/p>\n<p>En el mismo lapso durante el primer mandato de Trump, se registraron nueve muertes de migrantes bajo custodia de la agencia, de acuerdo con <a href=\"https:\/\/assets.aclu.org\/live\/uploads\/2024\/06\/2024-07-01-ICE-Detainee-Deaths.pdf\">datos<\/a> obtenidos por la Uni\u00f3n Estadounidense por las Libertades Civiles (ACLU), Physicians for Human Rights (PHR) y American Oversight para el informe de investigaci\u00f3n \u201cDeadly Failures: Preventable Deaths in U.S. Immigration Detention\u201d.<\/p>\n<p>En tanto, en los primeros nueve meses de Joe Biden como presidente de Estados Unidos, se registraron cuatro muertes de migrantes que estaba bajo custodia de ICE, muestran los <a href=\"https:\/\/www.ice.gov\/detain\/detainee-death-reporting\">datos<\/a> de la agencia estadounidense.<\/p>\n<p>En una nota diplom\u00e1tica, la Secretar\u00eda de Relaciones Exteriores (SRE) de M\u00e9xico <a href=\"https:\/\/www.gob.mx\/sre\/prensa\/acciones-consulares-ante-el-fallecimiento-de-persona-mexicana-bajo-custodia-de-ice-en-california\">expres\u00f3<\/a> este mi\u00e9rcoles su \u201cpreocupaci\u00f3n ante lo acontecido\u201d y pidi\u00f3 que se realice una \u201cinvestigaci\u00f3n rigurosa\u201d para esclarecer los hechos alrededor del fallecimiento de Ismael Ayala, que calific\u00f3 como graves.<\/p>\n<p>La SRE a\u00f1adi\u00f3 que el Consulado de M\u00e9xico en San Bernardino, en California, est\u00e1 en contacto con el centro de detenci\u00f3n de Adelanto \u201cpara asegurar la realizaci\u00f3n de una investigaci\u00f3n exhaustiva que permita esclarecer plenamente la causa de la muerte, en atenci\u00f3n a la gravedad de los hechos\u201d.<\/p>\n<p>El Consulado mexicano en San Bernardino, indic\u00f3 la SRE, est\u00e1 en contacto con la familia de Ayala Uribe para brindar asistencia legal y acompa\u00f1amiento.<\/p>\n<p>CNN contact\u00f3 a Jos\u00e9 y Mayra Ayala, hermanos de Ismael, y comentaron que el Consulado mexicano los est\u00e1 apoyando con la defensa legal, que est\u00e1 a cargo del abogado Jes\u00fas Arias.<\/p>\n<p>CNN se comunic\u00f3 con Arias para saber cu\u00e1l es la postura de la familia respecto a la muerte de Ayala Uribe bajo custodia del ICE y cu\u00e1les ser\u00e1n los pasos legales a seguir, y espera respuesta.<\/p>\n<p>La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo el mi\u00e9rcoles en su conferencia matutina que Ayala Uribe falleci\u00f3 en un hospital \u201cpresuntamente producto de una detenci\u00f3n\u201d.<\/p>\n<p>\u201cSe envi\u00f3 una nota diplom\u00e1tica sobre este caso, solicitando que se hagan todas las investigaciones y que, si hay alguna responsabilidad y violaci\u00f3n a los derechos humanos, sea sancionada\u201d, coment\u00f3 Sheinbaum.<\/p>\n<p>La organizaci\u00f3n sin fines de lucro Disability Rights California (DRC) dijo estar \u201cfuriosa y triste\u201d por el fallecimiento de Ayala Uribe.<\/p>\n<p>\u201cLa tr\u00e1gica muerte de Ayala Uribe subraya la urgente necesidad de reformas importantes en Adelanto\u201d \u2014centro de detenci\u00f3n que es gestionado por la empresa GEO Group y que inici\u00f3 operaciones en 2011\u2014, se\u00f1al\u00f3 DRC el mi\u00e9rcoles en un <a href=\"https:\/\/www.disabilityrightsca.org\/latest-news\/death-at-adelanto-detention-facility-heightens-alarm-about-treatment\">comunicado<\/a>.<\/p>\n<p>DRC denunci\u00f3 las malas condiciones en el centro de detenci\u00f3n de Adelanto en un <a href=\"https:\/\/www.disabilityrightsca.org\/drc-advocacy\/investigations\/inside-the-adelanto-ice-processing-center\">informe publicado en julio<\/a>, el cual menciona que, tras una visita de monitoreo llevada a cabo en junio, la organizaci\u00f3n pudo escuchar gritos de detenidos que dec\u00edan \u201c\u00a1nos tratan como perros!\u201d.<\/p>\n<p>\u201cEl informe describe condiciones preocupantes, incluida la falta de acceso a atenci\u00f3n m\u00e9dica y de salud mental apropiada y a procesos que aborden adecuadamente las necesidades relacionadas con la discapacidad\u201d, agreg\u00f3 DRC en el comunicado del mi\u00e9rcoles.<\/p>\n<p>Sobre estos se\u00f1alamientos contra el centro de detenci\u00f3n de Adelanto, CNN contact\u00f3 a GEO Group para conocer su postura. En su respuesta, refiri\u00f3 al comunicado de ICE publicado <a href=\"https:\/\/www.ice.gov\/news\/releases\/mexican-national-dies-ice-custody-after-being-referred-local-hospital-day-prior\">el martes<\/a> y no dio m\u00e1s detalles.<\/p>\n<p>Por su parte, la ONG Inland Coalition for Immigrant Justice <a href=\"https:\/\/www.instagram.com\/ic4ij\/p\/DO-LjKyDoJb\/\">exigi\u00f3 el mi\u00e9rcoles<\/a> que se haga justicia en el caso de Ismael Ayala y pidi\u00f3 que se realice \u201cun informe completo, independiente y transparente sobre las circunstancias que llevaron a la muerte\u201d del ciudadano mexicano. \u201cICE no debe esconderse detr\u00e1s de comunicados de prensa vagos; el p\u00fablico y su familia merecen saber la verdad\u201d, agreg\u00f3 en un comunicado.<\/p>\n<p>Respecto a las condiciones en centros de detenci\u00f3n migratorios, el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) dijo este jueves a CNN que \u201ces una pr\u00e1ctica de larga data proporcionar atenci\u00f3n m\u00e9dica integral\u201d a los migrantes que est\u00e1n bajo custodia de ICE.<\/p>\n<p>\u201cEsto incluye ex\u00e1menes m\u00e9dicos, dentales y de salud mental dentro de las 12 horas de llegar a cada centro de detenci\u00f3n, una evaluaci\u00f3n completa de salud dentro de los 14 d\u00edas de ingresar a la custodia de ICE o de llegar a un centro, y acceso a citas m\u00e9dicas y atenci\u00f3n de emergencia las 24 horas\u201d, asegur\u00f3 Tricia McLaughlin, portavoz del DHS, en un comunicado enviado por correo electr\u00f3nico.<\/p>\n<p>Seg\u00fan la informaci\u00f3n del ICE, Ayala Uribe fue beneficiario de DACA a partir de 2012, a\u00f1o en que <a href=\"https:\/\/cnnespanol.cnn.com\/2021\/09\/27\/que-es-daca-como-funciona-programa-protege-dreamers-deportacion-orix\">comenz\u00f3<\/a> este programa de migraci\u00f3n insignia del Gobierno del expresidente Barack Obama.<\/p>\n<p>El programa <a href=\"https:\/\/cnnespanol.cnn.com\/2021\/09\/27\/que-es-daca-como-funciona-programa-protege-dreamers-deportacion-orix\">DACA<\/a> protege de la deportaci\u00f3n y da autorizaci\u00f3n de trabajo a miles de j\u00f3venes inmigrantes que llegaron o se quedaron en Estados Unidos de manera ilegal antes de cumplir los 16 a\u00f1os, conocidos como <em>dreamers<\/em>. Actualmente, por decisi\u00f3n de tribunales federales, <a href=\"https:\/\/www.uscis.gov\/es\/DACA\">el programa DACA<\/a> acepta renovaciones, pero no tramita nuevas solicitudes.<\/p>\n<p>En 2016, al tratar de renovar al programa DACA, la solicitud de Ismael Ayala fue rechazada.<\/p>\n<p>Previamente, en septiembre de 2015, Ayala Uribe fue condenado por manejar bajo la influencia del alcohol (en mayo de ese a\u00f1o) en la Corte Superior de California en el condado de Orange y sentenciado a tres a\u00f1os de libertad condicional. Asimismo, se le impuso una multa de US$ 390, 40 horas de servicio comunitario y un programa de tres meses para personas que comenten este delito por primera vez, seg\u00fan pudo ver CNN en registros judiciales.<\/p>\n<p>El Servicio de Ciudadan\u00eda e Inmigraci\u00f3n de Estados Unidos (USCIS, por sus siglas en ingl\u00e9s) indica que cualquier persona que cometa el delito de manejar bajo la influencia del alcohol <a href=\"https:\/\/www.uscis.gov\/es\/DACA\">no ser\u00e1 considerado<\/a> para el programa DACA.<\/p>\n<p>Jes\u00fas Arias, el abogado de la familia de Ismael, dijo a CNN que la condena y sentencia por manejar bajo la influencia del alcohol en 2015 fue el motivo por el cual la solicitud de renovaci\u00f3n al programa DACA de Ayala Uribe fue rechazada.<\/p>\n<p>En junio de 2019, Ayala Uribe fue condenado por el mismo delito (ocurrido en mayo de 2018, al estar bajo libertad condicional) en la Corte Superior de California en el condado de Orange y sentenciado a 120 d\u00edas de c\u00e1rcel (cuatro meses, que comenzaron en agosto de 2019), cinco a\u00f1os de libertad condicional, una multa de US$ 265 y un programa de 18 meses para personas que manejan bajo la influencia del alcohol en m\u00faltiples ocasiones, seg\u00fan registros judiciales. Ismael Ayala finaliz\u00f3 sus cinco a\u00f1os de libertad condicional el 11 de junio de 2024.<\/p>\n<p>Seg\u00fan ICE, Ayala Uribe fue detenido el 17 de agosto de este a\u00f1o en una operaci\u00f3n migratoria de la Oficina de Aduanas y Protecci\u00f3n Fronteriza (CBP, por sus siglas en ingl\u00e9s) de Estados Unidos. KCAL, afiliada de CNN, <a href=\"https:\/\/www.instagram.com\/reel\/DO_jQrWCaN2\/\">dijo<\/a> que el arresto ocurri\u00f3 en un autolavado de Los \u00c1ngeles donde el mexicano trabajaba. CNN pregunt\u00f3 a Arias sobre el caso y espera respuesta.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ismael Ayala Uribe, mexicano que fue detenido en una operaci\u00f3n migratoria el pasado 17 de agosto en California, falleci\u00f3 el lunes mientras se encontraba en un centro m\u00e9dico bajo la custodia del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus sus siglas en ingl\u00e9s) de Estados Unidos. Luego de ser detenido, el mexicano [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466831","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ismael Ayala Uribe, mexicano que fue detenido en una operaci\u00f3n migratoria el pasado 17 de agosto en California, falleci\u00f3 el lunes mientras se encontraba en un centro m\u00e9dico bajo la custodia del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus sus siglas en ingl\u00e9s) de Estados Unidos. Luego de ser detenido, el mexicano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-26T00:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n\",\"datePublished\":\"2025-09-26T00:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/\"},\"wordCount\":1604,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/\",\"name\":\"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-26T00:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n - Noticias","og_description":"Ismael Ayala Uribe, mexicano que fue detenido en una operaci\u00f3n migratoria el pasado 17 de agosto en California, falleci\u00f3 el lunes mientras se encontraba en un centro m\u00e9dico bajo la custodia del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus sus siglas en ingl\u00e9s) de Estados Unidos. Luego de ser detenido, el mexicano [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-26T00:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/"},"author":{"name":"","@id":""},"headline":"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n","datePublished":"2025-09-26T00:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/"},"wordCount":1604,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/","name":"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-26T00:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\u00e9xico y ONG exigen investigaci\u00f3n","url":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/09\/25\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-26T00:03:52Z","datePublished":"2025-09-26T00:03:52Z","dateModified":"2025-09-26T00:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere un mexicano exbeneficiario de DACA bajo custodia del ICE; autoridades de M\\u00e9xico y ONG exigen investigaci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/25\\\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/09\\\/25\\\/muere-mexicano-daca-custodia-ice-autoridades-mexico-organizaciones-justicia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-26T00:03:52Z\",\"datePublished\":\"2025-09-26T00:03:52Z\",\"dateModified\":\"2025-09-26T00:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466999,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/30\/tragedia-pudo-evitarse-familia-mexicano-muerto-ice-acciones-legales-orix\/","url_meta":{"origin":1466831,"position":0},"title":"&#171;Es una tragedia que pudo haber sido evitada&#187;: familia de mexicano muerto bajo custodia de ICE inicia acciones legales","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"La familia de Ismael Ayala Uribe, el mexicano de 39 a\u00f1os que muri\u00f3 el 22 de septiembre bajo custodia del Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos (ICE, por sus siglas en ingl\u00e9s), anunci\u00f3 este martes que inici\u00f3 acciones legales para exigir el esclarecimiento de la muerte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472757,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/01\/que-paso-14-mexicanos-muertos-custodia-ice-trump-orix\/","url_meta":{"origin":1466831,"position":1},"title":"Qu\u00e9 pas\u00f3 con los 14 mexicanos que murieron bajo custodia de ICE y en operativos migratorios en el segundo mandato de Trump","author":"","date":"abril 1, 2026","format":false,"excerpt":"Una de las tr\u00e1gicas consecuencias de la ofensiva migratoria de Donald Trump en su segundo mandato como presidente de Estados Unidos ha sido el aumento de las muertes de mexicanos bajo custodia de Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) y en operativos anti\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473110,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/13\/muerte-inmigrante-ice-louisiana-orix\/","url_meta":{"origin":1466831,"position":2},"title":"Muere en Louisiana otro inmigrante mexicano bajo custodia de ICE, el tercer caso en poco menos de un mes","author":"","date":"abril 13, 2026","format":false,"excerpt":"Un inmigrante mexicano muri\u00f3 este s\u00e1bado bajo custodia del Servicio de Inmigraci\u00f3n y Aduanas de Estados Unidos (ICE, por sus siglas en ingl\u00e9s) en Louisiana, inform\u00f3 la agencia este lunes, el tercer caso que se conoce en poco menos de un mes en medio de las duras pol\u00edticas de inmigraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472645,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/28\/muere-inmigrante-mexicano-custodia-ice-segundo-caso-10-dias-orix\/","url_meta":{"origin":1466831,"position":3},"title":"Muere un inmigrante mexicano bajo custodia de ICE, el segundo caso que se conoce en 10 d\u00edas","author":"","date":"marzo 28, 2026","format":false,"excerpt":"Un inmigrante mexicano muri\u00f3 el mi\u00e9rcoles en un centro de detenci\u00f3n de California bajo custodia del Servicio de Inmigraci\u00f3n y Aduanas de Estados Unidos (ICE, por sus siglas en ingl\u00e9s), inform\u00f3 la Secretar\u00eda de Relaciones Exteriores (SRE) de M\u00e9xico el viernes en un comunicado.La causa de muerte a\u00fan no ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472365,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/19\/muere-inmigrante-mexicano-ice-florida-orix\/","url_meta":{"origin":1466831,"position":4},"title":"Muere un inmigrante mexicano bajo custodia de ICE en Florida","author":"","date":"marzo 19, 2026","format":false,"excerpt":"Un mexicano de 19 a\u00f1os muri\u00f3 bajo custodia del Servicio de Inmigraci\u00f3n y Aduanas de Estados Unidos (ICE, por sus siglas en ingl\u00e9s) en Florida, inform\u00f3 la agencia este mi\u00e9rcoles, en un caso que eleva a 13 las muertes registradas este a\u00f1o en centros de detenci\u00f3n y a 44 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464186,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/07\/03\/migrante-cubano-60-anios-viviendo-detenido-fallecio-custodia-ice-orix\/","url_meta":{"origin":1466831,"position":5},"title":"\u00bfQu\u00e9 pas\u00f3 con el migrante cubano que falleci\u00f3 bajo custodia de ICE? Esto es lo que sabemos","author":"","date":"julio 3, 2025","format":false,"excerpt":"Isidro P\u00e9rez lleg\u00f3 a Estados Unidos en 1966, cuando ten\u00eda apenas 16 a\u00f1os. En ese entonces, las autoridades concedieron a este migrante de Cuba un permiso de permanencia temporal (parole, en ingl\u00e9s) para residir de forma legal en el pa\u00eds.Pero todo cambi\u00f3 el mes pasado. Tras casi 60 a\u00f1os viviendo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1466831"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1466831\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1466831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1466831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1466831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}