{"id":1467230,"date":"2025-10-09T07:03:40","date_gmt":"2025-10-09T14:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/"},"modified":"2025-10-09T07:03:40","modified_gmt":"2025-10-09T14:03:40","slug":"eeuu-rechaza-version-petro-ataque-lancha-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/","title":{"rendered":"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos"},"content":{"rendered":"<p>La Casa Blanca desestim\u00f3 el jueves la afirmaci\u00f3n del presidente de Colombia, Gustavo Petro, quien se\u00f1al\u00f3 que el <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/03\/eeuu\/ataque-bote-frente-costa-venezuela-mata-cuatro-secretario-defensa-trax\">ataque militar m\u00e1s reciente<\/a> de Estados Unidos en el Caribe pudo haber tenido como objetivo una embarcaci\u00f3n colombiana, y dijo a CNN que la acusaci\u00f3n era \u201cinfundada y reprochable\u201d.<\/p>\n<p>\u201cEstados Unidos espera que el presidente Petro se retracte p\u00fablicamente de su declaraci\u00f3n infundada y reprochable para que podamos volver a un di\u00e1logo productivo con miras a construir un futuro s\u00f3lido y pr\u00f3spero para los pueblos de Estados Unidos y Colombia\u201d, se\u00f1al\u00f3 un funcionario de la Casa Blanca, en un comunicado a CNN.<\/p>\n<p>\u201cA pesar de las diferencias pol\u00edticas con el Gobierno actual, Colombia sigue siendo un socio estrat\u00e9gico fundamental. Estamos comprometidos con una estrecha cooperaci\u00f3n en una variedad de prioridades compartidas, incluida la seguridad y la estabilidad regional, y seguimos enfocados en iniciativas que mejoren la vida tanto de estadounidenses como de colombianos\u201d, a\u00f1adi\u00f3 el funcionario.<\/p>\n<p>El mi\u00e9rcoles, el mandatario sudamericano afirm\u00f3 en una publicaci\u00f3n en X que la \u00faltima embarcaci\u00f3n que Estados Unidos atac\u00f3 la semana pasada en el Caribe podr\u00eda haber sido colombiana.<\/p>\n<p>\u201cIndicios muestran que la \u00faltima lancha bombardeada era colombiana con ciudadanos colombianos en su interior\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/08\/colombia\/petro-ultimo-barco-bombardeado-podria-ser-colombiano-trax\">escribi\u00f3 Petro<\/a>, sin ofrecer detalles ni pruebas. \u201cLa agresi\u00f3n es contra toda Am\u00e9rica Latina y el Caribe\u201d, agreg\u00f3.<\/p>\n<p>El secretario de Defensa, Pete Hegseth, dijo el viernes que EE.UU. atac\u00f3 lo que describi\u00f3 como una \u201cembarcaci\u00f3n de narcotr\u00e1fico\u201d en aguas internacionales, frente a la costa de Venezuela, matando a las cuatro personas a bordo.<\/p>\n<p>Se trata de al menos el cuarto ataque militar conocido de Estados Unidos en la regi\u00f3n desde principios de septiembre, todos dirigidos a embarcaciones que la administraci\u00f3n afirma est\u00e1n \u201cvinculadas\u201d a c\u00e1rteles de la droga. EE.UU. se\u00f1al\u00f3 que al menos dos de las embarcaciones salieron de Venezuela.<\/p>\n<p>Petro tambi\u00e9n sugiri\u00f3 a finales de septiembre que otro de esos operativos podr\u00eda haber causado la muerte de ciudadanos colombianos.<\/p>\n<p>En relaci\u00f3n con una nave que fue atacada el 19 de septiembre, el presidente colombiano dijo en ese momento: \u201cSi la lancha fue hundida en Rep\u00fablica Dominicana, entonces es posible que fueran colombianos. Eso significar\u00eda que funcionarios de EE.UU. y Rep\u00fablica Dominicana ser\u00edan culpables de asesinato de ciudadanos colombianos\u201d.<\/p>\n<p>El secretario de Estado de EE.UU., Marco Rubio, asegur\u00f3 el domingo que Estados Unidos tiene la certeza de que todas las personas a bordo de las cuatro embarcaciones eran narcotraficantes.<\/p>\n<p>\u201cEl Departamento de Defensa no toma esto a la ligera. Hay muchas embarcaciones que cruzan esa regi\u00f3n, algunas de las cuales sospechamos que pueden llevar drogas, y no disparan contra ellas porque necesitan tener una certeza del 100%\u201d, afirm\u00f3.<\/p>\n<p>Los ataques ocurrieron tras el despliegue de buques de guerra estadounidenses en el mar Caribe, en lo que Washington insiste es una misi\u00f3n para combatir el narcotr\u00e1fico, pero Caracas sostiene que busca un cambio de r\u00e9gimen. EE.UU. ha acusado al l\u00edder venezolano Nicol\u00e1s Maduro de participaci\u00f3n en el narcotr\u00e1fico \u2014acusaci\u00f3n que \u00e9l niega enf\u00e1ticamente\u2014 y recientemente duplic\u00f3 la recompensa por su captura a US$50 millones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Casa Blanca desestim\u00f3 el jueves la afirmaci\u00f3n del presidente de Colombia, Gustavo Petro, quien se\u00f1al\u00f3 que el ataque militar m\u00e1s reciente de Estados Unidos en el Caribe pudo haber tenido como objetivo una embarcaci\u00f3n colombiana, y dijo a CNN que la acusaci\u00f3n era \u201cinfundada y reprochable\u201d. \u201cEstados Unidos espera que el presidente Petro se [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467230","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Casa Blanca desestim\u00f3 el jueves la afirmaci\u00f3n del presidente de Colombia, Gustavo Petro, quien se\u00f1al\u00f3 que el ataque militar m\u00e1s reciente de Estados Unidos en el Caribe pudo haber tenido como objetivo una embarcaci\u00f3n colombiana, y dijo a CNN que la acusaci\u00f3n era \u201cinfundada y reprochable\u201d. \u201cEstados Unidos espera que el presidente Petro se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-09T14:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos\",\"datePublished\":\"2025-10-09T14:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/\"},\"wordCount\":588,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/\",\"name\":\"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-09T14:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos - Noticias","og_description":"La Casa Blanca desestim\u00f3 el jueves la afirmaci\u00f3n del presidente de Colombia, Gustavo Petro, quien se\u00f1al\u00f3 que el ataque militar m\u00e1s reciente de Estados Unidos en el Caribe pudo haber tenido como objetivo una embarcaci\u00f3n colombiana, y dijo a CNN que la acusaci\u00f3n era \u201cinfundada y reprochable\u201d. \u201cEstados Unidos espera que el presidente Petro se [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-09T14:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/"},"author":{"name":"","@id":""},"headline":"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos","datePublished":"2025-10-09T14:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/"},"wordCount":588,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/","name":"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-09T14:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos","url":"http:\/\/noticiasya.com\/lubbock\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-09T14:03:40Z","datePublished":"2025-10-09T14:03:40Z","dateModified":"2025-10-09T14:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Casa Blanca rechaza la versi\\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/10\\\/09\\\/eeuu-rechaza-version-petro-ataque-lancha-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2025\\\/10\\\/09\\\/eeuu-rechaza-version-petro-ataque-lancha-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-09T14:03:40Z\",\"datePublished\":\"2025-10-09T14:03:40Z\",\"dateModified\":\"2025-10-09T14:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467229,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/09\/petro-reclama-eeuu-nombres-muertos-caribe-orix\/","url_meta":{"origin":1467230,"position":0},"title":"Petro sube su apuesta y desaf\u00eda a la Casa Blanca a mostrar los nombres de los muertos en el ataque a una lancha en el Caribe","author":"","date":"octubre 9, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, reclam\u00f3 a la Casa Blanca que d\u00e9 detalles sobre las personas que murieron en un reciente ataque de EE.UU. a una lancha en el Caribe, luego de que el Gobierno del presidente Donald Trump le exija que se retracte por afirmar que la embarcaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469886,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/07\/trump-hablo-presidente-colombia-gustavo-petro-trax\/","url_meta":{"origin":1467230,"position":1},"title":"Trump habl\u00f3 con el presidente de Colombia, Gustavo Petro, y lo invit\u00f3 a una reuni\u00f3n en la Casa Blanca en el &#171;futuro cercano&#187;","author":"","date":"enero 7, 2026","format":false,"excerpt":"El presidente Donald Trump confirm\u00f3 este mi\u00e9rcoles en redes sociales que \u201caprecia\u201d la llamada que sostuvo con el presidente de Colombia, Gustavo Petro, e invit\u00f3 al mandatario sudamericano a una reuni\u00f3n en la Casa Blanca en el \u201cfuturo cercano\u201d.\u201cFue un gran honor hablar con el presidente de Colombia, Gustavo Petro,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467529,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/20\/colombia-llama-consultas-embajador-estados-unidos-orix\/","url_meta":{"origin":1467230,"position":2},"title":"En plena tensi\u00f3n diplom\u00e1tica con la administraci\u00f3n de Trump, Colombia llama a consultas a su embajador en EE.UU.","author":"","date":"octubre 20, 2025","format":false,"excerpt":"Luego de un fin de semana en el que se elevaron las tensiones entre Donald Trump y Gustavo Petro, Colombia llam\u00f3 a consultas a su embajador en Estados Unidos, Daniel Garc\u00eda-Pe\u00f1a.\u201cLa Canciller Rosa Yolanda Villavicencio Mapy informa a la opini\u00f3n p\u00fablica que, Daniel Garc\u00eda-Pe\u00f1a, Embajador de Colombia ante los Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470830,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","url_meta":{"origin":1467230,"position":3},"title":"Petro y Trump tuvieron una reuni\u00f3n &#171;muy buena&#187; que dej\u00f3 un &#171;aire optimista&#187;, tras un a\u00f1o marcado por el choque constante","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Despu\u00e9s de un a\u00f1o marcado por cruces verbales y amenazas, y en el que la relaci\u00f3n entre Colombia y Estados Unidos estuvo constantemente al borde de la ruptura, los presidentes Gustavo Petro y Donald Trump finalmente se vieron este martes cara a cara en Washington.Puede que los l\u00edderes no hayan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466785,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/09\/24\/casa-blanca-defiende-ataques-caribe-criticas-petro-trax\/","url_meta":{"origin":1467230,"position":4},"title":"La Casa Blanca defiende los ataques de Trump en el Caribe tras cr\u00edticas de Petro en la ONU","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"La Casa Blanca defendi\u00f3 este mi\u00e9rcoles los ataques del presidente de EE.UU. Donald Trump a embarcaciones que supuestamente transportaban contrabando de drogas en el Caribe, despu\u00e9s de que el presidente de Colombia Gustavo Petro pidiera que se iniciaran procesos penales en su contra por la reciente acci\u00f3n militar estadounidense.\u201cEl presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467649,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/22\/trump-advierte-petro-tenga-cuidado-respuesta-orix\/","url_meta":{"origin":1467230,"position":5},"title":"Trump advierte que Petro debe &#171;tener cuidado porque tomaremos acciones contra \u00e9l y su pa\u00eds&#187;","author":"","date":"octubre 22, 2025","format":false,"excerpt":"Los presidentes de Estados Unidos, Donald Trump, y de Colombia, Gustavo Petro, tuvieron un nuevo encontronazo este mi\u00e9rcoles, en medio de las tensiones que han mantenido a lo largo de la semana por la reciente presencia militar estadounidense en el Caribe con el argumento de combatir el narcotr\u00e1fico.Durante una conferencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1467230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1467230"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1467230\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1467230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1467230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1467230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}