{"id":1472824,"date":"2026-04-02T22:03:47","date_gmt":"2026-04-03T05:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/"},"modified":"2026-04-02T22:03:47","modified_gmt":"2026-04-03T05:03:47","slug":"cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/","title":{"rendered":"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos"},"content":{"rendered":"<p>El Gobierno cubano anunciar\u00e1 el jueves la liberaci\u00f3n de 2.010 prisioneros, la mayor en a\u00f1os, mientras <a href=\"https:\/\/www.cnn.com\/2026\/02\/18\/americas\/cuba-us-trump-oil-tourism-intl-latam\">la isla se ve sometida<\/a> a una presi\u00f3n cada vez mayor por parte de la administraci\u00f3n Trump.<\/p>\n<p>El Gobierno decidi\u00f3 conceder el indulto bas\u00e1ndose en la buena conducta de los reclusos, su estado de salud y la naturaleza de los \u201cactos cometidos\u201d, seg\u00fan la notificaci\u00f3n publicada en Granma, el peri\u00f3dico oficial del gobernante Partido Comunista.<\/p>\n<p>A\u00f1adi\u00f3 que entre los presos hab\u00eda j\u00f3venes, mujeres, personas mayores de 60 a\u00f1os y extranjeros. La lista no incluye a los condenados que cometieron delitos como asesinato, homicidio, agresi\u00f3n sexual o \u201cdelitos contra la autoridad\u201d.<\/p>\n<p>Seg\u00fan Human Rights Watch, Cuba detiene y persigue regularmente a disidentes, entre ellos activistas, periodistas, manifestantes y opositores pol\u00edticos.<\/p>\n<p>La Habana ya ha llevado a cabo liberaciones masivas de prisioneros como parte de acuerdos con partes internacionales. Por ejemplo, a principios de 2025, Cuba liber\u00f3 a 553 prisioneros tras negociaciones con Estados Unidos y el Vaticano, en las que la administraci\u00f3n Biden se comprometi\u00f3 a aliviar las sanciones contra la isla.<\/p>\n<p>El presidente estadounidense Donald Trump rescindi\u00f3 el acuerdo tras asumir el cargo, lo que llev\u00f3 a Cuba a <a href=\"https:\/\/www.reuters.com\/world\/americas\/cuba-concludes-release-553-prisoners-following-vatican-brokered-deal-2025-03-11\/\">suspender temporalmente<\/a> la liberaci\u00f3n de prisioneros, antes de completarla en marzo.<\/p>\n<p>El comunicado de Granma no mencion\u00f3 a Estados Unidos en su anuncio, citando la liberaci\u00f3n como motivo de las \u201ccelebraciones religiosas de la Semana Santa\u201d, mientras los cristianos de todo el mundo celebran la Pascua.<\/p>\n<p>Sin embargo, Cuba ha sido duramente criticada por la campa\u00f1a de presi\u00f3n del Gobierno de Trump, lo que ha empeorado la ya precaria econom\u00eda de la isla.<\/p>\n<p>A principios de este a\u00f1o, mediante acciones militares en Venezuela y amenazas de aranceles a M\u00e9xico, la administraci\u00f3n Trump <a href=\"https:\/\/www.cnn.com\/2026\/01\/30\/americas\/cuba-oil-supply-trump-tariff-mexico-latam-intl\">cort\u00f3 el flujo de petr\u00f3leo<\/a> a Cuba, intentando presionar a la isla gobernada por comunistas para que realizara importantes reformas pol\u00edticas y econ\u00f3micas.<\/p>\n<p>Trump ha insistido en que el Gobierno cubano debe finalmente abrir la econom\u00eda centralizada de la isla antes de que colapse. Trump tambi\u00e9n ha <a href=\"https:\/\/www.cnn.com\/2026\/03\/16\/americas\/cuba-power-grid-collapse-intl-latam\">hablado con frecuencia<\/a> de su deseo de \u201cconquistar Cuba\u201d.<\/p>\n<p>Muchos de los aliados pol\u00edticos de Trump, incluido el secretario de Estado Marco Rubio, son partidarios de una l\u00ednea dura contra Cuba y desde hace tiempo piden una reforma de su liderazgo comunista.<\/p>\n<p>La isla se est\u00e1 quedando r\u00e1pidamente sin el petr\u00f3leo que le queda, el cual utiliza para alimentar veh\u00edculos y generar electricidad, lo que agrava una <a href=\"https:\/\/www.cnn.com\/2026\/03\/18\/americas\/cuba-us-pressure-blackout-latam-intl\">crisis energ\u00e9tica que arrastra desde hace tiempo.<\/a><\/p>\n<p>La isla ya sufr\u00eda cortes de energ\u00eda prolongados, pero la situaci\u00f3n ha empeorado debido a la falta de combustible en las centrales el\u00e9ctricas. En marzo, Cuba experiment\u00f3 <a href=\"https:\/\/www.cnn.com\/2026\/03\/21\/americas\/cuba-second-nationwide-blackout-latam-intl\">dos apagones a nivel nacional<\/a> en tan solo una semana, dejando a sus m\u00e1s de 10 millones de habitantes sin electricidad.<\/p>\n<p>La vida se ha paralizado por completo: las clases se han suspendido en muchas escuelas, los trabajadores han sido enviados a casa con permiso retribuido para ahorrar energ\u00eda y se han cancelado vuelos desde algunos lugares porque Cuba no tiene suficiente combustible para aviones para vuelos de larga distancia.<\/p>\n<p>A principios de esta semana, Trump permiti\u00f3 la entrada de un petrolero con bandera rusa en aguas cubanas, rompiendo el <a href=\"https:\/\/www.cnn.com\/2026\/03\/18\/americas\/cuba-us-pressure-blackout-latam-intl\">bloqueo de combustible,<\/a> y declar\u00f3: \u201cTienen que sobrevivir\u201d. Posteriormente, la Casa Blanca afirm\u00f3 que esto \u201cno supon\u00eda un cambio de pol\u00edtica\u201d.<\/p>\n<p>Desde que los revolucionarios cubanos liderados por Fidel Castro derrocaron en 1959 al r\u00e9gimen de Fulgencio Batista, respaldado por Estados Unidos, el pa\u00eds ha estado bajo un estricto embargo econ\u00f3mico por parte de Estados Unidos, lo que ha bloqueado la mayor parte de la actividad comercial en la isla que involucre a estadounidenses y ha creado importantes barreras legales para cualquier nueva inversi\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno cubano anunciar\u00e1 el jueves la liberaci\u00f3n de 2.010 prisioneros, la mayor en a\u00f1os, mientras la isla se ve sometida a una presi\u00f3n cada vez mayor por parte de la administraci\u00f3n Trump. El Gobierno decidi\u00f3 conceder el indulto bas\u00e1ndose en la buena conducta de los reclusos, su estado de salud y la naturaleza de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472824","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno cubano anunciar\u00e1 el jueves la liberaci\u00f3n de 2.010 prisioneros, la mayor en a\u00f1os, mientras la isla se ve sometida a una presi\u00f3n cada vez mayor por parte de la administraci\u00f3n Trump. El Gobierno decidi\u00f3 conceder el indulto bas\u00e1ndose en la buena conducta de los reclusos, su estado de salud y la naturaleza de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-03T05:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos\",\"datePublished\":\"2026-04-03T05:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/\"},\"wordCount\":687,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/\",\"name\":\"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-03T05:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos - Noticias","og_description":"El Gobierno cubano anunciar\u00e1 el jueves la liberaci\u00f3n de 2.010 prisioneros, la mayor en a\u00f1os, mientras la isla se ve sometida a una presi\u00f3n cada vez mayor por parte de la administraci\u00f3n Trump. El Gobierno decidi\u00f3 conceder el indulto bas\u00e1ndose en la buena conducta de los reclusos, su estado de salud y la naturaleza de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-03T05:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/"},"author":{"name":"","@id":""},"headline":"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos","datePublished":"2026-04-03T05:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/"},"wordCount":687,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/","name":"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-03T05:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cuba liberar\u00e1 a m\u00e1s de 2.000 prisioneros mientras la crisis econ\u00f3mica se agrava bajo la presi\u00f3n de Estados Unidos","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/02\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-03T05:03:47Z","datePublished":"2026-04-03T05:03:47Z","dateModified":"2026-04-03T05:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cuba liberar\\u00e1 a m\\u00e1s de 2.000 prisioneros mientras la crisis econ\\u00f3mica se agrava bajo la presi\\u00f3n de Estados Unidos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/02\\\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/02\\\/cuba-liberara-prisioneros-crisis-economica-estados-unidos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-03T05:03:47Z\",\"datePublished\":\"2026-04-03T05:03:47Z\",\"dateModified\":\"2026-04-03T05:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472848,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/03\/cuba-nuevas-excarcelaciones-que-sabemos-orix\/","url_meta":{"origin":1472824,"position":0},"title":"Esto sabemos sobre las m\u00e1s de 2.000 nuevas excarcelaciones anunciadas por el Gobierno de Cuba: \u00bfqui\u00e9nes saldr\u00edan y cu\u00e1ndo?","author":"","date":"abril 3, 2026","format":false,"excerpt":"El Gobierno de Cuba anunci\u00f3 este jueves que excarcelar\u00e1 a 2.010 personas detenidas, una medida que, seg\u00fan La Habana, se deriva de un \u201cgesto humanitario y soberano\u201d tras analizar diversos casos y considerar \u201cla buena conducta\u201d de quienes saldr\u00e1n de prisi\u00f3n.Las excarcelaciones se suman a otras que Cuba ha llevado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457583,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/01\/16\/deshielo-repentino-cuba-cuanto-tiempo-trax\/","url_meta":{"origin":1472824,"position":1},"title":"Hay un deshielo repentino en las relaciones entre EE.UU. y Cuba, pero \u00bfpor cu\u00e1nto tiempo?","author":"","date":"enero 16, 2025","format":false,"excerpt":"Este jueves, funcionarios cubanos liberaron a un destacado activista opositor, un cambio diplom\u00e1tico de \u00faltima hora para el Gobierno de Biden, que hab\u00eda buscado su liberaci\u00f3n pero parec\u00eda incapaz de influir en los eventos en la isla.Jos\u00e9 Daniel Ferrer, l\u00edder de uno de los grupos antigubernamentales m\u00e1s grandes prohibidos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463333,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/06\/08\/desesperada-busqueda-rusia-ucrania-trax\/","url_meta":{"origin":1472824,"position":2},"title":"Desesperada por sacar de Rusia a sus civiles detenidos ilegalmente, Kyiv ofrece a cambio colaboradores ucranianos","author":"","date":"junio 8, 2025","format":false,"excerpt":"Ucrania excarcel\u00f3 y envi\u00f3 a decenas de sus propios ciudadanos a Rusia el mes pasado, en un intento de asegurar la liberaci\u00f3n de decenas de civiles ucranianos detenidos ilegalmente en c\u00e1rceles rusas, una medida descrita por activistas de derechos humanos como desesperada y preocupante.Seg\u00fan el gobierno de Ucrania, 70 civiles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467397,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/15\/jose-daniel-ferrer-disidente-cuba-entrevista-orix\/","url_meta":{"origin":1472824,"position":3},"title":"Jos\u00e9 Daniel Ferrer denuncia tortura y &#171;destierro obligado&#187; tras ser liberado de prisi\u00f3n en Cuba","author":"","date":"octubre 15, 2025","format":false,"excerpt":"El disidente cubano Jos\u00e9 Daniel Ferrer lleg\u00f3 a Estados Unidos tras lo que describe como un \u201cdestierro obligado\u201d, al asegurar a CNN que aceptar el exilio fue la \u00fanica opci\u00f3n que tuvo para salvar su vida y proteger a su familia del hostigamiento del r\u00e9gimen cubano.\u201cEra la \u00fanica opci\u00f3n que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467337,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/10\/13\/disidente-cubano-jose-daniel-ferrer-llega-estados-unidos-trax\/","url_meta":{"origin":1472824,"position":4},"title":"El disidente cubano Jos\u00e9 Daniel Ferrer llega a Estados Unidos tras ser liberado de prisi\u00f3n","author":"","date":"octubre 13, 2025","format":false,"excerpt":"El disidente cubano Jos\u00e9 Daniel Ferrer ha llegado a Estados Unidos despu\u00e9s de ser liberado de prisi\u00f3n en Cuba, dijo el lunes el secretario de Estado de EE.UU., Marco Rubio.Ferrer fue liberado y autorizado a salir hacia Estados Unidos tras una solicitud formal del Gobierno de EE.UU., seg\u00fan el Ministerio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461033,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/10\/eeuu-rusia-intercambio-prisioneros-ksenia-karelina-trax\/","url_meta":{"origin":1472824,"position":5},"title":"EE.UU. y Rusia llevan adelante un intercambio de prisioneros que incluye a Ksenia Karelina","author":"","date":"abril 10, 2025","format":false,"excerpt":"La rusoestadounidense Ksenia Karelina, quien estaba cumpliendo una sentencia de 12 a\u00f1os de prisi\u00f3n por traici\u00f3n en Rusia, fue liberada como parte de un intercambio de prisioneros en el que fue cambiada por un acusado de contrabando que se encontraba detenido en Estados Unidos.El secretario de Estado de EE.UU., Marco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1472824"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472824\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1472824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1472824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1472824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}