{"id":1472825,"date":"2026-04-03T01:03:38","date_gmt":"2026-04-03T08:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/"},"modified":"2026-04-03T01:03:38","modified_gmt":"2026-04-03T08:03:38","slug":"escuela-musica-irani-ataque-aereo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/","title":{"rendered":"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, &#171;no queda nada&#187;"},"content":{"rendered":"<p>Los sonidos de la m\u00fasica cl\u00e1sica persa sol\u00edan llenar las aulas de la Academia de M\u00fasica Honiak en Teher\u00e1n: el h\u00e1bil punteo del setar, el tintineo del santur.<\/p>\n<p>Era el orgullo y la alegr\u00eda del m\u00fasico iran\u00ed Hamidreza Afarideh, quien inaugur\u00f3 la escuela hace dos a\u00f1os junto a su esposa, Sheida Ebadatdoust.<\/p>\n<p>Hab\u00edan dedicado su coraz\u00f3n y su dinero a crear un espacio que se sintiera como un refugio para sus 250 alumnos, cuyas edades oscilaban entre los ni\u00f1os peque\u00f1os y los ancianos.<\/p>\n<p>Ahora, dice, todo ha sido <a href=\"https:\/\/www.instagram.com\/p\/DWUBcfJjBQi\/?img_index=1\">\u201carrasado\u201d.<\/a><\/p>\n<p>El 23 de marzo, un ataque a\u00e9reo israel\u00ed <a href=\"https:\/\/x.com\/Hafarideh\/status\/2036998784115224987\">impact\u00f3 el edificio<\/a> que albergaba su escuela de m\u00fasica, junto con otros negocios, entre ellos una cl\u00ednica de maternidad. <strong><\/strong>El edificio estaba <strong><\/strong>ubicado en el lado este de la capital iran\u00ed, a menos de dos kil\u00f3metros (1,3 millas) de una base a\u00e9rea militar.<\/p>\n<p>En aquel momento no hab\u00eda nadie en el centro de m\u00fasica: Afarideh y Ebadatdoust cerraron la escuela poco despu\u00e9s de que Estados Unidos e Israel lanzaran su ataque conjunto contra Ir\u00e1n, para proteger a sus alumnos y personal del incesante bombardeo.<\/p>\n<p>Pero la destrucci\u00f3n duele profundamente a la pareja, que ha <a href=\"https:\/\/x.com\/Hafarideh\/status\/2037269646944997863\">dedicado su vida<\/a> a compartir la alegr\u00eda de la m\u00fasica. Y refleja el impacto devastador de la guerra en la poblaci\u00f3n civil: la p\u00e9rdida de la normalidad, la seguridad, los medios de subsistencia y las pasiones, un impacto que va mucho m\u00e1s all\u00e1 de las crudas cifras de un n\u00famero de muertos que aumenta cada d\u00eda.<\/p>\n<p>\u201cTodas las propiedades y bienes que mi c\u00f3nyuge y yo hab\u00edamos acumulado durante 15 a\u00f1os de duro trabajo fueron destruidos de la noche a la ma\u00f1ana. Quedaron completamente arrasados, sin que quedara nada\u201d, dijo Afarideh.<\/p>\n<p>La primera se\u00f1al de problemas lleg\u00f3 cuando el sistema de alarma de la escuela de m\u00fasica empez\u00f3 a sonar justo despu\u00e9s del amanecer.<\/p>\n<p>Afarideh y Ebadatdoust, que tambi\u00e9n es m\u00fasico, pensaron que alguien podr\u00eda estar intentando entrar a robar y corrieron hacia el lugar. Al acercarse, se dieron cuenta de que era algo mucho peor.<\/p>\n<p>\u201cVimos una densa humareda y niebla en el cielo\u201d, cont\u00f3. \u201cEra tan espesa que no pod\u00edamos ver hacia adelante y ni siquiera pudimos conducir correctamente hacia el instituto\u201d.<\/p>\n<p>Esperaron afuera durante muchas horas angustiosas antes de que las autoridades iran\u00edes concluyeran las operaciones de b\u00fasqueda y rescate y les permitieran entrar.<\/p>\n<p>Su escuela estaba en el cuarto piso del edificio, y \u201ccon cada piso que sub\u00edamos, el nivel de destrucci\u00f3n era tan grave que las escaleras se derrumbaban a medida que avanz\u00e1bamos\u201d, record\u00f3.<\/p>\n<p>Cuando finalmente llegaron a su unidad, se encontraron con ruinas. El ataque hab\u00eda destrozado las ventanas de la escuela y derrumbado su muro exterior; en el interior, todo lo que amaban se hab\u00eda convertido en cenizas y escombros.<\/p>\n<p>\u201cNo quedaba ning\u00fan instrumento musical\u201d, indic\u00f3. \u201cNinguno de los equipos que ten\u00edamos \u2014como televisores, sistemas de audio o cualquier otra instalaci\u00f3n que deber\u00eda tener un instituto profesional\u2014 permanec\u00eda en pie. Todas las paredes que hab\u00edan sido construidas con aislamiento ac\u00fastico profesional quedaron completamente destruidas\u201d.<\/p>\n<p>Las fotos y los videos posteriores al suceso muestran algunos indicios de lo que hab\u00eda all\u00ed antes: el cuerpo de madera roto de un la\u00fad, el m\u00e1stil partido de una guitarra. Pero, sobre todo, \u201cla fuerza de la explosi\u00f3n del dron fue tan intensa que fue como si ninguno de esos objetos hubiera existido jam\u00e1s\u201d, afirm\u00f3.<\/p>\n<p>Ese d\u00eda, Teher\u00e1n fue bombardeada con ataques a\u00e9reos, como ven\u00eda sucediendo desde hac\u00eda semanas, tras el inicio de la guerra conjunta entre Estados Unidos e Israel contra Ir\u00e1n.<\/p>\n<p>Al anochecer, el ej\u00e9rcito israel\u00ed anunci\u00f3 que los ataques a gran escala en Teher\u00e1n hab\u00edan tenido como objetivo infraestructura oficial y militar, incluyendo f\u00e1bricas de armas y cuarteles generales de seguridad.<\/p>\n<p>Pero eso no es todo lo que afectaron, ya que otro edificio residencial en el norte de la ciudad fue alcanzado, y un <a href=\"https:\/\/www.cnn.com\/world\/live-news\/iran-war-us-israel-trump-03-23-26#cmn3zihm600003b6um0ifkv9q\">ni\u00f1o peque\u00f1o qued\u00f3 atrapado en su interior<\/a> hasta que fue rescatado horas despu\u00e9s.<\/p>\n<p>Al ser contactadas para obtener comentarios, las Fuerzas de Defensa de Israel confirmaron haber \u201cllevado a cabo un ataque selectivo contra un cuartel general de inteligencia de la Fuerza Quds cerca del lugar especificado\u201d.<\/p>\n<p>A\u00f1adi\u00f3 que los ataques de las FDI se ajustan al derecho internacional y que \u201cse evalu\u00f3 que la ventaja militar prevista del ataque era significativa y superaba los da\u00f1os colaterales esperados, incluidos los causados \u200b\u200ba las estructuras cercanas\u201d.<\/p>\n<p>El Comando Central de Estados Unidos declar\u00f3 a CNN que no dispon\u00eda de informaci\u00f3n al respecto.<\/p>\n<p>Afarideh y Ebadatdoust se enfrentan ahora al reto de c\u00f3mo seguir adelante: c\u00f3mo reconstruir su instituto, d\u00f3nde encontrar los fondos y c\u00f3mo apoyar a su personal y a sus estudiantes en medio de la guerra.<\/p>\n<p>\u201cPara muchos de ellos, este lugar era como un segundo hogar\u201d, afirm\u00f3. \u201cLes brindaba una gran sensaci\u00f3n de comodidad y seguridad. Como mi esposa y yo trabaj\u00e1bamos all\u00ed juntos, el ambiente era muy familiar, lo que lo hac\u00eda muy atractivo para ellos\u201d.<\/p>\n<p>Ahora, a\u00f1adi\u00f3, los estudiantes est\u00e1n consternados \u201cporque ese tipo de espacio ya no existe para ellos\u201d.<\/p>\n<p>La escuela tambi\u00e9n hab\u00eda dado empleo a cerca de dos docenas de profesores y personal administrativo, muchos de los cuales eran j\u00f3venes graduados de veintitantos a\u00f1os que ahora se encontraban sin ingresos, en un momento en que la econom\u00eda de su naci\u00f3n, que ya estaba en dificultades, se ha visto a\u00fan m\u00e1s afectada por la guerra.<\/p>\n<p>Debido a los graves da\u00f1os sufridos por la estructura del edificio, probablemente tendr\u00e1n que trasladar la escuela de m\u00fasica a una nueva ubicaci\u00f3n. Sin embargo, no est\u00e1 claro si podr\u00e1n permitirse empezar de cero, sobre todo teniendo en cuenta el aumento del precio de los bienes debido a la alta inflaci\u00f3n.<\/p>\n<p>En total, calcula que perdieron cerca de US$ 42.000 en bienes da\u00f1ados y destruidos. En Ir\u00e1n, donde el PIB per c\u00e1pita en 2024 rondaba los US$ 5.120 anuales, seg\u00fan el Banco Mundial, eso es una fortuna.<\/p>\n<p>Ahora est\u00e1n buscando ayuda de otras asociaciones musicales en Ir\u00e1n, as\u00ed como del Ministerio de Cultura del Gobierno.<\/p>\n<p>Sin embargo, el alivio podr\u00eda tardar en llegar, ya que la guerra se prolonga por segundo mes.<\/p>\n<p>Estados Unidos e Ir\u00e1n contin\u00faan las negociaciones indirectas, pero ambas partes env\u00edan mensajes contradictorios sobre el estado de las conversaciones.<\/p>\n<p>Mientras tanto, los l\u00edderes lanzan amenazas y presionan para que se realicen ataques a\u00e9reos, y la poblaci\u00f3n sufre las consecuencias.<\/p>\n<p>\u201cPa\u00edses como Ir\u00e1n, con miles de a\u00f1os de cultura y arte, tienen una fuerte identidad ligada a la m\u00fasica\u201d, explic\u00f3 Afarideh. \u201cCuando esta identidad pretende transmitirse a trav\u00e9s de nuestros estudiantes y de nosotros mismos a las generaciones futuras, debe recibir apoyo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los sonidos de la m\u00fasica cl\u00e1sica persa sol\u00edan llenar las aulas de la Academia de M\u00fasica Honiak en Teher\u00e1n: el h\u00e1bil punteo del setar, el tintineo del santur. Era el orgullo y la alegr\u00eda del m\u00fasico iran\u00ed Hamidreza Afarideh, quien inaugur\u00f3 la escuela hace dos a\u00f1os junto a su esposa, Sheida Ebadatdoust. Hab\u00edan dedicado su [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472825","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, &quot;no queda nada&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, &quot;no queda nada&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los sonidos de la m\u00fasica cl\u00e1sica persa sol\u00edan llenar las aulas de la Academia de M\u00fasica Honiak en Teher\u00e1n: el h\u00e1bil punteo del setar, el tintineo del santur. Era el orgullo y la alegr\u00eda del m\u00fasico iran\u00ed Hamidreza Afarideh, quien inaugur\u00f3 la escuela hace dos a\u00f1os junto a su esposa, Sheida Ebadatdoust. Hab\u00edan dedicado su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-03T08:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, &#171;no queda nada&#187;\",\"datePublished\":\"2026-04-03T08:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/\"},\"wordCount\":1241,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/\",\"name\":\"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, \\\"no queda nada\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-03T08:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, &#171;no queda nada&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, \"no queda nada\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, \"no queda nada\" - Noticias","og_description":"Los sonidos de la m\u00fasica cl\u00e1sica persa sol\u00edan llenar las aulas de la Academia de M\u00fasica Honiak en Teher\u00e1n: el h\u00e1bil punteo del setar, el tintineo del santur. Era el orgullo y la alegr\u00eda del m\u00fasico iran\u00ed Hamidreza Afarideh, quien inaugur\u00f3 la escuela hace dos a\u00f1os junto a su esposa, Sheida Ebadatdoust. Hab\u00edan dedicado su [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-03T08:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/"},"author":{"name":"","@id":""},"headline":"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, &#171;no queda nada&#187;","datePublished":"2026-04-03T08:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/"},"wordCount":1241,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/","name":"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, \"no queda nada\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-03T08:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, &#171;no queda nada&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Esta escuela de m\u00fasica iran\u00ed era un refugio para ni\u00f1os. Tras un ataque a\u00e9reo, &#171;no queda nada&#187;","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/03\/escuela-musica-irani-ataque-aereo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-03T08:03:38Z","datePublished":"2026-04-03T08:03:38Z","dateModified":"2026-04-03T08:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Esta escuela de m\\u00fasica iran\\u00ed era un refugio para ni\\u00f1os. Tras un ataque a\\u00e9reo, &#171;no queda nada&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/03\\\/escuela-musica-irani-ataque-aereo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/03\\\/escuela-musica-irani-ataque-aereo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-03T08:03:38Z\",\"datePublished\":\"2026-04-03T08:03:38Z\",\"dateModified\":\"2026-04-03T08:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447619,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/01\/iran-acusa-israel-comandante-militar-consulado-siria-trax\/","url_meta":{"origin":1472825,"position":0},"title":"Ir\u00e1n acusa a Israel de matar a comandantes militares iran\u00edes y a otras personas en un ataque a\u00e9reo contra un consulado en Siria","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) --\u00a0Altos comandantes militares iran\u00edes se encontraban entre los siete funcionarios del Cuerpo de la Guardia Revolucionaria Isl\u00e1mica (CGRI) que murieron en un ataque a\u00e9reo contra el edificio del consulado del pa\u00eds en Damasco, Siria, seg\u00fan funcionarios iran\u00edes y medios de comunicaci\u00f3n afiliados al Estado, que culparon a Israel por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472695,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/30\/ataque-sinagoga-michigan-terrorismo-hezbollah-fbi-trax\/","url_meta":{"origin":1472825,"position":1},"title":"El ataque a una sinagoga en Michigan fue un acto de terrorismo inspirado por Hezbollah, dice el FBI","author":"","date":"marzo 30, 2026","format":false,"excerpt":"El ataque ocurrido a principios de este mes contra una sinagoga en West Bloomfield, Michigan, fue \u201cun acto de terrorismo inspirado por Hezbollah que ten\u00eda como objetivo deliberado a la comunidad jud\u00eda y al templo jud\u00edo m\u00e1s grande de Michigan\u201d, dijo el FBI en una conferencia de prensa el lunes.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471755,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/28\/iran-ninas-escuela-ataque-eeuu-israel-trax\/","url_meta":{"origin":1472825,"position":2},"title":"Medios estatales iran\u00edes afirman que decenas de ni\u00f1as murieron en uno de los ataques de EE.UU. e Israel a una escuela","author":"","date":"febrero 28, 2026","format":false,"excerpt":"Medios estatales iran\u00edes afirman que decenas de estudiantes murieron en un ataque contra una escuela de ni\u00f1as en el sur de Ir\u00e1n este s\u00e1bado, despu\u00e9s de que Estados Unidos e Israel lanzaran una ofensiva militar sobre el pa\u00eds.Mohammad Radmehr, gobernador del condado de Mindab, donde se produjo el supuesto ataque,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447637,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/02\/iran-venganza-ataque-israel-consulado-siria-trax\/","url_meta":{"origin":1472825,"position":3},"title":"Ir\u00e1n promete vengarse tras acusar a Israel del mort\u00edfero ataque contra su consulado en Siria","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN) -- Ir\u00e1n prometi\u00f3 tomar represalias tras acusar a Israel de bombardear el lunes el complejo de su embajada en Siria, en una mort\u00edfera escalada de las tensiones regionales por la guerra de Gaza que, una vez m\u00e1s, pareci\u00f3 aumentar el riesgo de un conflicto m\u00e1s amplio en Medio Oriente.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448266,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/19\/iran-drones-israel-como-trax\/","url_meta":{"origin":1472825,"position":4},"title":"Ir\u00e1n dice que derrib\u00f3 drones mientras aumentan las tensiones regionales. \u00bfC\u00f3mo se lleg\u00f3 a este punto?","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN) -- Un ataque a\u00e9reo no reivindicado en el centro de Ir\u00e1n el viernes se produce inmediatamente despu\u00e9s de los ataques iran\u00edes e israel\u00edes (en represalia a ataques previos) a principios de este mes, lo que marca una escalada potencialmente peligrosa del conflicto de Medio Oriente.Israel llev\u00f3 a cabo el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447633,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/04\/01\/medio-oriente-abismo-ataque-consulado-irani-trax\/","url_meta":{"origin":1472825,"position":5},"title":"AN\u00c1LISIS | Medio Oriente vuelve a estar al borde del abismo tras ataque a un consulado iran\u00ed en Siria","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El ataque de este lunes al consulado de Ir\u00e1n en Damasco, capital de Siria, puede representar la escalada m\u00e1s peligrosa fuera de Gaza en Medio Oriente, desde que comenz\u00f3 la guerra entre Israel y Hamas hace casi seis meses.Siria e Ir\u00e1n culparon a Israel por el ataque a\u00e9reo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1472825"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472825\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1472825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1472825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1472825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}