{"id":1472903,"date":"2026-04-06T13:03:48","date_gmt":"2026-04-06T20:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/"},"modified":"2026-04-06T13:03:48","modified_gmt":"2026-04-06T20:03:48","slug":"baja-excarcelaciones-presos-politicos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/","title":{"rendered":"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos"},"content":{"rendered":"<p>A 45 d\u00edas de la aprobaci\u00f3n de la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/19\/venezuela\/asamblea-nacional-aprueba-ley-amnistia-presos-politicos-orix\">ley de amnist\u00eda<\/a> en Venezuela, familiares de detenidos terminaron la Semana Santa con nuevas vigilias afuera de c\u00e1rceles donde, seg\u00fan organizaciones de derechos humanos, cientos de presos pol\u00edticos contin\u00faan tras las rejas a la espera de ser beneficiados por el proyecto que impuls\u00f3 el propio chavismo.<\/p>\n<p>Las autoridades han reportado que desde la aprobaci\u00f3n del proyecto m\u00e1s de 250 personas han sido excarceladas y que cerca de 8.000 recuperaron la libertad plena, ya que aunque estaban fuera de prisi\u00f3n, todav\u00eda ten\u00edan medidas cautelares, como la prohibici\u00f3n de salida del pa\u00eds o una presentaci\u00f3n peri\u00f3dica ante tribunales.<\/p>\n<p>Pero el proceso se ha ralentizado en las \u00faltimas semanas, seg\u00fan consignaron organizaciones como Foro Penal y la ONG Justicia, Encuentro y Perd\u00f3n (JEP). Pese a los reclamos de activistas, el Gobierno nunca public\u00f3 una lista oficial de detenidos, por lo que el seguimiento de cifras y casos pendientes depende del seguimiento particular que realizan las organizaciones civiles.<\/p>\n<p>Foro Penal <a href=\"https:\/\/x.com\/ForoPenal\/status\/2039828153624055872\">report\u00f3<\/a> a fines de marzo que 503 presos pol\u00edticos siguen encarcelados, y en muchos casos no se permite la designaci\u00f3n de abogados de confianza. \u201cDesde hace aproximadamente dos semanas se ha visto que ha bajado significativamente el n\u00famero de personas liberadas con la amnist\u00eda\u201d, dijo a EFE Gonzalo Himiob, vicepresidente de Foro Penal. El \u00faltimo balance registr\u00f3 34 excarcelaciones, frente a las 55 del <a href=\"https:\/\/x.com\/ForoPenal\/status\/2036509504003596510\">reporte previo<\/a>. Si el proceso no contin\u00faa, \u201cparecer\u00eda evidente que el Gobierno interino no tendr\u00eda verdadera voluntad pol\u00edtica de hacer cesar la prisi\u00f3n y la persecuci\u00f3n pol\u00edtica\u201d, agreg\u00f3 Himiob.<\/p>\n<p>En tanto, JEP contabiliz\u00f3 tambi\u00e9n a fines de marzo 679 detenidos por motivos pol\u00edticos y denunci\u00f3 en un <a href=\"https:\/\/x.com\/JEPvzla\/status\/2040521051386626449\">comunicado<\/a>: \u201cPese a anuncios oficiales y medidas recientes, no existe un cambio sustancial en la situaci\u00f3n. En los \u00faltimos 11 d\u00edas, desde nuestro balance anterior, \u00fanicamente se ha registrado la excarcelaci\u00f3n de 10 personas, lo que refleja un ritmo sumamente limitado frente a la magnitud del problema\u201d.<\/p>\n<p>El grupo afirm\u00f3 que las liberaciones son \u201caisladas y discrecionales, sin responder a una pol\u00edtica estructural orientada a garantizar derechos\u201d por lo que denunci\u00f3 que \u201cla privaci\u00f3n de libertad por motivos pol\u00edticos sigue siendo utilizada como mecanismo de control\u201d. Con ese marco, JEP reclam\u00f3 al Gobierno un indulto procesal como una v\u00eda constitucional \u201cm\u00e1s expedita\u201d que no quede sometida a tiempos judiciales.<\/p>\n<p>L\u00edderes sindicales que convocan a una marcha para este jueves tambi\u00e9n han denunciado que algunos representantes gremiales no han sido alcanzados por la amnist\u00eda.<\/p>\n<p>CNN consult\u00f3 al Gobierno de Venezuela sobre los se\u00f1alamientos de las ONG y espera respuesta.<\/p>\n<p>El presidente de la comisi\u00f3n legislativa encargada de darle seguimiento a la ley, el diputado Jorge Arreaza, declar\u00f3 el 28 de marzo en entrevista con Telesur que hab\u00eda recibido 13.685 solicitudes, aunque algunas estaban repetidas, y se lleg\u00f3 a 11.401 personas. El asamble\u00edsta no explic\u00f3 los motivos por las cuales m\u00e1s de 3.000 fueron rechazadas o todav\u00eda est\u00e1n pendientes de respuesta. Seg\u00fan dijo, en esta nueva etapa, se har\u00e1n las correcciones necesarias. \u201c(Debemos) entender que tenemos que unirnos. La unidad de la Revoluci\u00f3n Bolivariana para nosotros es un principio de esencia\u201d, sostuvo.<\/p>\n<p>La comisi\u00f3n fue instalada por propuesta de la sociedad civil durante el debate del proyecto de ley, pero la verificaci\u00f3n no qued\u00f3 vinculada a instituciones como la Oficina del Alto Comisionado para los Derechos Humanos de la ONU, la Cruz Roja, la Iglesia, comit\u00e9s de v\u00edctimas y otros organismos civiles.<\/p>\n<p>\u201cEntonces, hoy d\u00eda esta comisi\u00f3n lanza una cifra, 6.000, 5.000 solicitudes, dimos tanto (beneficios). Yo no puedo decir que es mentira, pero tampoco la puedo verificar, porque no hay posibilidad de contrastar ni de verificar esa cifra\u201d, dijo a EFE el coordinador general de la ONG Provea, \u00d3scar Murillo. Con todas esas limitaciones, el proceso ha estado \u201cenlodado en burocracia, en actitudes y respuestas discrecionales (de) a unos s\u00ed, a otros no\u201d, agreg\u00f3 Murillo.<\/p>\n<p>Mientras tanto, familiares contin\u00faan con sus movilizaciones. El viernes realizaron un Via Crucis por siete templos de la capital para exigir respuestas a las autoridades. El domingo, incendiaron un mu\u00f1eco de hojas y tela como parte de la tradicional quema de judas, bajo proclamas de justicia y libertad. \u201cNi uno, ni dos, \u00a1que sean todos!\u201d, cantaron afuera del Helicoide.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 45 d\u00edas de la aprobaci\u00f3n de la ley de amnist\u00eda en Venezuela, familiares de detenidos terminaron la Semana Santa con nuevas vigilias afuera de c\u00e1rceles donde, seg\u00fan organizaciones de derechos humanos, cientos de presos pol\u00edticos contin\u00faan tras las rejas a la espera de ser beneficiados por el proyecto que impuls\u00f3 el propio chavismo. Las [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472903","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos - Noticias\" \/>\n<meta property=\"og:description\" content=\"A 45 d\u00edas de la aprobaci\u00f3n de la ley de amnist\u00eda en Venezuela, familiares de detenidos terminaron la Semana Santa con nuevas vigilias afuera de c\u00e1rceles donde, seg\u00fan organizaciones de derechos humanos, cientos de presos pol\u00edticos contin\u00faan tras las rejas a la espera de ser beneficiados por el proyecto que impuls\u00f3 el propio chavismo. Las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-06T20:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos\",\"datePublished\":\"2026-04-06T20:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/\"},\"wordCount\":781,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/\",\"name\":\"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-06T20:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos - Noticias","og_description":"A 45 d\u00edas de la aprobaci\u00f3n de la ley de amnist\u00eda en Venezuela, familiares de detenidos terminaron la Semana Santa con nuevas vigilias afuera de c\u00e1rceles donde, seg\u00fan organizaciones de derechos humanos, cientos de presos pol\u00edticos contin\u00faan tras las rejas a la espera de ser beneficiados por el proyecto que impuls\u00f3 el propio chavismo. Las [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-06T20:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/"},"author":{"name":"","@id":""},"headline":"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos","datePublished":"2026-04-06T20:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/"},"wordCount":781,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/","name":"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-06T20:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cae el n\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\u00fan hay m\u00e1s de 500 presos pol\u00edticos","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/06\/baja-excarcelaciones-presos-politicos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-06T20:03:48Z","datePublished":"2026-04-06T20:03:48Z","dateModified":"2026-04-06T20:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cae el n\\u00famero de excarcelaciones en Venezuela, dicen ONG, pese a que a\\u00fan hay m\\u00e1s de 500 presos pol\\u00edticos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/06\\\/baja-excarcelaciones-presos-politicos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/06\\\/baja-excarcelaciones-presos-politicos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-06T20:03:48Z\",\"datePublished\":\"2026-04-06T20:03:48Z\",\"dateModified\":\"2026-04-06T20:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471674,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/26\/guanipa-amnistia-excluyente-liberar-presos-politicos-democracia-venezuela-orix\/","url_meta":{"origin":1472903,"position":0},"title":"Guanipa dice que la Ley de Amnist\u00eda es &#171;excluyente&#187; y pide liberar a todos los presos pol\u00edticos en Venezuela","author":"","date":"febrero 26, 2026","format":false,"excerpt":"El l\u00edder opositor venezolano Juan Pablo Guanipa, figura cercana a Mar\u00eda Corina Machado, dijo este mi\u00e9rcoles que considera \u201cexcluyente\u201d la ley de amnist\u00eda en una entrevista con CNN, despu\u00e9s de haber sido excarcelado tras la aprobaci\u00f3n hace unos d\u00edas de la cuestionada ley que permitir\u00eda la liberaci\u00f3n de cientos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451824,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/13\/asambela-naciona-venezuela-fascismo-ley-ong-orix\/","url_meta":{"origin":1472903,"position":1},"title":"La Asamblea Nacional de Venezuela debate este martes para \u201ccondenar el ciberfascismo\u201d y un proyecto de ley que regula organizaciones no gubernamentales","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Asamblea Nacional de Venezuela debatir\u00e1 este martes para \u201ccondenar el ciberfascismo\u201d y regular las organizaciones no gubernamentales (ONG), seg\u00fan public\u00f3 el \u00f3rgano legislativo en el orden del d\u00eda de la sesi\u00f3n ordinaria. Esto ocurre dos semanas despu\u00e9s de las elecciones presidenciales, cuyos resultados oficiales desglosados a\u00fan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470915,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/05\/asamblea-nacional-venezuela-ley-amnistia-presos-politicos-orix\/","url_meta":{"origin":1472903,"position":2},"title":"Asamblea Nacional de Venezuela aprueba en primera discusi\u00f3n la ley de amnist\u00eda para los presos pol\u00edticos. \u00bfQu\u00e9 falta ahora?","author":"","date":"febrero 5, 2026","format":false,"excerpt":"La Asamblea Nacional de Venezuela aprob\u00f3 este jueves, en primera discusi\u00f3n, un proyecto de ley de amnist\u00eda para presos pol\u00edticos, anunciado la semana pasada por la presidenta encargada, Delcy Rodr\u00edguez. La iniciativa pasar\u00e1 ahora a consulta p\u00fablica y posteriormente a una segunda discusi\u00f3n para ser aprobada.El proyecto de ley excluye\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470377,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/22\/excarcelacion-presos-politicos-proceso-orix\/","url_meta":{"origin":1472903,"position":3},"title":"Venezuela anunci\u00f3 excarcelaci\u00f3n de &#171;un n\u00famero significativo&#187; de presos pol\u00edticos. \u00bfCu\u00e1ntos han salido?","author":"","date":"enero 22, 2026","format":false,"excerpt":"Pasaron dos semanas desde que el Gobierno de Venezuela anunci\u00f3 un proceso de excarcelaciones \u201csignificativas\u201d en el pa\u00eds, aunque el conteo de las organizaciones locales que verifican el proceso indica que el n\u00famero de presos pol\u00edticos que salieron de prisi\u00f3n desde esa fecha no llega al 15 % del total,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470727,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/01\/excarcelan-activista-javier-tarazona-helicoide-orix\/","url_meta":{"origin":1472903,"position":4},"title":"Excarcelan al activista venezolano Javier Tarazona tras pasar m\u00e1s de cuatro a\u00f1os detenido en El Helicoide","author":"","date":"febrero 1, 2026","format":false,"excerpt":"El activista venezolano de derechos humanos Javier Tarazona fue excarcelado este domingo en Caracas, seg\u00fan anunci\u00f3 su familia, despu\u00e9s de pasar m\u00e1s de cuatro a\u00f1os detenido.\u201cLuego de 1.675 d\u00edas, 4 a\u00f1os y 7 meses, lleg\u00f3 este tan anhelado d\u00eda, mi hermano Javier Tarazona est\u00e1 en libertad\u201d, public\u00f3 en X Rafael\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470009,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/12\/excarcelaciones-presos-politicos-repaso-orix\/","url_meta":{"origin":1472903,"position":5},"title":"\u00bfQu\u00e9 sabemos de las excarcelaciones de presos pol\u00edticos en Venezuela?","author":"","date":"enero 12, 2026","format":false,"excerpt":"Desde que el Gobierno de Venezuela anunci\u00f3 la semana pasada que pondr\u00eda en libertad a \u201cun n\u00famero importante\u201d de presos pol\u00edticos, el proceso ha avanzado muy por debajo de las expectativas de cientos de familias que esperan por sus parientes. A su vez, las autoridades no han difundido una lista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1472903"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472903\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1472903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1472903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1472903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}