{"id":1472914,"date":"2026-04-06T19:03:58","date_gmt":"2026-04-07T02:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/"},"modified":"2026-04-06T19:03:58","modified_gmt":"2026-04-07T02:03:58","slug":"delanteras-goleadoras-cuartos-champions-league-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/","title":{"rendered":"Las delanteras m\u00e1s &#171;letales&#187; de los cuartos de final de la Champions League"},"content":{"rendered":"<p>Solo quedan ocho equipos en la carrera por el t\u00edtulo de la UEFA Champions League, la competencia m\u00e1s importante de clubes europeos, que tiene a algunos de los mejores ataques del mundo.<\/p>\n<p>El Barcelona es el cuarto equipo que m\u00e1s goles tiene en la presente Liga de Campeones. En total, el conjunto cul\u00e9 marc\u00f3 30 tantos, con nueve autores diferentes.<\/p>\n<p>El espa\u00f1ol Ferm\u00edn L\u00f3pez es el goleador del blaugrana, con seis dianas, seguido por el ingl\u00e9s Marcus Rashford y Lamine Yamal, quienes suman cinco.<\/p>\n<p>El cuadro catal\u00e1n es uno de los equipos m\u00e1s ofensivos del torneo, en parte gracias a su formaci\u00f3n con tres delanteros, con Yamal, el ariete polaco Robert Lewandowski y el extremo brasile\u00f1o Raphinha.<\/p>\n<p>El equipo colchonero tiene un gol m\u00e1s que el Barcelona en la previa de los cuartos de final del torneo, y hasta el momento el goleador del equipo es el delantero argentino Juli\u00e1n \u00c1lvarez, con ocho festejos.<\/p>\n<p>Los dirigidos por Diego Simeone, que utilizan el contragolpe como principal recurso, tienen tambi\u00e9n a Alexander Sorloth y Marcos Llorente con cinco y cuatro tantos, respectivamente.<\/p>\n<p>En total son 12 jugadores distintos los que han marcado en la presente campa\u00f1a, y siete de ellos lo han hecho en m\u00e1s de una ocasi\u00f3n.<\/p>\n<p>El equipo alem\u00e1n se perfila como uno de los m\u00e1s fuertes del torneo en la previa de los cuartos de final. Los dirigidos por Vincent Kompany tienen hasta el momento 32 dianas y un total de 10 anotadores distintos.<\/p>\n<p>El delantero centro Harry Kane es el goleador del conjunto b\u00e1varo en la Champions, con 10, todos con tiros desde adentro del \u00e1rea.<\/p>\n<p>La efectividad goleadora de Kane est\u00e1 complementada por la velocidad y gambeta del colombiano Luis D\u00edaz, quien cuenta con cuatro tantos.<\/p>\n<p>El joven volante Lennart Karl tiene los mismos goles que D\u00edaz y por detr\u00e1s de ambos est\u00e1n los delanteros Nicolas Jackson y Michael Olise, los dos con tres. Olise, adem\u00e1s, es uno de los m\u00e1ximos asistidores del torneo, con siete pases de gol.<\/p>\n<p>El campe\u00f3n defensor, el Paris Saint-Germain, es el equipo que m\u00e1s goles tiene hasta el momento en la edici\u00f3n 2025\/26 de la Liga de Campeones.<\/p>\n<p>El conjunto de Luis Enrique practica un f\u00fatbol moderno, involucrando a una gran cantidad de jugadores en la zona ofensiva, y eso se refleja en el n\u00famero de futbolistas que han marcado en la Champions.<\/p>\n<p>En total son 13 los que han anotado por lo menos un gol, y el extremo Khvicha Kvaratskhelia suma m\u00e1s que ninguno, con siete.<\/p>\n<p>Otros que han festejado son el volante Vitinha, con seis dianas, y el delantero franc\u00e9s D\u00e9sir\u00e9 Dou\u00e9, con cuatro. Pero ser defensor en un equipo tan ofensivo tambi\u00e9n tiene premio: todos los titulares de la \u00faltima l\u00ednea del PSG tienen por lo menos un gol.<\/p>\n<p>El Real Madrid es el quinto equipo con el mayor n\u00famero de goles anotados (29) en lo que va de la campa\u00f1a, pero lo llamativo es que tiene al goleador del torneo: Kylian Mbapp\u00e9. El delantero franc\u00e9s tiene 13 tantos, tres m\u00e1s que los ingleses Anthony Gordon y Harry Kane, que completan el podio.<\/p>\n<p>Por su parte, el brasile\u00f1o Vin\u00edcius Jr. comparte el liderato de m\u00e1ximo asistidor con Olise, tambi\u00e9n con siete pases de gol.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo quedan ocho equipos en la carrera por el t\u00edtulo de la UEFA Champions League, la competencia m\u00e1s importante de clubes europeos, que tiene a algunos de los mejores ataques del mundo. El Barcelona es el cuarto equipo que m\u00e1s goles tiene en la presente Liga de Campeones. En total, el conjunto cul\u00e9 marc\u00f3 30 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472914","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las delanteras m\u00e1s &quot;letales&quot; de los cuartos de final de la Champions League - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las delanteras m\u00e1s &quot;letales&quot; de los cuartos de final de la Champions League - Noticias\" \/>\n<meta property=\"og:description\" content=\"Solo quedan ocho equipos en la carrera por el t\u00edtulo de la UEFA Champions League, la competencia m\u00e1s importante de clubes europeos, que tiene a algunos de los mejores ataques del mundo. El Barcelona es el cuarto equipo que m\u00e1s goles tiene en la presente Liga de Campeones. En total, el conjunto cul\u00e9 marc\u00f3 30 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-07T02:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las delanteras m\u00e1s &#171;letales&#187; de los cuartos de final de la Champions League\",\"datePublished\":\"2026-04-07T02:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/\"},\"wordCount\":601,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/\",\"name\":\"Las delanteras m\u00e1s \\\"letales\\\" de los cuartos de final de la Champions League - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-07T02:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las delanteras m\u00e1s &#171;letales&#187; de los cuartos de final de la Champions League\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las delanteras m\u00e1s \"letales\" de los cuartos de final de la Champions League - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las delanteras m\u00e1s \"letales\" de los cuartos de final de la Champions League - Noticias","og_description":"Solo quedan ocho equipos en la carrera por el t\u00edtulo de la UEFA Champions League, la competencia m\u00e1s importante de clubes europeos, que tiene a algunos de los mejores ataques del mundo. El Barcelona es el cuarto equipo que m\u00e1s goles tiene en la presente Liga de Campeones. En total, el conjunto cul\u00e9 marc\u00f3 30 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-07T02:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/"},"author":{"name":"","@id":""},"headline":"Las delanteras m\u00e1s &#171;letales&#187; de los cuartos de final de la Champions League","datePublished":"2026-04-07T02:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/"},"wordCount":601,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/","name":"Las delanteras m\u00e1s \"letales\" de los cuartos de final de la Champions League - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-07T02:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las delanteras m\u00e1s &#171;letales&#187; de los cuartos de final de la Champions League"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las delanteras m\u00e1s &#171;letales&#187; de los cuartos de final de la Champions League","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/06\/delanteras-goleadoras-cuartos-champions-league-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-07T02:03:58Z","datePublished":"2026-04-07T02:03:58Z","dateModified":"2026-04-07T02:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las delanteras m\\u00e1s &#171;letales&#187; de los cuartos de final de la Champions League\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/06\\\/delanteras-goleadoras-cuartos-champions-league-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/06\\\/delanteras-goleadoras-cuartos-champions-league-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-07T02:03:58Z\",\"datePublished\":\"2026-04-07T02:03:58Z\",\"dateModified\":\"2026-04-07T02:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446926,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/03\/13\/sorteo-cuartos-champions-league-2023-2024-cuando-dia-hora-equipos-orix\/","url_meta":{"origin":1472914,"position":0},"title":"Sorteo de cuartos de la Champions League 2023\/2024: cu\u00e1ndo es, equipos clasificados, bombos, formato y m\u00e1s","author":"","date":"marzo 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los ocho mejores equipos de la Champions League 2023\/2024 ya quedaron definidos y ahora es momento del sorteo para determinar cu\u00e1les ser\u00e1n los duelos en los cuartos de final de la competencia.Este sorteo se llevar\u00e1 a cabo el viernes 15 de marzo. A continuaci\u00f3n, te damos todos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461753,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/29\/hora-como-ver-barcelona-inter-milan-ida-champions-league-previa-orix\/","url_meta":{"origin":1472914,"position":1},"title":"FC Barcelona &#8211; Inter de Mil\u00e1n de Champions League: previa, a qu\u00e9 hora, cu\u00e1ndo y c\u00f3mo ver por TV e internet","author":"","date":"abril 29, 2025","format":false,"excerpt":"El FC Barcelona \u2013 Inter de Mil\u00e1n es un duelo de colosos europeos; equipos due\u00f1os de un estilo que se ha convertido en casi una identidad de lo que ha sido jugar al f\u00fatbol en Espa\u00f1a e Italia a lo largo de los a\u00f1os. Varias de las estrellas m\u00e1s rutilantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450990,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/09\/quien-es-lamine-yamal-jugador-mas-jovendebutar-seleccion-espana-orix\/","url_meta":{"origin":1472914,"position":2},"title":"\u00bfQui\u00e9n es Lamine Yamal, la figura de Espa\u00f1a y goleador m\u00e1s joven de la Eurocopa?","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Lamine Yamal, a sus 16 a\u00f1os, es figura de la selecci\u00f3n de Espa\u00f1a en la Eurocopa 2024 y ha marcado varios hitos notables en su ascendente carrera. El m\u00e1s destacado lo logr\u00f3 en la semifinal contra Francia: es el goleador m\u00e1s joven de la historia de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450899,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/07\/05\/espana-alemania-mejores-eurocopa-orix\/","url_meta":{"origin":1472914,"position":3},"title":"\u00bfSon Espa\u00f1a y Alemania los mejores equipos de la Eurocopa? Esto dicen los n\u00fameros","author":"","date":"julio 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Espa\u00f1a hizo el puntaje perfecto en la fase de grupos de la Eurocopa y es hasta ahora el \u00fanico equipo que ha ganado todos los partidos. En cuartos elimin\u00f3 de manera rotunda a Georgia y es la favorita. Alemania, que se ha mostrado como el otro gran\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472319,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/18\/cruces-cuartos-final-champions-league-orix\/","url_meta":{"origin":1472914,"position":4},"title":"As\u00ed quedaron los cuartos de final de la Champions League 2025\/2026","author":"","date":"marzo 18, 2026","format":false,"excerpt":"Ocho equipos siguen con vida en la Champions League 2025\/2026 y Espa\u00f1a es el pa\u00eds con m\u00e1s representantes, tres: Real Madrid, FC, Barcelona y el Atl\u00e9tico de Madrid. Le sigue la Premier League de Inglaterra, con dos: Arsenal y Liverpool. Portugal, con el Sporting de Lisboa, Francia, con el PSG\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461724,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/28\/semifinales-champions-league-24-25-previa-horarios-como-ver-orix\/","url_meta":{"origin":1472914,"position":5},"title":"Semifinales de la Champions League 24\/25: previa, horarios y c\u00f3mo ver","author":"","date":"abril 28, 2025","format":false,"excerpt":"Para los cuatro semifinalistas de la Champions League de esta temporada, el torneo continental los ha puesto en un sendero particular.La definici\u00f3n, independientemente de quienes lleguen a la final en Munich el s\u00e1bado 31 de mayo, pondr\u00e1 cara a cara a un equipo que ya sabore\u00f3 las mieles de \u00e9xito,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1472914"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472914\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1472914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1472914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1472914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}