{"id":1472931,"date":"2026-04-07T07:03:48","date_gmt":"2026-04-07T14:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/"},"modified":"2026-04-07T07:03:48","modified_gmt":"2026-04-07T14:03:48","slug":"trump-amenaza-iran-civilizacion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/","title":{"rendered":"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: &#171;Toda una civilizaci\u00f3n morir\u00e1 esta noche&#187;"},"content":{"rendered":"<p>El presidente Donald Trump lanz\u00f3 una dura amenaza contra Ir\u00e1n al decir que \u201ctoda una civilizaci\u00f3n morir\u00e1 esta noche\u201d, mientras se acerca el plazo impuesto por el mandatario estadounidense para que Ir\u00e1n abra el estrecho de Ormuz.<\/p>\n<p>\u201cToda una civilizaci\u00f3n morir\u00e1 esta noche, para no volver jam\u00e1s. No quiero que eso ocurra, pero probablemente ocurrir\u00e1\u201d, escribi\u00f3 Trump en su red social TRUTH.<\/p>\n<p>\u201cSin embargo, ahora que tenemos un cambio de r\u00e9gimen completo y total, donde prevalecen mentes diferentes, m\u00e1s inteligentes y menos radicalizadas, quiz\u00e1 algo revolucionariamente maravilloso pueda suceder, \u00bfQUI\u00c9N SABE? Lo sabremos esta noche, uno de los momentos m\u00e1s importantes en la larga y compleja historia del mundo. 47 a\u00f1os de extorsi\u00f3n, corrupci\u00f3n y muerte finalmente terminar\u00e1n. \u00a1Que Dios bendiga al gran pueblo de Ir\u00e1n!\u201d, agreg\u00f3.<\/p>\n<p>Trump hab\u00eda amenazado previamente con destruir las plantas el\u00e9ctricas de Ir\u00e1n y otra infraestructura civil, al advertir que el pa\u00eds enfrentar\u00e1 graves consecuencias si no abre el estrecho de Ormuz antes de las 8 p.m., hora del Este, de este martes.<\/p>\n<p>Sin embargo, Trump ya ha fijado varios plazos que posteriormente han cambiado.<\/p>\n<p>El presidente y la Casa Blanca han desestimado las preocupaciones de que atacar este tipo de infraestructura podr\u00eda constituir un crimen de guerra.<\/p>\n<p>Seg\u00fan expertos en derecho internacional, los ataques deliberados contra infraestructura civil \u2014como plantas el\u00e9ctricas, sistemas de agua o instalaciones energ\u00e9ticas\u2014 pueden constituir <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/07\/mundo\/iran-trump-plazo-infraestructuras-trax\">cr\u00edmenes de guerra<\/a> si no tienen un objetivo militar claro o si el da\u00f1o a la poblaci\u00f3n civil es desproporcionado.<\/p>\n<p>Estas normas forman parte de las leyes de la guerra, que buscan limitar el impacto de los conflictos armados sobre civiles y bienes no militares.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump lanz\u00f3 una dura amenaza contra Ir\u00e1n al decir que \u201ctoda una civilizaci\u00f3n morir\u00e1 esta noche\u201d, mientras se acerca el plazo impuesto por el mandatario estadounidense para que Ir\u00e1n abra el estrecho de Ormuz. \u201cToda una civilizaci\u00f3n morir\u00e1 esta noche, para no volver jam\u00e1s. No quiero que eso ocurra, pero probablemente ocurrir\u00e1\u201d, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472931","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: &quot;Toda una civilizaci\u00f3n morir\u00e1 esta noche&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: &quot;Toda una civilizaci\u00f3n morir\u00e1 esta noche&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump lanz\u00f3 una dura amenaza contra Ir\u00e1n al decir que \u201ctoda una civilizaci\u00f3n morir\u00e1 esta noche\u201d, mientras se acerca el plazo impuesto por el mandatario estadounidense para que Ir\u00e1n abra el estrecho de Ormuz. \u201cToda una civilizaci\u00f3n morir\u00e1 esta noche, para no volver jam\u00e1s. No quiero que eso ocurra, pero probablemente ocurrir\u00e1\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-07T14:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: &#171;Toda una civilizaci\u00f3n morir\u00e1 esta noche&#187;\",\"datePublished\":\"2026-04-07T14:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/\",\"name\":\"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: \\\"Toda una civilizaci\u00f3n morir\u00e1 esta noche\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-07T14:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: &#171;Toda una civilizaci\u00f3n morir\u00e1 esta noche&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: \"Toda una civilizaci\u00f3n morir\u00e1 esta noche\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: \"Toda una civilizaci\u00f3n morir\u00e1 esta noche\" - Noticias","og_description":"El presidente Donald Trump lanz\u00f3 una dura amenaza contra Ir\u00e1n al decir que \u201ctoda una civilizaci\u00f3n morir\u00e1 esta noche\u201d, mientras se acerca el plazo impuesto por el mandatario estadounidense para que Ir\u00e1n abra el estrecho de Ormuz. \u201cToda una civilizaci\u00f3n morir\u00e1 esta noche, para no volver jam\u00e1s. No quiero que eso ocurra, pero probablemente ocurrir\u00e1\u201d, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-07T14:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/"},"author":{"name":"","@id":""},"headline":"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: &#171;Toda una civilizaci\u00f3n morir\u00e1 esta noche&#187;","datePublished":"2026-04-07T14:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/","name":"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: \"Toda una civilizaci\u00f3n morir\u00e1 esta noche\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-07T14:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: &#171;Toda una civilizaci\u00f3n morir\u00e1 esta noche&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump amenaza a Ir\u00e1n antes del plazo para abrir el estrecho de Ormuz: &#171;Toda una civilizaci\u00f3n morir\u00e1 esta noche&#187;","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/trump-amenaza-iran-civilizacion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-07T14:03:48Z","datePublished":"2026-04-07T14:03:48Z","dateModified":"2026-04-07T14:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump amenaza a Ir\\u00e1n antes del plazo para abrir el estrecho de Ormuz: &#171;Toda una civilizaci\\u00f3n morir\\u00e1 esta noche&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/07\\\/trump-amenaza-iran-civilizacion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/07\\\/trump-amenaza-iran-civilizacion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-07T14:03:48Z\",\"datePublished\":\"2026-04-07T14:03:48Z\",\"dateModified\":\"2026-04-07T14:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472941,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/militares-origen-mexicano-heridos-guerra-iran-orix\/","url_meta":{"origin":1472931,"position":0},"title":"4 militares de EE.UU. de ascendencia mexicana resultaron heridos en la guerra con Ir\u00e1n: esto sabemos","author":"","date":"abril 7, 2026","format":false,"excerpt":"Cuatro de los militares de Estados Unidos que han resultado heridos durante la guerra que el Gobierno de Donald Trump lanz\u00f3 contra Ir\u00e1n el 28 de febrero son de origen mexicano, de acuerdo con el m\u00e1s reciente reporte del Sistema de An\u00e1lisis de Bajas de Defensa del Departamento de Defensa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472950,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/precios-petroleo-caen-acciones-suben-alto-fuego-trump-trax\/","url_meta":{"origin":1472931,"position":1},"title":"Los precios del petr\u00f3leo caen y las acciones suben tras el anuncio de alto el fuego de Trump","author":"","date":"abril 7, 2026","format":false,"excerpt":"Los precios del petr\u00f3leo se desplomaron el martes despu\u00e9s de que el presidente Donald Trump acordara un alto el fuego de dos semanas con Ir\u00e1n, lo que aviv\u00f3 las esperanzas de que m\u00e1s petroleros pudieran transitar pronto por el estrat\u00e9gico estrecho de Ormuz.Sin embargo, los analistas advirtieron que a\u00fan quedan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472951,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/dia-borde-abismo-iran-guerra-taco-trump-trax\/","url_meta":{"origin":1472931,"position":2},"title":"Un d\u00eda al borde del abismo en la guerra con Ir\u00e1n termin\u00f3 con otro momento TACO de Trump y graves cuestiones constitucionales","author":"","date":"abril 7, 2026","format":false,"excerpt":"El d\u00eda comenz\u00f3 con la advertencia de Donald Trump de que \u201ctoda una civilizaci\u00f3n\u201d de 90 millones de iran\u00edes podr\u00eda morir.Todo termin\u00f3 con el mundo \u2014tras horas de tensi\u00f3n, pendiente con temor de cada uno de sus arrebatos\u2014 tratando de comprender su marcha atr\u00e1s.Una consecuencia extraordinaria de la guerra de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473012,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/09\/acuerdo-iran-estrecho-ormuz-trax\/","url_meta":{"origin":1472931,"position":3},"title":"\u00bfUn acuerdo o un espejismo? El cese del fuego de Trump con Ir\u00e1n choca con el caos sobre el terreno","author":"","date":"abril 9, 2026","format":false,"excerpt":"Menos de tres horas antes de la fecha l\u00edmite de las 8 p.m. fijada por el presidente de Estados Unidos, Donald Trump, para que Ir\u00e1n alcanzara un acuerdo o enfrentara su advertencia apocal\u00edptica de muerte y destrucci\u00f3n, el secretario de Defensa Pete Hegseth, y el jefe del Estado Mayor Conjunto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472754,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/01\/analisis-estrecho-ormuz-gas-precios-iran-trax\/","url_meta":{"origin":1472931,"position":4},"title":"Alejarse del estrecho de Ormuz no har\u00e1 que la gasolina vuelva a ser barata","author":"","date":"abril 1, 2026","format":false,"excerpt":"La econom\u00eda mundial est\u00e1 siendo reh\u00e9n del cierre de facto del estrecho de Ormuz.Los precios de la gasolina, el combustible para aviones y el di\u00e9sel se han disparado. Los mercados burs\u00e1tiles se han desplomado y las probabilidades de recesi\u00f3n han aumentado.Tras semanas de intentos fallidos por reabrir la crucial v\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472953,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/08\/ee-uu-iran-alto-fuego-sostienen-conversaciones-trax\/","url_meta":{"origin":1472931,"position":5},"title":"EE.UU. e Ir\u00e1n acuerdan un alto el fuego y sostienen conversaciones para superar sus diferencias. Estado actual del conflicto","author":"","date":"abril 8, 2026","format":false,"excerpt":"Tras un mes y medio de escalada del conflicto en Medio Oriente, Estados Unidos e Ir\u00e1n acordaron este martes un alto el fuego de dos semanas, menos de dos horas antes de la fecha l\u00edmite fijada por el presidente Donald Trump, que hab\u00eda prometido aniquilar a \u201ctoda una civilizaci\u00f3n\u201d.Esa amenaza,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1472931"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472931\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1472931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1472931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1472931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}