{"id":1472936,"date":"2026-04-07T10:03:45","date_gmt":"2026-04-07T17:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/"},"modified":"2026-04-07T10:03:45","modified_gmt":"2026-04-07T17:03:45","slug":"trump-bromea-postularse-presidente-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/","title":{"rendered":"Trump bromea sobre su popularidad en Venezuela: &#171;Me postular\u00e9 a la presidencia&#187;"},"content":{"rendered":"<p>En medio de la tensi\u00f3n mundial por la guerra en Ir\u00e1n, el presidente de Estados Unidos, Donald Trump, se dio tiempo para bromear sobre su popularidad en Venezuela.<\/p>\n<p>\u201cEn las encuestas estoy m\u00e1s alto que nadie\u201d, dijo Trump este lunes en una rueda de prensa sobre la misi\u00f3n de rescate de un oficial de la Fuerza A\u00e9rea cuyo avi\u00f3n fue derribado sobre Ir\u00e1n.<\/p>\n<p>\u201cAs\u00ed que, cuando termine con esto, podr\u00e9 ir a Venezuela\u201d, dijo Trump, y brome\u00f3: \u201cAprender\u00e9 espa\u00f1ol r\u00e1pidamente. No me llevar\u00e1 mucho tiempo. Se me dan bien los idiomas, e ir\u00e9 a Venezuela. Me postular\u00e9 a la presidencia\u201d.<\/p>\n<p>Tras esos comentarios, volvi\u00f3 a elogiar a la presidenta encargada de Venezuela, Delcy Rodr\u00edguez. \u201cEstamos muy contentos con la presidenta electa que tenemos ahora\u201d, dijo Trump. No es la primera vez que el presidente estadounidense elogia a Rodr\u00edguez, quien asumi\u00f3 el mando de Venezuela tras la captura de Nicol\u00e1s Maduro el 3 de enero.<\/p>\n<p>Anteriormente, Trump ya hab\u00eda se\u00f1alado que la consideraba <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/14\/venezuela\/video\/donald-trump-delcy-rodriguez-llamada-telefonica-orix\">\u201cuna persona estupenda\u201d<\/a> y que estaba haciendo un trabajo \u201cfant\u00e1stico\u201d al gobernar el pa\u00eds luego de la salida de Maduro.<\/p>\n<p>La administraci\u00f3n de Trump incluso ha reconocido oficialmente a Rodr\u00edguez como presidenta del pa\u00eds sudamericano, con el objetivo de \u201cfacilitar la transici\u00f3n\u201d en el pa\u00eds. Adem\u00e1s, ha levantado las sanciones en su contra, al igual que otras sanciones contra el pa\u00eds, fundamentalmente sobre el sector energ\u00e9tico, para alentar las inversiones.<\/p>\n<p>En discurso anteriores, Trump calific\u00f3 a Venezuela como su \u201cnuevo gran socio\u201d, al destacar la cooperaci\u00f3n entre ambos gobiernos en materia de petr\u00f3leo y gas. \u201cHa funcionado de maravilla\u201d, destac\u00f3 a principios de marzo sobre el v\u00ednculo con el Gobierno interino de Rodr\u00edguez.<\/p>\n<p>Delcy Rodr\u00edguez, por su parte,<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/26\/venezuela\/video\/delcy-rodriguez-amigo-socio-donald-trump-sanciones\"> ha llamado a Trump \u201camigo y socio\u201d<\/a> y ha celebrado la nueva agenda de cooperaci\u00f3n entre ambos pa\u00edses.<\/p>\n<p>Lo cierto es que, en los \u00faltimos meses, ambos pa\u00edses han mostrado un acercamiento antes impensado. En marzo, Estados Unidos y Venezuela restablecieron sus<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/05\/venezuela\/eeuu-reanudar-relaciones-diplomaticas-consulares-trax\"> relaciones diplom\u00e1ticas<\/a>, que se hab\u00edan roto en 2019 durante el primer mandato del presidente Trump.<\/p>\n<p>Pocas horas despu\u00e9s del inicio de la operaci\u00f3n militar en Caracas, Trump manifest\u00f3 su intenci\u00f3n de \u201ctomar el control\u201d y gobernar Venezuela hasta que pudiese llevarse a cabo una transici\u00f3n, algo para lo que desestim\u00f3, en principio, la participaci\u00f3n de la l\u00edder opositora, Mar\u00eda Corina Machado, mientras que se mostr\u00f3 abierto a trabajar junto a Rodr\u00edguez.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de la tensi\u00f3n mundial por la guerra en Ir\u00e1n, el presidente de Estados Unidos, Donald Trump, se dio tiempo para bromear sobre su popularidad en Venezuela. \u201cEn las encuestas estoy m\u00e1s alto que nadie\u201d, dijo Trump este lunes en una rueda de prensa sobre la misi\u00f3n de rescate de un oficial de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472936","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump bromea sobre su popularidad en Venezuela: &quot;Me postular\u00e9 a la presidencia&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump bromea sobre su popularidad en Venezuela: &quot;Me postular\u00e9 a la presidencia&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"En medio de la tensi\u00f3n mundial por la guerra en Ir\u00e1n, el presidente de Estados Unidos, Donald Trump, se dio tiempo para bromear sobre su popularidad en Venezuela. \u201cEn las encuestas estoy m\u00e1s alto que nadie\u201d, dijo Trump este lunes en una rueda de prensa sobre la misi\u00f3n de rescate de un oficial de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-07T17:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump bromea sobre su popularidad en Venezuela: &#171;Me postular\u00e9 a la presidencia&#187;\",\"datePublished\":\"2026-04-07T17:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/\"},\"wordCount\":461,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/\",\"name\":\"Trump bromea sobre su popularidad en Venezuela: \\\"Me postular\u00e9 a la presidencia\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-07T17:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump bromea sobre su popularidad en Venezuela: &#171;Me postular\u00e9 a la presidencia&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump bromea sobre su popularidad en Venezuela: \"Me postular\u00e9 a la presidencia\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Trump bromea sobre su popularidad en Venezuela: \"Me postular\u00e9 a la presidencia\" - Noticias","og_description":"En medio de la tensi\u00f3n mundial por la guerra en Ir\u00e1n, el presidente de Estados Unidos, Donald Trump, se dio tiempo para bromear sobre su popularidad en Venezuela. \u201cEn las encuestas estoy m\u00e1s alto que nadie\u201d, dijo Trump este lunes en una rueda de prensa sobre la misi\u00f3n de rescate de un oficial de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-07T17:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Trump bromea sobre su popularidad en Venezuela: &#171;Me postular\u00e9 a la presidencia&#187;","datePublished":"2026-04-07T17:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/"},"wordCount":461,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/","name":"Trump bromea sobre su popularidad en Venezuela: \"Me postular\u00e9 a la presidencia\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-07T17:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump bromea sobre su popularidad en Venezuela: &#171;Me postular\u00e9 a la presidencia&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump bromea sobre su popularidad en Venezuela: &#171;Me postular\u00e9 a la presidencia&#187;","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/trump-bromea-postularse-presidente-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-07T17:03:45Z","datePublished":"2026-04-07T17:03:45Z","dateModified":"2026-04-07T17:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump bromea sobre su popularidad en Venezuela: &#171;Me postular\\u00e9 a la presidencia&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/07\\\/trump-bromea-postularse-presidente-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/07\\\/trump-bromea-postularse-presidente-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-07T17:03:45Z\",\"datePublished\":\"2026-04-07T17:03:45Z\",\"dateModified\":\"2026-04-07T17:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470732,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/02\/01\/maria-corina-machado-presidencia-venezuela-trax\/","url_meta":{"origin":1472936,"position":0},"title":"Mar\u00eda Corina Machado dice que ser\u00e1 presidenta de Venezuela &#171;cuando llegue el momento&#187;","author":"","date":"febrero 1, 2026","format":false,"excerpt":"Mar\u00eda Corina Machado, l\u00edder opositora venezolana, dijo que ser\u00e1 presidenta de Venezuela cuando llegue el momento, cuando las condiciones en el pa\u00eds permitan elecciones democr\u00e1ticas.\u201cSer\u00e9 presidenta cuando llegue el momento. Pero eso no importa. Eso debe decidirse en elecciones por el pueblo venezolano\u201d, dijo Machado durante una entrevista transmitida el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470127,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/15\/claves-maria-corina-machado-delcy-rodriguez-trump-orix\/","url_meta":{"origin":1472936,"position":1},"title":"Claves del d\u00eda en que Mar\u00eda Corina Machado y Delcy Rodr\u00edguez compitieron por la atenci\u00f3n de Trump y el futuro de Venezuela","author":"","date":"enero 15, 2026","format":false,"excerpt":"Venezuela vivi\u00f3 este jueves, otra vez, una jornada intensa y potencialmente hist\u00f3rica. A menos de dos semanas del derrocamiento del presidente Nicol\u00e1s Maduro en un ataque militar de EE.UU., su flamante reemplazo, Delcy Rodr\u00edguez, ofreci\u00f3 su primer discurso del estado de la naci\u00f3n ante la Asamblea Nacional y mientras intenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469807,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/05\/delcy-rodriguez-jura-presidenta-encargada-orix\/","url_meta":{"origin":1472936,"position":2},"title":"Delcy Rodr\u00edguez asume formalmente como presidenta encargada y rechaza &#171;agresi\u00f3n militar ileg\u00edtima&#187; contra Venezuela","author":"","date":"enero 5, 2026","format":false,"excerpt":"La vicepresidenta Delcy Rodr\u00edguez asumi\u00f3 este lunes formalmente como presidenta encargada de Venezuela, luego de la captura del presidente Nicol\u00e1s Maduro en un operativo militar de Estados Unidos.La juramentaci\u00f3n se dio en una ceremonia en la Asamblea Nacional, encabezada por el diputado Jorge Rodr\u00edguez, hermano de la presidenta encargada y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470158,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/16\/murillo-ortega-rompen-silencio-venezuela-maduro-cuba-orix\/","url_meta":{"origin":1472936,"position":3},"title":"La pareja Murillo-Ortega rompe el silencio sobre Venezuela: pide el regreso de Maduro y alto a las amenazas de EE.UU. a Cuba","author":"","date":"enero 16, 2026","format":false,"excerpt":"Daniel Ortega, presidente de Nicaragua, y Rosario Murillo, copresidenta del pa\u00eds y esposa de Ortega, rompieron el silencio este viernes sobre el ataque militar de Estados Unidos contra Venezuela del s\u00e1bado 3 de enero, que deriv\u00f3 en la captura del presidente derrocado Nicol\u00e1s Maduro y de la primera dama Cilia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472840,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/03\/trump-iran-venezuela-delcy-rodriguez-diferente-orix\/","url_meta":{"origin":1472936,"position":4},"title":"Trump quiere que Ir\u00e1n se parezca a la Venezuela de Delcy Rodr\u00edguez. Nada es hoy m\u00e1s diferente","author":"","date":"abril 3, 2026","format":false,"excerpt":"En el pa\u00eds de los perdedores, el presidente Donald Trump es rey. La adaptaci\u00f3n del refr\u00e1n puede parecer exagerada, pero no lo es.Es una cita de un discurso de Donald Trump ante inversionistas en Miami el 27 de marzo. All\u00ed el mandatario, quien por lo general se sale del libreto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469794,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/05\/paises-trump-advertencias-ataque-venezuela-trax\/","url_meta":{"origin":1472936,"position":5},"title":"Estos son los pa\u00edses a los que Trump lanz\u00f3 advertencias tras el ataque en Venezuela","author":"","date":"enero 5, 2026","format":false,"excerpt":"Desde que las fuerzas de Estados Unidos capturaron al presidente de Venezuela, Nicol\u00e1s Maduro, durante el fin de semana, el presidente Donald Trump y miembros de su Gobierno han emitido advertencias a varios pa\u00edses y territorios, entre ellos Colombia, Cuba, M\u00e9xico, Ir\u00e1n y Groenlandia, un territorio aut\u00f3nomo de Dinamarca.Trump dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1472936"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472936\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1472936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1472936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1472936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}