{"id":1472947,"date":"2026-04-07T18:03:59","date_gmt":"2026-04-08T01:03:59","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/"},"modified":"2026-04-07T18:03:59","modified_gmt":"2026-04-08T01:03:59","slug":"derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/","title":{"rendered":"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados"},"content":{"rendered":"<p>El juez federal en el proceso penal contra Nicol\u00e1s Maduro en Nueva York dio este martes un nuevo golpe a la defensa del depuesto presidente venezolano al prohibir que sus abogados compartan pruebas del caso con otros acusados que siguen sin ser detenidos, seg\u00fan documentos judiciales.<\/p>\n<p>En una orden judicial, el juez Alvin K. Hellerstein se\u00f1al\u00f3 que el material del caso \u201cno podr\u00e1 compartirse con ning\u00fan acusado que a\u00fan no haya sido arrestado, ni con sus abogados\u201d. Tambi\u00e9n dijo que \u201cno es necesario compartir estas pruebas para preparar la defensa\u201d.<\/p>\n<p>La decisi\u00f3n respalda a la Fiscal\u00eda, que hab\u00eda pedido limitar el acceso a la evidencia por posibles \u201criesgos\u201d para los testigos y para la investigaci\u00f3n. La medida deja fuera a otros acusados que a\u00fan no han sido detenidos, entre ellos el ministro del Interior, Diosdado Cabello y el hijo mayor de Maduro, Nicol\u00e1s Maduro Guerra.<\/p>\n<p>En su acusaci\u00f3n, Estados Unidos <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/26\/venezuela\/nicolas-maduro-cilia-flores-segunda-audiencia-eeuu-proceso-penal-orix\">tambi\u00e9n incluy\u00f3<\/a> a Cabello, a Maduro Guerra, y al pol\u00edtico y exfuncionario Ram\u00f3n Rodr\u00edguez Chac\u00edn, quienes rechazan los se\u00f1alamientos en su contra. En ese documento, Estados Unidos tambi\u00e9n acusa a H\u00e9ctor Guerrero Flores, alias \u201cNi\u00f1o Guerrero\u201d, presunto l\u00edder del grupo delictivo Tren de Aragua, una pandilla a la que el gobierno de Donald Trump <a href=\"https:\/\/www.state.gov\/terrorist-designations-of-international-cartels\/\">design\u00f3 como organizaci\u00f3n terrorista transnacional<\/a>.<\/p>\n<p>Se trata del segundo rev\u00e9s reciente para Maduro y su esposa, Cilia Flores, qui\u00e9nes fueron capturados en un operativo militar estadounidense a principios de enero en Caracas y trasladados a Nueva York, donde permanecen recluidos desde hace m\u00e1s de 90 d\u00edas en el <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/25\/venezuela\/nicolas-maduro-cilia-flores-vida-prision-eeuu-orix\">Centro de Detenci\u00f3n Metropolitano de Brooklyn.<\/a> Ambos enfrentan <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/26\/mundo\/maduro-regresa-tribunales-estados-unidos-defensa-trax\">cargos por narcotr\u00e1fico, lavado de dinero y corrupci\u00f3n<\/a>, de los que se han declarado inocentes.<\/p>\n<p>El pasado 26 de marzo, en su segunda audiencia, el juez Hellerstein <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/26\/eeuu\/live-news\/ultima-hora-audiencia-nicolas-maduro-venezuela-noticias-reacciones-trax?post-id=cmn7rj7sy007h356r0wbf09ee\">rechaz\u00f3 desestimar el caso<\/a>, como ped\u00eda la defensa, que sostiene que el Gobierno de Estados Unidos<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/25\/venezuela\/abogado-maduro-ofac-eeuu-obstaculiza-defensa-orix\"> est\u00e1 obstaculizando la defensa de su cliente<\/a>, al no conceder una licencia que permitir\u00eda al gobierno venezolano pagar por los honorarios legales.<\/p>\n<p>Aunque el juez, designado por el expresidente Bill Clinton, dijo que<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/26\/eeuu\/maduro-flores-segunda-audiencia-orix\"> pronto emitir\u00e1 una decisi\u00f3n<\/a> sobre la posibilidad de que se deba permitir a Caracas cubrir los gastos de representaci\u00f3n legal, dej\u00f3 claro que esa cuesti\u00f3n no invalidaba el proceso.<\/p>\n<p>Durante esa sesi\u00f3n, los<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/26\/eeuu\/live-news\/ultima-hora-audiencia-nicolas-maduro-venezuela-noticias-reacciones-trax?post-id=cmn7rj7sy007h356r0wbf09ee\"> fiscales acusaron <\/a>a Maduro y Flores de \u201csaquear la riqueza de Venezuela\u201d, mientras la defensa insist\u00eda en que la pareja no puede pagar sus honorarios legales por su cuenta y que el Gobierno de Venezuela deb\u00eda asumirlos. Hellerstein, por su parte, cuestion\u00f3 a ambas partes sobre las implicaciones del uso de sanciones y la disponibilidad de otros fondos para pagar la defensa legal.<\/p>\n<p>El avance del caso judicial coincide con que Delcy Rodr\u00edguez ya super\u00f3 los 90 d\u00edas como presidenta encargada de Venezuela, un l\u00edmite establecido por el Tribunal Supremo tras la captura de Maduro.<\/p>\n<p>Seg\u00fan la Constituci\u00f3n de Venezuela, cuando el presidente est\u00e1 ausente temporalmente, su lugar debe ser ocupado por el vicepresidente \u2014cargo que Rodr\u00edguez desempe\u00f1aba antes\u2014 por un m\u00e1ximo de 90 d\u00edas. La Asamblea Nacional puede extender este per\u00edodo interino por otros 90 d\u00edas si lo considera necesario.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El juez federal en el proceso penal contra Nicol\u00e1s Maduro en Nueva York dio este martes un nuevo golpe a la defensa del depuesto presidente venezolano al prohibir que sus abogados compartan pruebas del caso con otros acusados que siguen sin ser detenidos, seg\u00fan documentos judiciales. En una orden judicial, el juez Alvin K. Hellerstein [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472947","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados - Noticias\" \/>\n<meta property=\"og:description\" content=\"El juez federal en el proceso penal contra Nicol\u00e1s Maduro en Nueva York dio este martes un nuevo golpe a la defensa del depuesto presidente venezolano al prohibir que sus abogados compartan pruebas del caso con otros acusados que siguen sin ser detenidos, seg\u00fan documentos judiciales. En una orden judicial, el juez Alvin K. Hellerstein [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-08T01:03:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados\",\"datePublished\":\"2026-04-08T01:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/\",\"name\":\"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-08T01:03:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados - Noticias","og_description":"El juez federal en el proceso penal contra Nicol\u00e1s Maduro en Nueva York dio este martes un nuevo golpe a la defensa del depuesto presidente venezolano al prohibir que sus abogados compartan pruebas del caso con otros acusados que siguen sin ser detenidos, seg\u00fan documentos judiciales. En una orden judicial, el juez Alvin K. Hellerstein [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-08T01:03:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/"},"author":{"name":"","@id":""},"headline":"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados","datePublished":"2026-04-08T01:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/","name":"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-08T01:03:59+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-08T01:03:59Z","datePublished":"2026-04-08T01:03:59Z","dateModified":"2026-04-08T01:03:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Nueva derrota para Nicol\\u00e1s Maduro en EE.UU.: juez proh\\u00edbe compartir pruebas del caso con otros acusados\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/07\\\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/07\\\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-08T01:03:59Z\",\"datePublished\":\"2026-04-08T01:03:59Z\",\"dateModified\":\"2026-04-08T01:03:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473606,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","url_meta":{"origin":1472947,"position":0},"title":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa","author":"","date":"abril 28, 2026","format":false,"excerpt":"El juez Alvin K. Hellerstein, quien est\u00e1 a cargo del caso contra Nicol\u00e1s Maduro, acept\u00f3 la decisi\u00f3n del Gobierno de Estados Unidos de permitir que el Gobierno de Venezuela pague la defensa legal del derrocado presidente de Venezuela y de su esposa, la diputada Cilia Flores, quienes desde enero est\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472397,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/20\/nicolas-maduro-cilia-flores-intensifican-ofensiva-legal-ee-uu-orix\/","url_meta":{"origin":1472947,"position":1},"title":"Abogados de Nicol\u00e1s Maduro y Cilia Flores insisten en que se desestime el caso en su contra en Nueva York","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Los abogados de Nicol\u00e1s Maduro y su esposa, Cilia Flores, presentaron el jueves una nueva moci\u00f3n ante la corte federal de Nueva York en la que insisten en que se desestimen los cargos de narcoterrorismo y cuestionan directamente los argumentos del Gobierno de Estados Unidos en el caso, a menos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472196,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/14\/fiscales-extraordinaria-solicitud-maduro-honorarios-legales-trax\/","url_meta":{"origin":1472947,"position":2},"title":"Fiscales califican de &#171;extraordinaria&#187; la solicitud de Maduro de que Venezuela pague su defensa legal","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Fiscales federales de Estados Unidos afirmaron que un juez deber\u00eda denegar la solicitud del presidente derrocado de Venezuela, Nicol\u00e1s Maduro, de desestimar los cargos de narcoterrorismo, alegando que el Gobierno estadounidense ha obstaculizado su derecho a la defensa.El mes pasado, los abogados de Maduro y su esposa, Cilia Flores, quienes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472565,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/","url_meta":{"origin":1472947,"position":3},"title":"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Nicol\u00e1s Maduro, el derrocado presidente de Venezuela, intentar\u00e1 convencer este jueves a un juez federal de que el Gobierno estadounidense est\u00e1 interfiriendo en su capacidad para defenderse de los cargos relacionados con el narcoterrorismo y que el caso debe ser desestimado.El juez Alvin Hellerstein fij\u00f3 inicialmente la audiencia para dar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471866,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/04\/cilia-flores-nicolas-maduro-venezuela-desestimar-cargos-eeuu-orix\/","url_meta":{"origin":1472947,"position":4},"title":"Cilia Flores, esposa de Nicol\u00e1s Maduro, pide unirse a solicitud para desestimar cargos de narcoterrorismo en EE.UU.","author":"","date":"marzo 4, 2026","format":false,"excerpt":"La esposa del derrocado presidente de Venezuela, Cilia Flores de Maduro, pidi\u00f3 a un juez federal en Nueva York que le permita sumarse a la ofensiva legal de Nicol\u00e1s Maduro para desestimar la acusaci\u00f3n penal que ambos enfrentan en Estados Unidos.En documentos presentados ante la corte este martes, los abogados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472621,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/03\/27\/juez-hellerstein-maduro-flores-orix\/","url_meta":{"origin":1472947,"position":5},"title":"\u00bfQu\u00e9 le espera a Maduro y Flores en su proceso legal de ahora en m\u00e1s? El juez Hellerstein dio varias pistas","author":"","date":"marzo 27, 2026","format":false,"excerpt":"\u201c\u00bfCu\u00e1l es la alternativa entonces?\u201dLa recurrente pregunta del juez Alvin Hellerstein desde su estrado, entre frecuentes sorbos de agua, tanto al fiscal adjunto Kyle Adam Wirshba como al abogado de Nicol\u00e1s Maduro, Barry Pollack, indica cu\u00e1nto valora la justicia de Estados Unidos la posibilidad de que un acusado, as\u00ed sea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1472947"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1472947\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1472947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1472947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1472947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}