{"id":1473042,"date":"2026-04-10T16:03:41","date_gmt":"2026-04-10T23:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/"},"modified":"2026-04-10T16:03:41","modified_gmt":"2026-04-10T23:03:41","slug":"detienen-cinco-personas-protestas-caracas-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/","title":{"rendered":"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG"},"content":{"rendered":"<p>Al menos cinco personas fueron detenidas durante las protestas que el jueves recorrieron calles de Caracas con direcci\u00f3n al palacio presidencial de Miraflores, seg\u00fan denunciaron organizaciones venezolanas este viernes.<\/p>\n<p>Carlos Salazar, coordinador de la Coalici\u00f3n Nacional Sindical, dijo <a href=\"https:\/\/x.com\/torreseduardoj\/status\/2042667583954968991\">en un video publicado en X<\/a> que los detenidos son j\u00f3venes entre los que hay estudiantes, dirigentes comunitarios y comunicadores.<\/p>\n<p>Salazar asegur\u00f3 que la Polic\u00eda Nacional Bolivariana (PNB) se confront\u00f3 con manifestantes y realiz\u00f3 las detenciones a pesar de que la protesta comenz\u00f3 de forma pac\u00edfica y de que el Ministerio del Interior de Venezuela, del que depende la PNB, hab\u00eda sido informado previamente sobre la ruta que buscar\u00eda cubrir la marcha.<\/p>\n<p>\u201cEstamos aqu\u00ed en Marip\u00e9rez, en la jefatura policial, esperando la salida de ellos con normalidad. Ustedes nos dieron golpes, porrazos, gas pimienta y dem\u00e1s y lo aguantamos. Un empujoncito y entonces ustedes nos quieren meter presos\u201d, dijo Salazar sobre las tensiones que se registraron el jueves.<\/p>\n<p>CNN contact\u00f3 al Ministerio para Comunicaci\u00f3n e Informaci\u00f3n de Venezuela para pedir comentarios. Tambi\u00e9n busca contactar al Ministerio del Interior y a la PNB.<\/p>\n<p>El activista Eduardo Torres, abogado en derechos humanos, dijo <a href=\"https:\/\/x.com\/torreseduardoj\/status\/2042684913070030912\">en otro video publicado en X<\/a> que un grupo de personas permanecer\u00e1 afuera de la jefatura policial de Marip\u00e9rez, en Caracas, para exigir la liberaci\u00f3n de los detenidos.<\/p>\n<p>\u201cMucho nos ha costado la salida de algunos presos pol\u00edticos, faltan miles. No vamos a permitir que esa puerta giratoria comience hoy con estos cinco inocentes\u201d, se\u00f1al\u00f3.<\/p>\n<p>La protesta del jueves se realiz\u00f3 un d\u00eda despu\u00e9s de que la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 un aumento salarial que caus\u00f3 inconformidad entre grupos de trabajadores. A la par, se llevaron a cabo marchas a favor del Gobierno.<\/p>\n<p>Por la tarde, un contingente de la PNB bloque\u00f3 la ruta de los contingentes de inconformes <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/10\/venezuela\/marcha-venezuela-trabajadores-salario-bloqueo-policial-efe\">e impidi\u00f3 su avance hasta Miraflores<\/a>. Adem\u00e1s, algunos periodistas denunciaron agresiones, una situaci\u00f3n que tambi\u00e9n fue registrada y condenada por organizaciones no gubernamentales como el Programa Venezolano Educaci\u00f3n Acci\u00f3n en Derechos Humanos (<a href=\"https:\/\/x.com\/_Provea\/status\/2042282782630490345\">Provea<\/a>).<\/p>\n<p>Las protestas contra el Gobierno de Venezuela, usuales en otros momentos del pa\u00eds, se tornaron poco comunes durante los \u00faltimos meses de la presidencia de Nicol\u00e1s Maduro, quien el 3 de enero fue capturado en un operativo militar de Estados Unidos. La de este jueves fue una de las primeras en su tipo durante el mandato de Delcy Rodr\u00edguez, quien asumi\u00f3 como presidenta encargada poco despu\u00e9s de la captura de Maduro y su traslado a Nueva York.<\/p>\n<p>En un mensaje publicado en X, Amnist\u00eda Internacional critic\u00f3 este viernes el despliegue policial observado en Caracas.<\/p>\n<p>\u201cLas im\u00e1genes de la represi\u00f3n de la protesta de ayer en Caracas son indignantes\u201d, <a href=\"https:\/\/x.com\/amnistia\/status\/2042659104007635107\">dijo la organizaci\u00f3n en X<\/a>. \u201cReprimir una manifestaci\u00f3n no es \u2018mantener el orden\u2019, es violar derechos humanos. Desde Amnist\u00eda lo decimos claro: el Estado debe proteger, no atacar. \u00a1Manifestar es un derecho!\u201d, concluy\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos cinco personas fueron detenidas durante las protestas que el jueves recorrieron calles de Caracas con direcci\u00f3n al palacio presidencial de Miraflores, seg\u00fan denunciaron organizaciones venezolanas este viernes. Carlos Salazar, coordinador de la Coalici\u00f3n Nacional Sindical, dijo en un video publicado en X que los detenidos son j\u00f3venes entre los que hay estudiantes, dirigentes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473042","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al menos cinco personas fueron detenidas durante las protestas que el jueves recorrieron calles de Caracas con direcci\u00f3n al palacio presidencial de Miraflores, seg\u00fan denunciaron organizaciones venezolanas este viernes. Carlos Salazar, coordinador de la Coalici\u00f3n Nacional Sindical, dijo en un video publicado en X que los detenidos son j\u00f3venes entre los que hay estudiantes, dirigentes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T23:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG\",\"datePublished\":\"2026-04-10T23:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/\"},\"wordCount\":540,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/\",\"name\":\"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-10T23:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG - Noticias","og_description":"Al menos cinco personas fueron detenidas durante las protestas que el jueves recorrieron calles de Caracas con direcci\u00f3n al palacio presidencial de Miraflores, seg\u00fan denunciaron organizaciones venezolanas este viernes. Carlos Salazar, coordinador de la Coalici\u00f3n Nacional Sindical, dijo en un video publicado en X que los detenidos son j\u00f3venes entre los que hay estudiantes, dirigentes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-10T23:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/"},"author":{"name":"","@id":""},"headline":"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG","datePublished":"2026-04-10T23:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/"},"wordCount":540,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/","name":"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-10T23:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/10\/detienen-cinco-personas-protestas-caracas-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-10T23:03:41Z","datePublished":"2026-04-10T23:03:41Z","dateModified":"2026-04-10T23:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Detienen al menos a cinco personas durante las protestas del jueves en Caracas, denuncian ONG\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/10\\\/detienen-cinco-personas-protestas-caracas-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/10\\\/detienen-cinco-personas-protestas-caracas-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-10T23:03:41Z\",\"datePublished\":\"2026-04-10T23:03:41Z\",\"dateModified\":\"2026-04-10T23:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473031,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/10\/marcha-venezuela-trabajadores-salario-bloqueo-policial-efe\/","url_meta":{"origin":1473042,"position":0},"title":"Volvieron las marchas a las calles de Venezuela y tambi\u00e9n el bloqueo policial","author":"","date":"abril 10, 2026","format":false,"excerpt":"Un fuerte cerco de la Polic\u00eda Nacional Bolivariana (PNB) de Venezuela bloque\u00f3 y dispers\u00f3 con gas pimienta a cientos de trabajadores que intentaban marchan este jueves hacia el palacio presidencial de Miraflores, en el centro de Caracas, para exigir un aumento de salario, congelado desde 2022.En su intento por llegar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452169,"url":"https:\/\/noticiasya.com\/lubbock\/2024\/08\/26\/excarcelan-periodista-carmela-longo-orix\/","url_meta":{"origin":1473042,"position":1},"title":"Excarcelan en Venezuela a la periodista Carmela Longo, detenida el domingo en Caracas","author":"","date":"agosto 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La periodista venezolana Carmela Longo, detenida el domingo por funcionarios de la Polic\u00eda Nacional Bolivariana (PNB), fue excarcelada este lunes luego de ser imputada con cargos de terrorismo e incitaci\u00f3n al odio en una audiencia virtual celebrada el lunes, inform\u00f3 el Sindicato Nacional de Trabajadores de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469871,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/","url_meta":{"origin":1473042,"position":2},"title":"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU","author":"","date":"enero 7, 2026","format":false,"excerpt":"Cuando apenas han pasado cinco d\u00edas del ataque de Estados Unidos a Caracas y la captura de Nicol\u00e1s Maduro, los venezolanos intentan recuperar cierto grado de normalidad. Pero hay algo que refleja la tensi\u00f3n latente: aunque durante el d\u00eda la circulaci\u00f3n va recuperando el ritmo usual, en la noche el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442557,"url":"https:\/\/noticiasya.com\/lubbock\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez\/","url_meta":{"origin":1473042,"position":3},"title":"Excarcelan en Venezuela al estudiante John \u00c1lvarez","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad.El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442560,"url":"https:\/\/noticiasya.com\/lubbock\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-2\/","url_meta":{"origin":1473042,"position":4},"title":"Excarcelan en Venezuela al estudiante John \u00c1lvarez","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad.El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442561,"url":"https:\/\/noticiasya.com\/lubbock\/2023\/12\/23\/excarcelan-en-venezuela-al-estudiante-john-alvarez-3\/","url_meta":{"origin":1473042,"position":5},"title":"Excarcelan en Venezuela al estudiante John \u00c1lvarez","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Tras 115 d\u00edas de detenci\u00f3n, el estudiante de antropolog\u00eda de la Universidad Central de Venezuela, John \u00c1lvarez, fue excarcelado en la tarde de este s\u00e1bado, en v\u00edsperas de Navidad.El joven de 24 a\u00f1os de edad fue detenido por funcionarios de la Direcci\u00f3n de Acciones Estrat\u00e9gicas y T\u00e1cticas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1473042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1473042"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1473042\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1473042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1473042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1473042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}