{"id":1473395,"date":"2026-04-22T06:03:43","date_gmt":"2026-04-22T13:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/"},"modified":"2026-04-22T06:03:43","modified_gmt":"2026-04-22T13:03:43","slug":"operativos-seguridad-mundial-tiroteo-teotihuacan-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/","title":{"rendered":"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad"},"content":{"rendered":"<p>\u201c\u00bfC\u00f3mo es que entra con un arma? Es la pregunta que se hacen todos\u201d, reconoci\u00f3 este martes la presidenta de M\u00e9xico, Claudia Sheinbaum, al hablar del agresor del tiroteo ocurrido el lunes en la zona arqueol\u00f3gica de Teotihuac\u00e1n, Estado de M\u00e9xico, donde murieron una turista canadiense y el propio atacante y <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/mexico\/victimas-tiroteo-teotihuacan-esto-sabemos-orix\">13 personas<\/a> m\u00e1s de distintas nacionalidades resultaron heridas.<\/p>\n<p>En un pa\u00eds con altos niveles de violencia que se reflejan en homicidios y otros delitos delitos \u2014muchos de ellos asociados al crimen organizado\u2014, el episodio resulta in\u00e9dito para M\u00e9xico porque sucedi\u00f3 en un concurrido destino arqueol\u00f3gico y tur\u00edstico, remarcan tanto las autoridades mexicanas como especialistas. Adem\u00e1s, ocurre pocas semanas antes de que comience Mundial de F\u00fatbol en el que M\u00e9xico ser\u00e1 coanfitri\u00f3n junto con Estados Unidos y Canad\u00e1.<\/p>\n<p>Por estos factores, el tiroteo en Teotihuac\u00e1n aumenta las dudas sobre M\u00e9xico, un pa\u00eds que tendr\u00e1 tres ciudades sede a partir del 11 de junio y que ya <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/13\/mexico\/copa-mundo-seguridad-narcoterrorismo-orix\">enfrentaba cuestionamientos<\/a> sobre su capacidad para brindar seguridad p\u00fablica a millones de visitantes.<\/p>\n<p>Desde el Gobierno de Sheinbaum, tanto la mandataria como su Gabinete dan muestras de ser conscientes de que existe esta desconfianza y continuamente buscan atajarla con llamados a la calma.<\/p>\n<p>La seguridad del Mundial \u201cest\u00e1 garantizada\u201d, dijo este martes el secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, quien argument\u00f3 que los operativos en la materia se revisan a diario y que lo ocurrido en Teotihuac\u00e1n se trat\u00f3 de un hecho sin ning\u00fan antecedente similar.<\/p>\n<p>\u201cEste hecho tan lamentable nunca hab\u00eda ocurrido en una zona arqueol\u00f3gica de nuestro pa\u00eds\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/mexico\/teotihuacan-tiroteo-que-paso-ataque-trax#:~:text=%E2%80%9CEstamos%20convencidos%20que,Harfuch%20este%20martes.\">dijo Garc\u00eda Harfuch<\/a>, que remarc\u00f3 que son millones los visitantes que cada a\u00f1o llegan a estos sitios arqueol\u00f3gicos y que \u201cjam\u00e1s hab\u00eda habido un solo incidente\u201d.<\/p>\n<p>El ataque hizo que las autoridades anunciaran horas despu\u00e9s el reforzamiento de la seguridad en zonas arqueol\u00f3gicas en coordinaci\u00f3n con la Secretar\u00eda de Cultura y otras autoridades que est\u00e1n relacionadas a los operativos para el Mundial. \u201cTodos estos protocolos de seguridad ya est\u00e1n, ya se han estado trabajando desde hace m\u00e1s de un a\u00f1o\u201d, dijo el secretario.<\/p>\n<p>A principios de marzo, el Gobierno de M\u00e9xico anunci\u00f3 que <a href=\"https:\/\/efe.com\/deportes\/2026-03-06\/mexico-dispositivo-seguridad-mundial-futbol-2026\/\">casi 100.000 personas participar\u00e1n<\/a> en las tareas de seguridad por el Mundial, entre fuerzas estatales y guardias de seguridad privada.<\/p>\n<p>Ubicado a unos 48 kil\u00f3metros al noreste de Ciudad de M\u00e9xico, Teotihuac\u00e1n es un importante sitio arqueol\u00f3gico y destino tur\u00edstico, declarado Patrimonio de la Humanidad por la UNESCO. Tiene entre sus monumentos dos grandes pir\u00e1mides: la Pir\u00e1mide de la Luna y la Pir\u00e1mide del Sol.<\/p>\n<p>El agresor, quien <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/mexico\/teotihuacan-tiroteo-que-paso-ataque-trax#:~:text=Casta%C3%B1eda%20Camarillo%20asegur%C3%B3%20que%2C%20tras%20establecer%20una%20mesa%20de%20trabajo%20con%20la%20Fiscal%C3%ADa%20del%20Estado%20de%20M%C3%A9xico%2C%20se%20determin%C3%B3%20que%20fue%20%E2%80%9Cun%20solo%20atacante%2C%20esta%20persona%20actu%C3%B3%20sola%E2%80%9D.\">\u201cactu\u00f3 solo\u201d<\/a>, dispar\u00f3 desde la Pir\u00e1mide de la Luna, precis\u00f3 este martes el coronel Crist\u00f3bal Casta\u00f1eda Camarillo, secretario de Seguridad del Estado de M\u00e9xico. Pasadas las 11:00 de la ma\u00f1ana del lunes, hora local, el hombre de 27 a\u00f1os mat\u00f3 a una persona e hiri\u00f3 a otras que se encuentran fuera de peligro.<\/p>\n<p>Seg\u00fan las autoridades, el atacante <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/mexico\/teotihuacan-tiroteo-que-paso-ataque-trax\">se quit\u00f3 la vida<\/a> al verse rodeado por oficiales de la Guardia Nacional.<\/p>\n<p>El secretario de Seguridad de M\u00e9xico <a href=\"https:\/\/x.com\/OHarfuch\/status\/2046592824955564499\">dijo<\/a> que, tras lo ocurrido, orden\u00f3 fortalecer la seguridad en zonas arqueol\u00f3gicas y en los principales destinos tur\u00edsticos del pa\u00eds, adem\u00e1s de incrementar la presencia de la Guardia Nacional y reforzar las revisiones, los controles de acceso y los sistemas de vigilancia en estos espacios p\u00fablicos.<\/p>\n<p>Mediante el patrullaje f\u00edsico y cibern\u00e9tico, a cargo de la Guardia Nacional y del Centro Nacional de Inteligencia, las autoridades buscar\u00e1n prevenir potenciales amenazas, agreg\u00f3 Garc\u00eda Harfuch.<\/p>\n<p>Despu\u00e9s del tiroteo en Teotihuac\u00e1n, algunos especialistas eval\u00faan lo sucedido y las implicaciones que puede tener en el contexto del Mundial.<\/p>\n<p>\u201cEs un hecho poco com\u00fan en nuestro pa\u00eds, se trata de una situaci\u00f3n aislada que no corresponde a la vida natural de M\u00e9xico\u201d, dice a CNN Francisco Rivas, director del <a href=\"https:\/\/onc.org.mx\/\">Observatorio Nacional Ciudadano<\/a>, una organizaci\u00f3n que monitorea pol\u00edticas p\u00fablicas, incidencia delictiva y acceso a la legalidad en M\u00e9xico.<\/p>\n<p>Rivas dice que M\u00e9xico es un pa\u00eds violento, pero explica que la violencia la sufren los ciudadanos y \u201crara vez\u201d los turistas, por lo que en principio no ve que lo ocurrido vaya a tener impacto en el Mundial. En cambio, s\u00ed cree que esta es una oportunidad para que el Gobierno de M\u00e9xico refuerce, sobre todo, la prevenci\u00f3n para que los turistas extremen precauciones sobre ciertas zonas o situaciones que puedan ser problem\u00e1ticas.<\/p>\n<p>Antes del ataque, el Gobierno de Sheinbaum ya hab\u00eda reiterado en varias oportunidades que la seguridad para el evento est\u00e1 garantizada. \u201cEs seguro que vengan a nuestro pa\u00eds, a cualquiera de las tres ciudades donde se van a desarrollar los partidos o a las otras ciudades que est\u00e1n incorporadas por FIFA o a cualquier ciudad del pa\u00eds. Pueden venir con seguridad y certeza. La van a pasar muy bien\u201d,<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/23\/mexico\/seguridad-turismo-mundial-futbol-mexico-orix#:~:text=Es%20seguro%20que,de%20prensa%20matutina.\"> dijo Sheinbaum en marzo<\/a>.<\/p>\n<p>Las dudas sobre la capacidad para garantizar la seguridad para millones de turistas y jugadores crecieron luego de la ola de violencia que se desat\u00f3 en febrero en distintas regiones tras <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/23\/mexico\/mundial-guadalajara-violencia-mencho-cjng-orix\">la muerte de Nemesio \u201cel Mencho\u201d Oseguera<\/a>, l\u00edder del Cartel Jalisco Nueva Generaci\u00f3n. Veh\u00edculos incendiados, bloqueos de rutas y enfrentamientos fueron algunas de las im\u00e1genes de esa incertidumbre.<\/p>\n<p>Para Rodrigo Pe\u00f1a, especialista en seguridad, investigador y profesor del Instituto Tecnol\u00f3gico de Monterrey, el ataque armado en Teotihuac\u00e1n tiene al menos dos implicaciones: la primera en t\u00e9rminos de proyecci\u00f3n e imagen, que impacta directamente en las expectativas del recibimiento de turismo de cara a la Copa del Mundo. \u201cHay una consecuencia directa y se suma a las consecuencias anteriores, derivadas del caso del \u2018Mencho\u2019, que puso en el radar la seguridad en M\u00e9xico y el Mundial\u201d, dice.<\/p>\n<p>En segundo lugar, el acad\u00e9mico ve surgir una \u201cnueva dimensi\u00f3n de inseguridad\u201d, que tiene que ver con c\u00f3mo se entrecruzan los discursos de odio con acciones de violencia concretas en espacios p\u00fablicos.<\/p>\n<p>Es un tipo de violencia al que Pe\u00f1a vincula a tiroteos masivos como los que ocurren en Estados Unidos, que s\u00ed ser\u00edan algo novedoso en M\u00e9xico. \u201cEs una alerta de un tipo de violencia viejo, pero con nueva identidad en el contexto mexicano\u201d, dice.<\/p>\n<p>Seg\u00fan las primeras investigaciones de las autoridades mexicanas, el atacante llevaba una mochila con m\u00e1s de 50 cartuchos \u00fatiles, un arma punzocortante y material \u201cpresuntamente relacionado\u201d con hechos violentos que \u201cpudieron haber sucedido en Estados Unidos en abril de 1999\u201d, dijo el fiscal del Estado de M\u00e9xico, Jos\u00e9 Luis Cervantes Mart\u00ednez. El 20 de abril de 1999, ocurri\u00f3 el <a href=\"https:\/\/cnnespanol.cnn.com\/2022\/03\/27\/peores-tiroteos-escuelas-violencia-armada-estados-unidos-orix\">tiroteo masivo<\/a> en la escuela <a href=\"https:\/\/www.cnn.com\/2013\/09\/18\/us\/columbine-high-school-shootings-fast-facts\/index.html\">secundaria Columbine en Littleton, Colorado<\/a>, en la que 13 personas fueron asesinadas.<\/p>\n<p>Si bien las autoridades se\u00f1alan que el tiroteo en Teotihuac\u00e1n puede verse como un hecho aislado sin vinculaciones con la delincuencia, es suficiente para que algunos especialistas planteen cuestionamientos, tanto antes como despu\u00e9s de los eventos del Mundial.<\/p>\n<p>La pregunta es si las autoridades \u201ctienen las capacidades de despliegue, contenci\u00f3n y de generaci\u00f3n de inteligencia para evitar este tipo de eventos\u201d, dice Pe\u00f1a, <a href=\"https:\/\/libros.colmex.mx\/tienda\/metodologias-para-la-seguridad-y-la-paz-social\/\">autor<\/a> del libro \u201cMetodolog\u00eda(s) para la seguridad y la paz social\u201d.<\/p>\n<p>Arcos de seguridad con rayos X y mayor presencia de la Guardia Nacional en grandes puntos tur\u00edsticos del pa\u00eds son algunas de las medidas anunciadas por la presidenta Sheinbaum este martes, quien aclar\u00f3 que estos ajustes no se dar\u00e1n \u201cde un d\u00eda para otro\u201d.<\/p>\n<p>Frente a la cercan\u00eda del Mundial y los cuestionamientos sobre M\u00e9xico por hechos recientes, Pe\u00f1a considera que para el torneo existe una estrategia \u201crazonablemente bien desplegada\u201d en torno a los centros de las ciudades sede \u2014Guadalajara, Ciudad de M\u00e9xico y Monterrey\u2014, donde probablemente se concentrar\u00eda la mayor afluencia de gente.<\/p>\n<p>La gran pregunta, advierte el acad\u00e9mico, es qu\u00e9 pasar\u00e1 con otros grandes espacios que no necesariamente est\u00e1n cerca de los estadios. \u201cTeotihuac\u00e1n est\u00e1 en el centro de las miradas ahora, pero hay muchos otros que tambi\u00e9n podr\u00edan correr ese nivel de riesgo\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c\u00bfC\u00f3mo es que entra con un arma? Es la pregunta que se hacen todos\u201d, reconoci\u00f3 este martes la presidenta de M\u00e9xico, Claudia Sheinbaum, al hablar del agresor del tiroteo ocurrido el lunes en la zona arqueol\u00f3gica de Teotihuac\u00e1n, Estado de M\u00e9xico, donde murieron una turista canadiense y el propio atacante y 13 personas m\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1473395","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u201c\u00bfC\u00f3mo es que entra con un arma? Es la pregunta que se hacen todos\u201d, reconoci\u00f3 este martes la presidenta de M\u00e9xico, Claudia Sheinbaum, al hablar del agresor del tiroteo ocurrido el lunes en la zona arqueol\u00f3gica de Teotihuac\u00e1n, Estado de M\u00e9xico, donde murieron una turista canadiense y el propio atacante y 13 personas m\u00e1s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-22T13:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad\",\"datePublished\":\"2026-04-22T13:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/\"},\"wordCount\":1445,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/\",\"name\":\"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-22T13:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad - Noticias","og_description":"\u201c\u00bfC\u00f3mo es que entra con un arma? Es la pregunta que se hacen todos\u201d, reconoci\u00f3 este martes la presidenta de M\u00e9xico, Claudia Sheinbaum, al hablar del agresor del tiroteo ocurrido el lunes en la zona arqueol\u00f3gica de Teotihuac\u00e1n, Estado de M\u00e9xico, donde murieron una turista canadiense y el propio atacante y 13 personas m\u00e1s de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-22T13:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/"},"author":{"name":"","@id":""},"headline":"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad","datePublished":"2026-04-22T13:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/"},"wordCount":1445,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/","name":"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-22T13:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\u00e1n eleva las dudas sobre el pa\u00eds y lo obliga a reforzar la seguridad","url":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/lubbock\/2026\/04\/22\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-22T13:03:43Z","datePublished":"2026-04-22T13:03:43Z","dateModified":"2026-04-22T13:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e9xico en la mira antes del Mundial: tiroteo en Teotihuac\\u00e1n eleva las dudas sobre el pa\\u00eds y lo obliga a reforzar la seguridad\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/22\\\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/lubbock\\\/2026\\\/04\\\/22\\\/operativos-seguridad-mundial-tiroteo-teotihuacan-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-22T13:03:43Z\",\"datePublished\":\"2026-04-22T13:03:43Z\",\"dateModified\":\"2026-04-22T13:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1473361,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/21\/teotihuacan-tiroteo-que-paso-ataque-trax\/","url_meta":{"origin":1473395,"position":0},"title":"Tiroteo en Teotihuac\u00e1n: qu\u00e9 pas\u00f3 en el ataque que dej\u00f3 una turista muerta y varios heridos","author":"","date":"abril 21, 2026","format":false,"excerpt":"Una mujer canadiense muri\u00f3 y seis turistas estadounidenses est\u00e1n entre m\u00e1s de una docena de personas heridas despu\u00e9s de que un hombre armado abri\u00f3 fuego este lunes cerca de las pir\u00e1mides de Teotihuac\u00e1n, en M\u00e9xico, dijeron autoridades.Seg\u00fan informaci\u00f3n preliminar, un hombre dispar\u00f3 en el popular sitio arqueol\u00f3gico, mat\u00f3 a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473376,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/21\/victimas-tiroteo-teotihuacan-esto-sabemos-orix\/","url_meta":{"origin":1473395,"position":1},"title":"Una mujer fallecida y 13 personas heridas: lo que sabemos de las v\u00edctimas del tiroteo en Teotihuac\u00e1n","author":"","date":"abril 21, 2026","format":false,"excerpt":"Trece son las personas extranjeras que resultaron heridas en diversos grados durante el ataque con arma de fuego ocurrido en la ma\u00f1ana del lunes en la concurrida zona arqueol\u00f3gica de Teotihuac\u00e1n, en el Estado de M\u00e9xico. Se trata de tres ciudadanos colombianos \u2014entre ellos, un menor\u2014, seis estadounidenses, un hombre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473380,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/21\/julio-cesar-jasso-ramirez-atacante-teotihuacan-orix\/","url_meta":{"origin":1473395,"position":2},"title":"Plane\u00f3 con tiempo el ataque en Teotihuac\u00e1n, se arm\u00f3 y actu\u00f3 &#171;de manera solitaria&#187;: esto sabemos de Julio C\u00e9sar Jasso Ram\u00edrez","author":"","date":"abril 21, 2026","format":false,"excerpt":"Un tiroteo el lunes en la zona arqueol\u00f3gica de Teotihuac\u00e1n, ubicada en el Estado de M\u00e9xico, en el centro del pa\u00eds, dej\u00f3 como saldo una turista canadiense fallecida y 13 extranjeros m\u00e1s lesionados, seg\u00fan informaron las autoridades mexicanas.La Fiscal\u00eda del Estado de M\u00e9xico identific\u00f3 al atacante como Julio C\u00e9sar Jasso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462730,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/05\/23\/heridos-accidente-globo-aerostatico-teotihuacan-mexico-orix\/","url_meta":{"origin":1473395,"position":3},"title":"Al menos 12 heridos en accidente de globo aerost\u00e1tico cerca Teotihuac\u00e1n, un popular sitio tur\u00edstico en M\u00e9xico","author":"","date":"mayo 23, 2025","format":false,"excerpt":"Al menos doce personas resultaron heridas en un accidente de globo aerost\u00e1tico cerca de un sitio arqueol\u00f3gico pr\u00f3ximo en la Ciudad de M\u00e9xico el viernes, informaron las autoridades locales.El globo realiz\u00f3 un \u201caterrizaje forzado\u201d en San Mart\u00edn de las Pir\u00e1mides tras chocar con una burbuja de aire, seg\u00fan un comunicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473340,"url":"https:\/\/noticiasya.com\/lubbock\/2026\/04\/20\/teotihuacan-balacera-muertos-heridos-mexico-orix\/","url_meta":{"origin":1473395,"position":4},"title":"Al menos una persona y un presunto agresor mueren tras una balacera en las pir\u00e1mides de Teotihuac\u00e1n","author":"","date":"abril 20, 2026","format":false,"excerpt":"Una balacera en las pir\u00e1mides de Teotihuac\u00e1n dej\u00f3 al menos una persona muerta y varias m\u00e1s heridas, inform\u00f3 este lunes el gabinete de seguridad de M\u00e9xico.Un hombre abri\u00f3 fuego en el popular sitio arqueol\u00f3gico, matando a una mujer canadiense, antes de quitarse la vida, se\u00f1al\u00f3 el gabinete en su cuenta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461122,"url":"https:\/\/noticiasya.com\/lubbock\/2025\/04\/12\/altar-cuerpos-antigua-ciudad-maya-teotihuacan-trax\/","url_meta":{"origin":1473395,"position":5},"title":"Un misterioso altar con cuerpos hallado en una antigua ciudad maya revelar\u00eda fuerte influencia de la cultura teotihuacana","author":"","date":"abril 12, 2025","format":false,"excerpt":"Arque\u00f3logos que trabajan en una antigua ciudad maya desenterraron un misterioso altar de 1.700 a\u00f1os de antig\u00fcedad cuyas brillantes decoraciones y siniestros contenidos pueden contener la clave para desentra\u00f1ar la compleja geopol\u00edtica de la \u00e9poca.A pesar de encontrar el altar en Tikal, una ciudad maya en ruinas situada en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/lubbock\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1473395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/comments?post=1473395"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/posts\/1473395\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/media?parent=1473395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/categories?post=1473395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/lubbock\/wp-json\/wp\/v2\/tags?post=1473395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}