{"id":1447355,"date":"2024-03-25T20:03:50","date_gmt":"2024-03-26T03:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/"},"modified":"2024-03-25T20:03:50","modified_gmt":"2024-03-26T03:03:50","slug":"jovenes-organizan-fiestas-powerpoint-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/","title":{"rendered":"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint"},"content":{"rendered":"<p>(CNN) &#8212; Para el festejo de 21 a\u00f1os de McCall Mirabella el mes pasado, ella pidi\u00f3 a los invitados que trajeran solo un regalo: una presentaci\u00f3n de PowerPoint.<\/p>\n<p>Mirabella, una personalidad de TikTok y YouTube con m\u00e1s de 1,3 millones de seguidores en ambas plataformas, reuni\u00f3 a sus amigos m\u00e1s cercanos y les pidi\u00f3 que expusieran una presentaci\u00f3n de diapositivas sobre cualquier cosa que se les ocurriera. El \u00fanico criterio era &#171;cuanto m\u00e1s tonto, mejor&#187;.<\/p>\n<p>Sus invitados cumplieron. Un asistente calific\u00f3 el atractivo de 10 personajes animados mientras que otro explor\u00f3 con humor las distintas etapas de la drogadicci\u00f3n. La propia Mirabella present\u00f3 sus predicciones sobre cu\u00e1nto tiempo sobrevivir\u00edan sus amigos en los Juegos del Hambre (y c\u00f3mo ser\u00edan sus finales violentos, aparentemente una plantilla popular para una fiesta de PowerPoint).<\/p>\n<p>Este hombre est\u00e1 troleando a una aerol\u00ednea con presentaciones de PowerPoint para encontrar su maleta perdida<\/p>\n<p>Son tales los placeres de las noches de presentaciones de PowerPoint, que ganaron popularidad durante el pico de la pandemia de covid-19, pero que todav\u00eda gustan a los invitados a la fiesta (esto a pesar de su uso regular en oficinas corporativas de todo el mundo). A trav\u00e9s de una tonta presentaci\u00f3n de diapositivas, grupos de amigos conocen los intereses espec\u00edficos de cada uno, sus pasatiempos secretos y, con frecuencia, versiones hilarantes de las peculiaridades y fortalezas de sus amigos.<\/p>\n<p>Ver a las personas que ella ama enojarse por asignarse mutuamente canciones de Taylor Swift que coincidan con sus personalidades o cr\u00edmenes ficticios que los llevar\u00edan a prisi\u00f3n es una alegr\u00eda espec\u00edfica de las fiestas centradas en presentaciones de diapositivas, dijo Mirabella.<\/p>\n<p>&#171;Son tan poco serias&#187;, dijo sobre las noches de PowerPoint a las que asisti\u00f3 y organiz\u00f3. \u201cLa mayor\u00eda de las veces, la gente llora de tanto re\u00edr o se inclina y respira con dificultad\u201d.<\/p>\n<p>Las fiestas de PowerPoint se hicieron populares durante la pandemia, pero han existido durante a\u00f1os<\/p>\n<p>Las noches de PowerPoint implican poco m\u00e1s que un televisor compatible con HDMI, una presentaci\u00f3n de diapositivas y la voluntad de entusiasmar a tus amigos o revelar tus pasiones ocultas. El software en s\u00ed tiene casi 40 a\u00f1os y desde entonces se ha convertido en un elemento b\u00e1sico en muchas oficinas y aulas, pero la ingeniosa fiesta de PowerPoint convierte la tecnolog\u00eda familiar en un medio para la comedia y el compa\u00f1erismo.<\/p>\n<p>El concepto de fiesta de PowerPoint se formaliz\u00f3 en 2012, cuando tres estudiantes de la Universidad de Waterloo en Ontario, Canad\u00e1, organizaron el evento \u201cBebe, habla y aprende\u201d. Los invitados a estas primeras fiestas tuvieron que presentarse con una presentaci\u00f3n sobre un tema de su elecci\u00f3n, como la alineaci\u00f3n moral del personaje de Sonic the Hedgehog, Shadow, seg\u00fan Buzzfeed News .<\/p>\n<p>Microsoft agregar\u00e1 inteligencia artificial a sus productos m\u00e1s populares<\/p>\n<p>La tem\u00e1tica se hizo cada vez m\u00e1s popular y en 2018 m\u00e1s entusiastas de PowerPoint en Estados Unidos se sumaron a la tendencia. Pronto, muchos, desde ingenieros de software en Seattle hasta estudiantes en Boston, presentaron diapositivas sobre temas muy espec\u00edficos ante una peque\u00f1a multitud, a menudo con una bebida en la mano.<\/p>\n<p>En el relato del Harvard Crimson sobre una fiesta de PowerPoint local, un estudiante present\u00f3 su argumento de por qu\u00e9 el rey Claudio es el verdadero h\u00e9roe de \u201cHamlet\u201d de Shakespeare, una opini\u00f3n divisiva si alguna vez la hubo. El presentador dijo al peri\u00f3dico escolar que su entusiasmo por el tema hab\u00eda quedado relegado hasta ese momento a \u201cuna perorata con mis amigos. Finalmente puedo present\u00e1rselo a extra\u00f1os\u201d.<\/p>\n<p>Cuando lleg\u00f3 el covid-19 en 2020 y millones de estadounidenses se aislaron en sus hogares, las fiestas virtuales de PowerPoint se convirtieron en una forma segura y distanciada para que los amigos se pusieran al d\u00eda sobre sus vidas y se brindaran la ligereza que tanto necesitaban. Los grupos separados por la pandemia compartieron sus pantallas en Zoom o incluso reunieron a sus compa\u00f1eros de casa para convertir una noche com\u00fan y corriente en aislamiento en una oportunidad para una TedTalk privada.<\/p>\n<p>En Filadelfia, una mujer comparti\u00f3 una presentaci\u00f3n sobre su amigo soltero con la esperanza de presentarle una posible pareja. Cr\u00e9dito: Charles Fox\/The Philadelphia Inquirer\/Zum.<\/p>\n<p>Algunos fragmentos tentadores de estas presentaciones llegaron a TikTok (los usuarios rara vez revelan el jugoso contenido de las presentaciones de diapositivas m\u00e1s all\u00e1 de sus escandalosos t\u00edtulos), e inspiraron a otros usuarios a organizar sus propias reuniones. Los temas suelen ser tomas estrafalarias y alegres de las idiosincrasias de un grupo de amigos, como c\u00f3mo les ir\u00eda a cada uno durante un apocalipsis zombie, y pasiones menores o teor\u00edas dudosas como la raz\u00f3n &#171;real&#187; (l\u00e9ase: ficticia) por la que murieron los dinosaurios.<\/p>\n<p>Desde que el formato de fiesta despeg\u00f3 en 2020 (y desde entonces ha acumulado m\u00e1s de 40 millones de visitas en TikTok con hashtags relacionados), los usuarios de TikTok han probado nuevas variaciones ingeniosas de la t\u00edpica presentaci\u00f3n de diapositivas y han encuestado a los usuarios en diferentes plataformas, como Reddit, para obtener sugerencias \u00fanicas para las presentaciones. Tomemos como ejemplo al anfitri\u00f3n que tendi\u00f3 una emboscada a sus invitados oblig\u00e1ndolos a presentar el PowerPoint de otra persona sobre un tema del que no sab\u00edan nada, como el desventurado amigo que los enga\u00f1\u00f3 durante una presentaci\u00f3n sobre c\u00f3mo elegir acciones. Un grupo de Filadelfia crea presentaciones de diapositivas para que sus amigos solteros capten la atenci\u00f3n de otros solteros. Un usuario creativo de TikTok incluso sali\u00f3 del closet con su familia en un PowerPoint en Navidad.<\/p>\n<p>Aunque el software Microsoft PowerPoint no es un requisito para estas presentaciones (los servicios de la competencia como Prezi, Canva y Google Slides tambi\u00e9n son populares), Microsoft emiti\u00f3 su propio consejo para organizar una fiesta de PowerPoint de primer nivel. Entre sus sugerencias: aprovechar esas transiciones extravagantes para que las fotos puedan hacer boomerang en la pantalla y los t\u00edtulos desaparezcan con un clic.<\/p>\n<p>Desde que sus primos le presentaron las fiestas de PowerPoint durante una pijamada hace ocho meses, las presentaciones de Mirabella s\u00f3lo han mejorado en calidad y teatralidad. Su reciente presentaci\u00f3n de diapositivas con el tema de los Juegos del Hambre incluy\u00f3 elementos multimedia como Taylor Swift entrando a la arena ficticia para una breve presentaci\u00f3n en el medio tiempo para detener el derramamiento de sangre. Sus amigos la votaron como la mejor presentaci\u00f3n de la noche.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Para el festejo de 21 a\u00f1os de McCall Mirabella el mes pasado, ella pidi\u00f3 a los invitados que trajeran solo un regalo: una presentaci\u00f3n de PowerPoint. Mirabella, una personalidad de TikTok y YouTube con m\u00e1s de 1,3 millones de seguidores en ambas plataformas, reuni\u00f3 a sus amigos m\u00e1s cercanos y les pidi\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447355","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Para el festejo de 21 a\u00f1os de McCall Mirabella el mes pasado, ella pidi\u00f3 a los invitados que trajeran solo un regalo: una presentaci\u00f3n de PowerPoint. Mirabella, una personalidad de TikTok y YouTube con m\u00e1s de 1,3 millones de seguidores en ambas plataformas, reuni\u00f3 a sus amigos m\u00e1s cercanos y les pidi\u00f3 que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T03:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint\",\"datePublished\":\"2024-03-26T03:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/\"},\"wordCount\":1140,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/\",\"name\":\"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-26T03:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint - Noticias","og_description":"(CNN) &#8212; Para el festejo de 21 a\u00f1os de McCall Mirabella el mes pasado, ella pidi\u00f3 a los invitados que trajeran solo un regalo: una presentaci\u00f3n de PowerPoint. Mirabella, una personalidad de TikTok y YouTube con m\u00e1s de 1,3 millones de seguidores en ambas plataformas, reuni\u00f3 a sus amigos m\u00e1s cercanos y les pidi\u00f3 que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-26T03:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/"},"author":{"name":"","@id":""},"headline":"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint","datePublished":"2024-03-26T03:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/"},"wordCount":1140,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/","name":"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-26T03:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Por qu\u00e9 los j\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/03\/25\/jovenes-organizan-fiestas-powerpoint-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-26T03:03:50Z","datePublished":"2024-03-26T03:03:50Z","dateModified":"2024-03-26T03:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Por qu\\u00e9 los j\\u00f3venes de EE.UU. ahora organizan fiestas de PowerPoint\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/03\\\/25\\\/jovenes-organizan-fiestas-powerpoint-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/03\\\/25\\\/jovenes-organizan-fiestas-powerpoint-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-26T03:03:50Z\",\"datePublished\":\"2024-03-26T03:03:50Z\",\"dateModified\":\"2024-03-26T03:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461784,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/04\/30\/mujer-asesinato-australia-hongos-venenosos-accidente-trax\/","url_meta":{"origin":1447355,"position":0},"title":"Defensa de mujer australiana acusada de matar a tres personas con hongos venenosos dice que fue un &#171;terrible accidente&#187;","author":"","date":"abril 30, 2025","format":false,"excerpt":"Los abogados de una mujer australiana acusada de envenenar fatalmente a tres miembros de su familia con hongos mortales dijeron al jurado que sus muertes fueron un \u201cterrible accidente\u201d.Erin Patterson est\u00e1 siendo juzgada por las muertes en 2023 de su suegra, Gail Patterson; su suegro, Donald Patterson, y la hermana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469123,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/09\/padres-fuera-australia-prohibicion-redes-sociales-trax\/","url_meta":{"origin":1447355,"position":1},"title":"\u00bfDeber\u00edan los padres fuera de Australia adoptar una prohibici\u00f3n de redes sociales? Nuestros hijos podr\u00edan estar agradecidos","author":"","date":"diciembre 9, 2025","format":false,"excerpt":"El mi\u00e9rcoles 10 de diciembre, los ni\u00f1os australianos se despertaron en un mundo que antes era inconcebible: ya no tienen redes sociales. El pa\u00eds fue el primero en prohibir las aplicaciones sociales para menores de 16 a\u00f1os. La prohibici\u00f3n afecta a 10 plataformas, entre ellas TikTok, Instagram, YouTube, Snapchat, Facebook,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465995,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/30\/china-encuentro-putin-modi-xi-trump-trax\/","url_meta":{"origin":1447355,"position":2},"title":"China despliega la alfombra roja para Putin y Modi mientras Trump altera las relaciones globales","author":"","date":"agosto 30, 2025","format":false,"excerpt":"Aut\u00f3cratas, populistas, amigos y enemigos, un hombre fuerte que libra una guerra en Europa y el primer ministro de la mayor democracia del mundo ser\u00e1n recibidos por el presidente de China, Xi Jinping, este fin de semana en una cumbre dise\u00f1ada para mostrar al pa\u00eds como un l\u00edder global capaz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464280,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/07\/hongos-mujer-australiana-culpable-invitados-trax\/","url_meta":{"origin":1447355,"position":3},"title":"Jurado declara culpable de homicidio a mujer australiana que sirvi\u00f3 hongos t\u00f3xicos a sus invitados a almorzar","author":"","date":"julio 7, 2025","format":false,"excerpt":"Erin Patterson, la mujer australiana acusada de matar a tres familiares con una comida de hongos horneados en un almuerzo de Beef Wellington, fue declarada culpable de tres cargos de homicidio e intento de homicidio del \u00fanico sobreviviente.Un jurado de 12 miembros lleg\u00f3 al veredicto tras seis d\u00edas de deliberaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463811,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/06\/21\/hongos-venenosos-comida-muerte-juicio-trax\/","url_meta":{"origin":1447355,"position":4},"title":"Tres comensales murieron por ingerir hongos venenosos. \u00bfFue un asesinato o un &#171;terrible accidente&#187;?","author":"","date":"junio 21, 2025","format":false,"excerpt":"Una comida meticulosamente planificada y preparada en la casa de una presunta asesina es el centro de un juicio por triple homicidio que se acerca a su dram\u00e1tico final en Australia.Durante ocho semanas, el p\u00fablico ha estado pendiente de las noticias diarias y los podcasts sobre un inusual caso en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459041,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/02\/21\/ramiro-arzuaga-revelo-detalles-del-cumpleanos-de-mirtha-legrand-este-ano-quiero-sorprender\/","url_meta":{"origin":1447355,"position":5},"title":"Ramiro Arzuaga revel\u00f3 detalles del cumplea\u00f1os de Mirtha Legrand: &#171;Este a\u00f1o quiero sorprender&#187;","author":"","date":"febrero 21, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2014 Ramiro Arzuaga, el organizador y ambientador del cumplea\u00f1os de Mirtha Legrand, cont\u00f3 en Los Primeros de la Tarde con P\u00eda Shaw c\u00f3mo ser\u00e1 la celebraci\u00f3n de los 98 a\u00f1os de la diva. \u201cEs el octavo o noveno a\u00f1o consecutivo que organiz\u00f3 su cumplea\u00f1os\u201d, se\u00f1al\u00f3. Inicialmente, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1447355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1447355"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1447355\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1447355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1447355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1447355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}