{"id":1448706,"date":"2024-04-30T13:03:49","date_gmt":"2024-04-30T20:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/"},"modified":"2024-04-30T13:03:49","modified_gmt":"2024-04-30T20:03:49","slug":"hombre-oregon-lucha-cancer-ganador-powerball-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/","title":{"rendered":"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones"},"content":{"rendered":"<p>(CNN) &#8212; Un hombre de Oregon que afirma llevar ocho a\u00f1os luchando contra el c\u00e1ncer y haber recibido quimioterapia la semana pasada es uno de los tres ganadores del premio mayor de la loter\u00eda Powerball de US$ 1.300 millones de este mes.<\/p>\n<p>Cheng &#171;Charlie&#187; Saephan dijo que compartir\u00e1 el premio con su esposa, Duanpen Saephan, y su amiga Laiza Chao. El tr\u00edo eligi\u00f3 la opci\u00f3n en efectivo, de m\u00e1s de US$ 422 millones despu\u00e9s de impuestos. Chao recibir\u00e1 el 50% de las ganancias y los Saephan se llevar\u00e1n el 25% cada uno.<\/p>\n<p>El Powerball tiene ganador: un boleto de Oregon se queda con el bote de casi US$ 1.330 millones<\/p>\n<p>&#171;Estoy feliz por mi familia. Tendr\u00e1n una buena vida&#187;, dijo Cheng Saephan, de 46 a\u00f1os, el lunes en una rueda de prensa de la Loter\u00eda de Oregon. &#171;Pero para m\u00ed, estoy en plena lucha contra el c\u00e1ncer, as\u00ed que pienso: &#8216;\u00bfC\u00f3mo voy a tener tiempo para gastar todo este dinero?&#187;.<\/p>\n<p>Saephan dijo que planea llevar una vida &#171;normal&#187; en el futuro y comprar a su familia una &#171;casa de ensue\u00f1o&#187;.<\/p>\n<p>Este es el cuarto premio m\u00e1s grande de la historia, seg\u00fan Powerball. El hist\u00f3rico sorteo del 6 de abril se retras\u00f3 m\u00e1s de tres horas para dar el tiempo adicional necesario para completar los procedimientos previos al sorteo. Este premio fue tambi\u00e9n el mayor de Powerball ganado en Oregon.<\/p>\n<p>El boleto ganador se vendi\u00f3 en una tienda Plaid Pantry de Portland, seg\u00fan la Loter\u00eda de Oregon. La tienda recibe un bono de US$ 100.000 por haber vendido el boleto ganador.<\/p>\n<p>Saephan, nacido en Laos y residente en Portland desde hace 30 a\u00f1os, dijo que los n\u00fameros ganadores fueron generados por computadora utilizando la opci\u00f3n Quick Pick.<\/p>\n<p>&#171;Dios eligi\u00f3 por m\u00ed&#187;, dijo.<\/p>\n<p>Cuando Saephan descubri\u00f3 que hab\u00eda ganado, llam\u00f3 a su amigo Chao, de Milwaukie, Oregon, que le hab\u00eda dado US$ 100 para comprar los billetes de loter\u00eda.<\/p>\n<p>&#171;Ella iba conduciendo de camino al trabajo&#187;, dijo Saephan. &#171;Y le dije: &#8216;Ahora no tienes que ir a trabajar. Nos ganamos la loter\u00eda. Nos toc\u00f3 el premio mayor'&#187;.<\/p>\n<p>&#8212; Amanda Musa de CNN contirbuy\u00f3 con este reportaje.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un hombre de Oregon que afirma llevar ocho a\u00f1os luchando contra el c\u00e1ncer y haber recibido quimioterapia la semana pasada es uno de los tres ganadores del premio mayor de la loter\u00eda Powerball de US$ 1.300 millones de este mes. Cheng &#171;Charlie&#187; Saephan dijo que compartir\u00e1 el premio con su esposa, Duanpen Saephan, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448706","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un hombre de Oregon que afirma llevar ocho a\u00f1os luchando contra el c\u00e1ncer y haber recibido quimioterapia la semana pasada es uno de los tres ganadores del premio mayor de la loter\u00eda Powerball de US$ 1.300 millones de este mes. Cheng &#171;Charlie&#187; Saephan dijo que compartir\u00e1 el premio con su esposa, Duanpen Saephan, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T20:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones\",\"datePublished\":\"2024-04-30T20:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/\"},\"wordCount\":407,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/\",\"name\":\"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-30T20:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones - Noticias","og_description":"(CNN) &#8212; Un hombre de Oregon que afirma llevar ocho a\u00f1os luchando contra el c\u00e1ncer y haber recibido quimioterapia la semana pasada es uno de los tres ganadores del premio mayor de la loter\u00eda Powerball de US$ 1.300 millones de este mes. Cheng &#171;Charlie&#187; Saephan dijo que compartir\u00e1 el premio con su esposa, Duanpen Saephan, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-30T20:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/"},"author":{"name":"","@id":""},"headline":"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones","datePublished":"2024-04-30T20:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/"},"wordCount":407,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/","name":"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-30T20:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un hombre de Oregon que lucha contra el c\u00e1ncer gan\u00f3 el premio mayor de Powerball de US$ 1.300 millones","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/04\/30\/hombre-oregon-lucha-cancer-ganador-powerball-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-30T20:03:49Z","datePublished":"2024-04-30T20:03:49Z","dateModified":"2024-04-30T20:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un hombre de Oregon que lucha contra el c\\u00e1ncer gan\\u00f3 el premio mayor de Powerball de US$ 1.300 millones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/04\\\/30\\\/hombre-oregon-lucha-cancer-ganador-powerball-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/04\\\/30\\\/hombre-oregon-lucha-cancer-ganador-powerball-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-30T20:03:49Z\",\"datePublished\":\"2024-04-30T20:03:49Z\",\"dateModified\":\"2024-04-30T20:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466069,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/02\/premio-mayor-powerball-vacante-trax\/","url_meta":{"origin":1448706,"position":0},"title":"El premio mayor de Powerball se dispara a US$ 1.300 millones despu\u00e9s de que ning\u00fan boleto acertara los seis n\u00fameros","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"El premio mayor del Powerball salt\u00f3 a una asombrosa cifra de US$ 1.300 millones despu\u00e9s de que no hubiera grandes ganadores en el sorteo de este lunes por la noche: el quinto premio m\u00e1s grande en la historia del juego.Los n\u00fameros de la suerte fueron las bolas blancas 8, 23,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447819,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/07\/powerball-estos-son-los-numeros-ganadores-del-sorteo-del-sabado-trax\/","url_meta":{"origin":1448706,"position":1},"title":"Powerball: estos son los n\u00fameros ganadores del sorteo del s\u00e1bado, que tiene un bote estimado en US$ 1.300 millones","author":"","date":"abril 7, 2024","format":false,"excerpt":"(CNN) -- Ya se han extra\u00eddo los n\u00fameros ganadores del sorteo de Powerball, que tiene un bote estimado en US$ 1.300 millones, el cuarto m\u00e1s grande de la historia de la loter\u00eda.Los n\u00fameros ganadores del s\u00e1bado son 44, 27, 52, 22, 69 y Powerball 9.El sorteo hab\u00eda sido retrasado durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464701,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/20\/hombre-massachusetts-millonario-error-loteria-trax\/","url_meta":{"origin":1448706,"position":2},"title":"Este hombre de Massachusetts se convirti\u00f3 en millonario dos veces en una sola noche gracias a un afortunado error de loter\u00eda","author":"","date":"julio 20, 2025","format":false,"excerpt":"Un afortunado hombre de Massachusetts compr\u00f3 dos boletos ganadores de loter\u00eda en dos tiendas distintas, lo que le vali\u00f3 un premio de US$ 2 millones.Paul Corcoran, de Fitchburg \u2014una peque\u00f1a ciudad en el centro-norte de Massachusetts\u2014, ten\u00eda previsto participar en el sorteo de Powerball del 9 de julio. Inicialmente hab\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466803,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/09\/25\/afortunado-missouri-premio-mayor-powerball-trax\/","url_meta":{"origin":1448706,"position":3},"title":"Un afortunado en Missouri se lleva la mitad del enorme premio mayor de Powerball de US$ 1.780 millones","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"El afortunado de Missouri que gan\u00f3 la mitad del premio mayor de Powerball de casi US$ 1.800 millones se present\u00f3 para reclamar su enorme premio, seg\u00fan la Loter\u00eda de Missouri.La persona, a quien la loter\u00eda no identific\u00f3, ten\u00eda uno de los dos billetes vendidos que coincidieron con todos los n\u00fameros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442593,"url":"https:\/\/noticiasya.com\/midland-odessa\/2023\/12\/24\/el-premio-mayor-del-powerball-llega-a-los-us-638-millones-para-el-sorteo-de-navidad\/","url_meta":{"origin":1448706,"position":4},"title":"El premio mayor del Powerball llega a los US$ 638 millones para el sorteo de Navidad","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"(CNN) -- El premio mayor del Powerball llega a los US$ 638 millones justo a tiempo para su pr\u00f3ximo sorteo la noche de Navidad.En el pasado, ha habido tres premios mayores de Powerball el d\u00eda de Navidad, seg\u00fan un comunicado de prensa de Powerball. La \u00faltima vez fue hace 10\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469206,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/12\/premios-gordos-loteria-ee-uu-millones-trax\/","url_meta":{"origin":1448706,"position":5},"title":"Los premios gordos de la loter\u00eda en EE.UU. nunca alcanzaban los US$ 1.000 millones. Ya van 12 veces en los \u00faltimos cinco a\u00f1os","author":"","date":"diciembre 12, 2025","format":false,"excerpt":"El sorteo de Powerball de este mi\u00e9rcoles por la noche no tuvo ganador, lo que elev\u00f3 el premio mayor a aproximadamente US$ 1.000 millones para el s\u00e1bado.Este monto es el segundo m\u00e1s grande del a\u00f1o, solo superado por el premio mayor de Powerball de US$ 1.787 millones de septiembre, ganado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1448706"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448706\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1448706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1448706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1448706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}