{"id":1448810,"date":"2024-05-03T04:03:42","date_gmt":"2024-05-03T11:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/"},"modified":"2024-05-03T04:03:42","modified_gmt":"2024-05-03T11:03:42","slug":"daca-servicios-salud-eeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/","title":{"rendered":"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU."},"content":{"rendered":"<p>(CNN) &#8212; Cientos de miles de beneficiarios del programa de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA) de la era Obama ser\u00e1n elegibles para la cobertura de atenci\u00f3n m\u00e9dica asequible este a\u00f1o tras la finalizaci\u00f3n de un regulaci\u00f3n, anunci\u00f3 este viernes la administraci\u00f3n de Biden.<\/p>\n<p>El nuevo reglamento federal ampliar\u00e1 el acceso al seguro m\u00e9dico a los beneficiarios del programa DACA \u2014que permite a los inmigrantes indocumentados tra\u00eddos a Estados Unidos de ni\u00f1os vivir y trabajar legalmente en el pa\u00eds\u2014 modificando la definici\u00f3n de &#171;presente legalmente&#187; para inscribirse en determinados programas de asistencia sanitaria.<\/p>\n<p>&#171;Los &#8216;dreamers&#8217; reciben ahora el mismo trato que otros inmigrantes&#187;, dijo a la prensa Xavier Becerra, secretario del Departamento de Salud y Servicios Humanos, antes del anuncio.<\/p>\n<p>&#171;Estamos comprometidos a hacer que la cobertura de salud sea accesible para todos los estadounidenses, incluidos los beneficiarios de DACA, &#171;dreamers&#187;, que han trabajado duro para vivir el sue\u00f1o americano. Hoy, damos un paso importante hacia el cumplimiento de ese objetivo&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Qu\u00e9 es y c\u00f3mo funciona DACA, el programa que protege a los \u201cdreamers\u201d de la deportaci\u00f3n<\/p>\n<p>Es el \u00faltimo esfuerzo de Biden para fortalecer el programa DACA, mientras el impulso de una reforma migratoria integral se ha estancado en el Congreso. La norma entrar\u00e1 en vigor el 1 de noviembre.<\/p>\n<p>El anuncio tambi\u00e9n se produce mientras la campa\u00f1a de Biden intenta hacer incursiones con los votantes latinos en un tema clave: la inmigraci\u00f3n. Biden busca atraer a los latinos como su predecesor ha tratado de ganar terreno en una comunidad que durante mucho tiempo ha sido importante para la coalici\u00f3n dem\u00f3crata. En elecciones anteriores, los beneficiarios del DACA han ayudado a movilizar a los votantes dem\u00f3cratas, sondeando a las comunidades latinas de todo el pa\u00eds.<\/p>\n<p>Hay m\u00e1s de 530.000 beneficiarios activos del programa DACA al 31 de diciembre de 2023, seg\u00fan datos federales. De ellos, unos 429.000 son mexicanos. Los beneficiarios de DACA a menudo provienen de hogares de estatus mixto, incluidos ciudadanos estadounidenses, residentes permanentes legales o familiares indocumentados.<\/p>\n<p>&#171;So\u00f1adora&#187; pas\u00f3 de Wall Street a buscar becas para j\u00f3venes<\/p>\n<p>El HHS estima que 100.000 beneficiarios de DACA que actualmente no tienen seguro probablemente aprovechar\u00e1n la nueva norma y se inscribir\u00e1n en la cobertura de salud a trav\u00e9s del Mercado de Seguros de Salud de la Ley de Asistencia Asequible o a trav\u00e9s de un Programa B\u00e1sico de Salud, seg\u00fan una hoja informativa del departamento.<\/p>\n<p>Este n\u00famero no es el n\u00famero total de beneficiarios elegibles, sino una estimaci\u00f3n del departamento de cu\u00e1ntas personas creen que se aprovechar\u00e1n del cambio, explicaron altos funcionarios de la administraci\u00f3n. Muchos beneficiarios de DACA ya tienen derecho a la asistencia sanitaria a trav\u00e9s de sus empleadores.<\/p>\n<p>La cuesti\u00f3n del acceso a la ciudadan\u00eda para los beneficiarios de DACA<\/p>\n<p>La inmigraci\u00f3n ha sido un frecuente punto de conflicto pol\u00edtico entre la Casa Blanca y los republicanos, que han criticado la gesti\u00f3n de la administraci\u00f3n de la seguridad fronteriza y desafiado repetidamente en los tribunales las medidas de la administraci\u00f3n para fortalecer DACA y ampliar otros programas que conceden a los inmigrantes un estatus legal temporal.<\/p>\n<p>El a\u00f1o pasado, algunos legisladores republicanos instaron a la administraci\u00f3n Biden a no ampliar los programas de los contribuyentes a los beneficiarios de DACA.<\/p>\n<p>La norma, propuesta inicialmente el a\u00f1o pasado, hace poco para cambiar el estancamiento en el Congreso, donde la \u00faltima ronda de conversaciones sobre la reforma migratoria no abord\u00f3 a los &#171;dreamers&#187;. El Congreso ha intentado y fracasado durante a\u00f1os para aprobar una legislaci\u00f3n que proporcione una v\u00eda a la ciudadan\u00eda para los &#171;dreamers&#187;, o de otra manera abordar los problemas con el sistema de inmigraci\u00f3n m\u00e1s amplio.<\/p>\n<p>&#171;El presidente continuar\u00e1 luchando por los &#8216;dreamers&#8217;, pero solo el Congreso puede proporcionarles un estatus permanente y un camino hacia la ciudadan\u00eda. El Congreso debe actuar para garantizar que los &#8216;dreamers&#8217; puedan permanecer aqu\u00ed de forma permanente&#187;, dijo a la prensa la directora del Consejo de Pol\u00edtica Interior de la Casa Blanca, Neera Tanden.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Cientos de miles de beneficiarios del programa de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA) de la era Obama ser\u00e1n elegibles para la cobertura de atenci\u00f3n m\u00e9dica asequible este a\u00f1o tras la finalizaci\u00f3n de un regulaci\u00f3n, anunci\u00f3 este viernes la administraci\u00f3n de Biden. El nuevo reglamento federal ampliar\u00e1 el acceso al [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448810","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Cientos de miles de beneficiarios del programa de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA) de la era Obama ser\u00e1n elegibles para la cobertura de atenci\u00f3n m\u00e9dica asequible este a\u00f1o tras la finalizaci\u00f3n de un regulaci\u00f3n, anunci\u00f3 este viernes la administraci\u00f3n de Biden. El nuevo reglamento federal ampliar\u00e1 el acceso al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T11:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU.\",\"datePublished\":\"2024-05-03T11:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/\"},\"wordCount\":745,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/\",\"name\":\"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-03T11:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU. - Noticias","og_description":"(CNN) &#8212; Cientos de miles de beneficiarios del programa de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA) de la era Obama ser\u00e1n elegibles para la cobertura de atenci\u00f3n m\u00e9dica asequible este a\u00f1o tras la finalizaci\u00f3n de un regulaci\u00f3n, anunci\u00f3 este viernes la administraci\u00f3n de Biden. El nuevo reglamento federal ampliar\u00e1 el acceso al [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-03T11:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/"},"author":{"name":"","@id":""},"headline":"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU.","datePublished":"2024-05-03T11:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/"},"wordCount":745,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/","name":"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-03T11:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cientos de miles de beneficiarios de DACA podr\u00e1n acceder a servicios de salud en EE.UU.","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/03\/daca-servicios-salud-eeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-03T11:03:42Z","datePublished":"2024-05-03T11:03:42Z","dateModified":"2024-05-03T11:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cientos de miles de beneficiarios de DACA podr\\u00e1n acceder a servicios de salud en EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/03\\\/daca-servicios-salud-eeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/03\\\/daca-servicios-salud-eeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-03T11:03:42Z\",\"datePublished\":\"2024-05-03T11:03:42Z\",\"dateModified\":\"2024-05-03T11:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464148,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/07\/02\/beneficiarios-daca-testimonios-incertidumbre-trump-orix\/","url_meta":{"origin":1448810,"position":0},"title":"DACA les permiti\u00f3 quedarse, pero no les dio ciudadan\u00eda: ahora los \u2018dreamers\u2019 temen que Trump vaya por ellos","author":"","date":"julio 2, 2025","format":false,"excerpt":"Para Jos\u00e9 L\u00f3pez, la vida cambi\u00f3 en 2012. Pero su lucha empez\u00f3 mucho antes. \u201cYo nunca supe que era indocumentado hasta que estaba en preparatoria y quise comenzar a tramitar mi licencia de manejo. Me pidieron mi Seguro Social\u201d, recuerda Jos\u00e9, en entrevista con CNN. Su historia refleja la de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471679,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/02\/26\/ice-arresto-261-beneficiarios-daca-trax\/","url_meta":{"origin":1448810,"position":1},"title":"ICE arrest\u00f3 a 261 beneficiarios de DACA en 10 meses, informa Noem","author":"","date":"febrero 26, 2026","format":false,"excerpt":"El Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) arrest\u00f3 a 261 beneficiarios del programa de Acci\u00f3n Diferida para los Llegados en la Infancia (DACA) entre enero y noviembre del a\u00f1o pasado, inform\u00f3 la secretaria de Seguridad Nacional de Estados Unidos, Kristi Noem, en una carta al Congreso publicada el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450449,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/17\/biden-medida-deportacion-indocumentados-ciudadanos-estadounidenses-trax\/","url_meta":{"origin":1448810,"position":2},"title":"Biden anunciar\u00e1 una medida radical que proteger\u00e1 de la deportaci\u00f3n a los c\u00f3nyuges indocumentados de ciudadanos estadounidenses","author":"","date":"junio 17, 2024","format":false,"excerpt":"(CNN) -- El presidente de Estados Unidos, Joe Biden, se prepara para anunciar este martes una amplia acci\u00f3n ejecutiva que proteger\u00eda a ciertos c\u00f3nyuges indocumentados de ciudadanos estadounidenses de la deportaci\u00f3n y les permitir\u00eda trabajar legalmente en el pa\u00eds mientras buscan la ciudadan\u00eda, seg\u00fan personas familiarizadas con los planes.La pol\u00edtica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457777,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/22\/aportes-economicos-inmigrantes-indocumentados-orix\/","url_meta":{"origin":1448810,"position":3},"title":"\u00bfCu\u00e1nto aportan los inmigrantes indocumentados a la econom\u00eda de Estados Unidos?","author":"","date":"enero 22, 2025","format":false,"excerpt":"Los planes de deportaciones masivas de inmigrantes indocumentados que analiza el entrante gobierno de Donald Trump podr\u00edan tener fuertes impactos en la econom\u00eda estadounidense, teniendo en cuenta el aporte diversificado de esta poblaci\u00f3n en las comunidades, en las arcas del pa\u00eds y en puestos fundamentales del mercado laboral.El Pew Reasearch\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456321,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/06\/parole-in-place-trump-orix\/","url_meta":{"origin":1448810,"position":4},"title":"\u00bfQu\u00e9 puede pasar con el &#171;parole in place&#187; con Trump?","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"Los planes de Donald Trump para una deportaci\u00f3n masiva incluyen, seg\u00fan dijeron a CNN fuentes familiarizadas con las discusiones, la revocaci\u00f3n de uno de los mayores programas migratorios implementado durante el Gobierno del presidente Joe Biden que ampliaba el acceso a la autoridad legal existente conocida como \u201cparole in place\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465708,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/20\/tribunal-permite-poner-fin-tps-honduras-nicaragua-nepal-trax\/","url_meta":{"origin":1448810,"position":5},"title":"Tribunal de apelaciones avala que el Gobierno de Trump ponga fin temporal al TPS para personas de Honduras, Nicaragua y Nepal","author":"","date":"agosto 20, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones permiti\u00f3 que el Gobierno de Trump ponga fin temporal al Estatus de Protecci\u00f3n Temporal (TPS) para miles de inmigrantes indocumentados de Honduras, Nicaragua y Nepal.En una breve orden, un panel un\u00e1nime de tres jueces del 9\u00ba Circuito de Apelaciones de EE.UU. acord\u00f3 suspender el fallo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1448810"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448810\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1448810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1448810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1448810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}