{"id":1448885,"date":"2024-05-04T23:04:00","date_gmt":"2024-05-05T06:04:00","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/"},"modified":"2024-05-04T23:04:00","modified_gmt":"2024-05-05T06:04:00","slug":"canelo-alvarez-derrota-mungia-decision-unanime-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/","title":{"rendered":"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano"},"content":{"rendered":"<p>(CNN En Espa\u00f1ol) &#8212; El oriundo de Jalisco, M\u00e9xico, Sa\u00fal &#171;Canelo&#187; \u00c1lvarez, campe\u00f3n mundial de peso s\u00faper mediano, logr\u00f3 retener sus cuatro cetros tras derrotar a su compatriota Jaime Mungu\u00eda este s\u00e1bado en el T-Mobile Arena de Las Vegas, por decisi\u00f3n un\u00e1nime.<\/p>\n<p>Durante los doce rounds de la pelea, los dos pugilistas mexicanos lograron poner al filo de sus asientos a los miles de fan\u00e1ticos que presenciaron la pelea en la Arena. Una emoci\u00f3n que aument\u00f3 cuando el &#171;Canelo&#187; logr\u00f3 mandar a la lona a Mungu\u00eda en el cuarto asalto.<\/p>\n<p>Ante esta derrota, Mungu\u00eda, oriundo de Tijuana, M\u00e9xico, pierde su invicto. Quien lleg\u00f3 a este encuentro con un r\u00e9cord de 43-0-0 (34KO&#8217;s).<\/p>\n<p>Mientras que el pujilista Tapat\u00edo, con esta victoria, ahora suma un r\u00e9cord de: 61-2-2(39 KO&#8217;s).<\/p>\n<p>El pugilista Sa\u00fal &#171;Canelo&#187; \u00c1lvarez es uno de los mejores en el mundo del boxeo. El mexicano es el actual campe\u00f3n mundial de la Asociaci\u00f3n Mundial de Boxeo (AMB), Consejo Mundial de Boxeo (CMB), Organizaci\u00f3n Mundial de Boxeo (OMB), Federaci\u00f3n Internacional de Boxeo (FIB) y The Ring de peso supermediano, seg\u00fan detalla en su blog. Como boxeador profesional, \u00c1lvarez se ha enfrentado a rivales como Jos\u00e9 Miguel Cotto, Matthew &#171;Magic&#187; Hatton, Jos\u00e9 Manuel &#171;Josesito&#187; L\u00f3pez, Julio C\u00e9sar Ch\u00e1vez Jr., Gennady &#171;GGG&#187; Golovkin, entre otros.<\/p>\n<p>Con la informaci\u00f3n de Gonzalo Alvarado<\/p>\n<p>Noticia en desarrollo<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN En Espa\u00f1ol) &#8212; El oriundo de Jalisco, M\u00e9xico, Sa\u00fal &#171;Canelo&#187; \u00c1lvarez, campe\u00f3n mundial de peso s\u00faper mediano, logr\u00f3 retener sus cuatro cetros tras derrotar a su compatriota Jaime Mungu\u00eda este s\u00e1bado en el T-Mobile Arena de Las Vegas, por decisi\u00f3n un\u00e1nime. Durante los doce rounds de la pelea, los dos pugilistas mexicanos lograron poner [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448885","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN En Espa\u00f1ol) &#8212; El oriundo de Jalisco, M\u00e9xico, Sa\u00fal &#171;Canelo&#187; \u00c1lvarez, campe\u00f3n mundial de peso s\u00faper mediano, logr\u00f3 retener sus cuatro cetros tras derrotar a su compatriota Jaime Mungu\u00eda este s\u00e1bado en el T-Mobile Arena de Las Vegas, por decisi\u00f3n un\u00e1nime. Durante los doce rounds de la pelea, los dos pugilistas mexicanos lograron poner [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T06:04:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano\",\"datePublished\":\"2024-05-05T06:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/\",\"name\":\"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-05T06:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano - Noticias","og_description":"(CNN En Espa\u00f1ol) &#8212; El oriundo de Jalisco, M\u00e9xico, Sa\u00fal &#171;Canelo&#187; \u00c1lvarez, campe\u00f3n mundial de peso s\u00faper mediano, logr\u00f3 retener sus cuatro cetros tras derrotar a su compatriota Jaime Mungu\u00eda este s\u00e1bado en el T-Mobile Arena de Las Vegas, por decisi\u00f3n un\u00e1nime. Durante los doce rounds de la pelea, los dos pugilistas mexicanos lograron poner [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-05T06:04:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/"},"author":{"name":"","@id":""},"headline":"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano","datePublished":"2024-05-05T06:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/","name":"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-05T06:04:00+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Canelo \u00c1lvarez derrota a Mungu\u00eda por decisi\u00f3n un\u00e1nime y mantiene su t\u00edtulo de peso s\u00faper mediano","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/04\/canelo-alvarez-derrota-mungia-decision-unanime-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-05T06:04:00Z","datePublished":"2024-05-05T06:04:00Z","dateModified":"2024-05-05T06:04:00Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Canelo \\u00c1lvarez derrota a Mungu\\u00eda por decisi\\u00f3n un\\u00e1nime y mantiene su t\\u00edtulo de peso s\\u00faper mediano\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/04\\\/canelo-alvarez-derrota-mungia-decision-unanime-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/04\\\/canelo-alvarez-derrota-mungia-decision-unanime-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-05T06:04:00Z\",\"datePublished\":\"2024-05-05T06:04:00Z\",\"dateModified\":\"2024-05-05T06:04:00Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448775,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/02\/canelo-alvarez-vs-jaime-munguia-cartelera-horarios-como-ver-combate-en-vivo-trax\/","url_meta":{"origin":1448885,"position":0},"title":"Canelo \u00c1lvarez vs Jaime Mungu\u00eda: cartelera, horarios y c\u00f3mo ver el combate en vivo","author":"","date":"mayo 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00bfListo para las celebraciones del 5 de mayo? Si a\u00fan no lo est\u00e1s, prep\u00e1rate porque los mexicanos Sa\u00fal \"Canelo\" \u00c1lvarez y Jaime Mungu\u00eda s\u00ed.Este fin de semana festivo para los mexicanos \u2014sobre todo para los que viven en Estados Unidos\u2014\u00a0traer\u00e1 consigo la esperada pelea entre Canelo y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448771,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/02\/jaime-mungia-vida-record-carrera-orix\/","url_meta":{"origin":1448885,"position":1},"title":"\u00bfQui\u00e9n es\u00a0Jaime\u00a0Mungu\u00eda? As\u00ed es la vida, r\u00e9cord y carrera del boxeador mexicano","author":"","date":"mayo 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0\u201cEl respeto es mutuo y todos lo saben\u201d, dijo el boxeador\u00a0Jaime\u00a0Mungu\u00eda cuando estuvo frente a su compatriota Sa\u00fal \u201cCanelo\u201d \u00c1lvarez, uno de los pugilistas a los que creci\u00f3 admirando, durante un evento de prensa en marzo.Mungu\u00eda, oriundo de Tijuana, se enfrentar\u00e1 a \u00c1lvarez este s\u00e1bado en un combate\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461925,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/03\/pelea-canelo-alvarez-william-scull-cartelera-previa-horarios-como-ver-en-vivo-orix\/","url_meta":{"origin":1448885,"position":2},"title":"Pelea entre Canelo \u00c1lvarez y William Scull: cartelera, previa, horarios y c\u00f3mo ver en vivo","author":"","date":"mayo 3, 2025","format":false,"excerpt":"El multicampe\u00f3n mexicano Sa\u00fal \u201cCanelo\u201d \u00c1lvarez tendr\u00e1 el s\u00e1bado su primera pelea de 2025, en la que enfrentar\u00e1 a otro campe\u00f3n, el cubano William Scull, durante la funci\u00f3n estelar de box en la ANB Arena de Arabia Saudita.Se trata de la primera vez en la que ambos pugilistas se enfrentan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452684,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/09\/14\/canelo-alvarez-dice-que-esta-100-listo-para-enfrentar-al-invicto-edgar-berlanga-quien-quiere-sorprender-al-mundo\/","url_meta":{"origin":1448885,"position":3},"title":"&#171;Canelo&#187; \u00c1lvarez dice que est\u00e1 &#171;100% listo&#187; para enfrentar al invicto Edgar Berlanga, quien quiere &#171;sorprender al mundo&#187;","author":"","date":"septiembre 14, 2024","format":false,"excerpt":"(CNN) -- La superestrella mexicana Sa\u00fal \"Canelo\" \u00c1lvarez pondr\u00e1 en juego sus campeonatos de peso supermediano del Consejo Mundial de Boxeo (WBC, por sus siglas en ingl\u00e9s), la Asociaci\u00f3n Mundial de Boxeo (WBA, por sus siglas en ingl\u00e9s) y la Organizaci\u00f3n Mundial de Boxeo (WBO, por sus siglas en ingl\u00e9s)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452675,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/09\/14\/canelo-alvarez-vs-edgar-berlanga-cartelera-previa-hora-como-ver-en-vivo-orix\/","url_meta":{"origin":1448885,"position":4},"title":"Canelo \u00c1lvarez vs. Edgar Berlanga: cartelera, previa, a qu\u00e9 hora y c\u00f3mo ver en vivo el combate","author":"","date":"septiembre 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Sa\u00fal \u201cCanelo\u201d \u00c1lvarez regresar\u00e1 al ring durante el fin de semana de la Independencia de M\u00e9xico para defender al menos uno de los cinturones de campeonato de peso supermediano.Ahora puedes seguirnos en\u00a0WhatsApp ChannelSe medir\u00e1 el s\u00e1bado 14 de septiembre ante Edgar Berlanga, boxeador estadounidense de 27 a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469360,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/12\/17\/retiro-crawford-canelo-alvarez-pelea-benavidez-bivol-orix\/","url_meta":{"origin":1448885,"position":5},"title":"\u00bfPuede el retiro de Crawford acercar al Canelo \u00c1lvarez a pelear contra Benavidez o Bivol?","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Terence Crawford sacudi\u00f3 al mundo del boxeo dos veces en el mismo a\u00f1o. En septiembre de 2025, en Las Vegas, venci\u00f3 por la v\u00eda un\u00e1nime en las tarjetas a Sa\u00fal \u201cCanelo\u201d \u00c1lvarez para convertirse en el primer campe\u00f3n indiscutido en tres divisiones en el boxeo.Pero a\u00fan m\u00e1s impactante, fue la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1448885"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448885\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1448885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1448885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1448885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}