{"id":1448911,"date":"2024-05-05T20:03:51","date_gmt":"2024-05-06T03:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/"},"modified":"2024-05-05T20:03:51","modified_gmt":"2024-05-06T03:03:51","slug":"jose-mulino-gana-elecciones-panama-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/","title":{"rendered":"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El magistrado del Tribunal Electoral de Panam\u00e1, Alfredo Junc\u00e1, llam\u00f3 la noche de este domingo a Jos\u00e9 Ra\u00fal Mulino para notificarle que extraoficialmente es el candidato presidencial ganador, adem\u00e1s le invit\u00f3 a reuni\u00f3n con el pleno del Tribunal Electoral.<\/p>\n<p>Noticia en desarrollo&#8230;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El magistrado del Tribunal Electoral de Panam\u00e1, Alfredo Junc\u00e1, llam\u00f3 la noche de este domingo a Jos\u00e9 Ra\u00fal Mulino para notificarle que extraoficialmente es el candidato presidencial ganador, adem\u00e1s le invit\u00f3 a reuni\u00f3n con el pleno del Tribunal Electoral. Noticia en desarrollo&#8230;. The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448911","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El magistrado del Tribunal Electoral de Panam\u00e1, Alfredo Junc\u00e1, llam\u00f3 la noche de este domingo a Jos\u00e9 Ra\u00fal Mulino para notificarle que extraoficialmente es el candidato presidencial ganador, adem\u00e1s le invit\u00f3 a reuni\u00f3n con el pleno del Tribunal Electoral. Noticia en desarrollo&#8230;. The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T03:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino\",\"datePublished\":\"2024-05-06T03:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/\"},\"wordCount\":79,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/\",\"name\":\"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-06T03:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El magistrado del Tribunal Electoral de Panam\u00e1, Alfredo Junc\u00e1, llam\u00f3 la noche de este domingo a Jos\u00e9 Ra\u00fal Mulino para notificarle que extraoficialmente es el candidato presidencial ganador, adem\u00e1s le invit\u00f3 a reuni\u00f3n con el pleno del Tribunal Electoral. Noticia en desarrollo&#8230;. The-CNN-Wire&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-06T03:03:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/"},"author":{"name":"","@id":""},"headline":"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino","datePublished":"2024-05-06T03:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/"},"wordCount":79,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/","name":"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-06T03:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tribunal Electoral de Panam\u00e1 declara candidato presidencial ganador extraoficial a Jos\u00e9 Ra\u00fal Mulino","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/05\/jose-mulino-gana-elecciones-panama-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-06T03:03:51Z","datePublished":"2024-05-06T03:03:51Z","dateModified":"2024-05-06T03:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tribunal Electoral de Panam\\u00e1 declara candidato presidencial ganador extraoficial a Jos\\u00e9 Ra\\u00fal Mulino\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/05\\\/jose-mulino-gana-elecciones-panama-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/05\\\/jose-mulino-gana-elecciones-panama-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-06T03:03:51Z\",\"datePublished\":\"2024-05-06T03:03:51Z\",\"dateModified\":\"2024-05-06T03:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448693,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/30\/candidatos-panama-elecciones-presidente-orix\/","url_meta":{"origin":1448911,"position":0},"title":"Entre tropiezos y ocho candidatos, Panam\u00e1 elegir\u00e1 al pr\u00f3ximo presidente el 5 de mayo","author":"","date":"abril 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Este domingo los votantes en Panam\u00e1 decidir\u00e1n qui\u00e9n ser\u00e1 el pr\u00f3ximo presidente del pa\u00eds, entre ocho candidatos. El ganador gobernar\u00e1 desde el 1 de julio hasta el 30 de junio de 2029.M\u00e1s de 3 millones de electores ir\u00e1n a las urnas a partir de las 7:00 a.m.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446522,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/05\/panama-inhabilita-candidatura-ricardo-martinelli-orix\/","url_meta":{"origin":1448911,"position":1},"title":"Tribunal Electoral de Panam\u00e1 inhabilita candidaturas del expresidente Ricardo Martinelli","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pleno del Tribunal Electoral de Panam\u00e1 anunci\u00f3 la noche de este lunes su decisi\u00f3n de inhabilitar al expresidente Ricardo Martinelli como candidato presidencial y como candidato a diputado de la Asamblea Nacional, luego de que recibiera la certificaci\u00f3n de sentencia ejecutoriada contra el exmandatario en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446072,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/28\/primer-debate-presidencial-panama-candidatos-orix\/","url_meta":{"origin":1448911,"position":2},"title":"El primer debate presidencial en Panam\u00e1 se realiz\u00f3 con el podio del expresidente Ricardo Martinelli vac\u00edo","author":"","date":"febrero 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El primer debate presidencial en Panam\u00e1 para las elecciones generales del pr\u00f3ximo 5 de mayo, se hizo con un sitio vac\u00edo: el del expresidente Ricardo Martinelli. El candidato por el partido Realizando Metas se encuentra en condici\u00f3n de asilado en la Embajada de Nicaragua desde el pasado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449377,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/10\/mulino-panama-repatriacion-migracion-irregular-darien-orix\/","url_meta":{"origin":1448911,"position":3},"title":"Presidente electo de Panam\u00e1 anuncia proceso de repatriaci\u00f3n para frenar la migraci\u00f3n irregular por el Dari\u00e9n","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN) -- El presidente electo de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, anunci\u00f3 este jueves durante su proclamaci\u00f3n por parte de la Junta Nacional de Escrutinio, que empezar\u00e1 un proceso de repatriaci\u00f3n para frenar la migraci\u00f3n irregular que entra por la selva del Dari\u00e9n con rumbo a Estados Unidos.\"Panam\u00e1 y nuestro Dari\u00e9n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457359,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/01\/08\/edmundo-gonzalez-panama-actas-orix\/","url_meta":{"origin":1448911,"position":4},"title":"Edmundo Gonz\u00e1lez entrega al Gobierno de Panam\u00e1 actas electorales que, afirma, prueban su victoria presidencial en Venezuela","author":"","date":"enero 8, 2025","format":false,"excerpt":"El l\u00edder opositor venezolano Edmundo Gonz\u00e1lez Urrutia entreg\u00f3 este mi\u00e9rcoles al presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, las copias de las actas de escrutinio de las elecciones presidenciales de Venezuela que, asegura, son prueba de que result\u00f3 ganador de la contienda celebrada el pasado 28 de julio.En un acto celebrado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450814,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/06\/30\/jose-raul-mulino-cnn-propuesta-darien-narco-martinelli-oppenheimer-presenta-orix\/","url_meta":{"origin":1448911,"position":5},"title":"Jos\u00e9 Ra\u00fal Mulino en CNN: su propuesta de cerrar la ruta del Dari\u00e9n, la lucha contra el narco y su v\u00ednculo con Ricardo Martinelli","author":"","date":"junio 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente electo de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, se prepara para asumir funciones al mando del ejecutivo. En ese marco, particip\u00f3 del programa Oppenheimer Presenta, donde explic\u00f3 sus planes para contener la migraci\u00f3n ilegal a trav\u00e9s de la selva del Dari\u00e9n y combatir el narcotr\u00e1fico.Tambi\u00e9n adelant\u00f3 c\u00f3mo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1448911"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448911\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1448911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1448911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1448911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}