{"id":1448979,"date":"2024-05-06T18:03:48","date_gmt":"2024-05-07T01:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/"},"modified":"2024-05-06T18:03:48","modified_gmt":"2024-05-07T01:03:48","slug":"amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/","title":{"rendered":"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0A cinco meses de que finalice el sexenio, expertos en seguridad concluyen que el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, incumpli\u00f3 su promesa de pacificar el pa\u00eds mediante su premisa de \u201cabrazos, no balazos\u201d.<\/p>\n<p>Invitados al programa M\u00e9xico Opina de CNN en Espa\u00f1ol, que conduce el periodista Mario Gonz\u00e1lez, la especialista en temas de seguridad, Ana Mar\u00eda Salazar; la investigadora y directora de Global Thought M\u00e9xico, Daira Arana, y el director del Observatorio Nacional Ciudadano, Francisco Rivas, analizaron la estrategia y las cifras en materia de seguridad del actual sexenio.<\/p>\n<p>\u201cLos n\u00fameros nos dicen que estamos peor; la narrativa, yo s\u00e9 que hay una narrativa triunfalista\u201d, dijo Rivas, al explicar que cada mes la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana presenta las estad\u00edsticas oficiales asegurando un descenso en los \u00edndices de criminalidad \u201cmaquillando cifras\u201d y con \u201can\u00e1lisis metodol\u00f3gicamente equivocados\u201d.<\/p>\n<p>Sustent\u00f3 su argumento al se\u00f1alar que la dependencia federal no compara per\u00edodos similares, \u201csino que est\u00e1n comparando datos completamente desconectados entre s\u00ed\u201d.<\/p>\n<p>Seguridad, salud y educaci\u00f3n: los retos del pr\u00f3ximo presidente de M\u00e9xico<\/p>\n<p>En su m\u00e1s reciente informe, la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana dijo que los homicidios bajaron un 22% en marzo de 2024 en comparaci\u00f3n con diciembre de 2018, mes en que comenz\u00f3 este sexenio.<\/p>\n<p>El Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi) inform\u00f3 que el Gobierno de L\u00f3pez Obrador sum\u00f3 160.594 homicidios en sus primeros cuatro a\u00f1os y medio de sexenio, superando el r\u00e9cord de muertes alcanzado en toda la administraci\u00f3n de su antecesor, Enrique Pe\u00f1a Nieto.<\/p>\n<p>Al responder a una pregunta sobre la cifra r\u00e9cord de homicidios en M\u00e9xico durante su administraci\u00f3n, L\u00f3pez Obrador reconoci\u00f3 que hay m\u00e1s homicidios pero asegur\u00f3 que &#171;hay menos violencia&#187;. Seg\u00fan el mandatario, el contraste se da porque &#171;hay menos robos que en los sexenios anteriores, hay menos secuestros que en los sexenios anteriores; y delitos del orden federal, menos&#187;. Desde su punto de vista, la causa del ascenso de los homicidios es que &#171;se crearon bandas&#187; durante gobiernos anteriores, que son las que hoy act\u00faan.<\/p>\n<p>Rivas, quien se ha dedicado al an\u00e1lisis de datos en el Observatorio Nacional Ciudadano, agreg\u00f3 que \u201csi nosotros comparamos la tasa, es decir, la parte proporcional de v\u00edctimas respecto de carpetas de investigaci\u00f3n que ten\u00edamos en el pasado, estamos un 50% arriba del sexenio pasado, y estamos un 65% arriba de hace dos sexenios\u201d.<\/p>\n<p>\u201cActualmente ya superamos los 115 homicidios por cada 100.000 habitantes, cuando en todo el sexenio de [el expresidente Felipe] Calder\u00f3n (expresidente) fueron 90 homicidios por cada 100.000 habitantes y en todo el sexenio de [Enrique] Pe\u00f1a [Nieto] fueron 102\u201d, detall\u00f3 Rivas.<\/p>\n<p>Las estrategias de seguridad de los candidatos presidenciales en M\u00e9xico: \u00bfqu\u00e9 proponen?<\/p>\n<p>La investigadora Daira Arana opin\u00f3 que este sexenio en particular no tuvo una pol\u00edtica en materia de seguridad: \u201cTuvo un panfleto, tuvo un slogan, tuvo cosas medi\u00e1ticas, una narrativa medi\u00e1tica muy contundente\u201d, pero advirti\u00f3 que los n\u00fameros oficiales no dan para hablar de resultados positivos.<\/p>\n<p>\u201cLo que vivimos cotidianamente y lo que vemos en las noticias nos muestra que no estamos en un pa\u00eds en paz y creo que ese tema priorizar\u00eda yo, el tema de pacificar los hogares de este pa\u00eds\u201d, afirm\u00f3 al subrayar que hay altos \u00edndices de violencia contra las mujeres y las infancias.<\/p>\n<p>\u201cLos hogares son una fiel representaci\u00f3n de lo que se vive en todo el pa\u00eds\u201d, concluy\u00f3.<\/p>\n<p>Por su parte, la experta en seguridad Ana Mar\u00eda Salazar apunt\u00f3 que cada inicio de sexenio se presenta una crisis en seguridad donde los \u00edndices se incrementan debido a que, en su opini\u00f3n, \u201clos incentivos para ser violento van a ser m\u00e1s, porque es una forma de que estos grupos criminales o estas organizaciones negocien con el nuevo gobierno\u201d.<\/p>\n<p>Dijo que la pr\u00f3xima persona que gobierne M\u00e9xico deber\u00e1 distinguir entre seguridad nacional y seguridad p\u00fablica, y en base en ello definir su estrategia \u201cen contra de las organizaciones m\u00e1s violentas que hay en el pa\u00eds versus las organizaciones que son m\u00e1s locales y podr\u00edan ser m\u00e1s responsabilidad del estado\u201d.<\/p>\n<p>Agreg\u00f3 que los programas sociales son insuficientes para combatir la inseguridad y destac\u00f3 que es prioritario definir el futuro de los cuerpos polic\u00edacos.<\/p>\n<p>\u201c\u00bfM\u00e9xico necesita una polic\u00eda civil?, absolutamente, la pregunta es cu\u00e1ndo y c\u00f3mo lo vas a hacer y c\u00f3mo usas esta estructura de la Guardia Nacional con todos los recursos que se le metieron para que pueda enfrentar a las organizaciones criminales m\u00e1s violentas\u201d, concluy\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0A cinco meses de que finalice el sexenio, expertos en seguridad concluyen que el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, incumpli\u00f3 su promesa de pacificar el pa\u00eds mediante su premisa de \u201cabrazos, no balazos\u201d. Invitados al programa M\u00e9xico Opina de CNN en Espa\u00f1ol, que conduce el periodista Mario Gonz\u00e1lez, la especialista en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448979","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0A cinco meses de que finalice el sexenio, expertos en seguridad concluyen que el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, incumpli\u00f3 su promesa de pacificar el pa\u00eds mediante su premisa de \u201cabrazos, no balazos\u201d. Invitados al programa M\u00e9xico Opina de CNN en Espa\u00f1ol, que conduce el periodista Mario Gonz\u00e1lez, la especialista en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T01:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina\",\"datePublished\":\"2024-05-07T01:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/\"},\"wordCount\":832,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/\",\"name\":\"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-07T01:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/","og_locale":"es_ES","og_type":"article","og_title":"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0A cinco meses de que finalice el sexenio, expertos en seguridad concluyen que el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, incumpli\u00f3 su promesa de pacificar el pa\u00eds mediante su premisa de \u201cabrazos, no balazos\u201d. Invitados al programa M\u00e9xico Opina de CNN en Espa\u00f1ol, que conduce el periodista Mario Gonz\u00e1lez, la especialista en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-07T01:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/"},"author":{"name":"","@id":""},"headline":"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina","datePublished":"2024-05-07T01:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/"},"wordCount":832,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/","name":"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-07T01:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"L\u00f3pez Obrador no cumpli\u00f3 su promesa de pacificar el pa\u00eds, dicen expertos en M\u00e9xico Opina","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/06\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-07T01:03:48Z","datePublished":"2024-05-07T01:03:48Z","dateModified":"2024-05-07T01:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"L\\u00f3pez Obrador no cumpli\\u00f3 su promesa de pacificar el pa\\u00eds, dicen expertos en M\\u00e9xico Opina\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/06\\\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/06\\\/amlo-no-cumplio-promesa-pacificar-pais-mexico-opina-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-07T01:03:48Z\",\"datePublished\":\"2024-05-07T01:03:48Z\",\"dateModified\":\"2024-05-07T01:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1453151,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/09\/27\/como-esta-mexico-lopez-obrador-indicadores-balance-orix\/","url_meta":{"origin":1448979,"position":0},"title":"AN\u00c1LISIS | \u00bfMejor\u00f3 M\u00e9xico con L\u00f3pez Obrador? Estos indicadores sugieren resultados mixtos","author":"","date":"septiembre 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Est\u00e1 por concluir el Gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador en M\u00e9xico. Se trata de un pol\u00edtico que busc\u00f3 el cargo en tres ocasiones \u20142006, 2012 y 2018 (cuando finalmente gan\u00f3)\u2014 y una de las figuras p\u00fablicas m\u00e1s relevantes en la historia reciente del pa\u00eds.L\u00f3pez Obrador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450957,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/08\/proceso-electoral-2023-2024-mas-violento-historia-mexico-39-candidatos-asesinados-consultora-orix\/","url_meta":{"origin":1448979,"position":1},"title":"Proceso electoral 2023-2024 es el m\u00e1s violento en la historia de M\u00e9xico con 39 candidatos asesinados, seg\u00fan firma consultora","author":"","date":"julio 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El proceso electoral 2023-2024 ha sido el m\u00e1s violento en la historia moderna de M\u00e9xico con 889 v\u00edctimas, incluyendo el asesinato de 39 aspirantes o candidatos a alg\u00fan cargo de elecci\u00f3n popular, report\u00f3 este lunes la firma Integralia Consultores en su balance final sobre violencia pol\u00edtica en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459780,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/03\/11\/aranceles-mexico-eeuu-opinion-orix\/","url_meta":{"origin":1448979,"position":2},"title":"OPINI\u00d3N | Aranceles s\u00ed, aranceles no. El impacto en el futuro econ\u00f3mico de M\u00e9xico","author":"","date":"marzo 11, 2025","format":false,"excerpt":"Solo se pueden afirmar dos ideas a prop\u00f3sito del ir y venir del presidente Donald Trump en la imposici\u00f3n de aranceles elevados y generalizados a M\u00e9xico y a Canad\u00e1. Los aranceles que se iban a aplicar a todas las exportaciones mexicanas y canadienses a Estados Unidos se han pospuesto hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448040,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/12\/amlo-prometio-mexico-mejor-sistema-salud-publica-resultados-orix\/","url_meta":{"origin":1448979,"position":3},"title":"L\u00f3pez Obrador prometi\u00f3 que dejar\u00eda en M\u00e9xico \u201cel mejor sistema de salud p\u00fablica del mundo\u201d; algunos dudan si cumplir\u00e1","author":"","date":"abril 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente Andr\u00e9s Manuel L\u00f3pez Obrador incluy\u00f3 entre los 100 compromisos de su gobierno establecer un sistema de salud de primer nivel, universal, gratuito y de calidad, con atenci\u00f3n m\u00e9dica y medicamentos gratuitos, con m\u00e9dicos generales y especialistas suficientes, con estudios diagn\u00f3sticos en los centros de salud y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442736,"url":"https:\/\/noticiasya.com\/midland-odessa\/2023\/12\/27\/el-gobierno-de-lopez-obrador-alista-su-megafarmacia-un-plan-que-genera-dudas-entre-especialistas\/","url_meta":{"origin":1448979,"position":4},"title":"El Gobierno de L\u00f3pez Obrador alista su \u201cmegafarmacia\u201d, un plan que genera dudas entre especialistas","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN en Espa\u00f1ol) --\u00a0El Gobierno de M\u00e9xico se prepara para inaugurar una \u201cmegafarmacia\u201d que, seg\u00fan el presidente Andr\u00e9s Manuel L\u00f3pez Obrador, contar\u00e1 con todos los medicamentos existentes y podr\u00e1 surtir en 24 horas a las instituciones p\u00fablicas de salud que lo requieran. Sin embargo, el plan genera dudas entre especialistas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447376,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/26\/economia-salario-amlo-orix\/","url_meta":{"origin":1448979,"position":5},"title":"As\u00ed han evolucionado la econom\u00eda y los salarios de M\u00e9xico con AMLO","author":"","date":"marzo 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El desempe\u00f1o de la econom\u00eda en M\u00e9xico durante los cinco a\u00f1os que lleva el gobierno del presidente de M\u00e9xico Andr\u00e9s Manuel L\u00f3pez Obrador ha sido de claroscuros: el Producto Interno Bruto (PIB) cay\u00f3 8,5% en 2020, en medio de la pandemia de covid-19, pero de all\u00ed ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1448979"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1448979\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1448979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1448979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1448979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}