{"id":1449101,"date":"2024-05-07T15:03:47","date_gmt":"2024-05-07T22:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/"},"modified":"2024-05-07T15:03:47","modified_gmt":"2024-05-07T22:03:47","slug":"jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/","title":{"rendered":"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump"},"content":{"rendered":"<p>(CNN) &#8212; La jueza Aileen Cannon pospuso indefinidamente el juicio del expresidente Donald Trump sobre los documentos clasificados en Florida, citando cuestiones significativas relacionadas con pruebas clasificadas que tendr\u00edan que resolverse antes de que el caso penal federal pase a un jurado.<\/p>\n<p>En una orden este martes, Cannon cancel\u00f3 la fecha del juicio de mayo y no fij\u00f3 una nueva.<\/p>\n<p>Noticia en desarrollo&#8230;<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La jueza Aileen Cannon pospuso indefinidamente el juicio del expresidente Donald Trump sobre los documentos clasificados en Florida, citando cuestiones significativas relacionadas con pruebas clasificadas que tendr\u00edan que resolverse antes de que el caso penal federal pase a un jurado. En una orden este martes, Cannon cancel\u00f3 la fecha del juicio de mayo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449101","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La jueza Aileen Cannon pospuso indefinidamente el juicio del expresidente Donald Trump sobre los documentos clasificados en Florida, citando cuestiones significativas relacionadas con pruebas clasificadas que tendr\u00edan que resolverse antes de que el caso penal federal pase a un jurado. En una orden este martes, Cannon cancel\u00f3 la fecha del juicio de mayo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T22:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump\",\"datePublished\":\"2024-05-07T22:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/\"},\"wordCount\":92,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/\",\"name\":\"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-07T22:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump - Noticias","og_description":"(CNN) &#8212; La jueza Aileen Cannon pospuso indefinidamente el juicio del expresidente Donald Trump sobre los documentos clasificados en Florida, citando cuestiones significativas relacionadas con pruebas clasificadas que tendr\u00edan que resolverse antes de que el caso penal federal pase a un jurado. En una orden este martes, Cannon cancel\u00f3 la fecha del juicio de mayo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-07T22:03:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump","datePublished":"2024-05-07T22:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/"},"wordCount":92,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/","name":"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-07T22:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-07T22:03:47Z","datePublished":"2024-05-07T22:03:47Z","dateModified":"2024-05-07T22:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jueza federal aplaza indefinidamente el juicio sobre los documentos clasificados de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/07\\\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/07\\\/jueza-federal-aplaza-indefinidamente-juicio-documentos-clasificados-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-07T22:03:47Z\",\"datePublished\":\"2024-05-07T22:03:47Z\",\"dateModified\":\"2024-05-07T22:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447740,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/04\/jueza-cannon-rechaza-intento-trump-desestimar-cargos-penales-caso-documentos-clasificados-trax\/","url_meta":{"origin":1449101,"position":0},"title":"Jueza rechaza el intento de Trump por desestimar los cargos penales en el caso de documentos clasificados","author":"","date":"abril 4, 2024","format":false,"excerpt":"(CNN) -- La jueza federal Aileen Cannon rechaz\u00f3 desestimar los cargos penales contra el expresidente de Estados Unidos Donald Trump en el caso de los documentos clasificados, luego de que el exmandatario argumentara que ten\u00eda autoridad para llevarse consigo material clasificado o sensible tras dejar la Casa Blanca.La breve orden\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446970,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/03\/14\/conclusiones-audiencia-trump-documentos-clasificados-trax\/","url_meta":{"origin":1449101,"position":1},"title":"Conclusiones de la audiencia de Trump para desestimar las acusaciones sobre documentos clasificados","author":"","date":"marzo 14, 2024","format":false,"excerpt":"Fort Pierce, Florida (CNN) --\u00a0La jueza del Tribunal de Distrito de Estados Unidos Aileen Cannon rechaz\u00f3 este jueves desestimar el caso de los documentos clasificados contra Donald Trump tras horas de discusiones en parte sobre si los cargos contra el expresidente eran demasiado vagos.Ante la jueza se plantearon dos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447756,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/04\/05\/jueza-cannon-rechaza-intento-trump-desestimar-cargos-penales-trax\/","url_meta":{"origin":1449101,"position":2},"title":"Trump sufre reveses en sus esfuerzos por cerrar dos de las causas penales en su contra","author":"","date":"abril 5, 2024","format":false,"excerpt":"(CNN) -- El expresidente Donald Trump sufri\u00f3 dos importantes reveses el jueves en sus esfuerzos por hacer descarrilar los casos penales en su contra: los jueces del caso de interferencia electoral en Georgia y del caso federal de documentos clasificados rechazaron sendas peticiones del posible candidato presidencial del Partido Republicano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444304,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/01\/23\/grupo-de-medios-busca-revelar-informacion-en-caso-de-documentos-clasificados-de-trump\/","url_meta":{"origin":1449101,"position":3},"title":"Grupo de medios busca revelar informaci\u00f3n en caso de documentos clasificados de Trump","author":"","date":"enero 23, 2024","format":false,"excerpt":"(CNN) -- Un grupo de m\u00e1s de 30 importantes organizaciones de medios, incluida CNN, est\u00e1 buscando que se revele informaci\u00f3n sobre el caso de los documentos de Mar-a-Lago de Donald Trump, incluidos los nombres de algunos posibles testigos.\"Cualquiera que sea el resultado de este juicio, el p\u00fablico debe tener confianza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449754,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/24\/piden-orden-silencio-trump-documentos-clasificados-trax\/","url_meta":{"origin":1449101,"position":4},"title":"Fiscal especial pide al juez una orden de silencio a Trump en el caso de documentos clasificados","author":"","date":"mayo 24, 2024","format":false,"excerpt":"(CNN) -- Los fiscales de la oficina del fiscal especial pidieron a un juez federal de Florida que imponga una orden de silencio a Donald Trump que limitar\u00eda su capacidad de comentar sobre las fuerzas del orden que registraron su complejo tur\u00edstico de Mar-a-Lago.La solicitud, la primera en el caso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450870,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/07\/04\/fallo-inmunidad-corte-suprema-ayudar-donald-trump-cargos-criminales-trax\/","url_meta":{"origin":1449101,"position":5},"title":"C\u00f3mo el fallo de inmunidad de la Corte Suprema puede ayudar a Donald Trump a luchar contra todos los cargos criminales en su contra","author":"","date":"julio 4, 2024","format":false,"excerpt":"(CNN) -- Se espera que el equipo legal del expresidente Donald Trump utilice la hist\u00f3rica decisi\u00f3n de la Corte Suprema del lunes que le concede inmunidad presidencial parcial para atacar las pruebas en su contra en sus cuatro casos penales, seg\u00fan m\u00faltiples fuentes familiarizadas con su estrategia.El equipo legal salud\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449101"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449101\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}