{"id":1449244,"date":"2024-05-07T22:03:37","date_gmt":"2024-05-08T05:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/"},"modified":"2024-05-07T22:03:37","modified_gmt":"2024-05-08T05:03:37","slug":"relojes-sylvester-stallone-venta-subasta-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/","title":{"rendered":"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas"},"content":{"rendered":"<p>(CNN) &#8212; Poco despu\u00e9s de que Sylvester Stallone terminara de filmar \u201cRocky\u201d, la pel\u00edcula que lanz\u00f3 su carrera en Hollywood, vio a Gregg Allman, de Allman Brothers Band, que se hab\u00eda quedado dormido y hab\u00eda dejado el brazo colgando en el pasillo con un distintivo reloj de oro en la mu\u00f1eca.<\/p>\n<p>Ese reloj fue &#171;la cosa m\u00e1s hermosa que jam\u00e1s hab\u00eda visto&#187;, dijo Stallone en un video publicado por Sotheby&#8217;s, y despert\u00f3 por d\u00e9cadas un amor por coleccionar relojes.<\/p>\n<p>Y ahora, la estrella de Hollywood subastar\u00e1 11 relojes de su colecci\u00f3n personal en una venta de Sotheby&#8217;s en Nueva York el 5 de junio. Entre los art\u00edculos se encuentra el raro Patek Philippe Grandmaster Chime, que se espera que alcance hasta US$ 5 millones, as\u00ed como relojes que us\u00f3 en algunas de sus pel\u00edculas.<\/p>\n<p>Sylvester Stallone le da Carl Weathers, coprotagonista de &#171;Rocky&#187;, el &#171;incre\u00edble cr\u00e9dito&#187; que se merece<\/p>\n<p>Solo se fabricaron siete modelos del Grandmaster Chime, dado que se trata del reloj de pulsera m\u00e1s complicado jam\u00e1s fabricado por los famosos relojeros de lujo.<\/p>\n<p>Como tal, Sotheby&#8217;s lo apod\u00f3 el \u201csanto grial\u201d para los coleccionistas de relojes, apreciado por sus mecanismos extraordinariamente complejos que requirieron 100.000 horas para desarrollarse, producirse y ensamblarse.<\/p>\n<p>El Grandmaster Chime es el reloj Patek Philippe m\u00e1s complicado jam\u00e1s creado. Cr\u00e9dito: Sotheby&#8217;s.<\/p>\n<p>Cuenta con 20 complicaciones (funciones que van m\u00e1s all\u00e1 de decir la hora), como cinco mecanismos de timbre y un repetidor de fecha que indica de forma auditiva tanto la fecha como la hora.<\/p>\n<p>&#171;Esto no es f\u00e1cil de conseguir&#187;, dijo Stallone. \u201cTuve que apelar a ciertos poderes f\u00e1cticos, escribir muchas cartas a la junta y finalmente se determin\u00f3 que yo iba a ser el propietario de una de estas magn\u00edficas obras de arte\u201d.<\/p>\n<p>Otros recuerdos tambi\u00e9n vienen con el reloj, incluida una caja de presentaci\u00f3n grabada con el nombre de Stallone y un iPad y Airpods, cada uno completo con un estuche Patek Phillipe.<\/p>\n<p>Se espera que otro reloj Patek Philippe, este de la familia Nautilus, se venda por hasta US$ 400.000. Presenta una esfera verde oliva, rodeada por 32 diamantes baguette Wesselton, en una caja de acero inoxidable.<\/p>\n<p>Otros varios relojeros notables tambi\u00e9n est\u00e1n representados en la subasta, por ejemplo en algunos modelos que Stallone us\u00f3 frente a la c\u00e1mara.<\/p>\n<p>Un reloj Rolex lanzado en 2016 para conmemorar el 60\u00ba aniversario de un modelo que fue el primero en mostrar el d\u00eda y la fecha por separado podr\u00eda venderse por US$ 50.000.<\/p>\n<p>Mientras tanto, se estima que un reloj fabricado por Audemars Piguet con una esfera azul dentro de una caja de oro rosa se puede vender por hasta US$ 200.000.<\/p>\n<p>Los relojes Cartier se encuentran entre los que subasta Sylvester Stallone. Cr\u00e9dito: Sotheby&#8217;s.<\/p>\n<p>Tambi\u00e9n se incluyen en la subasta varios relojes Panerai, una marca que Stallone ha defendido durante mucho tiempo y que us\u00f3 frente a la c\u00e1mara en la pel\u00edcula de 1996 \u201cDaylight\u201d.<\/p>\n<p>Un modelo hecho exclusivamente para \u00e9l, con un grabado que lo conmemora en la parte posterior, se encuentra entre los relojes presentados en esta subasta y se espera que se venda por hasta US$ 60.000.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Poco despu\u00e9s de que Sylvester Stallone terminara de filmar \u201cRocky\u201d, la pel\u00edcula que lanz\u00f3 su carrera en Hollywood, vio a Gregg Allman, de Allman Brothers Band, que se hab\u00eda quedado dormido y hab\u00eda dejado el brazo colgando en el pasillo con un distintivo reloj de oro en la mu\u00f1eca. Ese reloj fue &#171;la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449244","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Poco despu\u00e9s de que Sylvester Stallone terminara de filmar \u201cRocky\u201d, la pel\u00edcula que lanz\u00f3 su carrera en Hollywood, vio a Gregg Allman, de Allman Brothers Band, que se hab\u00eda quedado dormido y hab\u00eda dejado el brazo colgando en el pasillo con un distintivo reloj de oro en la mu\u00f1eca. Ese reloj fue &#171;la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-08T05:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas\",\"datePublished\":\"2024-05-08T05:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/\"},\"wordCount\":578,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/\",\"name\":\"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-08T05:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas - Noticias","og_description":"(CNN) &#8212; Poco despu\u00e9s de que Sylvester Stallone terminara de filmar \u201cRocky\u201d, la pel\u00edcula que lanz\u00f3 su carrera en Hollywood, vio a Gregg Allman, de Allman Brothers Band, que se hab\u00eda quedado dormido y hab\u00eda dejado el brazo colgando en el pasillo con un distintivo reloj de oro en la mu\u00f1eca. Ese reloj fue &#171;la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-08T05:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/"},"author":{"name":"","@id":""},"headline":"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas","datePublished":"2024-05-08T05:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/"},"wordCount":578,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/","name":"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-08T05:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los relojes de Sylvester Stallone estar\u00e1n a la venta, incluido el \u201csanto grial\u201d de los coleccionistas","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/07\/relojes-sylvester-stallone-venta-subasta-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-08T05:03:37Z","datePublished":"2024-05-08T05:03:37Z","dateModified":"2024-05-08T05:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los relojes de Sylvester Stallone estar\\u00e1n a la venta, incluido el \\u201csanto grial\\u201d de los coleccionistas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/07\\\/relojes-sylvester-stallone-venta-subasta-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/07\\\/relojes-sylvester-stallone-venta-subasta-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-08T05:03:37Z\",\"datePublished\":\"2024-05-08T05:03:37Z\",\"dateModified\":\"2024-05-08T05:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472037,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/03\/09\/sylvester-stallone-precuela-john-rambo-orix\/","url_meta":{"origin":1449244,"position":0},"title":"Sylvester Stallone anuncia que producir\u00e1 la precuela de su ic\u00f3nico personaje John Rambo","author":"","date":"marzo 9, 2026","format":false,"excerpt":"Sylvester Stallone confirm\u00f3 a trav\u00e9s de sus redes sociales que se convertir\u00e1 en productor ejecutivo de la pel\u00edcula \u201cJohn Rambo\u201d, cinta que explorar\u00e1 los or\u00edgenes de su ic\u00f3nico personaje del mismo nombre.A trav\u00e9s de un video publicado en Instagram, el actor de 79 a\u00f1os comparti\u00f3 esta nueva forma en que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457053,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/12\/29\/aparece-chile-rolex-robado-casa-keanu-reeves-los-angeles-trax\/","url_meta":{"origin":1449244,"position":1},"title":"Aparece en Chile un Rolex robado de la casa de Keanu Reeves en Los \u00c1ngeles","author":"","date":"diciembre 29, 2024","format":false,"excerpt":"La Polic\u00eda de Chile dice haber recuperado tres relojes pertenecientes a la estrella de \u201cJohn Wick\u201d, Keanu Reeves, incluido un Rolex de US$ 9.000, que se cree que fueron robados de la casa del actor en Los \u00c1ngeles, a fines de 2023.El reloj Rolex Submariner, grabado con el nombre del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465490,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/08\/14\/analisis-stallone-gaynor-explican-trump-presidencia-trax\/","url_meta":{"origin":1449244,"position":2},"title":"C\u00f3mo Sylvester Stallone y Gloria Gaynor explican a Trump y su presidencia","author":"","date":"agosto 14, 2025","format":false,"excerpt":"Al presidente Donald Trump le encantar\u00eda que las \u00e9lites culturales despreciaran a sus homenajeados en el Kennedy Center.Disfrut\u00f3 revelar las estrellas que agasajar\u00e1 en la gala anual del ic\u00f3nico centro de arte a finales de este a\u00f1o, despu\u00e9s de dirigirse en caravana al complejo este mi\u00e9rcoles a trav\u00e9s de calles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444839,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/02\/03\/muere-carl-weathers-actor-recordado-por-su-papel-de-apollo-creed-en-rocky-a-los-76-anos-2\/","url_meta":{"origin":1449244,"position":3},"title":"Muere Carl Weathers, actor recordado por su papel de Apollo Creed en &#171;Rocky&#187;, a los 76 a\u00f1os","author":"","date":"febrero 3, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El actor Carl Weathers, quien salt\u00f3 a la fama con el personaje de Apollo Creed en las pel\u00edculas de \u201cRocky\u201d y particip\u00f3 en decenas de producciones desde \u201cPredator\u201d hasta \u201cThe Mandalorian\u201d, muri\u00f3 a los 76 a\u00f1os, inform\u00f3 su manager Matt Luber.El actor \u201cfalleci\u00f3 en paz en su casa\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442708,"url":"https:\/\/noticiasya.com\/midland-odessa\/2023\/12\/26\/apple-apela-al-fallo-que-impide-la-venta-de-algunos-modelos-de-apple-watch\/","url_meta":{"origin":1449244,"position":4},"title":"Apple apela al fallo que impide la venta de algunos modelos de Apple Watch","author":"","date":"diciembre 26, 2023","format":false,"excerpt":"(CNN) \u2013\u2013 Apple present\u00f3 una apelaci\u00f3n ante un tribunal del Circuito Federal de EE.UU. en un esfuerzo por revocar el fallo de la Comisi\u00f3n de Comercio Internacional que le impide vender el Apple Watch Series 9 y el Apple Watch Ultra 2, entre otros modelos m\u00e1s recientes, porque violan patentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442723,"url":"https:\/\/noticiasya.com\/midland-odessa\/2023\/12\/27\/apple-apela-al-fallo-que-impide-la-venta-de-algunos-modelos-de-apple-watch-2\/","url_meta":{"origin":1449244,"position":5},"title":"Apple apela al fallo que impide la venta de algunos modelos de Apple Watch","author":"","date":"diciembre 27, 2023","format":false,"excerpt":"(CNN) \u2013\u2013 Apple present\u00f3 una apelaci\u00f3n ante un tribunal del Circuito Federal de EE.UU. en un esfuerzo por revocar el fallo de la Comisi\u00f3n de Comercio Internacional que le impide vender el Apple Watch Series 9 y el Apple Watch Ultra 2, entre otros modelos m\u00e1s recientes, porque violan patentes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449244"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449244\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}