{"id":1449326,"date":"2024-05-09T03:03:46","date_gmt":"2024-05-09T10:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/"},"modified":"2024-05-09T03:03:46","modified_gmt":"2024-05-09T10:03:46","slug":"comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/","title":{"rendered":"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa"},"content":{"rendered":"<p>(CNN) &#8212; La celebraci\u00f3n del D\u00eda de la Victoria en la Plaza Roja de Mosc\u00fa comenz\u00f3, con menos personal de las fuerzas armadas y menos equipo militar en exhibici\u00f3n que el a\u00f1o pasado.<\/p>\n<p>El ministro de Defensa de la Federaci\u00f3n Rusa, general de Ej\u00e9rcito Sergu\u00e9i Shoig\u00fa, dijo en un comunicado en Telegram que &#171;nueve mil personas y 70 equipos militares participar\u00e1n en el principal desfile militar en la Plaza Roja&#187;.<\/p>\n<p>En una declaraci\u00f3n del Ministerio de Defensa de marzo de 2023, Shoigu dijo que m\u00e1s de 10.000 personas y 125 equipos militares participar\u00edan en el desfile en la Plaza Roja.<\/p>\n<p>En esta fotograf\u00eda de grupo distribuida por la agencia estatal rusa Sputnik, el presidente ruso, Vladimir Putin, y el ministro de Defensa, Sergei Shoigu, abandonan la Plaza Roja despu\u00e9s del desfile militar del D\u00eda de la Victoria en el centro de Mosc\u00fa el 9 de mayo de 2024. Rusia celebra el 79.\u00ba aniversario de la victoria sobre la Alemania nazi. en la Segunda Guerra Mundial. (Cr\u00e9dito: MIKHAIL KLIMENTYEV\/POOL\/AFP v\u00eda Getty Images)<\/p>\n<p>La procesi\u00f3n rusa del D\u00eda de la Victoria del 9 de mayo marca la contribuci\u00f3n del pa\u00eds a la derrota de la Alemania nazi en la Segunda Guerra Mundial.<\/p>\n<p>El presidente de Rusia, Vladimir Putin, se dirigir\u00e1 a la multitud en la Plaza Roja despu\u00e9s de inspeccionar la tradicional exhibici\u00f3n de tanques y columnas de tropas que desfilan por la capital.<\/p>\n<p>La agencia de medios estatal rusa Tass inform\u00f3 el jueves que estar\u00edan presentes presidentes extranjeros, incluidos Alexander Lukashenko de Bielorrusia, Kassym-Jomart Tokayev de Kazajst\u00e1n, Emomali Rahmon de Tayikist\u00e1n, Serdar Berdimuhamedow de Turkmenist\u00e1n, Miguel D\u00edaz-Canel de Cuba, Thongloun Sisoulith de Laos, y Umaro Sissoco Embalo, de Guinea-Bissau.<\/p>\n<p>La portavoz del Ministerio de Asuntos Exteriores ruso, Mar\u00eda Zakharova, dijo a TASS en una entrevista que &#171;pa\u00edses hostiles&#187; no ser\u00e1n invitados al desfile por tercer a\u00f1o desde que comenz\u00f3 la guerra en Ucrania.<\/p>\n<p>&#171;Est\u00e1n siguiendo una pol\u00edtica agresiva hacia nuestro pa\u00eds. La formulan como una derrota estrat\u00e9gica&#187;, dijo Zakharova.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La celebraci\u00f3n del D\u00eda de la Victoria en la Plaza Roja de Mosc\u00fa comenz\u00f3, con menos personal de las fuerzas armadas y menos equipo militar en exhibici\u00f3n que el a\u00f1o pasado. El ministro de Defensa de la Federaci\u00f3n Rusa, general de Ej\u00e9rcito Sergu\u00e9i Shoig\u00fa, dijo en un comunicado en Telegram que &#171;nueve mil [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449326","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La celebraci\u00f3n del D\u00eda de la Victoria en la Plaza Roja de Mosc\u00fa comenz\u00f3, con menos personal de las fuerzas armadas y menos equipo militar en exhibici\u00f3n que el a\u00f1o pasado. El ministro de Defensa de la Federaci\u00f3n Rusa, general de Ej\u00e9rcito Sergu\u00e9i Shoig\u00fa, dijo en un comunicado en Telegram que &#171;nueve mil [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-09T10:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa\",\"datePublished\":\"2024-05-09T10:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/\",\"name\":\"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-09T10:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa - Noticias","og_description":"(CNN) &#8212; La celebraci\u00f3n del D\u00eda de la Victoria en la Plaza Roja de Mosc\u00fa comenz\u00f3, con menos personal de las fuerzas armadas y menos equipo militar en exhibici\u00f3n que el a\u00f1o pasado. El ministro de Defensa de la Federaci\u00f3n Rusa, general de Ej\u00e9rcito Sergu\u00e9i Shoig\u00fa, dijo en un comunicado en Telegram que &#171;nueve mil [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-09T10:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/"},"author":{"name":"","@id":""},"headline":"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa","datePublished":"2024-05-09T10:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/","name":"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-09T10:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\u00fa","url":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/midland-odessa\/2024\/05\/09\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-09T10:03:46Z","datePublished":"2024-05-09T10:03:46Z","dateModified":"2024-05-09T10:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Comienza el Desfile de la Victoria de Rusia en la Plaza Roja de Mosc\\u00fa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/09\\\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/midland-odessa\\\/2024\\\/05\\\/09\\\/comienza-desfile-de-la-victoria-rusia-plaza-roja-de-moscu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-09T10:03:46Z\",\"datePublished\":\"2024-05-09T10:03:46Z\",\"dateModified\":\"2024-05-09T10:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473630,"url":"https:\/\/noticiasya.com\/midland-odessa\/2026\/04\/29\/putin-desfile-militar-plaza-roja-trax\/","url_meta":{"origin":1449326,"position":0},"title":"Putin organizar\u00e1 este a\u00f1o un desfile reducido en la Plaza Roja, en medio de crecientes presiones y amenazas","author":"","date":"abril 29, 2026","format":false,"excerpt":"El desfile del D\u00eda de la Victoria del 9 de mayo en la Plaza Roja de Mosc\u00fa es el evento principal para el presidente ruso Vladimir Putin: cada a\u00f1o, Rusia ofrece una exhibici\u00f3n de poder\u00edo militar que muestra las armas m\u00e1s impresionantes del pa\u00eds, incluidos sus misiles y tanques de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462024,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/06\/drones-ucranianos-atacan-moscu-gran-desfile-militar-trax\/","url_meta":{"origin":1449326,"position":1},"title":"Drones ucranianos atacan Mosc\u00fa antes de un gran desfile militar","author":"","date":"mayo 6, 2025","format":false,"excerpt":"Drones ucranianos atacaron Mosc\u00fa por segunda noche consecutiva, dijeron funcionarios rusos este martes, mientras la capital de Rusia se prepara para albergar un importante desfile militar anual al que se espera que asistan l\u00edderes mundiales, incluido Xi Jinping de China.El alcalde de Mosc\u00fa, Sergei Sobyanin, dijo este martes en una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449254,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/08\/donde-celebra-dia-victoria-alemania-nazi-orix\/","url_meta":{"origin":1449326,"position":2},"title":"\u00bfD\u00f3nde y por qu\u00e9 se celebra el D\u00eda de la Victoria sobre la Alemania nazi?","author":"","date":"mayo 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Casi seis a\u00f1os despu\u00e9s de que los primeros tanques alemanes cruzaran la frontera para invadir Polonia, la Segunda Guerra Mundial lleg\u00f3 a su fin en Europa mientras las tropas sovi\u00e9ticas celebraban la captura de Berl\u00edn y las fuerzas de Estados Unidos y el Reino Unido avanzaban sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462154,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/09\/putin-xi-dia-de-la-victoria-desfile-moscu-trax\/","url_meta":{"origin":1449326,"position":3},"title":"Putin, Xi y l\u00edderes mundiales amigos celebran el D\u00eda de la Victoria de Rusia en un desfile militar de Mosc\u00fa","author":"","date":"mayo 9, 2025","format":false,"excerpt":"El presidente ruso, Vladimir Putin, protagoniz\u00f3 el desfile del D\u00eda de la Victoria de Rusia el viernes, rodeado de l\u00edderes mundiales amigos en un espect\u00e1culo coreografiado con gran maestr\u00eda, dise\u00f1ado para mostrar al mundo occidental que Rusia est\u00e1 lejos del aislamiento.Mientras observaba c\u00f3mo miles de tropas marchaban por la Plaza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462152,"url":"https:\/\/noticiasya.com\/midland-odessa\/2025\/05\/09\/dia-victoria-alemania-nazi-orix\/","url_meta":{"origin":1449326,"position":4},"title":"\u00bfD\u00f3nde y por qu\u00e9 se celebra el D\u00eda de la Victoria sobre la Alemania nazi?","author":"","date":"mayo 9, 2025","format":false,"excerpt":"Casi seis a\u00f1os despu\u00e9s de que los primeros tanques alemanes cruzaran la frontera para invadir Polonia, la Segunda Guerra Mundial lleg\u00f3 a su fin en Europa mientras las tropas sovi\u00e9ticas celebraban la captura de Berl\u00edn y las fuerzas de Estados Unidos y el Reino Unido avanzaban sobre el norte y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449418,"url":"https:\/\/noticiasya.com\/midland-odessa\/2024\/05\/12\/putin-reemplaza-ministro-defensa-rusia-sergei-shoigu-trax\/","url_meta":{"origin":1449326,"position":5},"title":"Vladimir Putin reemplaza a Sergei Shoigu, ministro de Defensa de Rusia","author":"","date":"mayo 12, 2024","format":false,"excerpt":"(CNN) -- El presidente de Rusia, Vladimir Putin, reemplaz\u00f3 a su ministro de Defensa, Sergei Shoigu, por un civil, Andrey Belousov, argumentando el aumento del gasto militar del pa\u00eds y la necesidad de \"innovaci\u00f3n\".Shoigu fue \"relevado\" de su cargo de ministro de Defensa por decreto presidencial y nombrado secretario del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/midland-odessa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/comments?post=1449326"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/posts\/1449326\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/media?parent=1449326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/categories?post=1449326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/midland-odessa\/wp-json\/wp\/v2\/tags?post=1449326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}